{"id":33548,"date":"2025-04-29T12:46:26","date_gmt":"2025-04-29T15:46:26","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco.jpg"},"modified":"2025-04-29T12:46:26","modified_gmt":"2025-04-29T15:46:26","slug":"cordel-adeus-papa-francisco","status":"inherit","type":"attachment","link":"https:\/\/correiodasemana.com\/site\/em-tempo-274\/cordel-adeus-papa-francisco\/","title":{"rendered":"Cordel Adeus Papa Francisco"},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-33548","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco.jpg'><img loading=\"lazy\" width=\"300\" height=\"169\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"Cordel Adeus Papa Francisco\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-300x169.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-1024x577.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-768x433.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco.jpg 1239w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1239,"height":698,"file":"2025\/04\/Cordel-Adeus-Papa-Francisco.jpg","filesize":141190,"sizes":{"medium":{"file":"Cordel-Adeus-Papa-Francisco-300x169.jpg","width":300,"height":169,"filesize":14806,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-300x169.jpg"},"large":{"file":"Cordel-Adeus-Papa-Francisco-1024x577.jpg","width":1024,"height":577,"filesize":115373,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-1024x577.jpg"},"thumbnail":{"file":"Cordel-Adeus-Papa-Francisco-150x150.jpg","width":150,"height":150,"filesize":8663,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg"},"medium_large":{"file":"Cordel-Adeus-Papa-Francisco-768x433.jpg","width":768,"height":433,"filesize":72345,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-768x433.jpg"},"covernews-slider-full":{"file":"Cordel-Adeus-Papa-Francisco-1115x698.jpg","width":1115,"height":698,"filesize":158526,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-1115x698.jpg"},"covernews-slider-center":{"file":"Cordel-Adeus-Papa-Francisco-800x500.jpg","width":800,"height":500,"filesize":88103,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-800x500.jpg"},"covernews-featured":{"file":"Cordel-Adeus-Papa-Francisco-1024x577.jpg","width":1024,"height":577,"filesize":115373,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-1024x577.jpg"},"covernews-medium":{"file":"Cordel-Adeus-Papa-Francisco-540x340.jpg","width":540,"height":340,"filesize":46763,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-540x340.jpg"},"covernews-medium-square":{"file":"Cordel-Adeus-Papa-Francisco-400x250.jpg","width":400,"height":250,"filesize":28079,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-400x250.jpg"},"full":{"file":"Cordel-Adeus-Papa-Francisco.jpg","width":1239,"height":698,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33547,"source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco.jpg","_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/33548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=33548"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":33547,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}