{"id":34024,"date":"2025-06-04T00:17:49","date_gmt":"2025-06-04T03:17:49","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8.jpeg"},"modified":"2025-06-04T00:17:49","modified_gmt":"2025-06-04T03:17:49","slug":"muticom-diocesano-8","status":"inherit","type":"attachment","link":"https:\/\/correiodasemana.com\/site\/muticom-diocesano-marca-jubileu-do-mundo-das-comunicacoes-em-sobral\/muticom-diocesano-8\/","title":{"rendered":"muticom diocesano (8)"},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-34024","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8.jpeg'><img loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"muticom diocesano (8)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-1024x683.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-1536x1024.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8.jpeg 1620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1620,"height":1080,"file":"2025\/06\/muticom-diocesano-8.jpeg","filesize":206374,"sizes":{"medium":{"file":"muticom-diocesano-8-300x200.jpeg","width":300,"height":200,"filesize":17997,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-300x200.jpeg"},"large":{"file":"muticom-diocesano-8-1024x683.jpeg","width":1024,"height":683,"filesize":115527,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-1024x683.jpeg"},"thumbnail":{"file":"muticom-diocesano-8-150x150.jpeg","width":150,"height":150,"filesize":7922,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-150x150.jpeg"},"medium_large":{"file":"muticom-diocesano-8-768x512.jpeg","width":768,"height":512,"filesize":74440,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-768x512.jpeg"},"1536x1536":{"file":"muticom-diocesano-8-1536x1024.jpeg","width":1536,"height":1024,"filesize":214643,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-1536x1024.jpeg"},"covernews-slider-full":{"file":"muticom-diocesano-8-1115x715.jpeg","width":1115,"height":715,"filesize":128157,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-1115x715.jpeg"},"covernews-slider-center":{"file":"muticom-diocesano-8-800x500.jpeg","width":800,"height":500,"filesize":75701,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-800x500.jpeg"},"covernews-featured":{"file":"muticom-diocesano-8-1024x683.jpeg","width":1024,"height":683,"filesize":115527,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-1024x683.jpeg"},"covernews-medium":{"file":"muticom-diocesano-8-540x340.jpeg","width":540,"height":340,"filesize":41824,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-540x340.jpeg"},"covernews-medium-square":{"file":"muticom-diocesano-8-400x250.jpeg","width":400,"height":250,"filesize":26329,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8-400x250.jpeg"},"full":{"file":"muticom-diocesano-8.jpeg","width":1620,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":34016,"source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/muticom-diocesano-8.jpeg","_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/34024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=34024"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":34016,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/34016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}