{"id":34878,"date":"2025-07-28T13:07:41","date_gmt":"2025-07-28T16:07:41","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg"},"modified":"2025-07-28T13:07:41","modified_gmt":"2025-07-28T16:07:41","slug":"seminarista-do-3o-ano-de-teologia-da-diocese-de-sobral-elivelton-balbino-presente-no-5o-comise","status":"inherit","type":"attachment","link":"https:\/\/correiodasemana.com\/site\/comise-2025-reune-mais-de-200-participantes-de-todo-o-brasil-em-teresina-pi\/seminarista-do-3o-ano-de-teologia-da-diocese-de-sobral-elivelton-balbino-presente-no-5o-comise\/","title":{"rendered":"Seminarista do 3\u00ba ano de Teologia da Diocese de Sobral, Elivelton Balbino, presente no 5\u00ba COMISE"},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-34878","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg'><img loading=\"lazy\" width=\"225\" height=\"300\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-225x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"Seminarista do 3\u00ba ano de Teologia da Diocese de Sobral, Elivelton Balbino, presente no 5\u00ba COMISE\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-225x300.jpeg 225w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-768x1025.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1151x1536.jpeg 1151w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1024x1366.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg 1176w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" loading=\"lazy\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1176,"height":1569,"file":"2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg","filesize":774839,"sizes":{"medium":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-225x300.jpeg","width":225,"height":300,"filesize":19068,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-225x300.jpeg"},"large":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-768x1024.jpeg","width":768,"height":1024,"filesize":172222,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-768x1024.jpeg"},"thumbnail":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-150x150.jpeg","width":150,"height":150,"filesize":7278,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-150x150.jpeg"},"medium_large":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-768x1025.jpeg","width":768,"height":1025,"filesize":173280,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-768x1025.jpeg"},"1536x1536":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1151x1536.jpeg","width":1151,"height":1536,"filesize":365377,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1151x1536.jpeg"},"covernews-slider-full":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1115x715.jpeg","width":1115,"height":715,"filesize":146535,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1115x715.jpeg"},"covernews-slider-center":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-800x500.jpeg","width":800,"height":500,"filesize":79245,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-800x500.jpeg"},"covernews-featured":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1024x1366.jpeg","width":1024,"height":1366,"filesize":295647,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-1024x1366.jpeg"},"covernews-medium":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-540x340.jpeg","width":540,"height":340,"filesize":39850,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-540x340.jpeg"},"covernews-medium-square":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-400x250.jpeg","width":400,"height":250,"filesize":23641,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE-400x250.jpeg"},"full":{"file":"Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg","width":1176,"height":1569,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":34875,"source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/Seminarista-do-3o-ano-de-Teologia-da-Diocese-de-Sobral-Elivelton-Balbino-presente-no-5o-COMISE.jpeg","_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/34878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=34878"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":34875,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/34875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}