{"id":38325,"date":"2026-05-12T23:30:42","date_gmt":"2026-05-13T02:30:42","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4.jpeg"},"modified":"2026-05-12T23:30:42","modified_gmt":"2026-05-13T02:30:42","slug":"encontro-diocese-de-jordao-4","status":"inherit","type":"attachment","link":"https:\/\/correiodasemana.com\/site\/comunidade-paroquial-de-jordao-celebrou-solenemente-os-atos-liturgicos-da-semana-santa\/encontro-diocese-de-jordao-4\/","title":{"rendered":"encontro diocese de jordao (4)"},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-38325","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4.jpeg'><img loading=\"lazy\" width=\"300\" height=\"221\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-300x221.jpeg\" class=\"attachment-medium size-medium\" alt=\"encontro diocese de jordao (4)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-300x221.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-1024x755.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-768x566.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-1536x1132.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4.jpeg 1593w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1593,"height":1174,"file":"2026\/05\/encontro-diocese-de-jordao-4.jpeg","filesize":533248,"sizes":{"medium":{"file":"encontro-diocese-de-jordao-4-300x221.jpeg","width":300,"height":221,"filesize":18708,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-300x221.jpeg"},"large":{"file":"encontro-diocese-de-jordao-4-1024x755.jpeg","width":1024,"height":755,"filesize":139427,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-1024x755.jpeg"},"thumbnail":{"file":"encontro-diocese-de-jordao-4-150x150.jpeg","width":150,"height":150,"filesize":7530,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-150x150.jpeg"},"medium_large":{"file":"encontro-diocese-de-jordao-4-768x566.jpeg","width":768,"height":566,"filesize":87060,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-768x566.jpeg"},"1536x1536":{"file":"encontro-diocese-de-jordao-4-1536x1132.jpeg","width":1536,"height":1132,"filesize":261348,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-1536x1132.jpeg"},"covernews-featured":{"file":"encontro-diocese-de-jordao-4-1024x755.jpeg","width":1024,"height":755,"filesize":139427,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-1024x755.jpeg"},"covernews-medium":{"file":"encontro-diocese-de-jordao-4-540x340.jpeg","width":540,"height":340,"filesize":43846,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4-540x340.jpeg"},"full":{"file":"encontro-diocese-de-jordao-4.jpeg","width":1593,"height":1174,"mime_type":"image\/jpeg","source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":38321,"source_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/encontro-diocese-de-jordao-4.jpeg","_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/38325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=38325"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38321,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}