{"id":10262,"date":"2019-12-23T03:37:15","date_gmt":"2019-12-23T03:37:15","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=10262"},"modified":"2019-12-23T03:37:15","modified_gmt":"2019-12-23T03:37:15","slug":"politica-em-evidencia-17","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-17\/","title":{"rendered":"Pol\u00edtica em Evid\u00eancia"},"content":{"rendered":"<p>O secret\u00e1rio dos Direitos Humanos, Habita\u00e7\u00e3o e Assist\u00eancia Social de Sobral, J\u00falio Cesar Alexandre, recebeu uma premia\u00e7\u00e3o nacional do Minist\u00e9rio da Cidadania por boas pr\u00e1ticas de educa\u00e7\u00e3o permanente dos visitadores sociais do Programa Primeira Inf\u00e2ncia no SUAS (Sistema \u00danico de Assist\u00eancia Social)\/Crian\u00e7a Feliz. A cerimonia aconteceu em Bras\u00edlia, na \u00faltima quinta-feira (12\/12), durante o encontro nacional do programa. Acompanharam o secret\u00e1rio a supervisora Maria Alc\u00e2ntara e a visitadora social Benedita Lidiane.<br \/>\nOs vereadores de Sobral limparam a pauta e entraram de recesso, voltando somente em fevereiro de 2020. Em conversa com o \u201cPol\u00edtica em Evid\u00eancia\u201d, o presidente Carlos do Calisto avaliou como bastante positivo, apesar de ter que conviver com o caso Rom\u00e1rio Ara\u00fajo. Disse tamb\u00e9m que a experi\u00eancia de administrar o legislativo sobralense foi muito v\u00e1lido, e agora com mais calejado com o cargo no segundo mandato far\u00e1 melhor ainda.<br \/>\nDeputado federal Le\u00f4nidas Cristino, anuncia que o ministro da sa\u00fade Luiz Henrique Mandetta, autorizou a portaria\u00a0\u00a0de habilita\u00e7\u00e3o da Unidade de Pronto Atendimento\u00a0(UPA) de sobral.Usando as m\u00eddias sociais, o deputado registrou esse momento e agradeceu ao ministro pela assinatura da Portaria.\u00a0\u201cMeus agradecimentos ao ministro e queria parabenizar o prefeito Ivo Gomes e o secret\u00e1rio de sa\u00fade Gerardo Cristino pela garantia de recursos Federais para essa importante unidade de sa\u00fade\u201d.<br \/>\nO ano de 2019 marcou diversas a\u00e7\u00f5es, propostas, discuss\u00f5es, momentos festivos na C\u00e2mara Municipal de Meruoca.Na noite da segunda-feira (16), o Presidente da C\u00e2mara Municipal de Meruoca, vereador Mard\u00f4nio Cavalcante, juntamente com os demais vereadores, funcion\u00e1rios e p\u00fablico presente, encerraram os trabalhos legislativos em Sess\u00e3o Solene no Plen\u00e1rio Osvaldo Soares de Oliveira, quando limparam toda a pauta e agradeceram aos meruoquenses pelo apoio.<br \/>\nO Prefeito de Massap\u00ea, Jacques Albuquerque e seu Vice Nilson Frota, continuam entregando brinquedos para as crian\u00e7as, dentro do projeto da secretaria da Cultura, Turismo e Esporte, coordenado por Meire Frota, denominado Natal dos Desejos.Na quinta-feira dia 19 de dezembro, o prefeito entregou brinquedos na Creche do Mumbaba de Cima, Escola Francisco Canuto; Campestre, Santa Luzia; Morgado e Salgadinho. Na sexta-feira, foi realizado na Meruoquinha e Terra Nova.<br \/>\nO prefeito de Meruoca, Ant\u00f4nio Fonteles esteve ao lado de sua esposa Socorro Fonteles e seus filhos, participando e recebendo em Sobral, o trof\u00e9u Personalidade Classe A.Usando as redes sociais, o prefeito registrou:\u00a0\u201cParticipei no Buffet Dona Flor em Sobral, da solenidade de entrega do trof\u00e9u personalidade classe A, O Oscar da Regi\u00e3o Norte.Na oportunidade fui reconhecido como destaque, pela experi\u00eancia e efici\u00eancia na gest\u00e3o p\u00fablica, mostrando que \u00e9 poss\u00edvel fazer mais, com menos, e assim, driblar a crise e garantir a\u00e7\u00f5es e investimentos no munic\u00edpio. Agradecer meus familiares\u00a0e amigos pelo apoio e a comiss\u00e3o julgadora pelo reconhecimento\u201d.<br \/>\nPara iniciar as obras de restaura\u00e7\u00e3o do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, unidade da Santa Casa de Miseric\u00f3rdia de Sobral, foi realizada uma visita t\u00e9cnica de alinhamento no local. Na ocasi\u00e3o, estiveram presentes respons\u00e1veis pelo Abrigo, construtores da empresa que ganhou a licita\u00e7\u00e3o e equipe de coordena\u00e7\u00e3o da obra.\u00a0\u00a0Durante a reforma, que tem previs\u00e3o de oito meses, os 34 idosos ficar\u00e3o remanejados em um dos lados do pr\u00e9dio.<br \/>\nO prefeito Joaquim do Quinca, para finalizar a semana dos 62 anos de emancipa\u00e7\u00e3o pol\u00edtica na vida dos alcantarenses, inaugurou a quadra poliesportiva do S\u00edtio Bel\u00e9m.Usando as m\u00eddias sociais, o prefeito Joaquinzim registrou:\u00a0\u201cEstive no S\u00edtio Bel\u00e9m para fazer a inaugura\u00e7\u00e3o da Quadra de Esportes da localidade. Na ocasi\u00e3o, aconteceu um torneio entre os times Real Madrid (Distrito Silva), FFC (Alc\u00e2ntaras), Coleguinhas (Bel\u00e9m) e Atitude Feminina (S\u00e3o Bento), no qual tive a honra de dar o pontap\u00e9 inicial. A quadra poliesportiva \u00e9 mais uma conquista para o S\u00edtio Bel\u00e9m, que agora conta com um equipamento de lazer e esporte para o bem-estar da comunidade\u201d.<br \/>\nO deputado estadual do PT, Mois\u00e9s Braz esteve participando em Fortaleza, da posse dos membros do\u00a0\u00a0Diret\u00f3rio e a nova Executiva Estadual do PT no Cear\u00e1.Usando as redes sociais, Mois\u00e9s Braz, afirmou convicto:\u00a0\u201cAssumimos mais uma vez a vice-presid\u00eancia do partido e renovamos as for\u00e7as por meio do debate, para seguirmos enfrentando os desafios do Cear\u00e1 e do Brasil\u201d.<br \/>\nDica do Marcelo Marques. Leia mais em www.politicaemevidencia.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio dos Direitos Humanos, Habita\u00e7\u00e3o e Assist\u00eancia Social de Sobral, J\u00falio Cesar Alexandre, recebeu&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,48],"tags":[],"class_list":["post-10262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-politica-em-evidencia"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg",4928,2993,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594-300x182.jpg",300,182,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594-768x466.jpg",640,388,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594-1024x622.jpg",640,389,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg",1536,933,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg",2048,1244,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg",1024,622,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg",540,328,false]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/politica-em-evidencia\/\" rel=\"category tag\">Pol\u00edtica em Evid\u00eancia<\/a>","tag_info":"Pol\u00edtica em Evid\u00eancia","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg","jetpack-related-posts":[{"id":11216,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-25\/","url_meta":{"origin":10262,"position":0},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Mar\u00e7o 18, 2020","format":false,"excerpt":"O secret\u00e1rio dos Direitos Humanos, Habita\u00e7\u00e3o e Assist\u00eancia Social de Sobral, J\u00falio Cesar Alexandre, recebeu uma premia\u00e7\u00e3o nacional do Minist\u00e9rio da Cidadania por boas pr\u00e1ticas de educa\u00e7\u00e3o permanente dos visitadores sociais do Programa Primeira Inf\u00e2ncia no SUAS (Sistema \u00danico de Assist\u00eancia Social) \/ Crian\u00e7a Feliz. A cerimonia aconteceu em Bras\u00edlia,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16971,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-69\/","url_meta":{"origin":10262,"position":1},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Julho 12, 2021","format":false,"excerpt":"O deputado federal, Le\u00f4nidas Cristino (PDT), no dia do anivers\u00e1rio de Sobral pelos 248 anos de emancipa\u00e7\u00e3o pol\u00edtica, comemorado no dia 5 de julho, usando as m\u00eddias sociais, o deputado federal, Le\u00f4nidas Cristino, deixou sua mensagem.\u00a0\u201c\u00c9 com imensa alegria que celebramos o anivers\u00e1rio de 248 anos da nossa querida Sobral.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17428,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-75\/","url_meta":{"origin":10262,"position":2},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Setembro 6, 2021","format":false,"excerpt":"A Prefeitura de Sobral divulgou edital para contrata\u00e7\u00e3o tempor\u00e1ria de profissionais\u00a0para as secretarias da Infraestrutura (Seinfra) e do Tr\u00e2nsito e Transportes (Setran). ser\u00e3o 16 vagas para diferentes \u00e1reas (Edital n\u00ba 003 \/2021). As inscri\u00e7\u00f5es come\u00e7aram na segunda-feira (30\/08), e vai prosseguir at\u00e9 o dia 12 de setembro, de forma virtual,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18894,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-96\/","url_meta":{"origin":10262,"position":3},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Fevereiro 14, 2022","format":false,"excerpt":"O prefeito de Sobral, Ivo Gomes, governador Camilo Santana, estar\u00e3o inaugurando neste s\u00e1bado (12), o Parque Evangelina Saboya de Albuquerque. O novo parque, localizado no bairro Sinh\u00e1 Saboia, possui 43.500 m\u00b2 e contempla academia ao ar livre, playground, anfiteatro, areninha, quadra de areia e ciclovia. O projeto tamb\u00e9m incluiu os\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17659,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-79\/","url_meta":{"origin":10262,"position":4},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Outubro 4, 2021","format":false,"excerpt":"Presidente da C\u00e2mara de Sobral, Paulo Albuquerque (Paul\u00e3o), anunciando que est\u00e1\u00a0preparando junto com a sua equipe de trabalho, programa\u00e7\u00e3o de entrega de T\u00edtulo de Cidadania, que dever\u00e3o acontecer por todo o m\u00eas de outubro. De acordo com Paul\u00e3o, v\u00e1rias Audi\u00eancias P\u00fablicas tamb\u00e9m dever\u00e3o ser realizadas, tratando de assuntos de interesse\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11741,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-29\/","url_meta":{"origin":10262,"position":5},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Julho 12, 2020","format":false,"excerpt":"Com a pandemia do coronav\u00edrus a nossa coluna ficou ausente, mais aos poucos estamos voltando, e lamentando as mortes dos muitos amigos leitores ou n\u00e3o que n\u00e3o resistiram essa doen\u00e7a. Com todo os esfor\u00e7os do prefeito Ivo Gomes, governador Camilo Santana, e o trabalho da secretaria da Sa\u00fade, poucos escaparam\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/10262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=10262"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/10262\/revisions"}],"predecessor-version":[{"id":10263,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/10262\/revisions\/10263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/8594"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=10262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=10262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=10262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}