{"id":11918,"date":"2020-07-16T10:51:45","date_gmt":"2020-07-16T10:51:45","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=11918"},"modified":"2020-07-16T10:51:45","modified_gmt":"2020-07-16T10:51:45","slug":"fiocruz-identifica-nova-variante-do-virus-influenza-no-brasil","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/fiocruz-identifica-nova-variante-do-virus-influenza-no-brasil\/","title":{"rendered":"Fiocruz identifica nova variante do v\u00edrus influenza no Brasil"},"content":{"rendered":"<p><em>Pesquisadores do Instituto Oswaldo Cruz (IOC\/Fiocruz) identificaram uma nova variante do v\u00edrus influenza, causador da gripe, em uma paciente da cidade de Ibipor\u00e3, no Paran\u00e1.<\/em><\/p>\n<p>As an\u00e1lises apontaram a presen\u00e7a do v\u00edrus influenza A(H1N2)v, que provoca infec\u00e7\u00e3o em porcos. O caso foi informado ao Minist\u00e9rio da Sa\u00fade, que notificou a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), seguindo o regulamento sanit\u00e1rio internacional. Todos os registros de infec\u00e7\u00e3o humana por novos subtipos virais precisam ser notificados j\u00e1 que muta\u00e7\u00f5es nestes microrganismos podem levar \u00e0 dissemina\u00e7\u00e3o de pessoa a pessoa, com potencial pand\u00eamico.<\/p>\n<figure id=\"attachment_11920\" aria-describedby=\"caption-attachment-11920\" style=\"width: 780px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-11920\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/whatsapp_image_2020-06-19_at_15.37.28.jpeg\" alt=\"\" width=\"780\" height=\"440\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/whatsapp_image_2020-06-19_at_15.37.28.jpeg 780w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/whatsapp_image_2020-06-19_at_15.37.28-300x169.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/whatsapp_image_2020-06-19_at_15.37.28-768x433.jpeg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><figcaption id=\"caption-attachment-11920\" class=\"wp-caption-text\">V\u00edrus influenza detectado no Paran\u00e1 causa a gripe em su\u00ednos, mas foi identificado em uma paciente humana (Foto: Getty Images)<\/figcaption><\/figure>\n<p>Um alerta emitido pela OMS informa que 26 casos de infec\u00e7\u00e3o por v\u00edrus influenza A(H1N2)v foram registrados desde 2005, e a maioria dos pacientes apresentou quadros leves. No Brasil, um registro j\u00e1 tinha sido realizado em 2016. N\u00e3o h\u00e1 evid\u00eancias de transmiss\u00e3o dessas variantes virais entre pessoas. A virologista Marilda Siqueira, chefe do Laborat\u00f3rio de V\u00edrus Respirat\u00f3rio e do Sarampo do IOC, refer\u00eancia para v\u00edrus respirat\u00f3rios no Brasil e respons\u00e1vel pela identifica\u00e7\u00e3o das variantes do influenza no pa\u00eds, afirma que o novo achado n\u00e3o \u00e9 motivo de preocupa\u00e7\u00e3o. \u201cEssas detec\u00e7\u00f5es ocorrem, ao longo dos anos, em diversos pa\u00edses. N\u00e3o significa que isso vai se transformar em uma pandemia. As medidas de controle s\u00e3o as mesmas para infec\u00e7\u00f5es de transmiss\u00e3o respirat\u00f3ria em geral, como lavar as m\u00e3os e, em caso de sintomas respirat\u00f3rios, procurar atendimento m\u00e9dico para fazer an\u00e1lise melhor do quadro cl\u00ednico\u201d, esclarece a pesquisadora.<\/p>\n<p>A paciente de Ibipor\u00e3, que j\u00e1 est\u00e1 recuperada e n\u00e3o precisou ser hospitalizada, apresentou sintomas de gripe em meados de abril. Ao procurar atendimento m\u00e9dico, ela teve uma amostra do trato respirat\u00f3rio coletada como parte das a\u00e7\u00f5es de rotina do sistema nacional de vigil\u00e2ncia da influenza. O Laborat\u00f3rio Central de Sa\u00fade P\u00fablica do Paran\u00e1 (Lacen-PR) identificou um v\u00edrus influenza A de subtipo desconhecido e encaminhou a amostra ao Laborat\u00f3rio de V\u00edrus Respirat\u00f3rio e do Sarampo do IOC, onde a caracteriza\u00e7\u00e3o do microrganismo foi realizada. Marilda destaca que o achado realizado em meio \u00e0 pandemia de Covid-19, que sobrecarrega os servi\u00e7os de sa\u00fade e a rede de laborat\u00f3rios do pa\u00eds, demonstra a capacidade de resposta brasileira.<\/p>\n<p>\u201cNo meio de uma pandemia de coronav\u00edrus, que est\u00e1 impactando todos os n\u00edveis de aten\u00e7\u00e3o \u00e0 sa\u00fade, trabalhamos dentro dos protocolos e fomos capazes de identificar uma nova variante do v\u00edrus influenza. Isso mostra a capacidade de resposta r\u00e1pida que o nosso pa\u00eds, atrav\u00e9s de um esfor\u00e7o grande do Minist\u00e9rio da Sa\u00fade, das Secretarias de Sa\u00fade, dos Laborat\u00f3rios Centrais de Sa\u00fade P\u00fablica(Lacens) e de institutos como IOC\/Fiocruz, Instituto Evandro Chagas (IEC) e Instituto Adolfo Lutz (IAL), \u00e9 capaz de dar para o controle da influenza\u201d, avalia Marilda.<\/p>\n<p>Uma vez que os v\u00edrus influenza ocorrem em diversas esp\u00e9cies de animais, o surgimento de novas variantes pode ocorrer tanto por muta\u00e7\u00f5es do genoma viral quanto pela recombina\u00e7\u00e3o entre microrganismos de diferentes esp\u00e9cies. Atrav\u00e9s do sequenciamento gen\u00e9tico, os pesquisadores identificaram que a nova variante viral apresentava segmentos do RNA associados a v\u00edrus detectados em porcos e humanos.<\/p>\n<p>\u201cO v\u00edrus identificado no Paran\u00e1 \u00e9 caracterizado como uma nova variante porque apresenta configura\u00e7\u00f5es gen\u00e9ticas diferentes de outros v\u00edrus influenza A (H1N2), incluindo a cepa detectada no Brasil em 2016. Realizando o sequenciamento gen\u00f4mico, observamos que os segmentos H e N da nova variante viral estavam associadas a v\u00edrus que circularam anteriormente em humanos e su\u00ednos. Al\u00e9m disso, detectamos genes internos associados ao v\u00edrus influenza A (H1N1), que circulam desde 2009\u201d, relata Paola Cristina Resende, pesquisadora do Laborat\u00f3rio de V\u00edrus Respirat\u00f3rios e do Sarampo do IOC.<\/p>\n<p>Segundo a OMS, as infec\u00e7\u00f5es humanas por v\u00edrus de gripe de su\u00ednos ocorrem principalmente pelo contato com animais infectados ou ambientes contaminados. No caso de Ibipor\u00e3, as investiga\u00e7\u00f5es ainda est\u00e3o em curso, mas \u00e9 poss\u00edvel que a paciente tenha sido infectada no frigor\u00edfico de su\u00ednos onde trabalha. No mesmo per\u00edodo, outro funcion\u00e1rio do local apresentou sintomas de gripe, mas n\u00e3o foram coletadas amostras na ocasi\u00e3o. A investiga\u00e7\u00e3o epidemiol\u00f3gica e laboratorial em andamento n\u00e3o encontrou ind\u00edcios de outros casos de infec\u00e7\u00e3o. \u201cVamos continuar as an\u00e1lises, mas, at\u00e9 o momento, n\u00e3o h\u00e1 evid\u00eancias de que tenha acontecido transmiss\u00e3o\u201d, refor\u00e7a Marilda.<\/p>\n<p>Por: Ma\u00edra Menezes (IOC\/Fiocruz)<\/p>\n<p>Fonte: <a href=\"http:\/\/www.fiocruz.br\/ioc\/cgi\/cgilua.exe\/sys\/start.htm\">Instituto Oswaldo Cruz<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisadores do Instituto Oswaldo Cruz (IOC\/Fiocruz) identificaram uma nova variante do v\u00edrus influenza, causador da&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-11918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/Jornal-Folha-de-Goi\u00e1s-Fiocruz-identifica-nova-variante-de-v\u00edrus-influenza-A.jpg","jetpack-related-posts":[{"id":18524,"url":"https:\/\/correiodasemana.com\/site\/avanco-de-casos-positivos-para-covid-com-sintomas-leves-e-influenza-geram-alerta-em-todo-o-brasil\/","url_meta":{"origin":11918,"position":0},"title":"Avan\u00e7o de casos positivos para Covid com sintomas leves e influenza geram alerta em todo o Brasil","author":"","date":"Janeiro 10, 2022","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Segundo dados do Conselho Nacional de Secret\u00e1rios de Sa\u00fade (Conass), em uma semana, o n\u00famero de infec\u00e7\u00f5es pela doen\u00e7a praticamente dobrou no pa\u00eds: em 27 de dezembro, a m\u00e9dia m\u00f3vel de contamina\u00e7\u00f5es era de 4.346; nesta segunda-feira (3\/1), o indicador registrou 8.400 \u2014\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/7253_bae1d03d-5e41-3bd5-9f0f-83983390d543.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/7253_bae1d03d-5e41-3bd5-9f0f-83983390d543.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/7253_bae1d03d-5e41-3bd5-9f0f-83983390d543.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/7253_bae1d03d-5e41-3bd5-9f0f-83983390d543.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33813,"url":"https:\/\/correiodasemana.com\/site\/gripe-e-a-principal-causa-de-mortes-por-srag-em-idosos-alerta-fiocruz\/","url_meta":{"origin":11918,"position":1},"title":"Gripe \u00e9 a principal causa de mortes por SRAG em idosos, alerta Fiocruz","author":"adminredacao","date":"Maio 19, 2025","format":false,"excerpt":"Em crian\u00e7as, o v\u00edrus \u00e9 uma das tr\u00eas principais causas de \u00f3bito por Douglas Corr\u00eaa - Rep\u00f3rter da Ag\u00eancia Brasil O boletim InfoGripe, da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) divulgado nesta quinta-feira (15) faz uma alerta sobre o v\u00edrus da influenza A, causador da gripe, que se tornou a principal causa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/dsc1377.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/dsc1377.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/dsc1377.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/dsc1377.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/dsc1377.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":24934,"url":"https:\/\/correiodasemana.com\/site\/24934-2\/","url_meta":{"origin":11918,"position":2},"title":"Notifica\u00e7\u00f5es de gripe avi\u00e1ria em avoantes na regi\u00e3o de Santa Quit\u00e9ria","author":"","date":"Maio 29, 2023","format":false,"excerpt":"Santa Quit\u00e9ria est\u00e1 em alerta ap\u00f3s notifica\u00e7\u00f5es de casos suspeitos de gripe avi\u00e1ria surgirem na regi\u00e3o. Conforme o diretor de sanidade animal da Ag\u00eancia de Defesa Agropecu\u00e1ria do Estado do Cear\u00e1 (Adagri), Amorim Sobreira, em entrevista \u00e0 imprensa na \u00faltima quinta-feira (25), foram identificados poss\u00edveis casos em avoantes nas cidades\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/73090121_2629762480424151_5933251651589636096_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/73090121_2629762480424151_5933251651589636096_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/73090121_2629762480424151_5933251651589636096_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/73090121_2629762480424151_5933251651589636096_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34243,"url":"https:\/\/correiodasemana.com\/site\/numero-de-casos-de-sindrome-respiratoria-e-o-maior-dos-ultimos-2-anos\/","url_meta":{"origin":11918,"position":3},"title":"N\u00famero de casos de s\u00edndrome respirat\u00f3ria \u00e9 o maior dos \u00faltimos 2 anos","author":"adminredacao","date":"Junho 16, 2025","format":false,"excerpt":"Especialista refor\u00e7a import\u00e2ncia da vacina contra gripe POR Douglas Corr\u00eaa - Rep\u00f3rter da Ag\u00eancia Brasil O boletim semanal InfoGripe - divulgado hoje (12) pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz), no Rio de Janeiro - alerta que este ano o total de casos de S\u00edndrome Respirat\u00f3ria Aguda (SRAG) no pa\u00eds tem sido\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/vacina_gripe_04.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/vacina_gripe_04.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/vacina_gripe_04.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/vacina_gripe_04.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/vacina_gripe_04.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":31501,"url":"https:\/\/correiodasemana.com\/site\/casos-respiratorios-graves-em-alta-no-rio-de-janeiro-rj-e-mais-9-estados\/","url_meta":{"origin":11918,"position":4},"title":"Casos respirat\u00f3rios graves em alta no Rio de Janeiro, RJ e mais 9 estados","author":"adminredacao","date":"Novembro 18, 2024","format":false,"excerpt":"Recomenda\u00e7\u00e3o \u00e9 manter a vacina\u00e7\u00e3o contra covid-19 e influenza em dia Por Tomaz Silva\/Ag\u00eancia Brasil Os casos de infec\u00e7\u00f5es respirat\u00f3rias graves est\u00e3o em alta em todas as faixas et\u00e1rias nos estados do Rio de Janeiro e Goi\u00e1s, mostra o Boletim InfoGripe, divulgado pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz). Nas crian\u00e7as e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/dsc8071.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/dsc8071.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/dsc8071.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/dsc8071.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/dsc8071.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18521,"url":"https:\/\/correiodasemana.com\/site\/governo-do-ceara-decreta-reducao-de-publico-em-eventos-festivos-por-30-dias\/","url_meta":{"origin":11918,"position":5},"title":"Governo do Cear\u00e1 decreta redu\u00e7\u00e3o de p\u00fablico em eventos festivos por 30 dias","author":"","date":"Janeiro 10, 2022","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana O governador Camilo Santana (PT) informou, em transmiss\u00e3o ao vivo na \u00faltima quarta-feira (5) a suspen\u00e7\u00e3o de todos os eventos de carnaval e pr\u00e9-carnaval na totalidade do estado do Cear\u00e1 assim como os outros eventos festivos e sociais com controle de acesso ter\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/220105_LIVE-NOVO-DECRETO_CGM8999.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/220105_LIVE-NOVO-DECRETO_CGM8999.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/220105_LIVE-NOVO-DECRETO_CGM8999.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/220105_LIVE-NOVO-DECRETO_CGM8999.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/220105_LIVE-NOVO-DECRETO_CGM8999.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/220105_LIVE-NOVO-DECRETO_CGM8999.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/11918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=11918"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/11918\/revisions"}],"predecessor-version":[{"id":11922,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/11918\/revisions\/11922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/11919"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=11918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=11918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=11918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}