{"id":12915,"date":"2020-08-18T09:34:22","date_gmt":"2020-08-18T12:34:22","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=12915"},"modified":"2020-08-18T09:34:22","modified_gmt":"2020-08-18T12:34:22","slug":"maia-cobra-do-governo-proposta-de-renda-minima-permanente","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/maia-cobra-do-governo-proposta-de-renda-minima-permanente\/","title":{"rendered":"Maia cobra do governo proposta de renda m\u00ednima permanente"},"content":{"rendered":"<p>&#8220;Precisamos saber quais condi\u00e7\u00f5es o governo brasileiro tem para transformar o bolsa fam\u00edlia num programa mais amplo\u201d, disse<\/p>\n<p>O presidente da C\u00e2mara dos Deputados, <a href=\"https:\/\/www.camara.leg.br\/deputados\/74693\">Rodrigo Maia (DEM-RJ)<\/a>, defendeu que o governo apresente proposta de renda m\u00ednima permanente para substituir os atuais R$ 600 do aux\u00edlio emergencial, cujo benef\u00edcio se encerra no m\u00eas que vem. Segundo ele, mesmo que a origem do aux\u00edlio emergencial tenha sido da C\u00e2mara \u2013 projeto do deputado Eduardo Barbosa (PSDB-MG) \u2013, o importante \u00e9 que a sociedade foi atendida pelo aux\u00edlio. A declara\u00e7\u00e3o foi feita em entrevista \u00e0 <em>TV Tropical<\/em>, do Rio Grande do Norte, nesta segunda-feira (17).<\/p>\n<p>\u201cPrecisamos, j\u00e1 olhando para o pr\u00f3ximo ano, organizar algo que garanta \u00e0s fam\u00edlias mais vulner\u00e1veis uma condi\u00e7\u00e3o, uma renda m\u00ednima que deixe de ser emergencial para ser permanente. Precisamos saber quais condi\u00e7\u00f5es o governo brasileiro tem para transformar o bolsa fam\u00edlia num programa mais amplo\u201d, disse o presidente.<\/p>\n<p><strong>Reformas <\/strong><br \/>\nMaia tamb\u00e9m voltou a pedir que o governo encaminhe a proposta de reforma administrativa e ressaltou que o texto n\u00e3o tem como objetivo perseguir servidor nem cortar sal\u00e1rios do funcionalismo. Para Rodrigo Maia, a reforma administrativa vai melhorar a qualidade do servi\u00e7o p\u00fablico prestado, atender melhor o cidad\u00e3o, reduzir a burocracia para garantir um estado moderno e eficiente.<\/p>\n<p>\u201cQueremos \u00e9 valorizar os servidores, e a gente sabe que h\u00e1 reclama\u00e7\u00e3o da sociedade. Queremos melhorar esse marco regulat\u00f3rio para ter um Estado moderno e eficiente na presta\u00e7\u00e3o do servi\u00e7o para o cidad\u00e3o\u201d, defendeu Maia. \u201cN\u00e3o queremos desgastar o presidente com esse tema\u201d, refor\u00e7ou.<\/p>\n<p>Rodrigo Maia tamb\u00e9m ressaltou a import\u00e2ncia da reforma tribut\u00e1ria. Para ele, o sistema tribut\u00e1rio brasileiro \u00e9 muito complexo, e a unifica\u00e7\u00e3o e simplifica\u00e7\u00e3o do sistema vai facilitar os investimentos privados no Pa\u00eds. \u201cA tributa\u00e7\u00e3o s\u00f3 \u00e9 boa quando ela vem para o Estado e \u00e9 aplicada em servi\u00e7os p\u00fablicos com qualidade\u201d, disse o presidente.<\/p>\n<p><strong>Impeachment<\/strong><br \/>\nQuestionado sobre o andamento dos processos de impeachment do presidente\u00a0 Jair Bolsonaro, Maia reafirmou que a prioridade deve ser o enfrentamento ao coronav\u00edrus e a crise econ\u00f4mica por ele provocada. No entanto, destacou que, no momento adequado, vai se posicionar sobre o tema, avaliar o m\u00e9rito e decidir de forma correta \u201cpara n\u00e3o criar uma crise institucional\u201d, disse.<\/p>\n<p><strong>Reportagem \u2013 Luiz Gustavo Xavier<br \/>\nEdi\u00e7\u00e3o &#8211; Wilson Silveira<\/strong><\/p>\n<p>Fonte: Ag\u00eancia C\u00e2mara de Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Precisamos saber quais condi\u00e7\u00f5es o governo brasileiro tem para transformar o bolsa fam\u00edlia num programa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-12915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/170820-maia-record-3-768x512-1.jpeg","jetpack-related-posts":[{"id":13181,"url":"https:\/\/correiodasemana.com\/site\/bolsonaro-diz-que-proposta-do-renda-brasil-esta-suspensa\/","url_meta":{"origin":12915,"position":0},"title":"Bolsonaro diz que proposta do Renda Brasil est\u00e1 suspensa","author":"","date":"Agosto 26, 2020","format":false,"excerpt":"Atual proposta da equipe econ\u00f4mica n\u00e3o ser\u00e1 enviada ao Parlamento O presidente Jair Bolsonaro afirmou hoje (26), ao participar de evento em Ipatinga (MG), que a proposta do programa Renda Brasil est\u00e1 suspensa. O programa pretende expandir o Bolsa Fam\u00edlia. \"Ontem discutimos a proposta, a poss\u00edvel proposta do Renda Brasil.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/520271949837_756bd80295_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/520271949837_756bd80295_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/520271949837_756bd80295_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/520271949837_756bd80295_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/520271949837_756bd80295_o.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16019,"url":"https:\/\/correiodasemana.com\/site\/nova-rodada-do-auxilio-emergencial-como-serao-os-pagamentos-quem-vai-receber-e-o-que-falta-saber\/","url_meta":{"origin":12915,"position":1},"title":"Nova rodada do Aux\u00edlio Emergencial: como ser\u00e3o os pagamentos, quem vai receber e o que falta saber","author":"","date":"Mar\u00e7o 22, 2021","format":false,"excerpt":"Pagamento ser\u00e1 feito em quarto parcelas; valor m\u00e9dio ser\u00e1 de R$ 250, mas pode variar conforme o perfil do benefici\u00e1rio. olta do benef\u00edcio. O novo aux\u00edlio ter\u00e1 4 parcelas de R$ 150 a R$ 375 Fonte: G1 Com o agravamento da pandemia de coronav\u00edrus em todo o pa\u00eds, o governo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13755,"url":"https:\/\/correiodasemana.com\/site\/governo-anuncia-renda-cidada-com-recursos-de-precatorios-e-do-fundeb\/","url_meta":{"origin":12915,"position":2},"title":"Governo anuncia Renda Cidad\u00e3, com recursos de precat\u00f3rios e do Fundeb","author":"","date":"Setembro 28, 2020","format":false,"excerpt":"Novo programa substituir\u00e1 o aux\u00edlio emergencial e o Bolsa Fam\u00edlia O presidente Jair Bolsonaro anunciou\u00a0hoje\u00a0(28) o Renda Cidad\u00e3, novo programa de transfer\u00eancia de renda do governo, que substituir\u00e1 o aux\u00edlio emergencial e o Bolsa Fam\u00edlia. Para financiar o programa, a proposta \u00e9 usar os recursos de pagamento de precat\u00f3rios e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/coletiva_de_imprensa_palacio_da_alvorada_pr_2809201330.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/coletiva_de_imprensa_palacio_da_alvorada_pr_2809201330.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/coletiva_de_imprensa_palacio_da_alvorada_pr_2809201330.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/coletiva_de_imprensa_palacio_da_alvorada_pr_2809201330.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/coletiva_de_imprensa_palacio_da_alvorada_pr_2809201330.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13745,"url":"https:\/\/correiodasemana.com\/site\/renda-cidada-entrara-na-pec-emergencial-e-tera-pelo-menos-r-25-bilhoes-a-mais-que-o-bolsa-familia\/","url_meta":{"origin":12915,"position":3},"title":"Renda Cidad\u00e3 entrar\u00e1 na PEC emergencial e ter\u00e1 pelo menos R$ 25 bilh\u00f5es a mais que o Bolsa Fam\u00edlia","author":"","date":"Setembro 28, 2020","format":false,"excerpt":"Governo deve apresentar nesta segunda-feira (28) proposta de novo programa social e a segunda etapa da reforma tribut\u00e1ria O novo programa social do governo, rebatizado de Renda Cidad\u00e3, estar\u00e1 contido dentro da proposta de emenda \u00e0 Constitui\u00e7\u00e3o (PEC) emergencial e ter\u00e1 pelo menos R$ 25 bilh\u00f5es a mais que o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12108,"url":"https:\/\/correiodasemana.com\/site\/dignidade-auxilio-emergencial-ajuda-familias-do-nordeste-a-encarar-pandemia\/","url_meta":{"origin":12915,"position":4},"title":"Dignidade: Aux\u00edlio Emergencial ajuda fam\u00edlias do Nordeste a encarar pandemia","author":"","date":"Julho 22, 2020","format":false,"excerpt":"A pandemia do novo coronav\u00edrus mudou a vida dos brasileiros. A rotina de trabalho, a ida ao supermercado e at\u00e9 o contato com as pessoas mais pr\u00f3ximas, familiares ou amigos, deixou de ser como era antes desde a ado\u00e7\u00e3o do isolamento social. O maior problema \u00e9 para quem perdeu o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/ae_ebc.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/ae_ebc.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/ae_ebc.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/ae_ebc.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12882,"url":"https:\/\/correiodasemana.com\/site\/auxilio-emergencial-impede-que-235-milhoes-caiam-na-pobreza\/","url_meta":{"origin":12915,"position":5},"title":"Aux\u00edlio emergencial impede que 23,5 milh\u00f5es caiam na pobreza","author":"","date":"Agosto 17, 2020","format":false,"excerpt":"Estudo mostra tamb\u00e9m que medidas do governo levam \u00e0 redu\u00e7\u00e3o tempor\u00e1ria da desigualdade Sem o aux\u00edlio emergencial, 63,1 milh\u00f5es de brasileiros teriam renda per capta inferior a R$ 348,33. Ganhar menos de \u2153 do sal\u00e1rio m\u00ednimo \u00e9 o crit\u00e9rio usado para determinar a pobreza no pa\u00eds. Com o benef\u00edcio, 23,5\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=12915"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12915\/revisions"}],"predecessor-version":[{"id":12919,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12915\/revisions\/12919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/12917"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=12915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=12915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=12915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}