{"id":12960,"date":"2020-08-18T15:19:08","date_gmt":"2020-08-18T18:19:08","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=12960"},"modified":"2020-08-18T15:19:08","modified_gmt":"2020-08-18T18:19:08","slug":"energia-eletrica-e-cara-ou-muito-cara-para-84-dos-brasileiros","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/energia-eletrica-e-cara-ou-muito-cara-para-84-dos-brasileiros\/","title":{"rendered":"Energia el\u00e9trica \u00e9 cara ou muito cara para 84% dos brasileiros"},"content":{"rendered":"<p>Pesquisa \u00e9 do Ibope e da Associa\u00e7\u00e3o dos Comercializadores de Energia<\/p>\n<p>Oitenta e quatro por cento dos brasileiros entrevistados pelo Ibope e pela Associa\u00e7\u00e3o Brasileira dos Comercializadores de Energia (Abraceel) consideram a energia el\u00e9trica cara\u00a0ou muito cara. Para a Abraceel, o valor pago pelos consumidores tem se tornado mais evidente nas despesas das fam\u00edlias, j\u00e1 que as pessoas que consideravam o servi\u00e7o caro ou muito caro no ano de 2014 \u2013 primeiro de realiza\u00e7\u00e3o da pesquisa \u2013 chegavam a 67%. O percentual atingiu a maior marca em 2014 (88%) e no ano passado (87%). A pesquisa ouviu 2 mil pessoas em todas as regi\u00f5es do pa\u00eds, entre os dias\u00a024 de mar\u00e7o e\u00a01\u00ba de abril.<\/p>\n<p>Considerando os dados deste ano, 55% dos entrevistados afirmaram\u00a0que o alto pre\u00e7o \u00e9 causado pelos impostos e 28%, pela falta de concorr\u00eancia no setor. \u201cHoje\u00a0a energia el\u00e9trica \u00e9 um dos servi\u00e7os mais taxados, por uma raz\u00e3o muito simples: os governos estaduais t\u00eam muita facilidade em arrecadar imposto por meio da conta de luz, ent\u00e3o incidem diversos impostos \u2013 federais, estaduais \u2013 e o consumidor percebe que a energia \u00e9 cara devido aos muitos tributos\u201d, disse o presidente da Abraceel, Reginaldo Medeiros.<\/p>\n<p>Ele lembra\u00a0que os valores dos impostos est\u00e3o descritos em cada conta, para que o consumidor possa consultar. Segundo Medeiros, al\u00e9m desses dois fatores apontados pelos entrevistados, outro motivo atrelado ao alto pre\u00e7o das contas s\u00e3o os subs\u00eddios cruzados, que, conforme explica, \u201c\u00e9 o que um consumidor paga pelo outro\u201d. Ele citou dois exemplos em que os mais pobres pagam pelos mais ricos: subs\u00eddios para o agroneg\u00f3cio \u2013 devido aos subs\u00eddios para \u00e1reas rurais \u2013 e para aqueles que instalam pain\u00e9is fotovoltaicos.<\/p>\n<p>\u201cH\u00e1\u00a0consumidor rural que tem desconto de 90% na irriga\u00e7\u00e3o durante a madrugada, isso \u00e9 um subs\u00eddio que algu\u00e9m paga. H\u00e1 muitos subs\u00eddios cruzados. Agora est\u00e1 se colocando muito painel fotovoltaico, quem coloca principalmente \u00e9 quem tem dinheiro para instalar. Quando ele instala o painel, h\u00e1 uma s\u00e9rie de benef\u00edcios que a rede el\u00e9trica traz para ele, que \u00e9 por exemplo regularizar energia\u201d, disse.<\/p>\n<p>Essa regulariza\u00e7\u00e3o diz respeito ao fornecimento de energia el\u00e9trica durante a noite, quando n\u00e3o h\u00e1 energia solar para garantir a demanda. \u201cIsso \u00e9 um benef\u00edcio que a rede el\u00e9trica traz,\u00a0\u00a0mas\u00a0hoje\u00a0ele n\u00e3o paga nada. Quem paga esse subs\u00eddio \u00e9 o consumidor, que n\u00e3o instalou um painel fotovoltaico para esse consumidor mais rico\u201d.<\/p>\n<p>Mercado livre<\/p>\n<p>Em 80% dos casos, os entrevistados gostariam de escolher sua operadora de energia el\u00e9trica, enquanto em 2014, esse percentual era de 66%. A Abraceel defende o modelo do mercado livre, em que o consumidor possa escolher sua fornecedora de energia, e considera que essa \u00e9 uma forma de tornar o setor mais competitivo.<\/p>\n<p>O estudo apresenta\u00a0dados sobre poss\u00edvel mudan\u00e7a do mercado cativo de energia \u2013 atual sistema no qual o consumidor compra energia da distribuidora \u2013 para o mercado livre \u2013 quando ele\u00a0tem a possibilidade de escolher quem ser\u00e1 a sua fornecedora de energia: 63% trocariam de fornecedor de energia caso a medida fosse implementada no pa\u00eds; em 2014, esse percentual era de 57% e, no ano passado, chegou a 68%.<\/p>\n<p>Para a maioria das pessoas entrevistadas (64%), o\u00a0principal motivo para a decis\u00e3o de troca da empresa continua sendo o pre\u00e7o, conforme os dados deste ano. No ano passado, o pre\u00e7o era tamb\u00e9m o principal motivo para 68% dos entrevistados.<\/p>\n<p>Energia limpa<\/p>\n<p>Outro resultado que mostra o perfil do consumidor\u00a0de energia \u00e9 que 17% escolheriam sua operadora com base em uma gera\u00e7\u00e3o de energia mais limpa. Esse percentual era de 13% em 2017, primeiro ano em que a pergunta entrou na pesquisa. No ano passado, eram 15% aqueles que se preocupavam com energia mais limpa na hora de escolher a fornecedora de energia.<\/p>\n<p>Questionados se gostariam de gerar sua pr\u00f3pria energia em casa, 90% dos entrevistados disseram que sim \u2013 o \u00edndice \u00e9 13 pontos percentuais maior que em 2014. Segundo a Abraceel, o\u00a0interesse em trocar de empresa, caso a medida de mercado livre seja implantada no Brasil, assim como o\u00a0interesse em gerar energia el\u00e9trica em casa, crescem \u00e0 medida que aumentam a renda familiar e escolaridade dos entrevistados.<\/p>\n<p>Apenas 39% dos entrevistados est\u00e3o dispostos a pagar um pre\u00e7o maior na conta de luz para incentivar a gera\u00e7\u00e3o de energia em outras resid\u00eancias brasileiras. Segundo avalia a associa\u00e7\u00e3o, como a popula\u00e7\u00e3o considera o pre\u00e7o da energia elevado, parcela significativa n\u00e3o se mostra disposta a pagar um pre\u00e7o mais alto na conta de luz para incentivar a gera\u00e7\u00e3o de energia el\u00e9trica em outras resid\u00eancias.<\/p>\n<p>Edi\u00e7\u00e3o: Gra\u00e7a Adjuto<\/p>\n<p>Por Camila Boehm \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; S\u00e3o Paulo<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa \u00e9 do Ibope e da Associa\u00e7\u00e3o dos Comercializadores de Energia Oitenta e quatro por&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-12960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/energia.jpg","jetpack-related-posts":[{"id":23179,"url":"https:\/\/correiodasemana.com\/site\/conta-de-luz-no-ceara-esta-9-mais-cara\/","url_meta":{"origin":12960,"position":0},"title":"Conta de luz no Cear\u00e1 est\u00e1 9% mais cara","author":"","date":"Janeiro 27, 2023","format":false,"excerpt":"A tarifa foi derrubada no ano passado. Segundo a Associa\u00e7\u00e3o Nacional dos Consumidores de Energia (Anace), diversos estados continuam aplicando a cobran\u00e7a indevidamente. Ap\u00f3s mais de seis meses de vig\u00eancia da lei que zera o Imposto Sobre Circula\u00e7\u00e3o de Mercadorias (ICMS) incidente sobre a distribui\u00e7\u00e3o de energia, a popula\u00e7\u00e3o continua\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/conta_de_luz-aneel_widelg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/conta_de_luz-aneel_widelg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/conta_de_luz-aneel_widelg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/conta_de_luz-aneel_widelg.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/conta_de_luz-aneel_widelg.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9117,"url":"https:\/\/correiodasemana.com\/site\/que-ideologias-estao-por-tras-de-nossas-dificuldades\/","url_meta":{"origin":12960,"position":1},"title":"Que ideologias est\u00e3o por tr\u00e1s de nossas dificuldades?","author":"","date":"Setembro 15, 2019","format":false,"excerpt":"Veja bem, a atual situa\u00e7\u00e3o em que n\u00f3s brasileiros passamos. \u00c9 que o valor do litro da gasolina, de maneira geral, beira os R$ 5,00, a tarifa da energia el\u00e9trica nos chega com bandeira vermelha, o pre\u00e7o dos alimentos s\u00f3 aumentam, por\u00e9m, os \u00edndices da infla\u00e7\u00e3o, segundo os \u00f3rg\u00e3os especializados,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/ideologia-cke.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/ideologia-cke.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/ideologia-cke.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16908,"url":"https:\/\/correiodasemana.com\/site\/contas-de-luz-ficarao-812-mais-caras-a-partir-de-julho-devido-a-crise-hidrica-no-pais\/","url_meta":{"origin":12960,"position":2},"title":"Contas de luz ficar\u00e3o 8,12% mais caras a partir de julho devido \u00e0 crise h\u00eddrica no pa\u00eds","author":"","date":"Julho 5, 2021","format":false,"excerpt":"Por Samuel Carvalho \/ Reda\u00e7\u00e3o Correio da Semana O agravamento da crise h\u00eddrica acarretou o pior cen\u00e1rio dos \u00faltimos 91 anos. Devido a isto, a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) poder\u00e1 aumentar ainda mais a bandeira vermelha n\u00edvel dois nas contas de luz nos pr\u00f3ximos meses. A Aneel vai\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Enel.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Enel.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Enel.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Enel.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Enel.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Enel.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":23525,"url":"https:\/\/correiodasemana.com\/site\/energia-solar-ultrapassa-25-gw-e-alcanca-116-da-matriz-eletrica\/","url_meta":{"origin":12960,"position":3},"title":"Energia solar ultrapassa 25 GW e alcan\u00e7a 11,6% da matriz el\u00e9trica","author":"adminredacao","date":"Fevereiro 14, 2023","format":false,"excerpt":"Segundo associa\u00e7\u00e3o, setor gerou 750 mil empregos em dez anos Por Wellton M\u00e1ximo \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia O Brasil ultrapassou a marca de 25 gigawatts (GW) de pot\u00eancia de energia solar em fevereiro, divulgou a Associa\u00e7\u00e3o Brasileira de Energia Solar Fotovoltaica (Absolar). O levantamento considera tanto as\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/solar.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/solar.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/solar.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14529,"url":"https:\/\/correiodasemana.com\/site\/guedes-se-houver-segunda-onda-governo-pagara-auxilio-emergencial\/","url_meta":{"origin":12960,"position":4},"title":"Guedes: se houver segunda onda, governo pagar\u00e1 aux\u00edlio emergencial","author":"","date":"Novembro 12, 2020","format":false,"excerpt":"Mas ele enfatizou que considera a probabilidade de nova onda de contamina\u00e7\u00f5es \u201cbaixa\u201d. O ministro da Economia, Paulo Guedes, ressaltou, hoje (12) que se houver uma segunda onda de contamina\u00e7\u00f5es pelo novo coronav\u00edrus no Brasil, o governo voltar\u00e1 a conceder o aux\u00edlio emergencial aos brasileiros em situa\u00e7\u00e3o de vulnerabilidade econ\u00f4mica.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5ea9f9a413672.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5ea9f9a413672.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5ea9f9a413672.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5ea9f9a413672.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5ea9f9a413672.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5ea9f9a413672.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":21846,"url":"https:\/\/correiodasemana.com\/site\/tarifa-de-energia-eletrica-deve-subir-em-media-56-em-2023\/","url_meta":{"origin":12960,"position":5},"title":"Tarifa de energia el\u00e9trica deve subir,  em m\u00e9dia, 5,6% em 2023","author":"","date":"Novembro 28, 2022","format":false,"excerpt":"Proje\u00e7\u00e3o foi apresentada pela\u00a0ag\u00eancia ao governo de transi\u00e7\u00e3o Por Paula Laboissi\u00e8re \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia A Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) estima que a tarifa de energia el\u00e9trica deve subir, em m\u00e9dia, 5,6% em 2023. O dado foi apresentado nesta\u00a0quarta-feira (23) ao grupo de Minas e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/conta_de_energia_mcajr_abr2907221115.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/conta_de_energia_mcajr_abr2907221115.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/conta_de_energia_mcajr_abr2907221115.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/conta_de_energia_mcajr_abr2907221115.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/conta_de_energia_mcajr_abr2907221115.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=12960"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12960\/revisions"}],"predecessor-version":[{"id":12963,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12960\/revisions\/12963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/12961"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=12960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=12960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=12960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}