{"id":12981,"date":"2020-08-19T14:44:47","date_gmt":"2020-08-19T17:44:47","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=12981"},"modified":"2020-08-19T14:49:02","modified_gmt":"2020-08-19T17:49:02","slug":"santa-casa-de-misericordia-de-sobral-adquire-nove-modernos-desfibriladores-e-treina-profissionais-para-manuseio-seguro","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-adquire-nove-modernos-desfibriladores-e-treina-profissionais-para-manuseio-seguro\/","title":{"rendered":"Santa Casa de Miseric\u00f3rdia de Sobral adquire nove modernos desfibriladores e treina profissionais para manuseio seguro"},"content":{"rendered":"<p>Os desfibriladores s\u00e3o equipamentos que evitam muitas mortes por parada card\u00edaca.<\/p>\n<p>Pensando na seguran\u00e7a e qualidade da assist\u00eancia prestada \u00e0 popula\u00e7\u00e3o de Sobral e regi\u00e3o, a Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) adquiriu nove novos desfibriladores, com designer moderno, leves, e pr\u00e1ticos para serem utilizados em situa\u00e7\u00f5es de emerg\u00eancia em v\u00e1rios servi\u00e7os do hospital. Investimento custou cerca de R$ 179 mil.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-12986\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-2.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-2.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-2-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-2-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-2-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-2-675x450.jpeg 675w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Os equipamentos foram distribu\u00eddos entre os Servi\u00e7os de Pediatria, Hemodi\u00e1lise, Tomografia e Resson\u00e2ncia, al\u00e9m de Unidades de Terapia Intensiva (UTIs). Para se adequarem \u00e0s novidades tecnol\u00f3gicas presentes nos equipamentos, os enfermeiros dos servi\u00e7os que receberam os desfibriladores, passaram por treinamentos, realizados na sexta-feira (07\/08) no Departamento de Ensino, Pesquisa e Extens\u00e3o (DEPE) da institui\u00e7\u00e3o. Momento foi conduzido por t\u00e9cnicos da empresa Biofors, fornecedora dos equipamentos.<\/p>\n<p><strong>Fun\u00e7\u00e3o<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignleft size-full wp-image-12985\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-3.jpeg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-3.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-3-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-3-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-3-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-3-675x450.jpeg 675w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>O Desfibrilador \u00e9 um aparelho usado para fazer com que os batimentos card\u00edacos de um paciente, que esteja sofrendo uma arritmia card\u00edaca maligna e\/ou um mal s\u00fabito, sejam reiniciados para voltar ao seu ritmo normal. O equipamento realiza essa a\u00e7\u00e3o por meio de choques el\u00e9tricos. Eles s\u00e3o emitidos no peito do paciente e chegam \u00e0 parede tor\u00e1cica do cora\u00e7\u00e3o.<\/p>\n<p>Santa Casa de Miseric\u00f3rdia de Sobral<\/p>\n<p>Assessoria de Comunica\u00e7\u00e3o<\/p>\n<p><strong>Thais Menezes\/ Henrique Brito\/ Domingos Jr<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os desfibriladores s\u00e3o equipamentos que evitam muitas mortes por parada card\u00edaca. Pensando na seguran\u00e7a e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-12981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Desfibrilador-1.jpeg","jetpack-related-posts":[{"id":10209,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-adquire-forno-combinado-para-o-servico-de-nutricao\/","url_meta":{"origin":12981,"position":0},"title":"Santa Casa de Miseric\u00f3rdia de Sobral adquire forno combinado para o Servi\u00e7o de Nutri\u00e7\u00e3o","author":"","date":"Dezembro 16, 2019","format":false,"excerpt":"Com o objetivo de otimizar os processos no servi\u00e7o de Nutri\u00e7\u00e3o hospitalar, a Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) adquiriu com recursos pr\u00f3prios, nesta quinta-feira (12\/12), um forno combinado. Com seu funcionamento, o equipamento ir\u00e1 auxiliar na prepara\u00e7\u00e3o de refei\u00e7\u00f5es mais saud\u00e1veis. \u201cO novo forno vai agilizar os nossos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/Foto1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/Foto1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/Foto1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/Foto1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/Foto1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/Foto1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13073,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-inicia-reestruturacao-de-uti-neonatal-com-aquisicao-de-14-incubadoras-de-alta-tecnologia\/","url_meta":{"origin":12981,"position":1},"title":"Santa Casa de Miseric\u00f3rdia de Sobral inicia reestrutura\u00e7\u00e3o de UTI Neonatal com aquisi\u00e7\u00e3o de 14 incubadoras de alta tecnologia","author":"","date":"Agosto 24, 2020","format":false,"excerpt":"Novas incubadoras proporcionar\u00e3o assist\u00eancia de qualidade a rec\u00e9m-nascidos prematuros de Sobral e outros 54 munic\u00edpios da regi\u00e3o norte do Cear\u00e1, atendidos pela institui\u00e7\u00e3o. Ascom Complexo SCMS Somente em 2019, cerca de 800 rec\u00e9m-nascidos prematuros precisaram dos cuidados do Servi\u00e7o de Neonatologia da Santa Casa de Miseric\u00f3rdia de Sobral (SCMS), principalmente\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Incubadoras-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Incubadoras-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Incubadoras-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Incubadoras-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Incubadoras-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Incubadoras-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16840,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-de-sobral-adquire-moderno-arco-cirurgico\/","url_meta":{"origin":12981,"position":2},"title":"Hospital do Cora\u00e7\u00e3o de Sobral adquire moderno arco cir\u00fargico","author":"","date":"Junho 27, 2021","format":false,"excerpt":"O equipamento permitir\u00e1 a realiza\u00e7\u00e3o de procedimentos minimamente invasivos A evolu\u00e7\u00e3o tecnol\u00f3gica \u00e9 uma grande aliada da pr\u00e1tica de uma medicina cada vez mais resolutiva. No Hospital do Cora\u00e7\u00e3o de Sobral, unidade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, o investimento em novas tecnologias que proporcionem mais qualidade ao\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Foto-1-Novo-arco.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Foto-1-Novo-arco.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Foto-1-Novo-arco.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Foto-1-Novo-arco.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13852,"url":"https:\/\/correiodasemana.com\/site\/uti-pediatrica-da-santa-casa-de-misericordia-de-sobral-recebe-dois-respiradores-pulmonares\/","url_meta":{"origin":12981,"position":3},"title":"UTI Pedi\u00e1trica da Santa Casa de Miseric\u00f3rdia de Sobral recebe dois respiradores pulmonares","author":"","date":"Setembro 30, 2020","format":false,"excerpt":"Para garantir mais qualidade e seguran\u00e7a no atendimento \u00e0s crian\u00e7as de Sobral e regi\u00e3o atendidas pela Santa Casa de Miseric\u00f3rdia de Sobral (SCMS), a Unidade de Terapia Intensiva (UTI) Pedi\u00e1trica da institui\u00e7\u00e3o recebeu na quarta-feira (16\/09) dois respiradores pulmonares, essenciais para tratar pacientes com insufici\u00eancia respirat\u00f3ria. Os dois equipamentos foram\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/RESPIRADORES-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/RESPIRADORES-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/RESPIRADORES-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/RESPIRADORES-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/RESPIRADORES-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/RESPIRADORES-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13629,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-adquire-10-novas-maquinas-para-o-servico-de-hemodialise\/","url_meta":{"origin":12981,"position":4},"title":"Santa Casa de Miseric\u00f3rdia de Sobral adquire 10 novas m\u00e1quinas para o Servi\u00e7o de Hemodi\u00e1lise","author":"","date":"Setembro 21, 2020","format":false,"excerpt":"Disponibilizadas para pacientes do Sistema \u00danico de Sa\u00fade (SUS), as novas m\u00e1quinas juntam-se a outras 45 adquiridas pelo hospital no ano passado. Ascom Complexo SCMS Visando garantir uma assist\u00eancia de qualidade \u00e0 pacientes renais cr\u00f4nicos de Sobral e outros 54 munic\u00edpios da regi\u00e3o norte do estado do Cear\u00e1, a Santa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Foto-1-Hemodialise.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Foto-1-Hemodialise.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Foto-1-Hemodialise.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Foto-1-Hemodialise.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8720,"url":"https:\/\/correiodasemana.com\/site\/servico-de-hemodialise-da-santa-casa-de-sobral-adquire-19-novas-maquinas-e-garante-assistencia-aos-pacientes\/","url_meta":{"origin":12981,"position":5},"title":"Servi\u00e7o de Hemodi\u00e1lise da Santa Casa de Sobral adquire 19 novas m\u00e1quinas e garante assist\u00eancia aos pacientes","author":"","date":"Agosto 17, 2019","format":false,"excerpt":"Compromisso com a hemodi\u00e1lise \u00e9 inova\u00e7\u00e3o tecnol\u00f3gica, seguran\u00e7a do paciente, e humaniza\u00e7\u00e3o Assessoria de comunica\u00e7\u00e3o da Santa Casa de Sobral Refer\u00eancia no procedimento de Terapia Renal Substitutiva (TRS), a Santa Casa de Miseric\u00f3rdia de Sobral recebeu, na ter\u00e7a-feira (13\/08), mais 19 m\u00e1quinas para a unidade de hemodi\u00e1lise. O setor atende\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/Foto-2-m%C3%A1quinas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/Foto-2-m%C3%A1quinas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/Foto-2-m%C3%A1quinas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/Foto-2-m%C3%A1quinas.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/Foto-2-m%C3%A1quinas.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=12981"}],"version-history":[{"count":3,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12981\/revisions"}],"predecessor-version":[{"id":12984,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/12981\/revisions\/12984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/12982"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=12981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=12981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=12981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}