{"id":13133,"date":"2020-08-25T08:04:22","date_gmt":"2020-08-25T11:04:22","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13133"},"modified":"2020-08-25T08:04:22","modified_gmt":"2020-08-25T11:04:22","slug":"economia-verde-pos-pandemia-pode-somar-r-28-trilhoes-a-economia","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/economia-verde-pos-pandemia-pode-somar-r-28-trilhoes-a-economia\/","title":{"rendered":"Economia verde p\u00f3s-pandemia pode somar R$ 2,8 trilh\u00f5es \u00e0 economia"},"content":{"rendered":"<p>Brasil poderia ser beneficiado com dois milh\u00f5es de empregos at\u00e9 2030<br \/>\nA ado\u00e7\u00e3o de op\u00e7\u00f5es de economia verde espec\u00edficas para determinados setores produtivos no per\u00edodo p\u00f3s-pandemia pode acrescentar \u00e0 economia brasileira R$ 2,8 trilh\u00f5es, com a gera\u00e7\u00e3o de dois milh\u00f5es de empregos at\u00e9 2030. A conclus\u00e3o \u00e9 apresentada no estudo Uma Nova Economia para uma Nova Era: Elementos para a Constru\u00e7\u00e3o de uma Economia Mais Eficiente e Resiliente para o Brasil. O estudo \u00e9 liderado pela organiza\u00e7\u00e3o n\u00e3o governamental (ONG) WRI Brasil e pela New Climate Economy e assinado por pesquisadores de seis institui\u00e7\u00f5es nacionais.<br \/>\nO professor de Planejamento Energ\u00e9tico do Instituto Alberto Luiz Coimbra de P\u00f3s-Gradua\u00e7\u00e3o e Pesquisa de Engenharia da Universidade Federal do Rio de Janeiro (Coppe\/UFRJ), Andr\u00e9 Lucena, disse \u00e0 Ag\u00eancia Brasil que essas op\u00e7\u00f5es de economia verde t\u00eam v\u00e1rios co-benef\u00edcios econ\u00f4micos que n\u00e3o s\u00e3o percebidos diretamente, \u201cmas que existem\u201d.<br \/>\nLucena exemplificou que medidas para aprimorar o transporte p\u00fablico, que melhorem a qualidade do ar nas cidades, seja pela substitui\u00e7\u00e3o de combust\u00edveis f\u00f3sseis por outros menos poluentes, significam menores gastos com a sa\u00fade, maior produtividade dos trabalhadores, menos tempo gasto em deslocamentos. \u201cIsso tudo tem ganhos econ\u00f4micos\u201d. Atrav\u00e9s da cria\u00e7\u00e3o de diferentes modelos, os pesquisadores puderam avaliar como custos associados a problemas ambientais podem gerar ganhos econ\u00f4micos.<br \/>\nA melhoria do transporte p\u00fablico poderia ser obtida tamb\u00e9m por medidas transit\u00f3rias, como os carros h\u00edbridos, em que n\u00e3o h\u00e1 mudan\u00e7a de combust\u00edvel, mas t\u00eam uma autonomia bem maior, ou seja, uma efici\u00eancia energ\u00e9tica muito maior. \u201cReduz o consumo de combust\u00edveis e, portanto, a polui\u00e7\u00e3o associada\u201d.<\/p>\n<p>Vantagens<br \/>\nAndr\u00e9 Lucena observou que o Brasil precisa usar vantagens comparativas que possui, associadas a essas medidas de economia verde, de curto, m\u00e9dio e longo prazos. \u201cO Brasil tem vantagens que podem ser utilizadas para tentar melhorar a qualidade e a percep\u00e7\u00e3o de seus produtos no mercado internacional, associadas, por exemplo, \u00e0 baixa intensidade de carbono da matriz el\u00e9trica brasileira\u201d.<br \/>\nO a\u00e7o nacional, por ter alguma participa\u00e7\u00e3o de carv\u00e3o vegetal, tem conte\u00fado de emiss\u00f5es de carbono menor do que pa\u00edses que produzem a\u00e7o baseado em carv\u00e3o mineral. \u201cDiante de uma a\u00e7\u00e3o coordenada global para reduzir emiss\u00f5es, isso pode dar ao Brasil vantagens competitivas a partir da menor intensidade de carbono. Isso precisa ser explorado tamb\u00e9m\u201d, sinalizou o professor da Coppe.<br \/>\nNo caso do setor de uso do solo, o primeiro passo \u00e9 conter o desmatamento, indica o estudo. Andr\u00e9 Lucena explicou que o Brasil n\u00e3o precisa de mais terra. \u201cO Brasil j\u00e1 tem terra suficiente para atender a uma demanda pr\u00f3pria e para exporta\u00e7\u00e3o no horizonte de 2050, principalmente se voc\u00ea considerar que o pa\u00eds tem 200 milh\u00f5es de hectares de pecu\u00e1ria de baixa produtividade que poderia facilmente aumentar, liberando um ter\u00e7o dessas terras para produ\u00e7\u00e3o agr\u00edcola\u201d.<br \/>\nLucena destacou que o pa\u00eds est\u00e1 vivenciando no atual momento uma perda de mercado em fun\u00e7\u00e3o do desmatamento. Acordos comerciais est\u00e3o em risco, como o existente entre o Mercosul e a Alemanha. Al\u00e9m disso, h\u00e1 uma avalia\u00e7\u00e3o negativa de produtos brasileiros no mercado internacional, cortes de fluxos de investimentos, tudo em fun\u00e7\u00e3o do desmatamento. \u201c\u00c9 um custo que n\u00e3o traz benef\u00edcios \u00e0 sociedade nem ao pa\u00eds\u201d, comentou.<\/p>\n<p>Integra\u00e7\u00e3o<br \/>\nO estudo refor\u00e7a que n\u00e3o h\u00e1 necessidade de aumentar a quantidade de terras mas, sim, de melhorar a sua produtividade. Isso pode ser alcan\u00e7ado por meio da recupera\u00e7\u00e3o de pastagens degradadas, da integra\u00e7\u00e3o entre lavoura e pecu\u00e1ria, a\u00e7\u00f5es que repercutem em benef\u00edcios ao meio ambiente. \u201cS\u00e3o medidas que podem fazer com que voc\u00ea tenha um uso mais rent\u00e1vel da terra, na medida em que usa ela n\u00e3o s\u00f3 para pecu\u00e1ria, mas para a lavoura, mantendo a qualidade do solo\u201d.<br \/>\nNa parte industrial, citou que h\u00e1 op\u00e7\u00f5es de eletrifica\u00e7\u00e3o que podem ser adotadas para reduzir emiss\u00f5es de g\u00e1s carb\u00f4nico. Outra \u00e1rea que o Brasil poderia explorar e mostra grande potencial futuro \u00e9 a da qu\u00edmica verde. \u201cA qu\u00edmica verde, embora n\u00e3o tenha um custo t\u00e3o baixo como a petroqu\u00edmica atualmente, em um cen\u00e1rio de descarboniza\u00e7\u00e3o isso pode se reverter. O Brasil tem alta vantagem comparativa nisso, tanto pelo lado do potencial de recursos, entre os quais a biomassa, o etanol, como tecnol\u00f3gica tamb\u00e9m\u201d.<br \/>\nLucena se referiu ao uso de biocombust\u00edveis avan\u00e7ados, como etanol e biodiesel, que substituem gasolina e diesel, que s\u00e3o combust\u00edveis f\u00f3sseis. O estudo sugere a possibilidade de adaptar a ind\u00fastria de biocombust\u00edveis brasileiros j\u00e1 existentes para a produ\u00e7\u00e3o de biocombust\u00edveis avan\u00e7ados em setores em que a substitui\u00e7\u00e3o n\u00e3o \u00e9 trivial, como a avia\u00e7\u00e3o, por exemplo. O querosene de avia\u00e7\u00e3o \u00e9 um combust\u00edvel de alt\u00edssimo valor adicionado e baix\u00edssima substitubilidade, mas h\u00e1 a possibilidade de se fazer o chamado biojet ou bioquerenose de avia\u00e7\u00e3o, indicou o professor de Planejamento Energ\u00e9tico da Coppe\/UFRJ. \u201cSeria um uso muito melhor para a ind\u00fastria j\u00e1 existente no Brasil\u201d.<\/p>\n<p>Governo<br \/>\nNa \u00e1rea de infraestrutura, uma sugest\u00e3o formulada \u00e9 fazer o transporte de mercadorias via cabotagem, que apresenta custo de investimento bem menor que ferrovias, aproveitando o fato de o Brasil ser um pa\u00eds com mais de 8 mil quil\u00f4metros de costa.<br \/>\nO estudo foi encaminhado para o governo federal, atrav\u00e9s do Minist\u00e9rio da Economia.<br \/>\nPor Alana Gandra &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brasil poderia ser beneficiado com dois milh\u00f5es de empregos at\u00e9 2030 A ado\u00e7\u00e3o de op\u00e7\u00f5es&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/cedulas.jpg","jetpack-related-posts":[{"id":22511,"url":"https:\/\/correiodasemana.com\/site\/impostos-pagos-por-brasileiros-em-2022-passam-de-r-28-trilhoes\/","url_meta":{"origin":13133,"position":0},"title":"Impostos pagos por brasileiros em 2022 passam de R$ 2,8 trilh\u00f5es","author":"","date":"Janeiro 4, 2023","format":false,"excerpt":"Os impostos pagos pelos contribuintes brasileiros em todo o pa\u00eds em 2022 totalizaram R$ 2.890.489.835.290,32, de acordo com o Impost\u00f4metro, painel instalado pela Associa\u00e7\u00e3o Comercial de S\u00e3o Paulo (ACSP) na regi\u00e3o central da capital paulista. Em 2021, o mesmo painel registrou aproximadamente R$ 2,6 trilh\u00f5es, aumento de 11,5% de um\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/r-1200-800-q-90-brasileiros-ja-pagaram-mais-de-r-2-trilhoes-em-impostos-este-ano-b37e6154-200c-4dfa-ab3f-25b44ae68bb7.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/r-1200-800-q-90-brasileiros-ja-pagaram-mais-de-r-2-trilhoes-em-impostos-este-ano-b37e6154-200c-4dfa-ab3f-25b44ae68bb7.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/r-1200-800-q-90-brasileiros-ja-pagaram-mais-de-r-2-trilhoes-em-impostos-este-ano-b37e6154-200c-4dfa-ab3f-25b44ae68bb7.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/r-1200-800-q-90-brasileiros-ja-pagaram-mais-de-r-2-trilhoes-em-impostos-este-ano-b37e6154-200c-4dfa-ab3f-25b44ae68bb7.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/r-1200-800-q-90-brasileiros-ja-pagaram-mais-de-r-2-trilhoes-em-impostos-este-ano-b37e6154-200c-4dfa-ab3f-25b44ae68bb7.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15540,"url":"https:\/\/correiodasemana.com\/site\/super-ricos-vao-recuperar-perdas-em-tempo-recorde-diz-relatorio\/","url_meta":{"origin":13133,"position":1},"title":"Super-ricos v\u00e3o recuperar perdas em tempo recorde, diz relat\u00f3rio","author":"","date":"Janeiro 25, 2021","format":false,"excerpt":"Pesquisa da Oxfam ser\u00e1 lan\u00e7ada hoje no F\u00f3rum Econ\u00f4mico Mundial As mil pessoas mais ricas do mundo levar\u00e3o apenas nove meses para ver suas fortunas retornarem aos n\u00edveis pr\u00e9-pandemia, enquanto os mais pobres v\u00e3o levar 14 vezes mais, ou seja, mais\u00a0de dez\u00a0anos, para conseguir repor as perdas devido ao impacto\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/dinheiro2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/dinheiro2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/dinheiro2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/dinheiro2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22045,"url":"https:\/\/correiodasemana.com\/site\/brasil-ja-responde-por-10-dos-empregos-verdes-em-todo-o-mundo\/","url_meta":{"origin":13133,"position":2},"title":"Brasil j\u00e1 responde por 10% dos empregos verdes em todo o mundo","author":"","date":"Dezembro 5, 2022","format":false,"excerpt":"A qualidade da matriz energ\u00e9tica, com quase 50% de energia renov\u00e1vel, e o potencial da economia verde podem alavancar o desenvolvimento do Brasil nos pr\u00f3ximos anos, com uma gera\u00e7\u00e3o de emprego mais sustent\u00e1vel. Para se ter ideia, hoje o Pa\u00eds j\u00e1 responde por 10% de todos os empregos verdes no\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/Acesse-Politica-O-site-de-politica-mais-acessado-da-Bahia-www.acessepolitica.com_.br-brasil-meio-ambiente-floresta.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/Acesse-Politica-O-site-de-politica-mais-acessado-da-Bahia-www.acessepolitica.com_.br-brasil-meio-ambiente-floresta.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/Acesse-Politica-O-site-de-politica-mais-acessado-da-Bahia-www.acessepolitica.com_.br-brasil-meio-ambiente-floresta.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/Acesse-Politica-O-site-de-politica-mais-acessado-da-Bahia-www.acessepolitica.com_.br-brasil-meio-ambiente-floresta.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14435,"url":"https:\/\/correiodasemana.com\/site\/joe-biden-eleito-nos-eua-quais-sao-suas-propostas-em-8-temas-cruciais\/","url_meta":{"origin":13133,"position":3},"title":"Joe Biden eleito nos EUA: quais s\u00e3o suas propostas em 8 temas cruciais","author":"","date":"Novembro 9, 2020","format":false,"excerpt":"Coronav\u00edrus, emprego e renda, mudan\u00e7a clim\u00e1tica, racismo... Veja como o presidente eleito se posiciona e o que promete em rela\u00e7\u00e3o a assuntos centrais para os Estados Unidos. Quando anunciou formalmente sua entrada na corrida presidencial de 2020, Joe Biden \u2013 s\u00e1bado (7\/11\/2020) presidente dos EUA\u00a0\u2013 afirmou que defendia duas coisas:\u00a0os\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/joe-biden.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/joe-biden.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/joe-biden.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":24470,"url":"https:\/\/correiodasemana.com\/site\/eventos-climaticos-podem-levar-milhoes-a-pobreza-extrema-no-brasil\/","url_meta":{"origin":13133,"position":4},"title":"Eventos clim\u00e1ticos podem levar milh\u00f5es \u00e0 pobreza extrema no Brasil","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"Segundo o Banco Mundial, pa\u00eds pode reverter o cen\u00e1rio com investimento Publicado em 04\/05\/2023 - 09:10 Por Paulliny Tort \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia Eventos relacionados ao clima podem levar de 800 mil a 3 milh\u00f5es de brasileiros \u00e0 pobreza extrema a partir de 2030. Os dados s\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/petropolis_chuvas_tnrgo_abr_1602220711.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/petropolis_chuvas_tnrgo_abr_1602220711.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/petropolis_chuvas_tnrgo_abr_1602220711.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/petropolis_chuvas_tnrgo_abr_1602220711.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/petropolis_chuvas_tnrgo_abr_1602220711.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18797,"url":"https:\/\/correiodasemana.com\/site\/riquezas-e-pobrezas\/","url_meta":{"origin":13133,"position":5},"title":"Riquezas e Pobrezas","author":"","date":"Fevereiro 7, 2022","format":false,"excerpt":"Quando falamos em riqueza o que nos vem logo \u00e0 mente s\u00e3o pessoas que possuem patrim\u00f4nios materiais como casas suntuosas, apartamentos de luxo, carros importados, fazendas, ind\u00fastrias. J\u00e1 quando ouvimos a palavra pobreza nos vem o pensamento a pessoas sem moradia ou que moram embaixo de pontes, em casas de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13133"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13133\/revisions"}],"predecessor-version":[{"id":13136,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13133\/revisions\/13136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13134"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}