{"id":13162,"date":"2020-08-26T08:22:03","date_gmt":"2020-08-26T11:22:03","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13162"},"modified":"2020-08-26T08:22:03","modified_gmt":"2020-08-26T11:22:03","slug":"casa-verde-e-amarela-incluira-1-milhao-de-familias-no-credito-imobiliario","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/casa-verde-e-amarela-incluira-1-milhao-de-familias-no-credito-imobiliario\/","title":{"rendered":"Casa Verde e Amarela incluir\u00e1 1 milh\u00e3o de fam\u00edlias no cr\u00e9dito imobili\u00e1rio"},"content":{"rendered":"<p>O Programa Casa Verde e Amarela, do Minist\u00e9rio do Desenvolvimento Regional (MDR), vai facilitar o acesso da popula\u00e7\u00e3o a uma moradia digna, garantindo mais qualidade de vida.<\/p>\n<p>A partir de medidas que garantir\u00e3o efici\u00eancia na aplica\u00e7\u00e3o dos recursos, a meta \u00e9 atender 1,6 milh\u00e3o de fam\u00edlias de baixa renda com o financiamento habitacional at\u00e9 2024, um incremento de 350 mil. Isso ser\u00e1 poss\u00edvel com a redu\u00e7\u00e3o na taxa de juros para a menor da hist\u00f3ria do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) e mudan\u00e7as na remunera\u00e7\u00e3o do agente financeiro.<\/p>\n<p>Para o presidente da C\u00e2mara Brasileira da Ind\u00fastria da Constru\u00e7\u00e3o (CBIC), Jos\u00e9 Carlos Martins, a iniciativa aprimora o antigo programa e traz inova\u00e7\u00f5es muito interessantes. \u201cUm aumento de 350 mil novas unidades que acrescer\u00e3o ao que j\u00e1 est\u00e1 previsto, sem a necessidade de gasto p\u00fablico \u00e9 um grande avan\u00e7o. Agora, vamos discutir perante o Senado e a C\u00e2mara os ajustes que se fizerem necess\u00e1rios\u201d, explicou Martins.<\/p>\n<p>J\u00e1 para garantir a continuidade das obras de 185 mil unidades habitacionais contratadas, a retomada de 100 mil resid\u00eancias e os empreendimentos de urbaniza\u00e7\u00e3o em andamento, h\u00e1 a previs\u00e3o de aporte de R$ 2,4 bilh\u00f5es do Or\u00e7amento Geral da Uni\u00e3o (OGU) para o pr\u00f3ximo ano.<\/p>\n<p>O ministro Rog\u00e9rio Marinho afirmou uma das prioridades do novo programa \u00e9 retomar as obras paralisadas. \u201cToda semana damos ordem de rein\u00edcio de obras por todo Brasil. Dessas cem mil unidades, quase 15 mil j\u00e1 foram retomadas. N\u00f3s estamos determinados a n\u00e3o desperdi\u00e7ar o recurso do povo brasileiro, obra parada \u00e9 um tapa na cara da popula\u00e7\u00e3o, \u00e9 jogar fora dinheiro p\u00fablico, \u00e9 n\u00e3o dar ao cidad\u00e3o a satisfa\u00e7\u00e3o de uma atividade governamental\u201d, destacou Marinho.<\/p>\n<p>Jos\u00e9 Carlos Martins prestigia lan\u00e7amento do Casa Verde e Amarela<\/p>\n<p>Com o objetivo de \u00a0detalhar o novo programa habitacional, a CBIC recebe no pr\u00f3ximo\u00a0<strong>\u2018Quintas da CBIC\u2019<\/strong>\u00a0o Secret\u00e1rio Nacional de Habita\u00e7\u00e3o do Minist\u00e9rio do Desenvolvimento Regional, Alfredo Eduardo dos Santos. O encontro ter\u00e1 in\u00edcio \u00e0s 17 horas, com media\u00e7\u00e3o do presidente da CBIC. Inscreva-se pelo link:\u00a0<a href=\"https:\/\/cbic.org.br\/es_ES\/casa-verde-e-amarela-incluira-1-milhao-de-familias-no-credito-imobiliario\/bit.ly\/quintascbic-278\"><strong>bit.ly\/quintascbic-278<\/strong><\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-13164\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/pre.jpg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/pre.jpg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/pre-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/pre-1024x682.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/pre-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/pre-675x450.jpg 675w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><strong>Abrang\u00eancia<\/strong><\/p>\n<p>As regi\u00f5es Norte e Nordeste ser\u00e3o contempladas com a redu\u00e7\u00e3o nas taxas em at\u00e9 0,5 ponto percentual para fam\u00edlias com renda de at\u00e9 R$ 2 mil mensais e 0,25 para quem ganha entre R$ 2 mil e R$ 2,6 mil. Nessas localidades, os juros poder\u00e3o chegar a 4,25% ao ano para cotistas do FGTS e, nas demais regi\u00f5es, a 4,5%.<\/p>\n<p>\u201cCom essas altera\u00e7\u00f5es, queremos estimular novas contrata\u00e7\u00f5es no Norte e Nordeste, que t\u00eam os maiores d\u00e9ficits habitacionais no Pa\u00eds. Essas taxas diferenciadas buscam reduzir as desigualdades regionais, que \u00e9 uma das principais miss\u00f5es do MDR\u201d, destaca o ministro Rog\u00e9rio Marinho. \u201cAl\u00e9m disso, as novas medidas possibilitar\u00e3o que, pelo menos, 1 milh\u00e3o de pessoas que estavam fora do sistema de financiamento habitacional possam ter acesso a ele\u201d, completa.<\/p>\n<p>Al\u00e9m dos juros menores, o Norte e o Nordeste ter\u00e3o, ainda, outros benef\u00edcios, como uma parcela mais abrangente de fam\u00edlias beneficiadas, com rendimento de at\u00e9 R$ 2,6 mil ao m\u00eas, ante 2 mil das demais regi\u00f5es. O limite do valor dos im\u00f3veis financiados tamb\u00e9m foi ampliado, com o objetivo de fomentar o interesse do setor da constru\u00e7\u00e3o civil em atuar nessas localidades.<\/p>\n<p>O programa tamb\u00e9m atuar\u00e1 com regulariza\u00e7\u00e3o fundi\u00e1ria e melhoria de resid\u00eancias, enfrentando problemas de inadequa\u00e7\u00f5es, como falta de banheiro, por exemplo. A meta \u00e9 regularizar 2 milh\u00f5es de moradias e promover melhorias em 400 mil at\u00e9 2024.<\/p>\n<p>\u201cNosso objetivo, seguindo as recomenda\u00e7\u00f5es do presidente Jair Bolsonaro, \u00e9 trazer resultados mais eficientes no atendimento \u00e0s necessidades habitacionais brasileiras e oferecer moradia digna \u00e0s fam\u00edlias mais vulner\u00e1veis\u201d, explica Marinho. \u201cFoi seguindo essa linha e ouvindo outros \u00f3rgaos e o\u00a0 setor da constru\u00e7\u00e3o civil que chegamos a esse modelo. O Casa Verde e Amarela ir\u00e1 movimentar o mercado e gerar emprego e renda\u201d, destaca.<\/p>\n<p>A previs\u00e3o \u00e9 disponibilizar, at\u00e9 o fim do ano, mais R$ 25 bilh\u00f5es do FGTS e R$ 500 milh\u00f5es do FDS para o Programa. Os empreendimentos devem gerar, at\u00e9 2024, mais de 2,3 milh\u00f5es de novos postos de trabalho diretos, indiretos e induzidos.<\/p>\n<p>Ap\u00f3s a publica\u00e7\u00e3o da Medida Provis\u00f3ria da cria\u00e7\u00e3o do Programa, as propostas ser\u00e3o analisadas e aprovadas pelos conselhos curadores do FGTS e do Fundo de Desenvolvimento Social (FDS). Ainda neste ano, ser\u00e3o publicados os primeiros editais para a contrata\u00e7\u00e3o de regulariza\u00e7\u00e3o fundi\u00e1ria e melhorias habitacionais.<\/p>\n<p><strong>Regulariza\u00e7\u00e3o fundi\u00e1ria e melhoria habitacional<\/strong><\/p>\n<p>De acordo com os dados preliminares da Funda\u00e7\u00e3o Jo\u00e3o Pinheiro (FJP), ano base 2019, 24,4 milh\u00f5es de moradias foram consideradas inadequadas por car\u00eancia de infraestrutura em todo o Pa\u00eds. Deste total, 10,7 milh\u00f5es s\u00e3o relativas \u00e0 edifica\u00e7\u00e3o. \u201cNossa premissa m\u00e1xima \u00e9 garantir moradia digna. Se a fam\u00edlia j\u00e1 tem o seu terreno e o im\u00f3vel constru\u00eddo, mas que \u00e9 prec\u00e1rio, vamos apoi\u00e1-la com a reforma. H\u00e1, ainda, muitas pessoas que vivem em lotes irregulares e, por isso, n\u00e3o conseguem melhorar seu im\u00f3vel. Nesse caso, apoiaremos com a regulariza\u00e7\u00e3o\u201d, explica o ministro Rog\u00e9rio Marinho.<\/p>\n<p>Com essas estrat\u00e9gias, o Governo Federal espera atender um n\u00famero mais amplo de pessoas em vulnerabilidade social a menor custo para o Poder P\u00fablico, j\u00e1 que o investimento nas duas modalidades \u00e9 muito inferior (de R$ 500 a R$ 20 mil) em compara\u00e7\u00e3o com a constru\u00e7\u00e3o de uma unidade habitacional \u2013 m\u00e9dia de R$ 80 mil.<\/p>\n<p>A Regulariza\u00e7\u00e3o Fundi\u00e1ria (RF) vai enfrentar um problema hist\u00f3rico no Pa\u00eds e dar o t\u00edtulo que garante o direito real sobre o lote das fam\u00edlias, oferecendo seguran\u00e7a jur\u00eddica, a redu\u00e7\u00e3o dos conflitos fundi\u00e1rios, a amplia\u00e7\u00e3o do acesso ao cr\u00e9dito, o est\u00edmulo \u00e0 formaliza\u00e7\u00e3o de empresas e o aumento do patrim\u00f4nio imobili\u00e1rio do Pa\u00eds. Ser\u00e3o contempladas \u00e1reas ocupadas, majoritariamente, por fam\u00edlias com renda de at\u00e9 R$ 5 mil mensais que vivam em n\u00facleos urbanos informais. N\u00e3o poder\u00e3o ser inclu\u00eddas casas localizadas em \u00e1reas n\u00e3o pass\u00edveis de regulariza\u00e7\u00e3o ou de risco.<\/p>\n<p>J\u00e1 a Melhoria Habitacional (MH) consiste na reforma e amplia\u00e7\u00e3o do im\u00f3vel, como constru\u00e7\u00e3o de telhado, quarto extra, banheiro, instala\u00e7\u00f5es el\u00e9tricas ou hidr\u00e1ulicas, coloca\u00e7\u00e3o de piso e acabamentos em geral. Tamb\u00e9m poder\u00e3o ser instalados equipamentos de aquecimento solar ou efici\u00eancia energ\u00e9tica.<\/p>\n<p>As melhorias habitacionais s\u00e3o uma forma de aproveitar os investimentos j\u00e1 realizados pelas fam\u00edlias em suas casas, al\u00e9m de respeitar os v\u00ednculos sociais e econ\u00f4micos. Ser\u00e3o atendidos propriet\u00e1rios de im\u00f3veis nos n\u00facleos urbanos selecionados para Regulariza\u00e7\u00e3o Fundi\u00e1ria, com renda mensal de at\u00e9 R$ 2 mil. \u00c9 necess\u00e1rio estar no Cad\u00danico do Governo Federal, n\u00e3o possuir outros im\u00f3veis no territ\u00f3rio nacional e o propriet\u00e1rio ser maior de 18 anos ou emancipado.<\/p>\n<p><strong>Sele\u00e7\u00e3o e execu\u00e7\u00e3o<\/strong><\/p>\n<p>A execu\u00e7\u00e3o das obras de melhoria habitacional e servi\u00e7os de regulariza\u00e7\u00e3o fundi\u00e1ria ser\u00e1 por meio de uma linha de financiamento para empresas privadas, que submeter\u00e3o propostas ao MDR ainda este ano, j\u00e1 com a indica\u00e7\u00e3o dos locais. A documenta\u00e7\u00e3o ser\u00e1 enviada por meio de preenchimento de carta-consulta\u00a0<em>on-line<\/em>, obrigatoriamente com a anu\u00eancia do poder p\u00fablico municipal ou distrital.<\/p>\n<p>As propostas selecionadas pelo Minist\u00e9rio dever\u00e3o ser apresentadas pelas empresas ao agente financeiro para an\u00e1lise de viabilidade t\u00e9cnica, jur\u00eddica e econ\u00f4mico- financeira visando contrata\u00e7\u00e3o da opera\u00e7\u00e3o de financiamento, que ser\u00e1 repassado \u00e0 fam\u00edlia beneficiada a valores quase que 100% subsidiados pelo FDS.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Financiamento Habitacional Popular<\/strong><\/p>\n<p>As mudan\u00e7as nos financiamentos possibilitar\u00e3o que o FGTS tenha mais recursos para novas contrata\u00e7\u00f5es. Em linhas gerais, ocorrer\u00e1 a redu\u00e7\u00e3o da parcela de\u00a0<em>spread\u00a0<\/em>banc\u00e1rio (diferen\u00e7a entre o valor pago pelo banco aos correntistas e o cobrado nas opera\u00e7\u00f5es de cr\u00e9dito) pago pelo Fundo aos agentes financeiros operadores do programa, sem comprometer a sustentabilidade das opera\u00e7\u00f5es<\/p>\n<p>As contrata\u00e7\u00f5es de cr\u00e9dito viabilizadas por meio do Casa Verde Amarela ocorrer\u00e3o nos moldes j\u00e1 implementados pelos agentes financeiros: os cidad\u00e3os interessados devem procurar diretamente as construtoras credenciadas e os bancos operadores.<\/p>\n<p><strong>Investimentos realizados<\/strong><\/p>\n<p>Desde 2019, o Governo Federal vem assegurando a continuidade das unidades habitacionais j\u00e1 contratadas e a retomada de obras paralisadas. Para tanto, j\u00e1 foram investidos R$ 5,78 bilh\u00f5es de Or\u00e7amento Geral da Uni\u00e3o no programa de habita\u00e7\u00e3o. Desse total, R$ 5 bilh\u00f5es foram para as moradias destinadas \u00e0s fam\u00edlias com renda mensal de at\u00e9 R$ 1,8 mil.<\/p>\n<p>Na \u00e1rea de financiamentos habitacionais, foram disponibilizados R$ 62 bilh\u00f5es do FGTS em 2019 e, neste ano, o montante deve alcan\u00e7ar R$ 61 bilh\u00f5es \u2013 dos quais R$ 25 bilh\u00f5es j\u00e1 ser\u00e3o direcionados para os contratos de cr\u00e9ditos no formato do novo programa.<\/p>\n<p>No mesmo per\u00edodo, foram entregues 612 mil resid\u00eancias, das quais 94 mil para fam\u00edlias mais vulner\u00e1veis, e mais de 13 mil unidades tiveram as obras retomadas. Al\u00e9m disso, mais de 620 mil im\u00f3veis foram contratados para as Faixas 1,5; 2; e 3 (renda familiar bruta entre R$ 2,6 mil e R$ 9 mil) e financiadas com recursos do FGTS.<\/p>\n<p><strong>Governo Federal retoma mais de 2.1 mil moradias em Macei\u00f3 (AL)<\/strong><\/p>\n<p>Refor\u00e7ando o compromisso do Governo Federal em dar continuidade \u00e0s obras j\u00e1 contratadas e retomar as paralisadas, o ministro Rog\u00e9rio Marinho vai assinar, na tarde de hoje, o termo de retomada da constru\u00e7\u00e3o de 2.160 unidades habitacionais em Macei\u00f3 (AL).<\/p>\n<p>As moradias fazem parte dos residenciais M\u00e1rio Peixoto Costa (I e II) e Vilas do Munda\u00fa, contratados em dezembro de 2018, e devem beneficiar 9 mil pessoas de baixa renda. Os investimentos federais somam R$ 172,8 milh\u00f5es. O MDR negociou a continuidade das obras com os valores contratados, sem aporte de recursos complementares.<\/p>\n<p>&nbsp;<\/p>\n<p><em>(com informa\u00e7\u00f5es Ascom MDR)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Programa Casa Verde e Amarela, do Minist\u00e9rio do Desenvolvimento Regional (MDR), vai facilitar o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg","jetpack-related-posts":[{"id":15360,"url":"https:\/\/correiodasemana.com\/site\/bolsonaro-sanciona-texto-da-casa-verde-e-amarela\/","url_meta":{"origin":13162,"position":0},"title":"Bolsonaro sanciona texto da Casa Verde e Amarela","author":"","date":"Janeiro 13, 2021","format":false,"excerpt":"O presidente Jair Bolsonaro\u00a0sancionou nesta quarta-feira (13) a Lei 14.118, que institui a Casa Verde e Amarela, programa substituto do \"Minha Casa, Minha Vida\". O texto foi publicado na edi\u00e7\u00e3o do\u00a0Di\u00e1rio Oficial da Uni\u00e3o\u00a0de hoje. A lei passa a prever subven\u00e7\u00f5es econ\u00f4micas para quem buscar moradias em \u00e1reas urbanas e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2020-10-16-at-12.47.41-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2020-10-16-at-12.47.41-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/WhatsApp-Image-2020-10-16-at-12.47.41-1.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13154,"url":"https:\/\/correiodasemana.com\/site\/bolsonaro-rebatiza-minha-casa-minha-vida-reduz-juros-e-mira-norte-e-nordeste\/","url_meta":{"origin":13162,"position":1},"title":"Bolsonaro rebatiza Minha Casa, Minha Vida, reduz juros e mira Norte e Nordeste","author":"","date":"Agosto 25, 2020","format":false,"excerpt":"O governo lan\u00e7ou hoje, em cerim\u00f4nia no Pal\u00e1cio do Planalto,\u00a0o programa habitacional Casa Verde e Amarela, novo nome do Minha Casa, Minha Vida. O lan\u00e7amento \u00e9 a primeira iniciativa do presidente\u00a0Jair Bolsonaro\u00a0(sem partido) de tentar criar sua pr\u00f3pria marca social. Lan\u00e7ado em 2009, o Minha Casa, Minha Vida \u00e9 uma\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13010,"url":"https:\/\/correiodasemana.com\/site\/guedes-diz-que-senado-deu-pessimo-sinal-ao-derrubar-veto-a-reajustes\/","url_meta":{"origin":13162,"position":2},"title":"Guedes diz que Senado deu \u201cp\u00e9ssimo sinal\u201d ao derrubar veto a reajustes","author":"","date":"Agosto 20, 2020","format":false,"excerpt":"Queda na remunera\u00e7\u00e3o do FGTS financiar\u00e1 novo programa habitacional A\u00a0derrubada, pelo Senado,\u00a0do veto do presidente Jair Bolsonaro ao reajuste de sal\u00e1rios de servidores da sa\u00fade e da educa\u00e7\u00e3o \u00a0representou \u201cum p\u00e9ssimo sinal\u201d, disse hoje (19) \u00e0 noite o ministro da Economia, Paulo Guedes. Segundo ele, os senadores cometeram \u201cum crime\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/19082020-solenidade-de-sano-de-medidas-provisrias-de-facilitao-de-acesso-ao-crdito_50245947791_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/19082020-solenidade-de-sano-de-medidas-provisrias-de-facilitao-de-acesso-ao-crdito_50245947791_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/19082020-solenidade-de-sano-de-medidas-provisrias-de-facilitao-de-acesso-ao-crdito_50245947791_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/19082020-solenidade-de-sano-de-medidas-provisrias-de-facilitao-de-acesso-ao-crdito_50245947791_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/19082020-solenidade-de-sano-de-medidas-provisrias-de-facilitao-de-acesso-ao-crdito_50245947791_o.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15170,"url":"https:\/\/correiodasemana.com\/site\/desenvolvimento-regional-conclui-62-mil-obras-em-2020-diz-ministro\/","url_meta":{"origin":13162,"position":3},"title":"Desenvolvimento Regional conclui 6,2 mil obras em 2020, diz ministro","author":"","date":"Dezembro 22, 2020","format":false,"excerpt":"Ao todo, foram entregues 410 mil unidades habitacionais Ao fazer hoje (22) um balan\u00e7o das a\u00e7\u00f5es executadas ao longo deste ano, o ministro do Desenvolvimento Regional, Rog\u00e9rio Marinho, disse que foram conclu\u00eddas 6,2 mil obras de pequeno, m\u00e9dio e grande portes nas \u00e1reas de habita\u00e7\u00e3o, saneamento, mobilidade, desenvolvimento regional e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/15_07_2020_cerimonia_saneamento-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/15_07_2020_cerimonia_saneamento-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/15_07_2020_cerimonia_saneamento-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/15_07_2020_cerimonia_saneamento-4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/15_07_2020_cerimonia_saneamento-4.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":34663,"url":"https:\/\/correiodasemana.com\/site\/lira-amplia-reducao-parcial-de-ir-para-quem-ganha-ate-r-7-350\/","url_meta":{"origin":13162,"position":4},"title":"Lira amplia redu\u00e7\u00e3o parcial de IR para quem ganha at\u00e9 R$ 7.350","author":"adminredacao","date":"Julho 15, 2025","format":false,"excerpt":"Relator manteve al\u00edquota m\u00e1xima de 10% para altas rendas POR Wellton M\u00e1ximo \u2013 Rep\u00f3rter da Ag\u00eancia Brasil* O relator do projeto de lei que reforma o Imposto de Renda (IR), deputado Arthur Lira (PP-AL), manteve em 10% a al\u00edquota m\u00e1xima a ser cobrada das pessoas que ganham a partir de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Brasil-deve-ser-a-9a-maior-economia-do-mundo-no-fim-da-decada.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Brasil-deve-ser-a-9a-maior-economia-do-mundo-no-fim-da-decada.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Brasil-deve-ser-a-9a-maior-economia-do-mundo-no-fim-da-decada.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Brasil-deve-ser-a-9a-maior-economia-do-mundo-no-fim-da-decada.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Brasil-deve-ser-a-9a-maior-economia-do-mundo-no-fim-da-decada.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":32946,"url":"https:\/\/correiodasemana.com\/site\/ceara-registra-queda-de-197-nos-casos-de-dengue-nos-2-primeiros-meses-de-2025\/","url_meta":{"origin":13162,"position":5},"title":"Cear\u00e1 registra queda de 19,7% nos casos de dengue nos 2 primeiros meses de 2025","author":"adminredacao","date":"Mar\u00e7o 17, 2025","format":false,"excerpt":"Segundo painel de monitoramento do Minist\u00e9rio da Sa\u00fade, foram contabilizados 1.309 casos prov\u00e1veis nas primeiras semanas de 2025 contra 1.632 no mesmo per\u00edodo do ano passado Nos dois primeiros meses de 2025, o Cear\u00e1 registrou uma redu\u00e7\u00e3o de 19,7% nos casos prov\u00e1veis de dengue em compara\u00e7\u00e3o com o mesmo per\u00edodo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/Dengue-em-Soibral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/Dengue-em-Soibral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/Dengue-em-Soibral.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/Dengue-em-Soibral.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/Dengue-em-Soibral.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/Dengue-em-Soibral.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13162"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13162\/revisions"}],"predecessor-version":[{"id":13166,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13162\/revisions\/13166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13163"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}