{"id":13201,"date":"2020-08-31T00:01:19","date_gmt":"2020-08-31T03:01:19","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13201"},"modified":"2020-08-31T00:01:19","modified_gmt":"2020-08-31T03:01:19","slug":"tabagismo-o-grande-vilao-da-saude-global","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/tabagismo-o-grande-vilao-da-saude-global\/","title":{"rendered":"Tabagismo: o grande vil\u00e3o da sa\u00fade global"},"content":{"rendered":"<p>Em tempos de pandemia, o Dia Nacional de Combate ao fumo acende o alerta para o aumento dos relatos de depend\u00eancia no tabagismo, provocada pela quarentena, e chama aten\u00e7\u00e3o para os danos causados tamb\u00e9m aos fumantes passivos<br \/>\nApontado pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS), como a principal causa de mortes em todo o mundo, o tabagismo \u00e9 considerado pelas autoridades de sa\u00fade o grande vil\u00e3o da qualidade de vida das popula\u00e7\u00f5es. Causador de doen\u00e7as pulmonares como bronquite, enfisema, c\u00e2ncer de pulm\u00e3o, doen\u00e7a coronariana (infarto e angina) e doen\u00e7as cerebrovasculares (acidente vascular cerebral), ele provoca anualmente mais de 7 milh\u00f5es de \u00f3bitos ao redor do mundo. Aqui no Brasil, s\u00e3o registradas todos os dias mais de 400 mortes atribu\u00eddas \u00e0 depend\u00eancia.<br \/>\nAos 34 anos, a publicit\u00e1ria Bruna dos Anjos, sabe bem o desafio di\u00e1rio que \u00e9 largar o h\u00e1bito que a acompanha desde a adolesc\u00eancia. \u201cComecei a fumar aos 13 anos e durante dez anos, cigarro e \u00e1lcool faziam parte da minha rotina. Com 23 anos e 1,68m de altura, cheguei a pesar mais 150 quilos. Na \u00e9poca, fumava e bebia bastante e o m\u00e9dico recomendou cirurgia bari\u00e1trica. Para o procedimento, precisei parar de fumar. Foram 79 quilos eliminados e novos h\u00e1bitos adquiridos. Consegui manter uma rotina saud\u00e1vel por um longo per\u00edodo, mas h\u00e1 3 anos eu tive problemas de ansiedade, s\u00edndrome do p\u00e2nico e voltei a fumar. Ano passado tentei parar novamente. Cheguei a ficar seis meses sem fumar, mas com a quarentena ficou muito dif\u00edcil. Tem dias que fumo 1 cigarro, mas tem dias que fumo 4\u201d, lamenta.<br \/>\nO caso de Bruna se confunde com o de outras milh\u00f5es de pessoas em todo o mundo e acendem o alerta global para os riscos do h\u00e1bito, por isso, neste s\u00e1bado, 29, Dia Nacional de Combate ao fumo, autoridades de sa\u00fade destacam a import\u00e2ncia de debater o assunto e mostram os malef\u00edcios desta pr\u00e1tica. \u201c\u00c9 um momento \u00edmpar de conscientizar a popula\u00e7\u00e3o dos males causados pelo tabagismo, principalmente em tempos de pandemia, j\u00e1 que fumantes t\u00eam 45% mais chances de agravamento se contra\u00edrem a covid-19\u201d, aponta o m\u00e9dico Eg\u00eddio Cuzziol, do Grupo Sabin Medicina Diagn\u00f3stica.<br \/>\nAl\u00e9m disso, o especialista aponta outro agravante do problema: o isolamento social. \u201cAs incertezas provocadas pela pandemia, aumentou n\u00edveis de estresse, ansiedade e outros fatores que contribu\u00edram para alavancar h\u00e1bitos ruins como este\u201d, o m\u00e9dico destaca ainda que pesquisas rec\u00e9m divulgadas pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz), Universidade Federal de Minas Gerais (UFMG) e Universidade Estadual de Campinas (Unicamp), confirmaram a afirmativa: 30% dos homens ouvidos e 38% das mulheres fumantes responderam \u00e0s pesquisas que passaram a consumir dez cigarros a mais por dia, desde o in\u00edcio da pandemia.<br \/>\nO problema, aponta o especialista, vai al\u00e9m de prejudicar a sa\u00fade do fumante. \u201cTemos que lembrar que hoje fumantes ativos e passivos dividem, em grande parte do dia, ambientes fechados e os passivos acabam ficando expostos aos componentes t\u00f3xicos contidos emitidos pelo cigarro\u201d, explica. Por isso, a campanha deste ano pretende refor\u00e7ar n\u00e3o somente as a\u00e7\u00f5es antifumo, mas tamb\u00e9m sensibilizar sobre os danos causados pelo consumo de tabaco. \u201cTodos os anos, s\u00e3o registradas mais de 1,2 milh\u00e3o de n\u00e3o fumantes que perdem a vida por estarem expostos ao fumo passivo, de acordo com a OMS. Por isso, \u00e9 importante alertar toda a sociedade e n\u00e3o apenas os dependentes\u201d, explica o m\u00e9dico.<\/p>\n<p>Tabagismo: os \u00edndices no Brasil<br \/>\nFator de risco para o desenvolvimento dos tipos de c\u00e2ncer: leucemia mieloide aguda; c\u00e2ncer de bexiga; c\u00e2ncer de p\u00e2ncreas; c\u00e2ncer de f\u00edgado; c\u00e2ncer do colo do \u00fatero; c\u00e2ncer de es\u00f4fago; c\u00e2ncer de rim e ureter; c\u00e2ncer de laringe (cordas vocais); c\u00e2ncer na cavidade oral (boca); c\u00e2ncer de faringe (pesco\u00e7o); c\u00e2ncer de est\u00f4mago; c\u00e2ncer de c\u00f3lon e reto; c\u00e2ncer de traqu\u00e9ia, br\u00f4nquios e pulm\u00e3o, o tabagismo tamb\u00e9m est\u00e1 associado \u00e0s doen\u00e7as cr\u00f4nicas n\u00e3o transmiss\u00edveis e \u00e9 um fator importante de risco para o desenvolvimento de outras doen\u00e7as como tuberculose, infec\u00e7\u00f5es respirat\u00f3rias, \u00falcera gastrintestinal, impot\u00eancia sexual, infertilidade em mulheres e homens, osteoporose, catarata, entre outras.<br \/>\nNo Brasil, s\u00e3o cerca de 428 mortes por dia por causa da depend\u00eancia. Em todo o ano, s\u00e3o mais de e 156.216 mortes que poderiam ter sido evitadas. Al\u00e9m de mais de R\ufe69 56 bilh\u00f5es de reais perdidos com custos m\u00e9dicos e perda de produtividade.<br \/>\nSegundo dados do Inca (Instituto Nacional do C\u00e2ncer), o maior peso \u00e9 atribu\u00eddo ao c\u00e2ncer, doen\u00e7a card\u00edaca e doen\u00e7a pulmonar obstrutiva cr\u00f4nica (DPOC). Das mortes anuais causadas pelo uso do tabaco: 34.999 mortes correspondem a doen\u00e7as card\u00edacas; 31.120 mortes por DPOC (doen\u00e7a pulmonar obstrutiva cr\u00f4nica); 26.651 por outros c\u00e2nceres; 23.762 por c\u00e2ncer de pulm\u00e3o; 17.972 mortes por tabagismo passivo; 10.900 por pneumonia; 10.812 por AVC (acidente vascular cerebral).<\/p>\n<p>Informa\u00e7\u00f5es \u00e0 imprensa-\u00a0FSB Comunica\u00e7\u00e3o S\u00e3o Paulo &#8211; Viviane Mel\u00e9m: (11) 97171.1524<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em tempos de pandemia, o Dia Nacional de Combate ao fumo acende o alerta para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Cigarro-e-cancer-de-bexiga_Dr-Joao-Alvaro_19_03.jpg","jetpack-related-posts":[{"id":30553,"url":"https:\/\/correiodasemana.com\/site\/com-25-milhoes-de-fumantes-o-brasil-acende-alerta-para-quadros-graves-como-a-trombose\/","url_meta":{"origin":13201,"position":0},"title":"Com 25 milh\u00f5es de fumantes, o Brasil acende alerta para quadros graves como a trombose","author":"adminredacao","date":"Setembro 2, 2024","format":false,"excerpt":"A doen\u00e7a \u00e9 uma das diversas relacionadas ao tabagismo, que neste m\u00eas ganha destaque devido ao Dia Nacional do Combate ao Fumo (29\/08) Cuidar da sa\u00fade das pernas passa por diversos h\u00e1bitos que incluem a boa alimenta\u00e7\u00e3o, atividade f\u00edsica, check-ups peri\u00f3dicos e evitar o consumo de produtos que podem causar\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/ministerio-da-saude.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/ministerio-da-saude.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/ministerio-da-saude.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/ministerio-da-saude.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/ministerio-da-saude.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/ministerio-da-saude.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14344,"url":"https:\/\/correiodasemana.com\/site\/lembrado-hoje-dia-mundial-do-avc-serve-de-alerta-a-populacao\/","url_meta":{"origin":13201,"position":1},"title":"Lembrado hoje, Dia Mundial do AVC serve de alerta \u00e0 popula\u00e7\u00e3o","author":"","date":"Outubro 29, 2020","format":false,"excerpt":"Acidente vascular cerebral \u00e9 segunda causa de morte principal no pa\u00eds Segunda principal causa de morte no Brasil, o acidente vascular cerebral (AVC) \u00e9 lembrado hoje (29), em data especial, que serve de alerta \u00e0 popula\u00e7\u00e3o. O Dia Mundial do AVC chama aten\u00e7\u00e3o para a quantidade de pessoas que o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_abr_numero_de_serie_de_4_digitos_090620_2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_abr_numero_de_serie_de_4_digitos_090620_2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_abr_numero_de_serie_de_4_digitos_090620_2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_abr_numero_de_serie_de_4_digitos_090620_2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_abr_numero_de_serie_de_4_digitos_090620_2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":36428,"url":"https:\/\/correiodasemana.com\/site\/estudo-mostra-que-inflamacao-no-cerebro-pode-ser-chave-do-alzheimer\/","url_meta":{"origin":13201,"position":2},"title":"Estudo mostra que inflama\u00e7\u00e3o no c\u00e9rebro pode ser chave do Alzheimer","author":"adminredacao","date":"Novembro 18, 2025","format":false,"excerpt":"Pesquisa foi liderada por laborat\u00f3rio do neurocientista Eduardo Zimmer POR Fl\u00e1via Albuquerque - Rep\u00f3rter da Ag\u00eancia Brasil Um estudo liderado pelo laborat\u00f3rio do neurocientista Eduardo Zimmer, professor da Universidade Federal do Rio Grande do Sul (UFRGS), sugere que o c\u00e9rebro precisa estar inflamado para que o Alzheimer se estabele\u00e7a e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/louis-reed-pwckf7l4-no-unsplash.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/louis-reed-pwckf7l4-no-unsplash.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/louis-reed-pwckf7l4-no-unsplash.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/louis-reed-pwckf7l4-no-unsplash.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/louis-reed-pwckf7l4-no-unsplash.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17571,"url":"https:\/\/correiodasemana.com\/site\/setembro-vermelho-chama-a-atencao-para-doencas-do-coracao-medico-especialista-alerta-para-fatores-de-risco-e-prevencao\/","url_meta":{"origin":13201,"position":3},"title":"\u201cSetembro Vermelho\u201d chama a aten\u00e7\u00e3o para doen\u00e7as do cora\u00e7\u00e3o; M\u00e9dico especialista alerta para fatores de risco e preven\u00e7\u00e3o","author":"","date":"Setembro 26, 2021","format":false,"excerpt":"Neste ano, at\u00e9 o dia 20 de setembro, mais de 290 mil pessoas morreram por problemas card\u00edacos no Brasil\u00a0\u00a0 O Setembro Vermelho \u00e9 celebrado em homenagem ao Dia Mundial do Cora\u00e7\u00e3o, que tem sua data oficial comemorada no dia 29 de setembro. A data tem por objetivo promover a conscientiza\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/foto.bmp","width":350,"height":200,"srcset":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/foto.bmp 1x, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/foto.bmp 1.5x"},"classes":[]},{"id":20806,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-promove-palestra-para-colaboradores-sobre-riscos-do-tabagismo-e-alcoolismo\/","url_meta":{"origin":13201,"position":4},"title":"Santa Casa de Sobral promove palestra para colaboradores sobre riscos do tabagismo e alcoolismo","author":"","date":"Agosto 29, 2022","format":false,"excerpt":"O educador f\u00edsico Douglas Prado, do CAPS AD, e a enfermeira Verena Emanuelle Soares, da Vigil\u00e2ncia Sanit\u00e1ria, conduziram a discuss\u00e3o. Ascom Complexo SCMS A Santa Casa de Miseric\u00f3rdia de Sobral (SCMS), por meio da\u00a0Comiss\u00e3o Interna de Preven\u00e7\u00e3o de Acidentes (CIPA) e do Servi\u00e7o Especializado em Engenharia de Seguran\u00e7a e em\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/sta-casa-de-sobral-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/sta-casa-de-sobral-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/sta-casa-de-sobral-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/sta-casa-de-sobral-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14591,"url":"https:\/\/correiodasemana.com\/site\/tres-fatores-chave-que-aumentam-o-risco-de-morte-por-covid-19\/","url_meta":{"origin":13201,"position":5},"title":"Tr\u00eas fatores chave que aumentam o risco de morte por Covid-19","author":"","date":"Novembro 17, 2020","format":false,"excerpt":"O novo coronav\u00edrus SARS-CoV-2, causador da Covid-19, afeta as pessoas de forma diferente - matando uns, enquanto outros permanecem sem sintomas e desconhecem sequer que est\u00e3o ou estiveram infectados Desde o in\u00edcio da pandemia que se tornou claro que os indiv\u00edduos mais velhos e com problemas pr\u00e9vios de sa\u00fade est\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13201"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13201\/revisions"}],"predecessor-version":[{"id":13203,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13201\/revisions\/13203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13202"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}