{"id":13797,"date":"2020-09-29T02:20:41","date_gmt":"2020-09-29T05:20:41","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13797"},"modified":"2020-09-29T02:20:41","modified_gmt":"2020-09-29T05:20:41","slug":"coligacoes-partidarias-apresentam-157-candidatos-as-vagas-para-a-camara-municipal-de-sobral-saiba-quais-ja-estao-registrados","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/coligacoes-partidarias-apresentam-157-candidatos-as-vagas-para-a-camara-municipal-de-sobral-saiba-quais-ja-estao-registrados\/","title":{"rendered":"Coliga\u00e7\u00f5es partid\u00e1rias apresentam 157 candidatos \u00e0s vagas para a C\u00e2mara Municipal de Sobral; saiba quais j\u00e1 est\u00e3o registrados"},"content":{"rendered":"<p>Em 2020, 157 candidatos disputar\u00e3o nas elei\u00e7\u00f5es municipais as 21 vagas dispon\u00edveis na C\u00e2mera Municipal de Sobral. At\u00e9 o momento, 154 candidatos j\u00e1 foram registrados no site do Tribunal Regional Eleitoral (TER) do Cear\u00e1.<br \/>\nSe a Justi\u00e7a Eleitoral homologar a proposta de todos eles, Sobral ter\u00e1 35% menos candidatos que nas elei\u00e7\u00f5es de 2016, quando 242 candidatos disputaram as 21 cadeiras do legislativo municipal.<br \/>\nA coliga\u00e7\u00e3o de Ivo Gomes (PDT), que concorre a reelei\u00e7\u00e3o, tem o maior n\u00famero de candidatos, com 86 nomes; os candidatos que concorrem na coliga\u00e7\u00e3o de Oscar Rodrigues (MDB) somam 66 postulantes. 05 candidatos optaram pela neutralidade, n\u00e3o tomando partido.<\/p>\n<p><strong>CONHE\u00c7A OS CANDIDATOS J\u00c1 CADASTRADOS, POR ORDEM ALFAB\u00c9TICA<\/strong><br \/>\nAc\u00e9lio Pez\u00e3o<br \/>\nAce Mario Sergio<br \/>\nAdail Alves<br \/>\nAdorico<br \/>\nAjax Cardoso<br \/>\nAleandro Linhares<br \/>\nAlessandra Pontes<br \/>\nAlexandre Pontes<br \/>\nAlex Paiva<br \/>\nAlex Silva<br \/>\nAmanda Bastos<br \/>\nAna Kecia<br \/>\nAp\u00f3stolo Jander<br \/>\nBatista Miguel<br \/>\nBelim do SAAE<br \/>\nBispo<br \/>\nCabo Berg<br \/>\nCamilo Motos<br \/>\nCarlos do Calisto<br \/>\nCarlos Rodrigues<br \/>\nCarmem Gl\u00f3ria<br \/>\nCatinha<br \/>\nC\u00e9lia Guimar\u00e3es<br \/>\nCezinha Lima<br \/>\nChico Joia<br \/>\nChico Sobral<br \/>\nConcei\u00e7\u00e3o Cavalcante<br \/>\nCristina Nunes<br \/>\nCumpady Bony<br \/>\nDaiana<br \/>\nDaniela<br \/>\nDiretora<br \/>\nDona Gra\u00e7a<br \/>\nDra. F\u00e1bia Karennina<br \/>\nDr. Estev\u00e3o<br \/>\nDr. Gerardo<br \/>\nDr. J\u00fanior Balreira<br \/>\nDr. Rafael Melo<br \/>\nDr. Wellington Vasconcelos<br \/>\nEdgleuma<br \/>\nEdiene Portela<br \/>\nEdson Lima<br \/>\nElaine Cristina<br \/>\nElizangela Lira<br \/>\nEmanuel Cruz<br \/>\nEnoque de Sousa<br \/>\nEudes Albuquerque<br \/>\nF\u00e1bio Melo<br \/>\nFab\u00edula Feitosa<br \/>\nFafa Farias<br \/>\nF\u00e1tima Gomes<br \/>\nF\u00e1tima Gomes<br \/>\nF\u00e1tima Samaritana<br \/>\nFl\u00e1vio Ximenes<br \/>\nFrancion Alc\u00e2ntara<br \/>\nFransquinha do Povo<br \/>\nFranz\u00e9<br \/>\nGald\u00eancio<br \/>\nGar\u00e7on Amigo<br \/>\nGege Rom\u00e3o<br \/>\nGeorge Ramos<br \/>\nGilmar Bastos<br \/>\nGuarda Edinaldo<br \/>\nHermegenildo<br \/>\nIgor Bezerra<br \/>\nItamar Ribeiro<br \/>\nIvan Frota<br \/>\nIvna<br \/>\nJalis Gomes<br \/>\nJeov\u00e1 J\u00fanior<br \/>\nJo\u00e3o do Povo<br \/>\nJocier Cruz<br \/>\nJohnson<br \/>\nJos\u00e9 Arteiro<br \/>\nJosefa de Patos<br \/>\nJuarez Macedo<br \/>\nJuliana Silva<br \/>\nJunior Darico<br \/>\nJ\u00fanior Mega Som<br \/>\nJ\u00fanior Rego<br \/>\nKaka Linhares<br \/>\nKerginaldo Prado<br \/>\nLe\u00e3o S\u00edlvio<br \/>\nLili da Claro<br \/>\nLurdinha<br \/>\nMael<br \/>\nMarcelo Ribeiro<br \/>\nMarciano Guerreiro<br \/>\nMarcio Vicktor<br \/>\nMarlon Sobreira<br \/>\nMarquinho do G\u00e1s<br \/>\nMichele Ibiapina<br \/>\nNadir Arag\u00e3o<br \/>\nNat\u00e1lia Cachorrona<br \/>\nNatanael Almeida<br \/>\nNilson<br \/>\nOscar Ribeiro<br \/>\nPapel da Topic<br \/>\nPastora Izelda<br \/>\nPastor Erivan Felix<br \/>\nPaul\u00e3o<br \/>\nPaulo Henrique<br \/>\nPaulo Porfirio<br \/>\nPepeta<br \/>\nProfessora Quiriane<br \/>\nProfessora Regina<br \/>\nProfessora Rita<br \/>\nProfessor Cleiton Prado;<br \/>\nProf Francisco Chiquinho<br \/>\nProf. Vicente Jr.<br \/>\nRaimundo Cruz<br \/>\nReginaldo Capoeira<br \/>\nRob\u00e9rio Cavalcante<br \/>\nRob\u00e9rio Lima Pot\u00eancia<br \/>\nRochelly<br \/>\nRog\u00e9rio Arruda<br \/>\nRonaldo Vigilante<br \/>\nRoque Hudson<br \/>\nRos\u00e1lio Martins<br \/>\nRosilene Coelho<br \/>\nSamir Mendes<br \/>\nSandra Arcanjo<br \/>\nSapateiro Lopes<br \/>\nSargento Ailton<br \/>\nS\u00e1vio Baia<br \/>\nSaymon Lopes<br \/>\nSerlene Paiva<br \/>\nShirley<br \/>\nSilva Feirante<br \/>\nS\u00edlvia<br \/>\nS\u00edlvio \u00c1vila<br \/>\nSocorrinha Brasileiro<br \/>\nSocorro Ferreira<br \/>\nSubtenente Crispim<br \/>\nTemoteo do Samu<br \/>\nTeresa Cristina<br \/>\nTeresinha de Jesus<br \/>\nThales Braga<br \/>\nThales Pinheiro<br \/>\nThiara Alves<br \/>\nTiago Ramos<br \/>\nToinho Arag\u00e3o<br \/>\nTony Brand\u00e3o<br \/>\nUlysses Magalh\u00e3es<br \/>\nVanusa da Sa\u00fade<br \/>\nVaulene Arag\u00e3o<br \/>\nVera<br \/>\nVer\u00f4nica Barbosa<br \/>\nVicente Lopes<br \/>\nVilma Damasceno<br \/>\nWellington Macedo<br \/>\nWostim Rodrigues<br \/>\nZ\u00e9 Victor<br \/>\nZilma Cristina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2020, 157 candidatos disputar\u00e3o nas elei\u00e7\u00f5es municipais as 21 vagas dispon\u00edveis na C\u00e2mera Municipal&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/camara-municipal-de-Sobral.jpg","jetpack-related-posts":[{"id":12469,"url":"https:\/\/correiodasemana.com\/site\/eleicoes-2020-pela-primeira-vez-vereadores-nao-poderao-concorrer-por-coligacoes\/","url_meta":{"origin":13797,"position":0},"title":"Elei\u00e7\u00f5es 2020: pela primeira vez, vereadores n\u00e3o poder\u00e3o concorrer por coliga\u00e7\u00f5es","author":"","date":"Agosto 4, 2020","format":false,"excerpt":"Candidatos ao cargo somente poder\u00e3o participar em chapa \u00fanica dentro do partido. Altera\u00e7\u00e3o na legisla\u00e7\u00e3o foi institu\u00edda pela reforma eleitoral de 2017 Nas Elei\u00e7\u00f5es Municipais de 2020, pela primeira vez, candidatos ao cargo de vereador n\u00e3o poder\u00e3o concorrer por meio de coliga\u00e7\u00f5es. O fim das coliga\u00e7\u00f5es na elei\u00e7\u00e3o proporcional foi\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/a480bf62-7cab-47ec-be51-d48efddef452.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/a480bf62-7cab-47ec-be51-d48efddef452.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/a480bf62-7cab-47ec-be51-d48efddef452.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12586,"url":"https:\/\/correiodasemana.com\/site\/eleicoes-2020-pela-primeira-vez-vereadores-nao-poderao-concorrer-por-coligacoes-2\/","url_meta":{"origin":13797,"position":1},"title":"Elei\u00e7\u00f5es 2020: pela primeira vez, vereadores n\u00e3o poder\u00e3o concorrer por coliga\u00e7\u00f5es","author":"","date":"Agosto 10, 2020","format":false,"excerpt":"Candidatos ao cargo somente poder\u00e3o participar em chapa \u00fanica dentro do partido. Altera\u00e7\u00e3o na legisla\u00e7\u00e3o foi institu\u00edda pela reforma eleitoral de 2017 Nas Elei\u00e7\u00f5es Municipais de 2020, pela primeira vez, candidatos ao cargo de vereador n\u00e3o poder\u00e3o concorrer por meio de coliga\u00e7\u00f5es. O fim das coliga\u00e7\u00f5es na elei\u00e7\u00e3o proporcional foi\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/urna_lecr-e1447217261594.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13639,"url":"https:\/\/correiodasemana.com\/site\/eleicoes-2020-conheca-os-candidatos-que-estao-na-disputa-em-sobral\/","url_meta":{"origin":13797,"position":2},"title":"Elei\u00e7\u00f5es 2020: conhe\u00e7a os candidatos que est\u00e3o na disputa em Sobral","author":"","date":"Setembro 21, 2020","format":false,"excerpt":"Ber\u00e7o pol\u00edtico da c\u00fapula do PDT no Estado do Cear\u00e1, o munic\u00edpio de Sobral deve ter uma disputa polarizada entre o atual prefeito, Ivo Gomes, e o opositor, Dr. Oscar Rodrigues. Maior col\u00e9gio eleitoral da regi\u00e3o Norte e quinto maior do Estado do Cear\u00e1, a cidade de Sobral deve ter\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/eleicoes-sobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/eleicoes-sobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/eleicoes-sobral.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":30418,"url":"https:\/\/correiodasemana.com\/site\/eleicoes-2024-mais-de-400-mil-candidaturas-estao-registradas\/","url_meta":{"origin":13797,"position":3},"title":"Elei\u00e7\u00f5es 2024: mais de 400 mil candidaturas est\u00e3o registradas","author":"adminredacao","date":"Agosto 19, 2024","format":false,"excerpt":"Prazo para o registro presencial se encerra \u00e0s 19h desta quinta-feira Por Felipe Pontes - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia Os partidos, coliga\u00e7\u00f5es e federa\u00e7\u00f5es t\u00eam at\u00e9 esta quinta-feira (15) registrem os candidatos a prefeito e vereador para as elei\u00e7\u00f5es municipais deste ano, marcadas para 6 de outubro, com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/50429036346_a9271a4327_o.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/50429036346_a9271a4327_o.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/50429036346_a9271a4327_o.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/50429036346_a9271a4327_o.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/50429036346_a9271a4327_o.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13691,"url":"https:\/\/correiodasemana.com\/site\/eleicoes-2020-tse-libera-ferramenta-para-consulta-de-candidaturas\/","url_meta":{"origin":13797,"position":4},"title":"Elei\u00e7\u00f5es 2020: TSE libera ferramenta para consulta de candidaturas","author":"","date":"Setembro 22, 2020","format":false,"excerpt":"Sistema pode ser consultado por qualquer cidad\u00e3o Consultas por munic\u00edpio e cargo, acesso \u00e0 informa\u00e7\u00f5es detalhadas sobre a situa\u00e7\u00e3o dos candidatos aos cargos de prefeito, vice-prefeito e vereador, que pediram registro para concorrer \u00e0s Elei\u00e7\u00f5es Municipais de 2020 j\u00e1 est\u00e3o dispon\u00edveis na plataforma\u00a0DivulgaCandContas, do Tribunal Superior Eleitoral (TSE). A ferramenta\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/tse_1908200982.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/tse_1908200982.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/tse_1908200982.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/tse_1908200982.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/tse_1908200982.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14315,"url":"https:\/\/correiodasemana.com\/site\/pt-e-psl-sao-aliados-nas-eleicoes-em-136-municipios-veja-a-lista\/","url_meta":{"origin":13797,"position":5},"title":"PT e PSL s\u00e3o aliados nas elei\u00e7\u00f5es em 136 munic\u00edpios. Veja a lista","author":"","date":"Outubro 28, 2020","format":false,"excerpt":"Expoentes da atual polariza\u00e7\u00e3o pol\u00edtica nacional, PT e PSL est\u00e3o coligados em 136 munic\u00edpios, revela levantamento do Congresso em Foco, com base em dados do Tribunal Superior Eleitoral (TSE). As alian\u00e7as envolvendo os dois partidos s\u00e3o, em sua maioria, com candidatos a prefeito de outras legendas. Em Aparecida de Goi\u00e2nia\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/belfor-roxo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/belfor-roxo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/belfor-roxo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13797"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13797\/revisions"}],"predecessor-version":[{"id":13799,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13797\/revisions\/13799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13798"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}