{"id":13835,"date":"2020-09-30T09:43:34","date_gmt":"2020-09-30T12:43:34","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13835"},"modified":"2020-09-30T09:43:34","modified_gmt":"2020-09-30T12:43:34","slug":"desemprego-chega-a-138-no-trimestre-encerrado-em-julho-maior-taxa-desde-2012","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/desemprego-chega-a-138-no-trimestre-encerrado-em-julho-maior-taxa-desde-2012\/","title":{"rendered":"Desemprego chega a 13,8% no trimestre encerrado em julho, maior taxa desde 2012"},"content":{"rendered":"<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span><span style=\"color: #000000;\">A taxa de desocupa\u00e7\u00e3o no Brasil foi de 13,8%, no trimestre de maio a julho de 2020, a maior taxa da s\u00e9rie hist\u00f3rica, iniciada em 2012. O \u00edndice corresponde a um aumento de 1,2 ponto percentual em rela\u00e7\u00e3o ao trimestre anterior (fevereiro a abril, de 12,6%). J\u00e1 em compara\u00e7\u00e3o com o mesmo trimestre de 2019 (11,8%) s\u00e3o 2 pontos percentuais a mais. A popula\u00e7\u00e3o desocupada chegou a 13,1 milh\u00f5es de pessoas, aumento de 4,5% (561 mil pessoas) em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2019.<\/span><\/span><\/span><\/p>\n<p align=\"justify\">A popula\u00e7\u00e3o ocupada recuou para 82 milh\u00f5es, o menor contingente da s\u00e9rie. Essa popula\u00e7\u00e3o caiu 8,1% (menos 7,2 milh\u00f5es pessoas) em rela\u00e7\u00e3o ao trimestre anterior, e 12,3% (menos 11,6 milh\u00f5es) frente ao per\u00edodo de maio a julho de 2019. O n\u00edvel de ocupa\u00e7\u00e3o tamb\u00e9m foi o mais baixo da s\u00e9rie, atingindo 47,1%, caindo 4,5 pontos frente ao trimestre anterior e 7,6 pontos contra o mesmo trimestre de 2019.<\/p>\n<p align=\"justify\">Os dados s\u00e3o da Pesquisa Nacional por Amostra de Domic\u00edlios Cont\u00ednua (PNAD Cont\u00ednua), divulgada hoje (30) pelo IBGE. A analista da pesquisa, Adriana Beringuy, explica que as quedas no per\u00edodo da pandemia de Covid-19 foram determinantes para os recordes negativos deste trimestre encerrado em julho. \u201cOs resultados das \u00faltimas cinco divulga\u00e7\u00f5es mostram uma retra\u00e7\u00e3o muito grande na popula\u00e7\u00e3o ocupada. \u00c9 um ac\u00famulo de perdas que leva a esses patamares negativos\u201d.<\/p>\n<p align=\"justify\">Outro indicador que est\u00e1 no menor patamar na s\u00e9rie hist\u00f3rica \u00e9 a for\u00e7a de trabalho (pessoas ocupadas e desocupadas), que chegou a 95,2 milh\u00f5es de pessoas, com queda de 6,8% (ou 6,9 milh\u00f5es) frente ao trimestre anterior, e de 10,4% (ou 11 milh\u00f5es de pessoas) em rela\u00e7\u00e3o ao mesmo trimestre de 2019.<\/p>\n<p align=\"justify\">J\u00e1 a popula\u00e7\u00e3o fora da for\u00e7a de trabalho atingiu o recorde da s\u00e9rie e chegou a 79 milh\u00f5es de pessoas &#8211; mais 8 milh\u00f5es em rela\u00e7\u00e3o ao trimestre anterior e mais 14,1 milh\u00f5es frente ao mesmo trimestre de 2019. Entretanto, o aumento foi menor do que no trimestre encerrado em junho, quando o ganho foi de 10 milh\u00f5es de pessoas. \u201cA popula\u00e7\u00e3o fora da for\u00e7a aumentou muito, mas em julho, aumentou menos. Isso pode indicar um certo retorno das pessoas ao trabalho. Os movimentos ainda s\u00e3o discretos no comparativo com todo o per\u00edodo, mas \u00e9 um indicativo\u201d, acrescenta Beringuy.<\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span><b><strong>Desalento atinge recorde de 5,8 milh\u00f5es de pessoas<\/strong><\/b><\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span><span style=\"color: #000000;\">O contingente de pessoas desalentadas \u2013 que n\u00e3o buscaram trabalho, mas que gostariam de conseguir uma vaga e estavam dispon\u00edveis para trabalhar \u2013 tamb\u00e9m atingiu recorde e agora soma 5,8 milh\u00f5es. O desalento segue aumentando, mas cresceu menos do que no trimestre anterior: 913 mil pessoas entraram no desalento no trimestre m\u00f3vel terminado em junho, contra 771 mil no trimestre terminado em julho.<\/span><\/span><\/span><\/p>\n<p align=\"justify\">Para Beringuy, a pandemia dificultou a busca por ocupa\u00e7\u00e3o e, com uma flexibiliza\u00e7\u00e3o cada vez maior da quarentena, a tend\u00eancia \u00e9 que as pessoas voltem a buscar trabalho. \u201cAl\u00e9m de tirar o trabalho, a pandemia tamb\u00e9m impossibilitou sua procura, ou por conta das medidas restritivas, ou porque as atividades econ\u00f4micas estavam suspensas ou, ainda, por quest\u00f5es de sa\u00fade pessoal\u201d, afirma.<\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span><b><strong>Com\u00e9rcio, Alojamento e alimenta\u00e7\u00e3o e Ind\u00fastria t\u00eam redu\u00e7\u00e3o da ocupa\u00e7\u00e3o em julho<\/strong><\/b><\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span><span style=\"color: #000000;\">Na compara\u00e7\u00e3o com o trimestre terminado em abril, a popula\u00e7\u00e3o ocupada diminuiu em oito dos 10 grupamentos de atividades analisados pela PNAD Cont\u00ednua e ficou est\u00e1vel em dois. A ocupa\u00e7\u00e3o em Alojamento e alimenta\u00e7\u00e3o caiu 23,2%, com menos 1,1 milh\u00e3o de pessoas empregadas. Tamb\u00e9m houve queda na Ind\u00fastria (- 8%), o que representou cerca de 916 mil pessoas a menos.<\/span><\/span><\/span><\/p>\n<p align=\"justify\">Constru\u00e7\u00e3o (queda de 9,5%, ou menos 559 mil pessoas) e Com\u00e9rcio (9,7%, ou menos 1,6 milh\u00e3o de pessoas) apresentaram quedas menores do que em junho, quando registraram redu\u00e7\u00f5es de 16,6% e 10,9%, respectivamente. \u201cEssa queda menor pode indicar um retorno de trabalhadores nesses setores, que foram beneficiados com a flexibiliza\u00e7\u00e3o da quarentena. Por exemplo, algumas obras interrompidas j\u00e1 voltaram e o com\u00e9rcio informal tamb\u00e9m\u201d, explica a analista.<\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><span><b><strong>Informalidade diminui e trabalho dom\u00e9stico chega ao menor n\u00edvel da s\u00e9rie<\/strong><\/b><\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span><span style=\"color: #000000;\">A taxa de informalidade chegou a 37,4% da popula\u00e7\u00e3o ocupada (o equivalente a 30,7 milh\u00f5es de trabalhadores informais). No trimestre anterior, a taxa fora de 38,8% e, no mesmo trimestre de 2019, de 41,3%.<\/span><\/span><\/span><\/p>\n<p align=\"justify\">Tamb\u00e9m atingindo o menor patamar da s\u00e9rie hist\u00f3rica da PNAD Cont\u00ednua, o n\u00famero de trabalhadores dom\u00e9sticos chegou a 4,6 milh\u00f5es de pessoas, queda de 16,8% (ou 931 mil pessoas) frente ao trimestre anterior, e de 26,9% (ou 1,7 milh\u00e3o de pessoas) frente ao mesmo trimestre de 2019. \u201cA trajet\u00f3ria ainda \u00e9 de queda\u201d, explica a especialista, \u201cmas a redu\u00e7\u00e3o \u00e9 menor do que a do trimestre encerrado em junho, quando foi de 21% frente ao trimestre anterior\u201d, finaliza Beringuy.<\/p>\n<div class=\"gmail_signature\" dir=\"ltr\" data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\"><b>Supervis\u00e3o de Documenta\u00e7\u00e3o e Dissemina\u00e7\u00e3o de Informa\u00e7\u00f5es<br \/>\n<\/b>Unidade Estadual do IBGE no Cear\u00e1<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A taxa de desocupa\u00e7\u00e3o no Brasil foi de 13,8%, no trimestre de maio a julho&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/desemprego-e-maior-entre-os-jovens-que-tem-dificuldade-para-conseguir-um-primeiro-emprego-com-carteira-assinada-1574329430345_v2_450x337.jpg","jetpack-related-posts":[{"id":14938,"url":"https:\/\/correiodasemana.com\/site\/desocupacao-avanca-no-3o-trimestre-de-2020-no-ceara\/","url_meta":{"origin":13835,"position":0},"title":"Desocupa\u00e7\u00e3o avan\u00e7a no 3\u00ba trimestre de 2020 no Cear\u00e1","author":"","date":"Dezembro 7, 2020","format":false,"excerpt":"A taxa de desocupa\u00e7\u00e3o do Cear\u00e1 no 3\u00ba trimestre de 2020 foi de 14,1%, subindo 2 pontos percentuais em rela\u00e7\u00e3o ao 2\u00ba trimestre de 2020 (12,1%). Na compara\u00e7\u00e3o com o mesmo trimestre de 2019 (11,3%), houve aumento de 2,8 p.p. Os dados s\u00e3o da Pesquisa Nacional por Amostra de Domic\u00edlios\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/image.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/image.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/image.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/image.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/image.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/image.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":8766,"url":"https:\/\/correiodasemana.com\/site\/1-em-cada-4-desempregados-procura-trabalho-ha-pelo-menos-dois-anos\/","url_meta":{"origin":13835,"position":1},"title":"1 em cada 4 desempregados procura trabalho h\u00e1 pelo menos dois anos","author":"","date":"Agosto 18, 2019","format":false,"excerpt":"No segundo trimestre, o pa\u00eds tinha 4,9 milh\u00f5es de desalentados, aqueles que desistiram de procurar emprego Ag\u00eancia IBGE Not\u00edcias Mais de um quarto (26,2%) dos desempregados procuram trabalho h\u00e1 no m\u00ednimo dois anos, o que equivale a 3,347 milh\u00f5es de pessoas nessa condi\u00e7\u00e3o. Esses n\u00fameros s\u00e3o os maiores para um\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/1092635-dia-d-inclusao-sociala81t4154.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/1092635-dia-d-inclusao-sociala81t4154.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/1092635-dia-d-inclusao-sociala81t4154.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/1092635-dia-d-inclusao-sociala81t4154.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/1092635-dia-d-inclusao-sociala81t4154.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28433,"url":"https:\/\/correiodasemana.com\/site\/rendimento-de-mulheres-em-2023-e-20-menor-que-o-dos-homens\/","url_meta":{"origin":13835,"position":2},"title":"Rendimento de mulheres em 2023 \u00e9 20% menor que o dos homens","author":"adminredacao","date":"Fevereiro 19, 2024","format":false,"excerpt":"Compara\u00e7\u00e3o faz parte da Pnad Cont\u00ednua, do IBGE Por Bruno de Freitas Moura - Rep\u00f3rter da Ag\u00eancia Brasil - Rio de Janeiro As trabalhadoras brasileiras tiveram no quarto trimestre de 2023 um rendimento m\u00e9dio real 20,8% menor que o dos homens. Enquanto o valor recebido por eles no trabalho principal\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/image_processing20240131-2144942-hun7vm.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/image_processing20240131-2144942-hun7vm.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/image_processing20240131-2144942-hun7vm.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/image_processing20240131-2144942-hun7vm.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24722,"url":"https:\/\/correiodasemana.com\/site\/desemprego-sobe-em-15-estados-e-no-df-no-primeiro-trimestre-de-2023-diz-ibge\/","url_meta":{"origin":13835,"position":3},"title":"Desemprego sobe em 15 estados e no DF no primeiro trimestre de 2023, diz IBGE","author":"","date":"Maio 18, 2023","format":false,"excerpt":"A taxa de desemprego no Brasil subiu em 16 das 27 Unidades da Federa\u00e7\u00e3o no primeiro trimestre de 2023, segundo a Pesquisa Nacional por Amostra de Domic\u00edlios (PNAD) Cont\u00ednua Trimestral, divulgada nesta quinta-feira (18) pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Nos demais estados, a taxa ficou est\u00e1vel. Segundo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_0343.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_0343.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_0343.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_0343.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_0343.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_0343.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15084,"url":"https:\/\/correiodasemana.com\/site\/no-ceara-abate-de-frangos-e-suinos-cresce-e-de-bovinos-cai-no-3o-trimestre-de-2020\/","url_meta":{"origin":13835,"position":4},"title":"No Cear\u00e1, abate de frangos e su\u00ednos cresce e de bovinos cai no 3\u00ba trimestre de 2020","author":"","date":"Dezembro 20, 2020","format":false,"excerpt":"No 3\u00ba trimestre de 2020, foram abatidos\u00a033 mil cabe\u00e7as de bovinos, quantidade 17% inferior \u00e0 obtida no 3\u00ba trimestre de 2019 e 5,7% acima da registrada no 2\u00ba trimestre de 2020. \u00c9 o resultado mais baixo para um 3\u00ba trimestre desde o in\u00edcio da pesquisa (em 1997). Foram abatidos\u00a06,6 milh\u00f5es\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/pe265835-768x433-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/pe265835-768x433-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/pe265835-768x433-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/pe265835-768x433-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31521,"url":"https:\/\/correiodasemana.com\/site\/ceara-tem-menor-taxa-de-desemprego-do-nordeste\/","url_meta":{"origin":13835,"position":5},"title":"Cear\u00e1 tem menor taxa de desemprego do Nordeste","author":"adminredacao","date":"Novembro 24, 2024","format":false,"excerpt":"Com o indicador de 6,7%, o Cear\u00e1 registra a menor taxa de desemprego do Nordeste, seguido por Maranh\u00e3o (7,6%) e Alagoas (7,7%). Os dados s\u00e3o da Pesquisa Nacional por Amostra de Domic\u00edlios (Pnad) Cont\u00ednua Trimestral, divulgada nesta sexta-feira (22) pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), e indicam ainda\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-22-at-16.49.55.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-22-at-16.49.55.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-22-at-16.49.55.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-22-at-16.49.55.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-22-at-16.49.55.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-22-at-16.49.55.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13835"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13835\/revisions"}],"predecessor-version":[{"id":13838,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13835\/revisions\/13838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13836"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}