{"id":13917,"date":"2020-10-05T09:49:27","date_gmt":"2020-10-05T12:49:27","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13917"},"modified":"2020-10-05T09:49:27","modified_gmt":"2020-10-05T12:49:27","slug":"municipios-terao-flexibilidade-nas-licitacoes","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/municipios-terao-flexibilidade-nas-licitacoes\/","title":{"rendered":"Munic\u00edpios ter\u00e3o flexibilidade nas licita\u00e7\u00f5es"},"content":{"rendered":"<p><span style=\"color: #000000;\"><span style=\"font-family: Noto Sans, sans-serif;\">De forma simplificada, podemos dizer que a Lei 14.065 tem objetivo de flexibilizar as licita\u00e7\u00f5es por todo o pa\u00eds at\u00e9 o dia 31 de dezembro deste ano<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\">Est\u00e1 em vigor a <\/span><\/span><\/span><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2019-2022\/2020\/lei\/L14065.htm\"><span style=\"color: #000000;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\"><strong>Lei 14.065<\/strong><\/span><\/span><\/span><\/a><span style=\"color: #000000;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\">, sancionada pelo presidente Jair Bolsonaro, que autoriza pagamentos antecipados nas licita\u00e7\u00f5es e nos contratos realizados no \u00e2mbito da administra\u00e7\u00e3o p\u00fablica; adequa os limites de dispensa de licita\u00e7\u00e3o; amplia o uso do Regime Diferenciado de Contrata\u00e7\u00f5es P\u00fablicas (RDC) durante o estado de calamidade reconhecido pelo <\/span><\/span><\/span><a href=\"https:\/\/legislacao.presidencia.gov.br\/atos\/?tipo=DLG&amp;numero=6&amp;ano=2020&amp;ato=b1fAzZU5EMZpWT794\"><span style=\"color: #000000;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\"><strong>Decreto Legislativo n\u00ba 6, de 20 de mar\u00e7o de 2020<\/strong><\/span><\/span><\/span><\/a><span style=\"color: #000000;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\">.<br \/>\nAqui \u00e9 importante destacar que o estado de calamidade p\u00fablica \u00e9 uma forma do Governo Federal reconhecer danos graves \u00e0 sociedade e perigo aos cidad\u00e3os, como uma medida que possibilita aos estados e munic\u00edpios a antecipa\u00e7\u00e3o de benef\u00edcios sociais, libera\u00e7\u00e3o de seguros e a prorroga\u00e7\u00e3o de pagamentos de empr\u00e9stimos federais, por exemplo.<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\">De forma mais simplificada, podemos dizer que a Lei 14.065 tem objetivo de flexibilizar as licita\u00e7\u00f5es por todo o pa\u00eds at\u00e9 31 de dezembro deste ano, e entre os pontos j\u00e1 citados, faz com que todos os \u00f3rg\u00e3os da administra\u00e7\u00e3o p\u00fablica possam dispensar a licita\u00e7\u00e3o para obras de engenharia de at\u00e9 R$ 100 mil e para compras de at\u00e9 R$ 50 mil durante o estado de calamidade relativo \u00e0 pandemia.<\/span><\/p>\n<p><span style=\"color: #000000;\">Segundo o especialista em administra\u00e7\u00e3o p\u00fablica, Karlos Gomes, essa lei vai favorecer as cidades, oferecendo maior agilidade na gest\u00e3o municipal, principalmente naqueles casos diretamente ligados ao combate contra a Covid-19. \u201cAgora, com essa lei, at\u00e9 31 de dezembro todas as licita\u00e7\u00f5es podem ser feitas pelo regime diferenciado. Isso vai ser ben\u00e9fico, pois vai trazer um custo menor para a administra\u00e7\u00e3o p\u00fablica, maior efici\u00eancia e uma contrata\u00e7\u00e3o mais r\u00e1pida do objeto que for alvo da licita\u00e7\u00e3o\u201d, explicou.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-13919\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/content_FLEXIBILIZACAO-DAS-REGRAS-DE-LICITACAO.jpg\" alt=\"\" width=\"800\" height=\"541\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/content_FLEXIBILIZACAO-DAS-REGRAS-DE-LICITACAO.jpg 800w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/content_FLEXIBILIZACAO-DAS-REGRAS-DE-LICITACAO-300x203.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/content_FLEXIBILIZACAO-DAS-REGRAS-DE-LICITACAO-768x519.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span style=\"color: #000000;\">Essa lei surgiu como forma de aumentar a rapidez nas licita\u00e7\u00f5es, pois at\u00e9 ent\u00e3o o Regime Diferenciado de Contrata\u00e7\u00f5es P\u00fablicas era aplicado em situa\u00e7\u00f5es espec\u00edficas, como obras e servi\u00e7os de engenharia do Sistema \u00danico de Sa\u00fade (SUS). Com a lei, tamb\u00e9m fica autorizado, sob certas condi\u00e7\u00f5es, o pagamento antecipado em licita\u00e7\u00f5es. Ou seja, os \u00f3rg\u00e3os p\u00fablicos poder\u00e3o efetuar o pagamento pelo servi\u00e7o ou produto antes mesmo que eles sejam entregues.<\/span><\/p>\n<p><span style=\"color: #000000;\">Atualmente, o <\/span><strong><a href=\"https:\/\/portal.tcu.gov.br\/inicio\/\"><span style=\"color: #000000;\">Tribunal de Contas da Uni\u00e3o (TCU)<\/span><\/a><\/strong><span style=\"color: #000000;\"> admite a antecipa\u00e7\u00e3o do pagamento apenas em situa\u00e7\u00f5es excepcionais. Por isso, \u00e9 necess\u00e1rio ter uma aten\u00e7\u00e3o maior nessas situa\u00e7\u00f5es para evitar problemas como corrup\u00e7\u00e3o ou improbidade administrativa \u2013 que \u00e9 o ato ilegal ou contr\u00e1rio aos princ\u00edpios b\u00e1sicos da Administra\u00e7\u00e3o P\u00fablica no Brasil, cometido por agente p\u00fablico, no exerc\u00edcio da fun\u00e7\u00e3o.<br \/>\n<\/span><span style=\"color: #000000;\">E \u00e9 isso o que destaca o advogado especialista em direito civil, Rodrigo Fagundes, ao afirmar que \u201cquando voc\u00ea flexibiliza regras, tamb\u00e9m fragiliza a seguran\u00e7a jur\u00eddica das contrata\u00e7\u00f5es, de uma forma geral. Nesse sentido, fica mais vulner\u00e1vel, de fato, para eventuais atos de corrup\u00e7\u00e3o ou alguma improbidade cometida pelo gestor. O que se recomenda nesses casos, nessa situa\u00e7\u00e3o espec\u00edfica \u00e9 que os \u00f3rg\u00e3os de controle atuem com mais efetividade para esses procedimentos realizados dentro dessa nova legisla\u00e7\u00e3o\u201d, disse.<\/span><\/p>\n<p><span style=\"color: #000000;\">Fonte: <a href=\"https:\/\/brasil61.com\/noticias\/municipios-terao-flexibilidade-nas-licitacoes-bras202093\" target=\"_blank\" rel=\"noopener noreferrer\">Brasil 61<\/a> <\/span><span style=\"color: #000000;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\">Munic\u00edpios ter\u00e3o flexibilidade nas licita\u00e7\u00f5es<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De forma simplificada, podemos dizer que a Lei 14.065 tem objetivo de flexibilizar as licita\u00e7\u00f5es&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/b6ddb1640e40bdd68db56d48e7164c4813c0819bad11420b1fe7db253f4a5ce3.jpg","jetpack-related-posts":[{"id":22934,"url":"https:\/\/correiodasemana.com\/site\/pf-investiga-suposta-fraude-na-contratacao-de-medicos-e-enfermeiros-no-ceara\/","url_meta":{"origin":13917,"position":0},"title":"PF investiga suposta fraude na contrata\u00e7\u00e3o de m\u00e9dicos e enfermeiros no Cear\u00e1","author":"","date":"Janeiro 20, 2023","format":false,"excerpt":"Esta \u00e9 a segunda vez que a PF cumpre mandados na investiga\u00e7\u00e3o do suposto esquema criminoso. H\u00e1 ind\u00edcios de que houve fraude na licita\u00e7\u00e3o de R$ 1,5 milh\u00e3o para contrata\u00e7\u00e3o de m\u00e9dicos e enfermeiros no munic\u00edpio de Reden\u00e7\u00e3o. A Pol\u00edcia Federal cumpre na manh\u00e3 desta sexta-feira, 20, mandados de busca\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/129433_1000x600_width.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/129433_1000x600_width.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/129433_1000x600_width.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/129433_1000x600_width.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13677,"url":"https:\/\/correiodasemana.com\/site\/sancionada-lei-que-regula-pagamento-de-auxilio-a-quem-teve-reducao-de-salario\/","url_meta":{"origin":13917,"position":1},"title":"Sancionada lei que regula pagamento de aux\u00edlio a quem teve redu\u00e7\u00e3o de sal\u00e1rio","author":"","date":"Setembro 21, 2020","format":false,"excerpt":"A lei permite ao Governo Federal contratar sem licita\u00e7\u00e3o a Caixa Econ\u00f4mica Federal e o Banco do Brasil para repassar os recursos aos bancos em que os trabalhadores possuem conta. A Lei 14.058, publicada no Di\u00e1rio Oficial da Uni\u00e3o da \u00faltima sexta-feira (18), define as regras para os bancos federais\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/patrulhadopovo-confira-pagamentos-e-tributos-adiados-ou-suspensos-durante-pandemia-7a1mv33ywngirsge126axcal8-678x381-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/patrulhadopovo-confira-pagamentos-e-tributos-adiados-ou-suspensos-durante-pandemia-7a1mv33ywngirsge126axcal8-678x381-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/patrulhadopovo-confira-pagamentos-e-tributos-adiados-ou-suspensos-durante-pandemia-7a1mv33ywngirsge126axcal8-678x381-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":24430,"url":"https:\/\/correiodasemana.com\/site\/camara-derruba-decretos-de-lula-que-flexibilizavam-lei-do-saneamento\/","url_meta":{"origin":13917,"position":2},"title":"C\u00e2mara derruba decretos de Lula que flexibilizavam lei do saneamento","author":"","date":"Maio 4, 2023","format":false,"excerpt":"A C\u00e2mara aprovou nesta quarta-feira, 3, o Projeto de Decreto Legislativo (PDL) que derruba trechos de dois decretos do presidente, Luiz In\u00e1cio Lula da Silva (PT), que propunham altera\u00e7\u00f5es no marco do saneamento. O projeto foi aprovado por 295 votos favor\u00e1veis e 136 contr\u00e1rios. O texto agora segue para o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/102560999.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/102560999.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/102560999.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/102560999.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10611,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-lanca-edital-de-licitacao-para-reforma-da-lavanderia-e-construcao-de-reservatorio-elevado\/","url_meta":{"origin":13917,"position":3},"title":"Santa Casa de Miseric\u00f3rdia de Sobral lan\u00e7a edital de licita\u00e7\u00e3o para reforma da Lavanderia e constru\u00e7\u00e3o de Reservat\u00f3rio Elevado","author":"","date":"Janeiro 27, 2020","format":false,"excerpt":"A Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) divulga edital de licita\u00e7\u00e3o do tipo menor pre\u00e7o para contrata\u00e7\u00e3o de empresa especializada na execu\u00e7\u00e3o de obras de constru\u00e7\u00e3o civil para a reforma da Lavanderia e constru\u00e7\u00e3o de um Reservat\u00f3rio Elevado, divididos em dois lotes. A documenta\u00e7\u00e3o exigida no edital dever\u00e1 ser\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Licita%C3%A7%C3%A3o.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Licita%C3%A7%C3%A3o.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Licita%C3%A7%C3%A3o.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9952,"url":"https:\/\/correiodasemana.com\/site\/lancada-licitacao-para-construcao-do-aeroporto-regional-de-sobral\/","url_meta":{"origin":13917,"position":4},"title":"Lan\u00e7ada licita\u00e7\u00e3o para constru\u00e7\u00e3o do Aeroporto Regional de Sobral","author":"","date":"Novembro 27, 2019","format":false,"excerpt":"O recebimento das propostas da Concorr\u00eancia P\u00fablica, do tipo Menor Pre\u00e7o, deve ocorrer no dia 18 de dezembro, na Central de Licita\u00e7\u00f5es da Procuradoria Geral do Estado (PGE). O edital de licita\u00e7\u00e3o para a implanta\u00e7\u00e3o da pista, dos acessos e servi\u00e7os complementares do novo Aeroporto Regional de Sobral, na Zona\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/aeroporto-Sobral-aviao-696x531.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/aeroporto-Sobral-aviao-696x531.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/aeroporto-Sobral-aviao-696x531.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":11928,"url":"https:\/\/correiodasemana.com\/site\/bolsonaro-sanciona-lei-do-novo-marco-legal-do-saneamento-basico\/","url_meta":{"origin":13917,"position":5},"title":"Bolsonaro sanciona lei do novo Marco Legal do Saneamento B\u00e1sico","author":"","date":"Julho 16, 2020","format":false,"excerpt":"Texto prev\u00ea universaliza\u00e7\u00e3o dos servi\u00e7os de \u00e1gua e esgoto at\u00e9 2033 O presidente Jair Bolsonaro sancionou hoje (15) a lei do novo Marco Legal do Saneamento B\u00e1sico no pa\u00eds, que prev\u00ea a universaliza\u00e7\u00e3o dos servi\u00e7os de \u00e1gua e esgoto at\u00e9 2033. O texto,\u00a0aprovado no Congresso\u00a0no m\u00eas passado ap\u00f3s muita discuss\u00e3o,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13917"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13917\/revisions"}],"predecessor-version":[{"id":13921,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13917\/revisions\/13921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13918"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}