{"id":13950,"date":"2020-10-07T11:37:10","date_gmt":"2020-10-07T14:37:10","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=13950"},"modified":"2020-10-07T11:37:10","modified_gmt":"2020-10-07T14:37:10","slug":"governo-lanca-campanha-para-deteccao-precoce-do-cancer-de-mama","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/governo-lanca-campanha-para-deteccao-precoce-do-cancer-de-mama\/","title":{"rendered":"Governo lan\u00e7a campanha para detec\u00e7\u00e3o precoce do c\u00e2ncer de mama"},"content":{"rendered":"<div class=\"col-lg-12 mb-3\">\n<div class=\"row\">\n<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">Cerim\u00f4nia online marca lan\u00e7amento do Outubro Rosa 2020<\/h3>\n<\/div>\n<\/div>\n<div class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<div class=\"post-item alt-font\">\n<div class=\"post-item-wrap\">\n<p>O Minist\u00e9rio da Sa\u00fade lan\u00e7a nesta quarta-feira (7), em evento\u00a0<em>on-line<\/em>, a Campanha do Outubro Rosa 2020. A a\u00e7\u00e3o \u00e9 um alerta sobre a import\u00e2ncia da detec\u00e7\u00e3o precoce do c\u00e2ncer de mama, bem como para a preven\u00e7\u00e3o da doen\u00e7a.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1390008&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1390008&amp;o=node\" \/><\/p>\n<p>A cerim\u00f4nia contar\u00e1 com a presen\u00e7a do ministro da Sa\u00fade, Eduardo Pazuello; da primeira-dama da Rep\u00fablica, Michelle Bolsonaro; e da ministra da Mulher, da Fam\u00edlia e dos Direitos Humanos, Damares Alves.<\/p>\n<\/div>\n<div class=\"post-item-wrap\">\n<h2><a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2020-10\/pandemia-pode-atrasar-tratamento-de-cancer-de-mama\" target=\"_blank\" rel=\"noopener noreferrer\">Pandemia pode atrasar tratamento de c\u00e2ncer de mama<\/a><\/h2>\n<p>Levantamento feito pela Funda\u00e7\u00e3o do C\u00e2ncer, com base em dados do Sistema \u00danico de Sa\u00fade (SUS), revela queda de 84% no n\u00famero de mamografias feitas no Brasil durante a pandemia do novo coronav\u00edrus, em compara\u00e7\u00e3o ao mesmo per\u00edodo do ano passado.<\/p>\n<h2><a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2020-10\/exposicao-de-fotografias-alerta-para-prevencao-do-cancer-de-mama\" target=\"_blank\" rel=\"noopener noreferrer\">Exposi\u00e7\u00e3o de fotografias alerta para preven\u00e7\u00e3o do c\u00e2ncer de mama<\/a><\/h2>\n<p>Durante todo o m\u00eas de outubro uma exposi\u00e7\u00e3o de fotografias de mulheres que venceram o c\u00e2ncer de mama estar\u00e1 dispon\u00edvel em seis pontos da capital paulista. Idealizada pela organiza\u00e7\u00e3o n\u00e3o governamental (Ong) Instituto Viver Hoje a mostra Mulheres no Espelho tem o objetivo de informar sobre a import\u00e2ncia do diagn\u00f3stico precoce do c\u00e2ncer de mama, al\u00e9m de incentivar o aumento da autoestima das mulheres que passaram pela doen\u00e7a.<\/p>\n<h2><a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2020-10\/psiquiatra-alerta-para-relacao-do-cancer-com-doencas-mentais\" target=\"_blank\" rel=\"noopener noreferrer\">Psiquiatra alerta para rela\u00e7\u00e3o do c\u00e2ncer de mama com doen\u00e7as mentais<\/a><\/h2>\n<p>O movimento Outubro Rosa marca o m\u00eas de conscientiza\u00e7\u00e3o do cuidado e de preven\u00e7\u00e3o ao c\u00e2ncer de mama, mas tamb\u00e9m ressalta a import\u00e2ncia de se compreender e dialogar sobre a rela\u00e7\u00e3o do tratamento do c\u00e2ncer de mama e as doen\u00e7as mentais, para o enfrentamento de todo o processo.<\/p>\n<p>Por Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cerim\u00f4nia online marca lan\u00e7amento do Outubro Rosa 2020 O Minist\u00e9rio da Sa\u00fade lan\u00e7a nesta quarta-feira&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-13950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_abr_numero_de_serie_de_4_digitos_090620_1.jpg","jetpack-related-posts":[{"id":13958,"url":"https:\/\/correiodasemana.com\/site\/campanha-outubro-rosa-incentiva-deteccao-precoce-do-cancer-de-mama\/","url_meta":{"origin":13950,"position":0},"title":"Campanha Outubro Rosa incentiva detec\u00e7\u00e3o precoce do c\u00e2ncer de mama","author":"","date":"Outubro 7, 2020","format":false,"excerpt":"N\u00famero de mamografias no pa\u00eds caiu neste ano O n\u00famero de mamografias realizadas pelo Sistema \u00danico de Sa\u00fade (SUS) caiu entre janeiro e julho deste ano, em compara\u00e7\u00e3o com os anos anteriores. O n\u00famero de\u00a0mamografias realizadas at\u00e9 julho de 2020 foi de 1,1 milh\u00e3o, contra 2,1 milh\u00f5es nos mesmos per\u00edodos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_cancer_de_mama_0710202082_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_cancer_de_mama_0710202082_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_cancer_de_mama_0710202082_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_cancer_de_mama_0710202082_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/mca_cancer_de_mama_0710202082_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35939,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-destaca-a-importancia-da-prevencao-e-do-diagnostico-precoce-do-cancer-de-mama\/","url_meta":{"origin":13950,"position":1},"title":"Santa Casa de Sobral destaca a import\u00e2ncia da preven\u00e7\u00e3o e do diagn\u00f3stico precoce do c\u00e2ncer de mama","author":"adminredacao","date":"Outubro 29, 2025","format":false,"excerpt":"H\u00e1 sete anos, a professora aposentada Maria Eurenides Fernandes, 78 anos, luta contra o c\u00e2ncer. Ela descobriu um tumor maligno nas mamas durante uma consulta de rotina com o ginecologista e, ap\u00f3s o diagn\u00f3stico de c\u00e2ncer de mama, passou a ser acompanhada pelo Centro de Alta Complexidade em Oncologia (CACON)\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/outubro-rosa-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/outubro-rosa-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/outubro-rosa-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/outubro-rosa-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/outubro-rosa-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13783,"url":"https:\/\/correiodasemana.com\/site\/desafios-do-diagnostico-e-tratamento-do-cancer-de-mama-nos-dias-atuais\/","url_meta":{"origin":13950,"position":2},"title":"Desafios do diagnostico e tratamento do c\u00e2ncer de mama nos dias atuais","author":"","date":"Setembro 29, 2020","format":false,"excerpt":"Ao ler um artigo super interessante sobre de - escalonamento do tratamento do c\u00e2ncer de mama , onde nos mostra a evolu\u00e7\u00e3o para diagn\u00f3sticos mais precoces , respostas altas aos quimioter\u00e1picos, cirurgias mais conservadoras com perspectivas futuras de at\u00e9 n\u00e3o operar estas mulheres , fazendo apenas um seguimento monitorado ,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-15-at-14.24.40.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-15-at-14.24.40.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-15-at-14.24.40.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-15-at-14.24.40.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-15-at-14.24.40.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35130,"url":"https:\/\/correiodasemana.com\/site\/agora-tem-especialistas-ministerio-da-saude-oferta-tecnologia-inovadora-para-deteccao-precoce-de-cancer-de-colo-do-utero-no-ceara\/","url_meta":{"origin":13950,"position":3},"title":"AGORA TEM ESPECIALISTAS: Minist\u00e9rio da Sa\u00fade oferta tecnologia inovadora para detec\u00e7\u00e3o precoce de c\u00e2ncer de colo do \u00fatero no Cear\u00e1","author":"adminredacao","date":"Agosto 17, 2025","format":false,"excerpt":"Medida do Agora Tem Especialistas ser\u00e1 implementada em 12 estados de forma gradativa. No Cear\u00e1, o teste beneficia, inicialmente, mulheres de Fortaleza O Minist\u00e9rio da Sa\u00fade iniciou, nesta sexta-feira (15), a implementa\u00e7\u00e3o do teste de biologia molecular DNA-HPV no Sistema \u00danico de Sa\u00fade (SUS). Trata-se de um m\u00e9todo moderno e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/ESPECIALISTAS-DE-FORTALEZA.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/ESPECIALISTAS-DE-FORTALEZA.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/ESPECIALISTAS-DE-FORTALEZA.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/ESPECIALISTAS-DE-FORTALEZA.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14167,"url":"https:\/\/correiodasemana.com\/site\/amamentar-reduz-risco-de-cancer-de-mama-orienta-especialista-do-hospital-regional-norte\/","url_meta":{"origin":13950,"position":4},"title":"Amamentar reduz risco de c\u00e2ncer de mama, orienta especialista do Hospital Regional Norte","author":"","date":"Outubro 20, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. - Com informa\u00e7\u00f5es de Teresa Fernandes. O outubro rosa \u00e9 uma campanha que anualmente incentiva o autocuidado e a preven\u00e7\u00e3o dos c\u00e2nceres de mama e ov\u00e1rio, que est\u00e3o entre os mais comuns em mulheres. Uma das formas de prevenir esses tipos de c\u00e2nceres \u00e9 a amamenta\u00e7\u00e3o. Al\u00e9m\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14054,"url":"https:\/\/correiodasemana.com\/site\/amamentar-reduz-risco-de-cancer-de-mama-orienta-especialista-do-hrn\/","url_meta":{"origin":13950,"position":5},"title":"Amamentar reduz risco de c\u00e2ncer de mama, orienta especialista do HRN","author":"","date":"Outubro 13, 2020","format":false,"excerpt":"O outubro rosa \u00e9 uma campanha que anualmente incentiva o autocuidado e a preven\u00e7\u00e3o dos c\u00e2nceres de mama e ov\u00e1rio, que est\u00e3o entre os mais comuns em mulheres. Uma das formas de prevenir esses tipos de c\u00e2nceres \u00e9 a amamenta\u00e7\u00e3o. Al\u00e9m de ser importante para o desenvolvimento do beb\u00ea, o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/foto-2-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=13950"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13950\/revisions"}],"predecessor-version":[{"id":13953,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/13950\/revisions\/13953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/13951"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=13950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=13950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=13950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}