{"id":14005,"date":"2020-10-13T00:36:22","date_gmt":"2020-10-13T03:36:22","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14005"},"modified":"2020-10-13T00:36:22","modified_gmt":"2020-10-13T03:36:22","slug":"sobral-sobral-11","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sobral-sobral-11\/","title":{"rendered":"Sobral, Sobral"},"content":{"rendered":"<p><strong>MINHAS HIST\u00d3RIAS\u2026<\/strong><br \/>\n<strong>JOS\u00c9 RIBEIRO E O AL\u00d4 PRA TIA BEN\u00c9 !<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-14006 size-medium\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.00-255x300.png\" alt=\"\" width=\"255\" height=\"300\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.00-255x300.png 255w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.00-872x1024.png 872w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.00-768x902.png 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.00.png 899w\" sizes=\"(max-width: 255px) 100vw, 255px\" \/><br \/>\nO cantor JOS\u00c9 RIBEIRO fez sua \u00faltima apresenta\u00e7\u00e3o em SOBRAL em junho de 2009. Foi no COQUEIRO\u2019S Club, junto com outros dois bregueiros: CARLOS ANDR\u00c9 e GENIVAL SANTOS. Na mesma noite de s\u00e1bado, um show aqui e outro na cidade de S\u00c3O BENEDITO, na Serra Grande. Respons\u00e1vel pela abertura do show em SOBRAL, antes de subir a serra, o artista mineiro levou a plateia do clube sobralense ao del\u00edrio quando, entre uma m\u00fasica e outra do seu imenso repert\u00f3rio de sucessos, disse enquanto enxugava o suor que banhava o rosto e sua blusa vermelha:<br \/>\n&#8212; Gostaria de saudar a todos aqui. Agrade\u00e7o a presen\u00e7a. E queria dizer que \u00e9 um grande prazer estar aqui nesta linda cidade mais uma vez. E mandar um abra\u00e7o e um beijo para a Tia BEN\u00c9 e as suas sobrinhas, com quem passei hoje uma tarde maravilhosa.<br \/>\nA TIA BEN\u00c9 era a dona de um conhecido lupanar que funcionava ali quase em frente a antiga CAPASA, no in\u00edcio da avenida que passa em frente ao cemit\u00e9rio S\u00c3O JOS\u00c9, o \u201ccemit\u00e9rio dos pobres\u201d, e termina nos fundos do Hospital Regional. Eu estava no outro show, mas o meu parceiro CLAYTON CARNEIRO n\u00e3o controlava o riso ao me contar pelo celular que a galera n\u00e3o parava de gritar e aplaudir, pedindo ao artista para repetir o al\u00f4 para as meninas da TIA BEN\u00c9.<br \/>\nEm 2018, na cidade de PINDORETAMA morreu JOS\u00c9 RIBEIRO. Tinha 84 anos e foi v\u00edtima de um ataque card\u00edaco.<br \/>\nA TIA BEN\u00c9, que era de MASSAP\u00ca, tamb\u00e9m morreu naquele mesmo ano, fato que decretou o fim das atividades de seu bar e \u201ccasa de recurso\u201d.<\/p>\n<p><strong>MINHAS M\u00daSICAS\u2026<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignleft wp-image-14007 size-medium\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.15-298x300.jpeg\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.15-298x300.jpeg 298w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.15-150x150.jpeg 150w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-08-at-09.33.15.jpeg 559w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/>A BELEZA DA ROSA &#8211; JOS\u00c9 RIBEIRO. 1972. Lan\u00e7ada no primeiro LP deste cantor cujo nome de batismo era JOS\u00c9 CIPRIANO. De voz anasalada, JOS\u00c9 RIBEIRO nasceu em BARBACENA-MG e o disco de 1972 trazia outros grandes hits como CAN\u00c7\u00c3O DOS NAMORADOS, SUELI, ERRO DE MATRIM\u00d4NIO, PENSANDO EM MARISA, UM AMOR VAI OUTRO VEM, A \u00daLTIMA NOITE DE UMA PAIX\u00c3O, etc. Anos depois, em 1994, voltou a fazer sucesso nacional com uma m\u00fasica chamada APENAS UM TRAGO, mais conhecida como BOM DIA MEU AMOR. Ela foi \u201credescoberta\u201d quando dirig\u00edamos a DRAG\u00c3O DO MAR 99 FM (Nesta \u00e9poca a dire\u00e7\u00e3o da DRAG\u00c3O DO MAR AM era confiada ao jornalista e posteriormente Deputado Estadual FERREIRA ARAG\u00c3O). O artista estava esquecido, numa cama de hospital, no RIO. Quando soube que era sucesso no CEAR\u00c1, ficou bom na hora. Sempre foi agradecido por isso e nos tornamos amigos. JOS\u00c9 RIBEIRO voltou a fazer shows, at\u00e9 sua morte, em 2018, v\u00edtima de infarto. Tinha 84 anos e morava em PINDORETAMA-CE, na GRANDE FORTALEZA. Sua \u00faltima apresenta\u00e7\u00e3o nesta regi\u00e3o do CEAR\u00c1 foi em janeiro de 2016, um show particular na localidade de CAMPAN\u00c1RIO, munic\u00edpio de URU\u00d3CA, promo\u00e7\u00e3o do empres\u00e1rio EVALDO MARQUES.<\/p>\n<p>MINHAS FRASES\u2026<br \/>\nQUEM OLHA PRA FORA, SONHA. QUEM OLHA PRA DENTRO, DESPERTA. (autor desconhecido)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINHAS HIST\u00d3RIAS\u2026 JOS\u00c9 RIBEIRO E O AL\u00d4 PRA TIA BEN\u00c9 ! O cantor JOS\u00c9 RIBEIRO&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,75],"tags":[],"class_list":["post-14005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-carolino-soares"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Carolino-Soares.png","jetpack-related-posts":[{"id":16536,"url":"https:\/\/correiodasemana.com\/site\/beco-ponto-com-2\/","url_meta":{"origin":14005,"position":0},"title":"Beco ponto Com","author":"","date":"Maio 24, 2021","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Das armadilhas do poder pelo poder via corrup\u00e7\u00e3o. Dos sofredores pobres encurralados da pandemia. Das pizzas enfeitadas por corruptos em plen\u00e1rios. Da baboseira de emissoras puxando-sacos na cidade. Da briga Ciro x Lula, pela presid\u00eancia meio surtados. De uma oposi\u00e7\u00e3o fraca e sem projetos pela c\u00e2mara. Do povo\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":36513,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-240\/","url_meta":{"origin":14005,"position":1},"title":"BECCO PONTO.COM","author":"adminredacao","date":"Novembro 25, 2025","format":false,"excerpt":"Livrai-nos, senhor! Das festas p\u00e3es e circos, t\u00e3o natalinas, ufa! Das mutretas ora politicas visando o poder. Das faculdades produzindo semianalfas. Dos golpes do pt lula, articulando a m\u00eddia. Das igrejas Evang\u00e9licas fabricando urnas. Dos papos moles dos puxa sacos do poder. Da cop 30: mais um fracasso dos peitistas.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":31316,"url":"https:\/\/correiodasemana.com\/site\/a-capela-nossa-senhora-da-conceicao-de-sao-jose-atual-patriarca\/","url_meta":{"origin":14005,"position":2},"title":"A Capela Nossa Senhora da Concei\u00e7\u00e3o de S\u00e3o Jos\u00e9, atual Patriarca","author":"adminredacao","date":"Novembro 3, 2024","format":false,"excerpt":"O Curato do Acara\u00fa que depois origem \u00e0 Par\u00f3quia de Nossa Senhora da Concei\u00e7\u00e3o de Sobral e \u00e0 pr\u00f3pria Diocese, tinha um territ\u00f3rio que ia da Serra da Ibiapaba at\u00e9 o rio Munda\u00fa, abrangendo as ribeiras do Corea\u00fa, Acara\u00fa, Aracatia\u00e7u e parte do Munda\u00fa. O Mons. Sadoc de Ara\u00fajo informa-nos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-01-at-15.51.24.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-01-at-15.51.24.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-01-at-15.51.24.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-01-at-15.51.24.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-01-at-15.51.24.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17705,"url":"https:\/\/correiodasemana.com\/site\/sobral-sobral-59\/","url_meta":{"origin":14005,"position":3},"title":"Sobral, Sobral","author":"","date":"Outubro 10, 2021","format":false,"excerpt":"INTELIGENTE N\u00c3O \u00c9 QUEM APRENDEU AONDE IR, MAS QUEM SABE PRA ONDE N\u00c3O DEVE VOLTAR !! MINHAS HIST\u00d3RIAS... ACONTECEU EM SOBRAL!! O MAIOR DAN\u00c7ADOR DO BRASIL... No final do s\u00e9culo passado em SOBRAL tivemos o maior \u201cdan\u00e7ador \u201c da hist\u00f3ria da PRINCESA DO NORTE. Ele simplesmente ganhou todas os CONCURSOS\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23235,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-113\/","url_meta":{"origin":14005,"position":4},"title":"Becco ponto Com","author":"adminredacao","date":"Janeiro 31, 2023","format":false,"excerpt":"COLUNA BECCO PONTO COM JANEIRO 2023 Livrai-nos, senhor! Nas demoras das obras p\u00fablicas, aqui. Das festas importadas na cultura, aqui. Dos acordos esp\u00farios pol\u00edticos, agora. Dos programas lixos da Rede Globo, ui! Do ensino moderno t\u00e3o fuleiragens, ui! Da viol\u00eancia contra a mulher no Cear\u00e1. Das atra\u00e7\u00f5es carnavalescas vale ter\u00e7os.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":36263,"url":"https:\/\/correiodasemana.com\/site\/tia-fransquinha-80-anos-de-dedicacao-a-deus-e-ao-proximo\/","url_meta":{"origin":14005,"position":5},"title":"TIA FRANSQUINHA: 80 anos de dedica\u00e7\u00e3o a Deus e ao pr\u00f3ximo","author":"adminredacao","date":"Novembro 12, 2025","format":false,"excerpt":"No s\u00e1bado, 8, no Solares Buffet, familiares e amigos da Sra. Francisca Alves Vasconcelos estiveram reunidos para agradecer a Deus e comemorar o transcurso dos seus 80 anos de vida prof\u00edcua e exemplar. Nascida em Sobral no dia 09 de novembro de 1945, s\u00e3o seus pais Gon\u00e7alo Alves da Costa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-10-at-20.13.18.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-10-at-20.13.18.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-10-at-20.13.18.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-10-at-20.13.18.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14005"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14005\/revisions"}],"predecessor-version":[{"id":14008,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14005\/revisions\/14008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/12393"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}