{"id":14009,"date":"2020-10-13T00:37:21","date_gmt":"2020-10-13T03:37:21","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14009"},"modified":"2020-10-13T00:37:21","modified_gmt":"2020-10-13T03:37:21","slug":"conselho-nacional-de-educacao-aprova-ensino-remoto-ate-2021-e-juncao-dos-anos-letivos","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/conselho-nacional-de-educacao-aprova-ensino-remoto-ate-2021-e-juncao-dos-anos-letivos\/","title":{"rendered":"Conselho Nacional de Educa\u00e7\u00e3o aprova ensino remoto at\u00e9 2021 e jun\u00e7\u00e3o dos anos letivos"},"content":{"rendered":"<p>Por Joc\u00e9lio Tavares.<br \/>\nNa noite da \u00faltima ter\u00e7a-feira (06\/10), o Conselho Nacional de Educa\u00e7\u00e3o (CNE) aprovou resolu\u00e7\u00e3o que permite o ensino remoto nas escolas p\u00fablicas e particulares at\u00e9 31 de dezembro de 2021.<br \/>\nDessa forma, as redes de ensino podem organizar calend\u00e1rios, com reposi\u00e7\u00f5es de aulas perdidas e avalia\u00e7\u00f5es at\u00e9 o ano que vem. O documento, aprovado por unanimidade e que agora vai para o aval do Minist\u00e9rio da Educa\u00e7\u00e3o, tamb\u00e9m recomenda que as escolas n\u00e3o deem faltas aos alunos nesse per\u00edodo todo de pandemia.<br \/>\nComo em outras resolu\u00e7\u00f5es durante essa crise, mais uma vez o CNE tamb\u00e9m n\u00e3o recomenda a reprova\u00e7\u00e3o em 2020 e sugere juntar os anos letivos. \u201cO reordenamento curricular do que restar do ano letivo de 2020 e o do ano letivo seguinte pode ser reprogramado, aumentando-se os dias letivos e a carga hor\u00e1ria do ano letivo de 2021 para cumprir, de modo cont\u00ednuo, os objetivos de aprendizagem e desenvolvimento previstos no ano letivo anterior\u201d, diz o texto.<br \/>\nAlgumas redes p\u00fablicas j\u00e1 anunciaram que juntar\u00e3o os dois anos letivos, como forma de n\u00e3o penalizar estudantes que n\u00e3o puderam acompanhar o ensino online. Uma delas \u00e9 a rede estadual de S\u00e3o Paulo, que ontem abriu matr\u00edculas para um novo 4\u00ba ano do ensino m\u00e9dio para os alunos que quiserem continuar estudando em 2021.<br \/>\nA Lei 14.040\/2020 previu que o CNE deveria dar as diretrizes para os estabelecimentos de ensino durante o \u201cestado de calamidade p\u00fablica\u201d causado pela pandemia da Covid-19. Ao ser aprovada, ser\u00e1 a mais importante resolu\u00e7\u00e3o nacional sobre o assunto, j\u00e1 que o MEC n\u00e3o se posicionou oficialmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Joc\u00e9lio Tavares. Na noite da \u00faltima ter\u00e7a-feira (06\/10), o Conselho Nacional de Educa\u00e7\u00e3o (CNE)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/65bjr291eim63vboalskfzqb8.jpg","jetpack-related-posts":[{"id":11652,"url":"https:\/\/correiodasemana.com\/site\/camara-aprova-mp-que-suspende-numero-minimo-de-dias-letivos\/","url_meta":{"origin":14009,"position":0},"title":"C\u00e2mara aprova MP que suspende n\u00famero m\u00ednimo de dias letivos","author":"","date":"Julho 8, 2020","format":false,"excerpt":"Por\u00a0Congresso Em Foco\u00a0Em\u00a007 jul, 2020 - 18:32\u00a0\u00daltima Atualiza\u00e7\u00e3o\u00a007 jul, 2020 - 18:33 \u00a0 \u00a0 A C\u00e2mara concluiu nesta ter\u00e7a-feira (7) a vota\u00e7\u00e3o da medida provis\u00f3ria\u00a0(MP 934\/2020), que prev\u00ea a flexibiliza\u00e7\u00e3o dos dias letivos por causa dos efeitos da pandemia de covid-19. O texto-base j\u00e1 havia sido aprovado semana passada. Hoje\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/escola-ebc-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/escola-ebc-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/escola-ebc-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14986,"url":"https:\/\/correiodasemana.com\/site\/mec-autoriza-aulas-nao-presenciais-ate-dezembro-de-2021\/","url_meta":{"origin":14009,"position":1},"title":"MEC autoriza aulas n\u00e3o presenciais at\u00e9 dezembro de 2021","author":"","date":"Dezembro 14, 2020","format":false,"excerpt":"Ministro homologou parecer do Conselho Nacional de Educa\u00e7\u00e3o O ministro da Educa\u00e7\u00e3o, Milton Ribeiro, homologou o Parecer n\u00ba 19, do Conselho Nacional de Educa\u00e7\u00e3o (CNE), que estende at\u00e9 31 de dezembro de 2021 a permiss\u00e3o para atividades remotas no ensino b\u00e1sico e superior em todo o pa\u00eds. A valida\u00e7\u00e3o da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/2020-10-07t133205z_9098542_rc2pdj9kebuw_rtrmadp_3_health-coronavirus-brazil.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/2020-10-07t133205z_9098542_rc2pdj9kebuw_rtrmadp_3_health-coronavirus-brazil.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/2020-10-07t133205z_9098542_rc2pdj9kebuw_rtrmadp_3_health-coronavirus-brazil.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/2020-10-07t133205z_9098542_rc2pdj9kebuw_rtrmadp_3_health-coronavirus-brazil.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/2020-10-07t133205z_9098542_rc2pdj9kebuw_rtrmadp_3_health-coronavirus-brazil.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14229,"url":"https:\/\/correiodasemana.com\/site\/uva-divulga-novo-calendario-letivo-2020-1-em-regime-de-atividades-pedagogicas-0n-line\/","url_meta":{"origin":14009,"position":2},"title":"UVA divulga novo Calend\u00e1rio Letivo 2020.1 em regime de atividades pedag\u00f3gicas 0n-line","author":"","date":"Outubro 25, 2020","format":false,"excerpt":"Reinicio do semestre ser\u00e1 em 3 de novembro A Pr\u00f3-Reitoria de Ensino de Gradua\u00e7\u00e3o da Universidade Estadual Vale do Acara\u00fa (PROGRAD\/UVA) divulgou na ter\u00e7a-feira, 20 de outubro de 2020, o novo Calend\u00e1rio Letivo para o Semestre 2020.1, interrompido em decorr\u00eancia da pandemia do novo coronav\u00edrus (COVID-19), em mar\u00e7o desse ano.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/UVA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/UVA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/UVA.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12989,"url":"https:\/\/correiodasemana.com\/site\/lei-que-flexibiliza-ano-letivo-e-publicada-com-vetos\/","url_meta":{"origin":14009,"position":3},"title":"Lei que flexibiliza ano letivo \u00e9 publicada com vetos","author":"","date":"Agosto 19, 2020","format":false,"excerpt":"Os vetos ser\u00e3o analisados pelos parlamentares A Lei n\u00ba 14.040\/2020 foi publicada hoje (19) no\u00a0Di\u00e1rio Oficial da Uni\u00e3o\u00a0(DOU) com seis vetos. A medida desobriga as escolas de educa\u00e7\u00e3o b\u00e1sica e as universidades de cumprirem a quantidade m\u00ednima de dias letivos neste ano, em raz\u00e3o da pandemia da covid-19. O texto,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/ensino_medio.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/ensino_medio.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/ensino_medio.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/ensino_medio.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/ensino_medio.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14504,"url":"https:\/\/correiodasemana.com\/site\/sobral-suspende-aulas-presenciais-ate-2021-na-rede-publica-e-privada\/","url_meta":{"origin":14009,"position":4},"title":"Sobral suspende aulas presenciais at\u00e9 2021 na rede p\u00fablica e privada","author":"","date":"Novembro 12, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. O retorno para as atividades letivas presenciais demandar\u00e1 mais tempo de espera aos alunos do munic\u00edpio de Sobral, localizado na Regi\u00e3o Norte do Estado. A decis\u00e3o publicada no Di\u00e1rio Oficial do Munic\u00edpio (DOM), no final de outubro, prorroga a suspens\u00e3o das aulas presenciais da rede p\u00fablica e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/image.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/image.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/image.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/image.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14956,"url":"https:\/\/correiodasemana.com\/site\/mec-determina-volta-as-aulas-presenciais-do-ensino-superior-a-partir-de-janeiro\/","url_meta":{"origin":14009,"position":5},"title":"MEC determina volta as aulas presenciais do ensino superior a partir de janeiro","author":"","date":"Dezembro 7, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. O Di\u00e1rio Oficial da Uni\u00e3o publica, na \u00faltima quarta-feira, (02\/12), portaria do Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), determinando que institui\u00e7\u00f5es federais de ensino superior voltem \u00e0s aulas presenciais, a partir de 4 de janeiro de 2021. Para isso, as institui\u00e7\u00f5es devem adotar um \u201cprotocolo de biosseguran\u00e7a\u201d, definido na\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14009"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14009\/revisions"}],"predecessor-version":[{"id":14011,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14009\/revisions\/14011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14010"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}