{"id":14071,"date":"2020-10-14T09:56:34","date_gmt":"2020-10-14T12:56:34","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14071"},"modified":"2020-10-14T09:56:34","modified_gmt":"2020-10-14T12:56:34","slug":"cnbb-68-anos-a-atual-presidencia-reflete-a-instituicao-entre-o-seu-passado-e-futuro","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/cnbb-68-anos-a-atual-presidencia-reflete-a-instituicao-entre-o-seu-passado-e-futuro\/","title":{"rendered":"CNBB 68 ANOS: A ATUAL PRESID\u00caNCIA REFLETE A INSTITUI\u00c7\u00c3O ENTRE O SEU PASSADO E FUTURO"},"content":{"rendered":"<p><em>Para celebrar o anivers\u00e1rio de 68 da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), neste dia 14 de outubro, os quatro bispos que integram a atual presid\u00eancia foram provocados a destacar os marcos do passado e do presente da institui\u00e7\u00e3o, bem como lan\u00e7ar um olhar sobre o seu futuro. Eleitos na 67\u00aa assembleia do episcopado brasileiro, realizada de 1\u00ba a 10 de maio de 2019, em Aparecida (SP), eles completaram o primeiro ano de mandato (2019 a 2023), marcado principalmente pelo contexto da pandemia, sem contudo deixar de compreender e dar respostas aos desafios da Igreja no Brasil. Neste caminho mission\u00e1rio da Confer\u00eancia Nacional dos Bispos do Brasil rumo aos seus 70 anos, o portal da CNBB faz essa pausa de reflex\u00e3o com a presid\u00eancia da entidade para perceber sua hist\u00f3ria, identidade e\u00a0 suas perspectivas futuras.\u00a0<\/em><\/p>\n<h3><strong>Pioneirismo, profecia e comunh\u00e3o: marcas da hist\u00f3ria da CNBB<\/strong><\/h3>\n<p>O arcebispo de Belo Horizonte (MG) e\u00a0<strong>presidente da CNBB, dom Walmor Oliveira de Azevedo<\/strong>, refor\u00e7a que a CNBB tem uma marcante trajet\u00f3ria de contribui\u00e7\u00f5es para a vida da Igreja e para a sociedade brasileira, com relevantes e insubstitu\u00edveis contribui\u00e7\u00f5es espirituais, human\u00edsticas e cidad\u00e3s.<\/p>\n<p>\u201c\u00c9 importante recordar o m\u00eas de outubro de 1952, quando bispos brasileiros se reuniram, no Rio de Janeiro, e, em profunda comunh\u00e3o eclesial com a S\u00e9 Apost\u00f3lica, iniciaram a rica hist\u00f3ria da CNBB. Um caminho bonito que se renova permanentemente e fortalece ainda mais a colegialidade e a unidade dos bispos brasileiros, em comunh\u00e3o com o magist\u00e9rio do Papa\u201d, disse do Walmor.<\/p>\n<p>O Brasil, quando surgiu a ideia de cria\u00e7\u00e3o das confer\u00eancias episcopais, foi um dos primeiros pa\u00edses que se prontificou a encaminhar junto \u00e0 Santa S\u00e9 o que fosse necess\u00e1rio para cria\u00e7\u00e3o da confer\u00eancia lembrou o arcebispo de Porto Alegre e\u00a0<strong>primeiro vice-presidente da entidade, dom Jaime Spengler.<\/strong><\/p>\n<blockquote><p>\u201cN\u00f3s tivemos v\u00e1rias figuras que foram protagonistas deste processo. E certamente aquilo que hoje a Confer\u00eancia representa para\u00a0 a sociedade brasileira \u00e9 fruto do trabalho destes homens pioneiros que h\u00e1 68 anos acreditaram na proposta como um caminho vi\u00e1vel para a maior comunh\u00e3o entre os bispos do Brasil\u201d, destacou.<\/p><\/blockquote>\n<p>Um marco do passado, destacado pelo bispo de Roraima e<strong>\u00a0segundo vice-presidente da CNBB, dom M\u00e1rio Ant\u00f4nio da Silva,<\/strong>\u00a0\u00e9 a caracter\u00edstica de ter sido prof\u00e9tica, com muita sabedoria e zelo pela mensagem do Evangelho. \u201cA CNBB exerceu, desde o seu in\u00edcio, e continua exercendo, um profetismo na defesa da vida em toda e qualquer circunst\u00e2ncia, do ser humano e de toda a cria\u00e7\u00e3o\u201d, afirmou.<\/p>\n<p>O bispo auxiliar do Rio de Janeiro (RJ) e\u00a0<strong>secret\u00e1rio-geral da CNBB, dom Joel Portella Amado<\/strong>, destaca o primeiro planejamento pastoral conjunto da Confer\u00eancia realizado, ainda em Roma, durante o Conc\u00edlio, por convoca\u00e7\u00e3o do Papa Jo\u00e3o XXIII. Neste momento, lembra dom Joel, foi constru\u00eddo o Plano de Emerg\u00eancia. \u201cEm 1966, bem no per\u00edodo de implanta\u00e7\u00e3o do Conc\u00edlio, os bispos brasileiros estabeleceram\u00a0<strong>o primeiro Plano de Pastoral de Conjunto<\/strong>. Desde ent\u00e3o, a CNBB tem sido instrumento de unidade pastoral em torno aos grandes desafios pastorais. Isso se concretiza nas Diretrizes Gerais da A\u00e7\u00e3o Evangelizadora da Igreja (DGAE)\u201d, refor\u00e7a.<\/p>\n<p>O secret\u00e1rio-geral tamb\u00e9m recorda-se n\u00e3o de um fato mas de uma atitude que marcou a trajet\u00f3ria da organiza\u00e7\u00e3o: a da defesa da verdade, da justi\u00e7a e dos fragilizados. Segundo ele, de modo especial a partir da d\u00e9cada de 1970, a CNBB, por meio de suas presid\u00eancias, manifestou-se in\u00fameras vezes de modo firme em favor dos direitos humanos e da democracia. Em 1988, na \u00e9poca da Constituinte, foi publicado o documento\u00a0<strong>\u201c<\/strong><em><strong>Por uma nova ordem constitucional<\/strong>\u201c<\/em>. Pouco tempo depois, em 1989, foi publicado outro documento importante para aquele momento e que se tornou bastante conhecido:\u00a0<strong>\u201c<em>Exig\u00eancias crist\u00e3s da ordem democr\u00e1tica\u201d<\/em>.<\/strong><\/p>\n<h4><strong>No presente, alimentando a esperan\u00e7a e a solidariedade<\/strong><\/h4>\n<p>O presidente da CNBB, dom Walmor Oliveira, diz que a Confer\u00eancia persevera, no dias atuais, em sua miss\u00e3o de anunciar o Evangelho, a servi\u00e7o da unidade da Igreja, da edifica\u00e7\u00e3o do Reino de Deus, com a\u00e7\u00f5es que promovem o amparo aos mais pobres, a inclus\u00e3o social e, consequentemente, contribuem para a justi\u00e7a e a paz.<\/p>\n<p>Entre estas a\u00e7\u00f5es, o segundo vice-presidente da entidade, dom Jaime Spengler, destaca o processo atual de\u00a0<strong>revis\u00e3o do Estatuto Can\u00f4nico<\/strong>, no qual todos os bispos do Brasil s\u00e3o chamados a participar e cooperar para responder aos desafios atuais. \u201cOs tempos mudaram e mudam constantemente e estar atento aos sinais dos tempos diz de uma sensibilidade especial para responder \u00e0 altura daquilo que os novos sinais pedem de n\u00f3s como Igreja no Brasil\u201d.<\/p>\n<p>Dom Jaime destacou tamb\u00e9m o\u00a0<strong>Pacto pela Vida e Pelo Brasil<\/strong>, assinado em abril deste ano pela Confer\u00eancia junto \u00e0 outras institui\u00e7\u00f5es brasileiras, com o intuito de promover um debate e di\u00e1logo, o mais amplo poss\u00edvel com as for\u00e7as da sociedade, a partir da premissa de que o pa\u00eds pode se tornar mais integrado e mais integrador, onde todos possam ter vida e vida em abund\u00e2ncia. \u201cO Pacto representa um marco no presente da Institui\u00e7\u00e3o e fala da disponibilidade da Igreja em cooperar com o momento que o pa\u00eds atravessa\u201d, disse.<\/p>\n<p>O segundo vice-presidente, dom M\u00e1rio Ant\u00f4nio, destaca a realiza\u00e7\u00e3o pela CNBB e C\u00e1ritas Brasileira da\u00a0<strong>A\u00e7\u00e3o Solid\u00e1ria Emergencial \u201c\u00c9 Tempo de Cuidar\u201d<\/strong>, com a ades\u00e3o de toda a Igreja Cat\u00f3lica no Brasil e entidades e institui\u00e7\u00f5es que buscam promover a vida, sobretudo no contexto da pandemia. Para ele, a solidariedade marca\u00a0 o trabalho da CNBB na atualidade.<\/p>\n<p>O secret\u00e1rio-geral da entidade destacou um desafio interno:\u00a0 a implanta\u00e7\u00e3o e manuten\u00e7\u00e3o das comunidades eclesiais mission\u00e1rias, conforme apresentado nas atuais DGAE (2019-2023). \u201c\u00c9 um tema que j\u00e1 vinha sendo amadurecido. Lembro, por exemplo, os documentos 100 e 108 da CNBB que falam respectivamente da rede de comunidades e dos servi\u00e7os e minist\u00e9rios em torno da Palavra de Deus\u201d, recordou.<\/p>\n<p>Dom Joel tamb\u00e9m destaca a a\u00e7\u00e3o emergencial \u201c\u00c9 tempo de Cuidar\u201d e o esfor\u00e7o por ajudar a alimentar a esperan\u00e7a, a justi\u00e7a e a paz, em meio a tantas ang\u00fastias e pandemias. \u201cVemos as pessoas sofrerem pela pandemia sanit\u00e1ria, mas tamb\u00e9m, para dar um exemplo significativo, com a fome. A campanha \u00c9 tempo de Cuidar \u00e9 um fato muito significativo dos dias atuais\u201d, disse.<\/p>\n<h1><strong>Novos desafios rumo \u00e0 maior sinodalidade e comunh\u00e3o<\/strong><\/h1>\n<p>Para permanecer fiel ao sonho dos que a fundaram, dom Walmor afirma que a CNBB est\u00e1 vivendo um processo de renova\u00e7\u00e3o, buscando responder aos desafios pr\u00f3prios deste terceiro mil\u00eanio. Ele apontou a\u00a0revis\u00e3o do Estatuto Can\u00f4nico como um caminho que possibilitar\u00e1 \u00e0 Confer\u00eancia ser ainda melhor e mais servidora, oferecendo novas contribui\u00e7\u00f5es para que o Brasil, \u00e0 luz da f\u00e9, torne-se mais fraterno e solid\u00e1rio.<\/p>\n<blockquote><p>\u201cAs novas respostas incluem a exig\u00eancia de sermos uma Igreja Sinodal e mais mission\u00e1ria, com efetivas e inclusivas participa\u00e7\u00f5es dos crist\u00e3os leigos e leigas, especialmente das mulheres\u201d, disse.<\/p><\/blockquote>\n<p>Em sua vis\u00e3o de futuro para a entidade, o primeiro vice-presidente, dom Jaime Spengler , alimenta o desejo de que ela esteja ancorada nos valores que formaram sua identidade: \u201cSer uma inst\u00e2ncia de promo\u00e7\u00e3o\u00a0 da comunh\u00e3o na Igreja no Brasil. Uma Igreja realmente constitu\u00edda de comunidades que se disp\u00f5em, na comunh\u00e3o, a cooperar para a implementa\u00e7\u00e3o do Reino de Deus j\u00e1 aqui entre n\u00f3s no tempo\u201d, disse.<\/p>\n<p>Numa perspectiva de renova\u00e7\u00e3o, dom M\u00e1rio Ant\u00f4nio, seu segundo vice-presidente, v\u00ea a CNBB atuando mais em rede junto \u00e0 outras entidades e institui\u00e7\u00f5es com objetivos semelhantes, sem contudo perder a sua identidade e a sua miss\u00e3o. \u201cO futuro da CNBB est\u00e1 tamb\u00e9m em evangelizar fazendo bom uso de toda a tecnologia digital, o que exige de n\u00f3s um preparo espec\u00edfico\u201d, desafiou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para celebrar o anivers\u00e1rio de 68 da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), neste&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Presidencia-da-CNBB-owvum80xl84ugjzhi2z7kkg8jajwtwf5cla6ohu454.jpg","jetpack-related-posts":[{"id":24373,"url":"https:\/\/correiodasemana.com\/site\/60a-assembleia-geral-presidencia-da-cnbb-nacional-tem-nova-presidencia-e-referenciais-para-as-comissoes-episcopais\/","url_meta":{"origin":14071,"position":0},"title":"60\u00aa Assembleia Geral: Presid\u00eancia da CNBB Nacional tem nova presid\u00eancia e referenciais para as Comiss\u00f5es Episcopais","author":"adminredacao","date":"Maio 1, 2023","format":false,"excerpt":"Durante a \u00faltima semana do m\u00eas de abril deste ano em curso, o episcopado brasileiro elegeu a nova presid\u00eancia da CNBB bem como dos bispos referenciais para as comiss\u00f5es episcopais durante a 60\u00aa Assembleia Geral em Aparecida\/SP. O arcebispo de Porto Alegre (RS) e atual primeiro vice-presidente da Confer\u00eancia Nacional\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/Vi-Holzbach-11-1600x914-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/Vi-Holzbach-11-1600x914-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/Vi-Holzbach-11-1600x914-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/Vi-Holzbach-11-1600x914-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/Vi-Holzbach-11-1600x914-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/Vi-Holzbach-11-1600x914-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24248,"url":"https:\/\/correiodasemana.com\/site\/o-papa-reza-por-este-importante-momento-de-encontro-e-unidade-dos-bispos-do-brasil-diz-nuncio-na-abertura-da-60a-ag-cnbb\/","url_meta":{"origin":14071,"position":1},"title":"\u201cO PAPA REZA POR ESTE IMPORTANTE MOMENTO DE ENCONTRO E UNIDADE DOS BISPOS DO BRASIL\u201d, DIZ N\u00daNCIO NA ABERTURA DA 60\u00aa AG CNBB","author":"adminredacao","date":"Abril 24, 2023","format":false,"excerpt":"\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Teve in\u00edcio nesta manh\u00e3, 19 de abril, a 60\u00aa Assembleia Geral da Confer\u00eancia Nacional dos Bispos do Brasil (AG CNBB), no Centro de Eventos Pe. V\u00edtor Coelho de Almeida, em Aparecida (SP). Est\u00e1 reunida, at\u00e9 o dia 28\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-21-at-15.53.36.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-21-at-15.53.36.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-21-at-15.53.36.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-21-at-15.53.36.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24145,"url":"https:\/\/correiodasemana.com\/site\/comeca-nesta-quarta-feira-19-em-aparecida-a-60a-assembleia-geral-dos-bispos-do-brasil\/","url_meta":{"origin":14071,"position":2},"title":"60\u00aa Assembl\u00e9ia Geral dos bispos do Brasil","author":"","date":"Abril 19, 2023","format":false,"excerpt":"Tem in\u00edcio nesta quarta-feira, dia 19 de abril e se conclui no pr\u00f3ximo dia 28 a 60\u00aa Assembleia Geral da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB). O encontro do episcopado brasileiro se realiza, como todos os anos, no Santu\u00e1rio Nacional de Nossa Senhora Aparecida, em Aparecida (SP). O tema\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Celebracao-de-abertura-da-59a-AG-CNBB-1280x640-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Celebracao-de-abertura-da-59a-AG-CNBB-1280x640-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Celebracao-de-abertura-da-59a-AG-CNBB-1280x640-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Celebracao-de-abertura-da-59a-AG-CNBB-1280x640-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Celebracao-de-abertura-da-59a-AG-CNBB-1280x640-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":38304,"url":"https:\/\/correiodasemana.com\/site\/cnbb-em-assembleia\/","url_meta":{"origin":14071,"position":3},"title":"CNBB em assembleia","author":"adminredacao","date":"Maio 12, 2026","format":false,"excerpt":"No dia 15 de abril, abre-se a 62\u00aa Assembleia Geral anual da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), \u201cinstitui\u00e7\u00e3o permanente que congrega os bispos da Igreja Cat\u00f3lica Apost\u00f3lica Romana do Brasil, na qual exercem conjuntamente algumas fun\u00e7\u00f5es pastorais em favor dos fi\u00e9is\u201d presentes em todo o Pa\u00eds (Estatuto, Art.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29033,"url":"https:\/\/correiodasemana.com\/site\/assembleia-geral-da-cnbb-conclui-com-celebracao-e-consagracao-a-padroeira-do-brasil\/","url_meta":{"origin":14071,"position":4},"title":"ASSEMBLEIA GERAL DA CNBB CONCLUI COM CELEBRA\u00c7\u00c3O E CONSAGRA\u00c7\u00c3O \u00c0 PADROEIRA DO BRASIL","author":"adminredacao","date":"Abril 22, 2024","format":false,"excerpt":"Fonte: CNBB A 61\u00aa Assembleia Geral da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB) foi encerrada na sexta-feira, 19 de abril de 2024, com a Celebra\u00e7\u00e3o Eucar\u00edstica realizada no Santu\u00e1rio Nacional de Nossa Senhora Aparecida. A cerim\u00f4nia com Laudes foi presidida pelo arcebispo de Porto Alegre (RS) e presidente da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Bispo-de-Sobral-presente-na-61a-Assembleia-Geral-dos-Bispos-do-Brasil.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Bispo-de-Sobral-presente-na-61a-Assembleia-Geral-dos-Bispos-do-Brasil.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Bispo-de-Sobral-presente-na-61a-Assembleia-Geral-dos-Bispos-do-Brasil.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Bispo-de-Sobral-presente-na-61a-Assembleia-Geral-dos-Bispos-do-Brasil.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Bispo-de-Sobral-presente-na-61a-Assembleia-Geral-dos-Bispos-do-Brasil.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Bispo-de-Sobral-presente-na-61a-Assembleia-Geral-dos-Bispos-do-Brasil.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24365,"url":"https:\/\/correiodasemana.com\/site\/assembleia-geral-da-cnbb\/","url_meta":{"origin":14071,"position":5},"title":"Assembleia Geral da CNBB","author":"adminredacao","date":"Maio 1, 2023","format":false,"excerpt":"Entre os dias 19 e 28 de abril, os bispos de todo o Brasil estiveram reunidos na 60\u00aa Assembleia Geral da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB). O evento acontece todos os anos e busca atualizar os desafios e perspectivas da caminhada eclesial em nosso pa\u00eds. A assembleia dos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14071"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14071\/revisions"}],"predecessor-version":[{"id":14074,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14071\/revisions\/14074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14072"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}