{"id":14080,"date":"2020-10-14T10:35:42","date_gmt":"2020-10-14T13:35:42","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14080"},"modified":"2020-10-14T10:36:19","modified_gmt":"2020-10-14T13:36:19","slug":"programa-que-permite-reducao-de-jornada-e-salario-e-prorrogado-ate-dezembro","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/programa-que-permite-reducao-de-jornada-e-salario-e-prorrogado-ate-dezembro\/","title":{"rendered":"Programa que permite redu\u00e7\u00e3o de jornada e sal\u00e1rio \u00e9 prorrogado at\u00e9 dezembro"},"content":{"rendered":"<p align=\"justify\"><span style=\"color: #222222;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\">O <\/span><\/span><\/span><a href=\"https:\/\/congressoemfoco.uol.com.br\/saude\/fas-de-bolsonaro-sabem-menos-sobre-covid-e-resistem-mais-a-vacina-revela-pesquisa\/\"><span style=\"color: #0080ce;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\"><b><strong>presidente Jair Bolsonaro<\/strong><\/b><\/span><\/span><\/span><\/a><span style=\"color: #222222;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\">\u00a0prorrogou por 60 dias o programa que autoriza empresas a reduzirem proporcionalmente, ou suspenderem, a jornada e o sal\u00e1rio dos funcion\u00e1rios. O decreto vale at\u00e9 31 de dezembro, data prevista para acabar o estado de calamidade p\u00fablica em raz\u00e3o da pandemia.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222;\">\u201c<\/span><span style=\"color: #222222;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\">Diante do cen\u00e1rio atual de crise social e econ\u00f4mica, e com a perman\u00eancia de medidas restritivas de isolamento social, faz-se necess\u00e1ria a prorroga\u00e7\u00e3o, mais uma vez, do prazo m\u00e1ximo de validade dos acordos. Essa a\u00e7\u00e3o ir\u00e1 permitir que empresas que est\u00e3o em situa\u00e7\u00e3o de vulnerabilidade possam continuar sobrevivendo a este per\u00edodo e, desta forma, preservar postos de trabalho e projetar uma melhor recupera\u00e7\u00e3o econ\u00f4mica\u201d, diz nota divulgada pelo Pal\u00e1cio do Planalto a respeito da decis\u00e3o do governo.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\">O Benef\u00edcio Emergencial de Preserva\u00e7\u00e3o do Emprego e da Renda (BEM) foi criado por medida provis\u00f3ria em abril e <\/span><\/span><\/span><a href=\"https:\/\/congressoemfoco.uol.com.br\/economia\/governo-amplia-prazo-para-suspensao-de-contrato-e-reducao-de-salario-veja-decreto\/\"><span style=\"color: #0080ce;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\"><b><strong>j\u00e1 havia sido prorrogado duas vezes<\/strong><\/b><\/span><\/span><\/span><\/a><span style=\"color: #222222;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\">. De acordo com a lei origin\u00e1ria da MP, o valor da compensa\u00e7\u00e3o equivale a um percentual do que o funcion\u00e1rio receberia de seguro-desemprego. O programa atende a trabalhadores que tiveram redu\u00e7\u00e3o de sal\u00e1rio e da jornada de trabalho ou a suspens\u00e3o do contrato.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: large;\"><span style=\"color: #222222;\">Nesses casos, o empregador \u00e9 obrigado a garantir o emprego do funcion\u00e1rio por per\u00edodo igual ao da redu\u00e7\u00e3o salarial ou suspens\u00e3o do contrato. Se forem cinco meses de suspens\u00e3o de contrato ou redu\u00e7\u00e3o da jornada, por exemplo, o trabalhador n\u00e3o poder\u00e1 ser demitido pelos cinco meses seguintes. Caso a regra n\u00e3o seja respeitada, o empregador ter\u00e1 de indenizar o funcion\u00e1rio.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #3a3a3a;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: medium;\"><a href=\"https:\/\/congressoemfoco.uol.com.br\/author\/edson\/\">Por <\/a><\/span><\/span><\/span><span style=\"color: #4d4d4d;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: medium;\"><b>Edson Sardinha<\/b><\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #4d4d4d;\"><span style=\"font-family: Merriweather;\"><span style=\"font-size: medium;\"><b>Ag\u00eancia Congresso em Foco.<\/b><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro\u00a0prorrogou por 60 dias o programa que autoriza empresas a reduzirem proporcionalmente,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/16_07_2020_movimentacao_sp-750x430-1.jpg","jetpack-related-posts":[{"id":14414,"url":"https:\/\/correiodasemana.com\/site\/antecipacao-do-auxilio-doenca-sera-limitada-ate-31-de-dezembro\/","url_meta":{"origin":14080,"position":0},"title":"Antecipa\u00e7\u00e3o do aux\u00edlio-doen\u00e7a ser\u00e1 limitada at\u00e9 31 de dezembro","author":"","date":"Novembro 3, 2020","format":false,"excerpt":"Regulamenta\u00e7\u00e3o saiu no Di\u00e1rio Oficial de hoje A antecipa\u00e7\u00e3o do aux\u00edlio-doen\u00e7a, adotada pelo governo durante a pandemia de covid-19, ser\u00e1 paga aos benefici\u00e1rios pelo per\u00edodo definido no atestado m\u00e9dico, limitado a at\u00e9 60 dias, mas n\u00e3o poder\u00e1 exceder o dia 31 de dezembro, quando terminam os efeitos do decreto de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/mc_previdencia_socialsantos_fc2108200888.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/mc_previdencia_socialsantos_fc2108200888.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/mc_previdencia_socialsantos_fc2108200888.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/mc_previdencia_socialsantos_fc2108200888.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/mc_previdencia_socialsantos_fc2108200888.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":36516,"url":"https:\/\/correiodasemana.com\/site\/prefeitura-de-sobral-prorroga-prazo-de-adesao-ao-refis-2025\/","url_meta":{"origin":14080,"position":1},"title":"Prefeitura de Sobral prorroga prazo de ades\u00e3o ao REFIS 2025","author":"adminredacao","date":"Novembro 25, 2025","format":false,"excerpt":"A Prefeitura de Sobral prorrogou, na quarta-feira (19), o prazo para ades\u00e3o ao Programa de Refinanciamento Fiscal (REFIS) 2025. Antes previsto para encerrar em 22 de novembro, o\u00a0per\u00edodo agora seguir\u00e1 at\u00e9 o dia 23 de dezembro, conforme a\u00a0Lei n\u00ba 97 de 19 de novembro de 2025, ampliando a oportunidade para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/REFIS-ITINERANRE-vs5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/REFIS-ITINERANRE-vs5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/REFIS-ITINERANRE-vs5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/REFIS-ITINERANRE-vs5.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/REFIS-ITINERANRE-vs5.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":11832,"url":"https:\/\/correiodasemana.com\/site\/programa-de-suspensao-de-contrato-e-reducao-de-jornada-sera-estendido\/","url_meta":{"origin":14080,"position":2},"title":"Programa de suspens\u00e3o de contrato e redu\u00e7\u00e3o de jornada ser\u00e1 estendido","author":"","date":"Julho 14, 2020","format":false,"excerpt":"ECONOMIA Prorroga\u00e7\u00e3o ser\u00e1 feita por decreto presidencial O programa que prev\u00ea a suspens\u00e3o de contrato de trabalho ou a redu\u00e7\u00e3o de jornada em troca da manuten\u00e7\u00e3o do emprego ser\u00e1 prorrogado, de acordo com o secret\u00e1rio especial de Previd\u00eancia e Trabalho, Bruno Bianco. Segundo o governo, o Benef\u00edcio Emergencial (BEm) preservou\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/pzzb1189.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/pzzb1189.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/pzzb1189.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/pzzb1189.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/pzzb1189.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12248,"url":"https:\/\/correiodasemana.com\/site\/sem-desoneracao-da-folha-ate-2021-servicos-de-transporte-publico-podem-ser-paralisados\/","url_meta":{"origin":14080,"position":3},"title":"Sem desonera\u00e7\u00e3o da folha at\u00e9 2021, servi\u00e7os de transporte p\u00fablico podem ser paralisados","author":"","date":"Julho 27, 2020","format":false,"excerpt":"Associa\u00e7\u00e3o que representa empresas de \u00f4nibus alerta que fim do incentivo em dezembro coloca em risco 405 mil empregos e pode levar sistema ao colapso Se a desonera\u00e7\u00e3o da folha de pagamento n\u00e3o for prorrogada at\u00e9 2021, o servi\u00e7o de transporte p\u00fablico no pa\u00eds pode ser totalmente paralisado. Esse risco\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/TRansporte-p%C3%BAblico-696x392-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/TRansporte-p%C3%BAblico-696x392-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/TRansporte-p%C3%BAblico-696x392-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":25541,"url":"https:\/\/correiodasemana.com\/site\/sem-vendas-renault-interrompe-producao-e-suspende-funcionarios-por-ate-3-meses\/","url_meta":{"origin":14080,"position":4},"title":"Sem vendas, Renault interrompe produ\u00e7\u00e3o e suspende funcion\u00e1rios por at\u00e9 3 meses","author":"","date":"Julho 6, 2023","format":false,"excerpt":"A f\u00e1brica da Renault em S\u00e3o Jos\u00e9 dos Pinhais, no Paran\u00e1, adotou o modelo de suspens\u00e3o tempor\u00e1ria de contrato ou redu\u00e7\u00e3o de jornada conhecido como \u201clayoff\u201d e suspendeu os contratos de cerca de 1.000 profissionais. A medida entrou em vigor na segunda-feira, dia 3, na f\u00e1brica de ve\u00edculos de passeio,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-10.58.42-850x560-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-10.58.42-850x560-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-10.58.42-850x560-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-10.58.42-850x560-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13129,"url":"https:\/\/correiodasemana.com\/site\/governo-quer-lancar-novo-minha-casa-minha-vida-e-pro-brasil-na-terca\/","url_meta":{"origin":14080,"position":5},"title":"Governo quer lan\u00e7ar novo Minha Casa Minha Vida e Pr\u00f3-Brasil na ter\u00e7a","author":"","date":"Agosto 24, 2020","format":false,"excerpt":"O governo federal promete para a ter\u00e7a-feira (25) o lan\u00e7amento de v\u00e1rias iniciativas de emprego e renda. O ministro da Economia, Paulo Guedes, faz nesta segunda-feira (24) diversas reuni\u00f5es com secret\u00e1rios e com o presidente Jair Bolsonaro para fechar os detalhes das iniciativas. Est\u00e1 previsto o lan\u00e7amento oficial de v\u00e1rios\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-24-at-12.59.40.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-24-at-12.59.40.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-24-at-12.59.40.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14080"}],"version-history":[{"count":3,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14080\/revisions"}],"predecessor-version":[{"id":14084,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14080\/revisions\/14084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14081"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}