{"id":14090,"date":"2020-10-14T15:19:04","date_gmt":"2020-10-14T18:19:04","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14090"},"modified":"2020-10-14T15:19:04","modified_gmt":"2020-10-14T18:19:04","slug":"idosos-do-abrigo-sagrado-coracao-de-jesus-em-sobral-realizam-ensaio-fotografico","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/idosos-do-abrigo-sagrado-coracao-de-jesus-em-sobral-realizam-ensaio-fotografico\/","title":{"rendered":"Idosos do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus em Sobral realizam ensaio fotogr\u00e1fico"},"content":{"rendered":"<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Levando alegria e descontra\u00e7\u00e3o aos 33 idosos acolhidos, uma decora\u00e7\u00e3o de conto de fadas foi organizada na ter\u00e7a-feira (29\/09) no Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, unidade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral. Com roupas especiais, os idosos participaram de um lindo ensaio fotogr\u00e1fico. A\u00e7\u00e3o fez parte da programa\u00e7\u00e3o da Semana do Idoso, comemorada neste ano de forma interna devido \u00e0 pandemia de Covid-19.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-14092\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-scaled.jpg 2560w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-1024x683.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-1536x1024.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-2048x1365.jpg 2048w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-3-1-675x450.jpg 675w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">De acordo com a diretora do Abrigo, Maria Eliane de Oliveira, o ensaio foi pensado com muito carinho como uma a\u00e7\u00e3o diferenciada para a Semana do Idoso deste ano:\u00a0\u201c<i>Todos os anos realizamos uma semana cheia de atividades, com a presen\u00e7a do p\u00fablico-externo. Devido \u00e0 pandemia, neste ano organizamos momentos especiais internamente, tomando todas as medidas de seguran\u00e7a contra a Covid-19\u201d, ressalta.<\/i><\/span><\/span><\/span><\/p>\n<p align=\"justify\"><img decoding=\"async\" class=\"alignleft size-full wp-image-14093\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-scaled.jpg 2560w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-1024x683.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-1536x1024.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-2048x1365.jpg 2048w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-4-675x450.jpg 675w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Todos os idosos foram vestidos com roupas especiais e maquiados pelos pr\u00f3prios profissionais da institui\u00e7\u00e3o.\u00a0\u201c<i>Foi um dia de beleza e divers\u00e3o para nossos acolhidos e tamb\u00e9m para nossos profissionais. Ver a emo\u00e7\u00e3o e satisfa\u00e7\u00e3o no rosto de cada um faz toda a diferen\u00e7a. E o resultado foi lindo.\u201d<\/i>, enfatiza a diretora.\u00a0<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #999999;\"><span style=\"font-family: arial, sans-serif;\"><span style=\"font-size: small;\">Santa Casa de Miseric\u00f3rdia de Sobral<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #999999;\"><span style=\"font-family: arial, sans-serif;\"><span style=\"font-size: small;\">Assessoria de Comunica\u00e7\u00e3o<\/span><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: arial, sans-serif;\"><span style=\"font-size: small;\"><b>Thais Menezes\/ Henrique Brito\/ Domingos Jr.<\/b><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Levando alegria e descontra\u00e7\u00e3o aos 33 idosos acolhidos, uma decora\u00e7\u00e3o de conto de fadas foi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Ensaio-1-1-scaled.jpg","jetpack-related-posts":[{"id":13884,"url":"https:\/\/correiodasemana.com\/site\/aniversario-arteterapia-massagens-e-ensaio-fotografico-marcam-semana-do-idoso-no-abrigo-sagrado-coracao-de-jesus\/","url_meta":{"origin":14090,"position":0},"title":"Anivers\u00e1rio, arteterapia, massagens e ensaio fotogr\u00e1fico marcam semana do idoso no Abrigo Sagrado Cora\u00e7\u00e3o de Jesus","author":"","date":"Outubro 4, 2020","format":false,"excerpt":"Semana iniciou com celebra\u00e7\u00e3o dos 67 anos de exist\u00eancia da institui\u00e7\u00e3o. Anualmente aberta ao p\u00fablico externo, a semana do idoso no Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, unidade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, aconteceu neste ano de forma restrita devido \u00e0 pandemia de Covid-19. Entre o s\u00e1bado (26\/09)\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Parabens.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Parabens.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Parabens.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Parabens.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Parabens.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14028,"url":"https:\/\/correiodasemana.com\/site\/maria-maria-projeto-criado-por-vicosense-realiza-acao-solidaria-na-semana-do-idoso-do-abrigo-sagrado-coracao-de-jesus\/","url_meta":{"origin":14090,"position":1},"title":"Maria Maria: projeto criado por Vi\u00e7osense realiza a\u00e7\u00e3o solid\u00e1ria na Semana do Idoso do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus","author":"","date":"Outubro 13, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. Aconteceu, no \u00faltimo s\u00e1bado (26\/09), no Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, localizado na cidade de Sobral (CE), a abertura da Semana do Idoso que contou com a\u00e7\u00e3o solid\u00e1ria realizada pelo projeto Maria Maria. O projeto, idealizado pelo vi\u00e7osense Victor Andrade (22), doou 50 pacotes de fraldas para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/20201005_211937-1024x1019-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/20201005_211937-1024x1019-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/20201005_211937-1024x1019-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/20201005_211937-1024x1019-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9345,"url":"https:\/\/correiodasemana.com\/site\/semana-nacional-do-idoso-marca-comemoracao-dos-66-anos-de-fundacao-do-abrigo-sagrado-coracao-de-jesus\/","url_meta":{"origin":14090,"position":2},"title":"Semana Nacional do Idoso marca comemora\u00e7\u00e3o dos 66 anos de funda\u00e7\u00e3o do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus","author":"","date":"Outubro 7, 2019","format":false,"excerpt":"O Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, uma das unidades do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, provido pelo bispo diocesano Dom Jos\u00e9 Luiz Gomes de Vasconcelos, celebra 66 anos de funda\u00e7\u00e3o. Em clima festivo, entre os dias 24 de setembro e 1\u00b0 de outubro, a quinta edi\u00e7\u00e3o da Semana\u2026","rel":"","context":"In &quot;Diocese&quot;","block_context":{"text":"Diocese","link":"https:\/\/correiodasemana.com\/site\/category\/diocese\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Foto-principal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Foto-principal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Foto-principal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Foto-principal.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Foto-principal.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9303,"url":"https:\/\/correiodasemana.com\/site\/abrigo-sagrado-coracao-de-jesus-comemora-66-anos-de-fundacao\/","url_meta":{"origin":14090,"position":3},"title":"Abrigo Sagrado Cora\u00e7\u00e3o de Jesus comemora 66 anos de funda\u00e7\u00e3o","author":"","date":"Setembro 30, 2019","format":false,"excerpt":"Do dia 24 de setembro a 01 de outubro, est\u00e1 acontecendo uma semana especial, n\u00e3o s\u00f3 para os idosos, mas para a popula\u00e7\u00e3o que tamb\u00e9m foi convidada para fazer parte da celebra\u00e7\u00e3o dos 66 anos do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus. Fundado no dia 26 de setembro de 1953, fruto\u2026","rel":"","context":"In &quot;Destaques&quot;","block_context":{"text":"Destaques","link":"https:\/\/correiodasemana.com\/site\/category\/destaques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_4092.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_4092.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_4092.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_4092.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_4092.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_4092.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":30833,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-preside-missa-em-acao-de-gracas-pelos-71-anos-de-criacao-do-abrigo-sagrado-coracao-de-jesus\/","url_meta":{"origin":14090,"position":4},"title":"Dom Vasconcelos preside Missa em A\u00e7\u00e3o de Gra\u00e7as pelos 71 anos de cria\u00e7\u00e3o do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus","author":"adminredacao","date":"Outubro 2, 2024","format":false,"excerpt":"\u00a0 No raiar desta quinta-feira, 26 de setembro, Dom Vasconcelos presidiu a Missa em A\u00e7\u00e3o de Gra\u00e7as pelos 71 anos do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus na Capela de Nossa Senhora das Gra\u00e7as (Abrigo). Fundado em 1953 por Dom Jos\u00e9 Tupinamb\u00e1 da Frota, o Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/Jornal-Correio-da-Semana-No-1039.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/Jornal-Correio-da-Semana-No-1039.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/Jornal-Correio-da-Semana-No-1039.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/Jornal-Correio-da-Semana-No-1039.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17649,"url":"https:\/\/correiodasemana.com\/site\/abrigo-sagrado-coracao-de-jesus-celebra-68-anos-com-programacao-especial-em-semana-dedicada-aos-idosos-momentos-espirituais-arteterapia\/","url_meta":{"origin":14090,"position":5},"title":"Abrigo Sagrado Cora\u00e7\u00e3o de Jesus celebra 68 anos com programa\u00e7\u00e3o especial em semana dedicada aos idosos Momentos espirituais, arteterapia","author":"","date":"Outubro 4, 2021","format":false,"excerpt":"\u00a0Show de Humor e passeios externos ao Sobral Shopping e ao Alto do Cristo marcaram a Semana do Idoso. Ascom Complexo SCMS Fundado em 1953 por Dom Jos\u00e9 Tupinamb\u00e1 da Frota, o Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, que nasceu das necessidades da terceira idade apresentadas por pacientes na Santa Casa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/Idosos-recebem-os-parabens.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/Idosos-recebem-os-parabens.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/Idosos-recebem-os-parabens.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/Idosos-recebem-os-parabens.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14090"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14090\/revisions"}],"predecessor-version":[{"id":14095,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14090\/revisions\/14095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14091"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}