{"id":14427,"date":"2020-11-05T07:29:07","date_gmt":"2020-11-05T10:29:07","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14427"},"modified":"2020-11-05T07:29:07","modified_gmt":"2020-11-05T10:29:07","slug":"lei-exige-medidas-rapidas-dos-novos-prefeitos-para-o-saneamento-basico","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/lei-exige-medidas-rapidas-dos-novos-prefeitos-para-o-saneamento-basico\/","title":{"rendered":"Lei exige medidas r\u00e1pidas dos novos prefeitos para o saneamento b\u00e1sico"},"content":{"rendered":"<h3 class=\"western\" align=\"center\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: large;\"><i><b><span style=\"color: #343a40;\">Investimento previne doen\u00e7as e\u00a0melhora a qualidade de vida nas cidades<\/span><\/b><\/i><\/span><\/span><\/h3>\n<p align=\"left\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">O acesso ao saneamento b\u00e1sico \u00e9 um dos\u00a0principais desafios que os novos prefeitos dever\u00e3o encarar a partir de 1\u00ba de janeiro de 2021 para melhorar as condi\u00e7\u00f5es de moradia, a preven\u00e7\u00e3o da sa\u00fade e o desenvolvimento sustent\u00e1vel dos munic\u00edpios.<img decoding=\"async\" src=\"file:\/\/\/C:\/Users\/User\/AppData\/Local\/Temp\/lu68402a8go2.tmp\/lu68402a8go9_tmp_99f00bc0fe1cb894.png\" width=\"2\" height=\"2\" name=\"Figura1\" align=\"bottom\" border=\"0\" \/> <img decoding=\"async\" src=\"file:\/\/\/C:\/Users\/User\/AppData\/Local\/Temp\/lu68402a8go2.tmp\/lu68402a8go9_tmp_79d5c0d206fe2599.png\" width=\"2\" height=\"2\" name=\"Figura2\" align=\"bottom\" border=\"0\" \/> <\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">De acordo com a s\u00edntese de indicadores sociais do IBGE (edi\u00e7\u00e3o de 2019), 37 de cada 100 brasileiros residem em domic\u00edlio onde falta ao menos um dos servi\u00e7os de saneamento b\u00e1sico: coleta de lixo, abastecimento de \u00e1gua pot\u00e1vel por rede de abastecimento ou esgotamento sanit\u00e1rio por rede coletora.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">Entre os mais pobres a situa\u00e7\u00e3o \u00e9 pior: seis de cada dez n\u00e3o contam com ao menos um desses tr\u00eas servi\u00e7os em casa. Conforme crit\u00e9rio do Banco Mundial, essas pessoas est\u00e3o abaixo da linha de pobreza, disp\u00f5em menos de R$ 32 por dia &#8211; ou abaixo de US$ 5,50 PPC (paridade de poder de compra) di\u00e1rios, segundo o\u00a0\u00a0conversor do\u00a0<\/span><\/span><\/span><span style=\"color: #28a745;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><u><b><a href=\"https:\/\/www.bcb.gov.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">site do Banco Central\u00a0<\/a><\/b><\/u><\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">\u00a0(acessado em 29\/10 \u00e0s 15h32).<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">As mudan\u00e7as estabelecidas na\u00a0<\/span><\/span><\/span><span style=\"color: #28a745;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><u><b><a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2020-07\/veja-principais-mudancas-no-novo-marco-legal-do-saneamento\" target=\"_blank\" rel=\"noopener noreferrer\">legisla\u00e7\u00e3o do saneamento b\u00e1sico<\/a><\/b><\/u><\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">, a partir da Lei n\u00ba 14.026\/2020, preveem a universaliza\u00e7\u00e3o desses servi\u00e7os at\u00e9 2033.\u00a0Os novos prefeitos, que ser\u00e3o eleitos agora em novembro, dever\u00e3o fazer a adapta\u00e7\u00e3o dos munic\u00edpios \u00e0s exig\u00eancias da lei para acessar recursos para melhoria do saneamento b\u00e1sico, como participar de cons\u00f3rcios regionais com outras cidades na presta\u00e7\u00e3o dos servi\u00e7os, aderir a uma ag\u00eancia reguladora e estabelecer novos mecanismos de cobran\u00e7a.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">No caso dos res\u00edduos s\u00f3lidos, o governo federal est\u00e1 elaborando um plano nacional ap\u00f3s a realiza\u00e7\u00e3o de\u00a0<\/span><\/span><\/span><span style=\"color: #28a745;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><u><b><a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2020-07\/mma-abre-consulta-publica-sobre-plano-para-residuos-solidos\" target=\"_blank\" rel=\"noopener noreferrer\">consulta p\u00fablica<\/a><\/b><\/u><\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">.\u00a0<\/span><\/span><\/span><\/p>\n<p align=\"left\"><a name=\"OBJ_PREFIX_DWT545_com_zimbra_date\"><\/a><a name=\"OBJ_PREFIX_DWT532_com_zimbra_date\"><\/a><a name=\"OBJ_PREFIX_DWT546_com_zimbra_date\"><\/a><a name=\"OBJ_PREFIX_DWT533_com_zimbra_date\"><\/a> <span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">A lei prev\u00ea que a cobran\u00e7a municipal dever\u00e1 estar institu\u00edda at\u00e9\u00a030 de junho, ap\u00f3s vota\u00e7\u00e3o nas c\u00e2maras dos vereadores. \u201cImagina iniciar o mandato com desemprego, com redu\u00e7\u00e3o de sal\u00e1rio, com economia fraca e\u00a0ter\u00a0que instituir cobran\u00e7a\u201d, assinala Cl\u00e1udia Lins, supervisora do N\u00facleo de Desenvolvimento Social da Confedera\u00e7\u00e3o Nacional dos Munic\u00edpios (CNM).<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"left\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: xx-large;\"><b><span style=\"color: #343a40;\">Responsabilidade intrafederativa<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"left\"><a name=\"OBJ_PREFIX_DWT547_com_zimbra_date\"><\/a><a name=\"OBJ_PREFIX_DWT534_com_zimbra_date\"><\/a> <span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">A especialista v\u00ea avan\u00e7os no marco regulat\u00f3rio, mas lembra que a responsabilidade sobre o acesso ao saneamento b\u00e1sico n\u00e3o \u00e9 apenas dos munic\u00edpios, mas \u201cintrafederativa\u201d, tamb\u00e9m dos governos estaduais e do governo federal. \u201cPara esses indicadores avan\u00e7arem, a gente precisaria\u00a0ter\u00a0a Constitui\u00e7\u00e3o Federal sendo cumprida na sua \u00edntegra, com Uni\u00e3o, estados e munic\u00edpios atuando em conjunto para promover melhorias no servi\u00e7o de saneamento b\u00e1sico.\u201d<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">Lins pondera que os munic\u00edpios n\u00e3o t\u00eam recursos para investir em saneamento, e que ficam com menos de um quinto de todos os tributos no Brasil. \u201cSe a concentra\u00e7\u00e3o da arrecada\u00e7\u00e3o est\u00e1 com os entres maiores, por que n\u00e3o esses entes maiores se responsabilizarem por esses servi\u00e7os que \u00e9 uma obriga\u00e7\u00e3o na Constitui\u00e7\u00e3o?\u201d, indaga a especialista da CNM.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><a name=\"OBJ_PREFIX_DWT548_com_zimbra_date\"><\/a><a name=\"OBJ_PREFIX_DWT535_com_zimbra_date\"><\/a> <span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">Ela lembra que nos munic\u00edpios menores e em \u00e1reas remotas &#8211; como ocorre na Regi\u00e3o Norte, onde est\u00e3o os piores indicadores de saneamento \u2013 a dificuldade de implanta\u00e7\u00e3o dos servi\u00e7os de saneamento \u00e9 ainda maior. \u201cEm munic\u00edpios pequenos e isolados, com maioria rural, os servi\u00e7os s\u00e3o t\u00e3o caros, que se deixar s\u00f3 a merc\u00ea dos munic\u00edpios, sem a participa\u00e7\u00e3o dos estados e da Uni\u00e3o, a gente vai\u00a0ter\u00a0uma evolu\u00e7\u00e3o muito lenta dos indicadores.\u201d<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"left\"><span style=\"font-family: Open Sans, sans-serif;\"><span style=\"font-size: xx-large;\"><b><span style=\"color: #343a40;\">A preserva\u00e7\u00e3o da \u00e1gua<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"left\"><span style=\"color: #28a745;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><u><b><a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2020-06\/novo-marco-legal-do-saneamento-basico-divide-entidades\" target=\"_blank\" rel=\"noopener noreferrer\">Como reportado<\/a><\/b><\/u><\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">\u00a0pela\u00a0<\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><b><strong>Ag\u00eancia Brasil<\/strong><\/b><\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">, desde a vota\u00e7\u00e3o das mudan\u00e7as no marco legal do saneamento que resultaram na da Lei n\u00ba 14.026\/2020, h\u00e1 divis\u00e3o de opini\u00f5es sobre efeitos da iniciativa.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">Associa\u00e7\u00f5es empresariais acreditam que haver\u00e1 mais condi\u00e7\u00f5es de investimento e ambiente de neg\u00f3cio para amplia\u00e7\u00e3o dos servi\u00e7os de saneamento. J\u00e1 algumas entidades da sociedade civil temem que a medida privatize o acesso a recursos h\u00eddricos, inviabilize o financiamento das redes mais onerosas e deixe a universaliza\u00e7\u00e3o do saneamento fora de perspectiva.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">O pesquisador Gesmar dos Santos, do Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea) aponta outros elementos que dever\u00e3o ser em considera\u00e7\u00e3o pelos novos prefeitos e outros gestores p\u00fablicos quanto a decis\u00e3o de investir em obras e sistemas de fornecimento de \u00e1gua, coleta de res\u00edduos e esgotamento.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"color: #495057;\">\u201c<span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">O saneamento tem que ser tratado como quest\u00e3o de sa\u00fade, como direito dos cidad\u00e3os. O Estado tem que fazer a\u00e7\u00f5es de financiamento, de pesquisa tecnol\u00f3gica, de regula\u00e7\u00e3o e de levar mesmo os sistemas de abastecimento de \u00e1gua com qualidade para todos\u201d, pondera.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">Santos lembra que para cada R$ 1 gasto com saneamento h\u00e1 retorno de R$ 5,20. O c\u00e1lculo \u00e9 da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) e est\u00e1 citado em\u00a0<\/span><\/span><\/span><span style=\"color: #28a745;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><u><b><a href=\"https:\/\/www.ipea.gov.br\/portal\/index.php?option=com_content&amp;view=article&amp;id=36258&amp;Itemid=7\" target=\"_blank\" rel=\"noopener noreferrer\">nota t\u00e9cnica<\/a><\/b><\/u><\/span><\/span><\/span><span style=\"color: #495057;\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">\u00a0publicada em julho pelo Ipea.<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\"><span style=\"color: #495057;\">O especialista ainda assinala que a discuss\u00e3o sobre saneamento tem que ser ampliada e incluir a preserva\u00e7\u00e3o de rios e mananciais. \u201cTem uma conta ainda que o Brasil n\u00e3o est\u00e1 colocando: \u00e9 necess\u00e1rio falar dos custos de preserva\u00e7\u00e3o dos mananciais, gest\u00e3o integrada da \u00e1gua. Alguns subsetores produtivos n\u00e3o aceitam que pague pela preserva\u00e7\u00e3o da \u00e1gua. Isso tem custo. A sociedade n\u00e3o quer pagar e n\u00e3o h\u00e1 essa discuss\u00e3o ampla e sincera.\u201d\u00a0\u00a0<\/span><\/span><\/span><\/p>\n<p align=\"left\"><span style=\"color: #495057;\">\u201c<span style=\"font-family: Source Serif Pro, serif;\"><span style=\"font-size: medium;\">N\u00e3o d\u00e1 para a gente destruir os mananciais de \u00e1gua do lado onde mora para depois buscar \u00e1gua mais longe, com o custo muito mais alto, e aumentar a tarifa de \u00e1gua porque n\u00e3o teve a gest\u00e3o integrada dos tr\u00eas componentes: ambiental, gest\u00e3o da \u00e1gua e saneamento\u201d, acrescenta Gesmar dos Santos.<\/span><\/span><\/span><\/p>\n<h4 class=\"col-10 offset-1 animated fadeInDown dealy-1100 alt-font font-italic my-2 small text-info text-center\">Por Gilberto Costa \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Investimento previne doen\u00e7as e\u00a0melhora a qualidade de vida nas cidades O acesso ao saneamento b\u00e1sico&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/saneamento_basico_arquivo_agencia_brasil.jpg","jetpack-related-posts":[{"id":11928,"url":"https:\/\/correiodasemana.com\/site\/bolsonaro-sanciona-lei-do-novo-marco-legal-do-saneamento-basico\/","url_meta":{"origin":14427,"position":0},"title":"Bolsonaro sanciona lei do novo Marco Legal do Saneamento B\u00e1sico","author":"","date":"Julho 16, 2020","format":false,"excerpt":"Texto prev\u00ea universaliza\u00e7\u00e3o dos servi\u00e7os de \u00e1gua e esgoto at\u00e9 2033 O presidente Jair Bolsonaro sancionou hoje (15) a lei do novo Marco Legal do Saneamento B\u00e1sico no pa\u00eds, que prev\u00ea a universaliza\u00e7\u00e3o dos servi\u00e7os de \u00e1gua e esgoto at\u00e9 2033. O texto,\u00a0aprovado no Congresso\u00a0no m\u00eas passado ap\u00f3s muita discuss\u00e3o,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/15_07_2020_cerimonia_saneamento-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12262,"url":"https:\/\/correiodasemana.com\/site\/levantamento-do-ibge-aponta-que-abastecimento-de-agua-chegou-a-996-dos-municipios-mas-esgoto-a-apenas-603\/","url_meta":{"origin":14427,"position":1},"title":"Levantamento do IBGE aponta que abastecimento de \u00e1gua chegou a 99,6% dos munic\u00edpios, mas esgoto a apenas 60,3%","author":"","date":"Julho 27, 2020","format":false,"excerpt":"BRASIL\/SANEAMENTO O abastecimento de \u00e1gua por rede chegou a cerca de 99,6% dos munic\u00edpios brasileiros em 2017. \u00c9 o que aponta um levantamento do IBGE (Instituto Brasileiro de Geografia e Estat\u00edstica). Isso quer dizer que apenas 22 munic\u00edpios brasileiros n\u00e3o tinham essa disponibilidade at\u00e9 o fechamento dos dados. O \u00f3rg\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/%C3%A1gua.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/%C3%A1gua.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/%C3%A1gua.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/%C3%A1gua.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9886,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-20\/","url_meta":{"origin":14427,"position":2},"title":"Panorama Pol\u00edtico","author":"","date":"Novembro 18, 2019","format":false,"excerpt":"Governador Camilo Santana e Prefeito Ivo Gomes entregaram \u00e0 popula\u00e7\u00e3o o Parque Paje\u00fa O governador do Cear\u00e1, Camilo Santana e o Prefeito de Sobral, Ivo Gomes, inauguraram domingo, dia 10, o Parque Paje\u00fa, uma \u00e1rea antes degradada que agora, juntamente com o Parque da Cidade e a Lagoa da Fazenda\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28731,"url":"https:\/\/correiodasemana.com\/site\/taxa-do-lixo-em-sobral-comeca-a-ser-cobrada-em-abril-entenda-como-vai-funcionar\/","url_meta":{"origin":14427,"position":3},"title":"Taxa do lixo em Sobral come\u00e7a a ser cobrada em abril; entenda como vai funcionar","author":"adminredacao","date":"Mar\u00e7o 18, 2024","format":false,"excerpt":"A Ag\u00eancia Reguladora Intermunicipal de Saneamento informou que nenhum im\u00f3vel ser\u00e1 isento da cobran\u00e7a. Por g1 CE Taxa do lixo em Sobral come\u00e7a a ser cobrada em abril. \u2014 Foto: Jos\u00e9 Leomar\/SVM A\u00a0cobran\u00e7a da taxa do lixo em\u00a0Sobral\u00a0come\u00e7a no pr\u00f3ximo m\u00eas de abril, conforme a Ag\u00eancia Reguladora Intermunicipal de Saneamento\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/Mutirao-de-limpeza-prefeitura-de-Sobral-7-768x576-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/Mutirao-de-limpeza-prefeitura-de-Sobral-7-768x576-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/Mutirao-de-limpeza-prefeitura-de-Sobral-7-768x576-1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/Mutirao-de-limpeza-prefeitura-de-Sobral-7-768x576-1.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12425,"url":"https:\/\/correiodasemana.com\/site\/bairro-cidade-doutor-jose-euclides-recebera-investimento-de-r-38-milhoes-para-obras-de-saneamento-e-pavimentacao-2\/","url_meta":{"origin":14427,"position":4},"title":"Bairro Cidade Doutor \u00a0Jos\u00e9 Euclides receber\u00e1 investimento de R$ 38 milh\u00f5es para obras de saneamento e pavimenta\u00e7\u00e3o","author":"","date":"Agosto 2, 2020","format":false,"excerpt":"O prefeito Ivo Gomes anunciou a autoriza\u00e7\u00e3o do lan\u00e7amento do edital de licita\u00e7\u00e3o que dever\u00e1 ser lan\u00e7ado no in\u00edcio do m\u00eas de agosto O prefeito Ivo Gomes anunciou, em suas redes sociais, a autoriza\u00e7\u00e3o do lan\u00e7amento do edital de licita\u00e7\u00e3o para obras de saneamento e pavimenta\u00e7\u00e3o (asfalto e piso intertravado)\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bairro-Jos%C3%A9-Euclides-Terrenos-Novos-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bairro-Jos%C3%A9-Euclides-Terrenos-Novos-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bairro-Jos%C3%A9-Euclides-Terrenos-Novos-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bairro-Jos%C3%A9-Euclides-Terrenos-Novos-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35975,"url":"https:\/\/correiodasemana.com\/site\/mais-de-93-mil-internacoes-por-doencas-relacionadas-a-falta-de-saneamento-ocorreram-no-nordeste\/","url_meta":{"origin":14427,"position":5},"title":"Mais de 93 mil interna\u00e7\u00f5es por doen\u00e7as relacionadas \u00e0 falta de saneamento ocorreram no Nordeste","author":"adminredacao","date":"Outubro 29, 2025","format":false,"excerpt":"As interna\u00e7\u00f5es por Doen\u00e7as Relacionadas ao Saneamento Ambiental Inadequado (DRSAI) geraram despesas de mais de R$ 42,7 milh\u00f5es para a regi\u00e3o Em 2024, a regi\u00e3o Nordeste registrou mais de 93 mil interna\u00e7\u00f5es por Doen\u00e7as Relacionadas ao Saneamento Ambiental Inadequado (DRSAI), representando 27,2% do total nacional. Entre os estados com os\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/saneamento_basico_arquivo_agencia_brasil.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/saneamento_basico_arquivo_agencia_brasil.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/saneamento_basico_arquivo_agencia_brasil.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/saneamento_basico_arquivo_agencia_brasil.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/saneamento_basico_arquivo_agencia_brasil.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14427"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14427\/revisions"}],"predecessor-version":[{"id":14430,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14427\/revisions\/14430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14428"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}