{"id":14435,"date":"2020-11-09T07:48:37","date_gmt":"2020-11-09T10:48:37","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14435"},"modified":"2020-11-09T07:48:37","modified_gmt":"2020-11-09T10:48:37","slug":"joe-biden-eleito-nos-eua-quais-sao-suas-propostas-em-8-temas-cruciais","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/joe-biden-eleito-nos-eua-quais-sao-suas-propostas-em-8-temas-cruciais\/","title":{"rendered":"Joe Biden eleito nos EUA: quais s\u00e3o suas propostas em 8 temas cruciais"},"content":{"rendered":"<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Coronav\u00edrus, emprego e renda, mudan\u00e7a clim\u00e1tica, racismo&#8230; Veja como o presidente eleito se posiciona e o que promete em rela\u00e7\u00e3o a assuntos centrais para os Estados Unidos.<\/span><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: inherit;\"><span style=\"font-size: large;\"><span style=\"color: #555555;\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\">Quando anunciou formalmente sua entrada na corrida presidencial de 2020, Joe Biden \u2013<\/span><\/span><a href=\"https:\/\/g1.globo.com\/mundo\/eleicoes-nos-eua\/2020\/noticia\/2020\/11\/07\/joe-biden-vence-na-pensilvania-e-garante-votos-para-ser-eleito-presidente-dos-eua-aponta-projecao-da-ap.ghtml\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><b> s\u00e1bado (7\/<\/b><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><b>11\/2020<\/b><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\"><b>) presidente dos EUA\u00a0<\/b><\/span><\/span><\/a><span style=\"color: #000000;\"><span style=\"font-family: Arial, sans-serif;\">\u2013 afirmou que defendia duas coisas:\u00a0os trabalhadores que &#8220;constru\u00edram este pa\u00eds&#8221; e valores que possam superar divis\u00f5es pessoais.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Prestes a assumir um pa\u00eds com grandes desafios, desde a devasta\u00e7\u00e3o causada pela pandemia do novo coronav\u00edrus at\u00e9 a desigualdade racial, ele concorreu (e venceu) com uma plataforma que propunha a cria\u00e7\u00e3o de novas oportunidades de trabalho e o restabelecimento de salvaguardas ambientais, alian\u00e7as internacionais e prote\u00e7\u00f5es de sa\u00fade aos americanos.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Abaixo, mais detalhes de como o presidente eleito se posiciona em 8 quest\u00f5es\u2010chave:<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">1. Coronav\u00edrus: programa nacional de testes e rastreamento<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">A proposta de Biden para enfrentar o avan\u00e7o do coronav\u00edrus nos EUA \u00e9 oferecer testes gr\u00e1tis \u00e0 popula\u00e7\u00e3o e contratar 100 mil colaboradores para criar uma rede nacional de rastreamento de contatos de pessoas potencialmente infectadas.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Ele diz que quer estabelecer ao menos dez centros de testagem em cada Estado, convocar ag\u00eancias federais para alocar recursos para a for\u00e7a-tarefa e usar especialistas das ag\u00eancias federais para dar uma orienta\u00e7\u00e3o mais firme em \u00e2mbito nacional.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden defende, por exemplo, que todos os governadores deveriam tornar obrigat\u00f3rio o uso de m\u00e1scaras.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Os eleitores que tradicionalmente desconfiam das autoridades federais v\u00e3o ver isso como um abuso, mas a medida est\u00e1 em linha com a vis\u00e3o geral de Biden ou do Partido Democrata sobre o papel do governo.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">2. Emprego e renda: reajuste do sal\u00e1rio m\u00ednimo e investimento em energia renov\u00e1vel<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Para fazer frente ao impacto causado pela pandemia de covid-19, Biden se comprometeu a gastar &#8220;o que fosse preciso&#8221; para estender os programas de concess\u00e3o de cr\u00e9dito a pequenos neg\u00f3cios e aumentar o pagamento de aux\u00edlio emergencial \u00e0s fam\u00edlias.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Entre as propostas, est\u00e1 um adicional de US$ 200 (R$ 1.070) no benef\u00edcio pago pela Seguridade Social, com consequente revoga\u00e7\u00e3o dos cortes de impostos promovidos por Trump durante seu mandato.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">A pol\u00edtica econ\u00f4mica encampada pela chapa, batizada de &#8220;Build Back Better&#8221; (&#8220;reconstruir melhor&#8221;, em tradu\u00e7\u00e3o livre), tem como foco principal dois grupos que tradicionalmente votam em candidatos democratas: jovens e trabalhadores bra\u00e7ais (os chamados &#8220;blue collar workers&#8221;).<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">A proposta de aumento do sal\u00e1rio m\u00ednimo federal para US$ 15 por hora (cerca de R$ 80) ecoou entre os eleitores mais jovens e virou uma esp\u00e9cie de s\u00edmbolo da sigla em 2020 &#8211; uma sinaliza\u00e7\u00e3o de um posicionamento mais \u00e0 esquerda.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden tamb\u00e9m j\u00e1 mencionou a inten\u00e7\u00e3o de investir algo em torno de US$ 2 trilh\u00f5es (mais de R$ 10 trilh\u00f5es) em energia renov\u00e1vel e defendeu produ\u00e7\u00e3o sustent\u00e1vel como um caminho para fortalecer os trabalhadores sindicalizados, bastante presentes nesses setores.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">H\u00e1 ainda a promessa de gastar em torno de US$ 400 bilh\u00f5es (R$ 2,1 trilh\u00f5es) em compras governamentais direcionadas a produtos da ind\u00fastria americana, alinhada ao compromisso mais amplo de fortalecer leis que incentivem a compra de produtos feitos por empresas locais em projetos na \u00e1rea de transportes.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden j\u00e1 foi criticado por apoiar o Nafta, acordo de livre com\u00e9rcio da Am\u00e9rica do Norte, que, para alguns, facilita a transfer\u00eancia de empregos que hoje est\u00e3o nos Estados Unidos para outros pa\u00edses.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">3. Quest\u00e3o racial: reforma do sistema judicial penal<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Na esteira dos protestos raciais que atingiram os EUA neste ano, ele disse acreditar que o racismo existe nos EUA e deve ser combatido por meio de amplos programas econ\u00f4micos e sociais de apoio \u00e0s minorias. Um dos pilares de seu programa de &#8220;reconstru\u00e7\u00e3o&#8221; \u00e9 criar suporte empresarial para minorias por meio de um fundo de investimento de US$ 30 bilh\u00f5es (R$ 160 bilh\u00f5es).<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Na justi\u00e7a criminal, ele se afastou de sua posi\u00e7\u00e3o muito criticada, de ser &#8220;duro contra o crime&#8221;, dos anos 1990. Biden agora prop\u00f4s pol\u00edticas para reduzir o encarceramento, lidar com disparidades de ra\u00e7a, g\u00eanero e de renda no sistema judici\u00e1rio e reabilitar prisioneiros libertados. Ele criaria agora um programa de doa\u00e7\u00f5es de US$ 20 bilh\u00f5es (R$ 107 bilh\u00f5es) para incentivar os estados a investirem em esfor\u00e7os de redu\u00e7\u00e3o do encarceramento, eliminar senten\u00e7as m\u00ednimas obrigat\u00f3rias, descriminalizar a maconha, e acabar com a pena de morte.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">No entanto, ele rejeitou pedidos para reduzir recursos \u00e0 pol\u00edcia, dizendo que os recursos deveriam ser vinculados \u00e0 manuten\u00e7\u00e3o de padr\u00f5es. Ele argumenta que parte do financiamento para a pol\u00edcia deve ser redirecionado para servi\u00e7os sociais, como sa\u00fade mental, e fala em um investimento de US$ 300 milh\u00f5es (R$ 1,6 bi) em programa de policiamento comunit\u00e1rio.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">4. Mudan\u00e7a clim\u00e1tica: reingressar no acordo global<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden classificou a mudan\u00e7a clim\u00e1tica como amea\u00e7a existencial e diz que vai reunir o resto do mundo para agir mais rapidamente na redu\u00e7\u00e3o das emiss\u00f5es, ingressando novamente no Acordo de Paris. O acordo, do qual Donald Trump se retirou, previa comprometimento dos EUA com a redu\u00e7\u00e3o dos gases de efeito estufa em at\u00e9 28% at\u00e9 2025, com base nos n\u00edveis de 2005.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Embora ele n\u00e3o adote o Green New Deal (pacote de clima e empregos apresentado pela ala esquerda de seu partido), Biden est\u00e1 propondo um investimento federal de US$ 1,7 trilh\u00e3o em pesquisas de tecnologias verdes (alguns dos quais se sobrep\u00f5em ao financiamento de seu plano econ\u00f4mico, a ser gasto nos pr\u00f3ximos 10 anos) e quer que os EUA atinjam emiss\u00f5es l\u00edquidas zero at\u00e9 2050 &#8211; um compromisso que foi feito por mais de 60 outros pa\u00edses no ano passado. China e \u00cdndia, os outros dois maiores emissores de carbono, ainda n\u00e3o aderiram ao compromisso.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Os investimentos se encaixam em seu plano econ\u00f4mico de criar empregos na fabrica\u00e7\u00e3o de produtos de &#8220;energia verde&#8221;.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">5. Pol\u00edtica externa: restaurar a reputa\u00e7\u00e3o da Am\u00e9rica&#8230; e lidar com a China<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden escreveu que, como presidente, ele se concentraria primeiro nas quest\u00f5es nacionais. Dito isso, pouco sugere que os valores de Biden na pol\u00edtica externa se afastaram do multilateralismo e do engajamento no cen\u00e1rio mundial, em oposi\u00e7\u00e3o aos valores claramente isolacionistas de Trump.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Ele tamb\u00e9m prometeu consertar rela\u00e7\u00f5es com os aliados dos EUA, especialmente com a alian\u00e7a da Otan (Organiza\u00e7\u00e3o do Tratado do Atl\u00e2ntico Norte), que Trump repetidamente amea\u00e7ou minar com cortes de recursos.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">O ex-vice-presidente disse que a China deveria ser responsabilizada por pr\u00e1ticas comerciais e ambientais injustas, mas em vez de tarifas unilaterais, ele prop\u00f4s uma coaliz\u00e3o internacional com outras democracias que a China &#8220;n\u00e3o pode ignorar&#8221;, embora tenha sido vago sobre o que isso significa.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">6. Sa\u00fade: expandir o Obamacare<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden diz que vai expandir o Obamacare, sistema que ampliou a cobertura de sa\u00fade para pessoas que nunca tiveram seguro no pa\u00eds, criado quando ele era vice do presidente Barack Obama, e implementar um plano para segurar cerca de 97% dos americanos.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Biden promete dar a todos os americanos a op\u00e7\u00e3o de se inscrever em um seguro de sa\u00fade p\u00fablico semelhante ao Medicare, que oferece benef\u00edcios m\u00e9dicos para os idosos, e para diminuir a idade de elegibilidade para o pr\u00f3prio Medicare de 65 para 60 anos. O Comit\u00ea para um Or\u00e7amento Federal Respons\u00e1vel, um grupo apartid\u00e1rio, estima que o plano Biden custaria um total de US$ 2,25 trilh\u00f5es (R$ 12 trilh\u00f5es) em 10 anos.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">7. Imigra\u00e7\u00e3o: desfazer as pol\u00edticas de Trump<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Em seus primeiros 100 dias no cargo, Biden promete reverter as pol\u00edticas de Trump que separam pais dos pr\u00f3prios filhos na fronteira EUA-M\u00e9xico, cancelar os limites do n\u00famero de pedidos de asilo e acabar com as proibi\u00e7\u00f5es de viagens de v\u00e1rios pa\u00edses de maioria mu\u00e7ulmana. Ele tamb\u00e9m promete proteger os &#8220;Dreamers&#8221; (Sonhadores), pessoas levadas ilegalmente para os Estados Unidos quando crian\u00e7as e que foram autorizadas a permanecer devido a uma pol\u00edtica da era Obama, bem como garantir que sejam eleg\u00edveis para aux\u00edlio federal a estudantes.<\/span><\/span><\/span><\/p>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b><span style=\"color: #000000;\">8. Educa\u00e7\u00e3o: pr\u00e9-escola universal e expandir faculdade gratuita<\/span><\/b><\/span><\/span><\/h2>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Em uma mudan\u00e7a not\u00e1vel para a esquerda, Biden endossou v\u00e1rios pontos de pol\u00edtica educacional que se tornaram populares dentro do partido: perd\u00e3o de d\u00edvidas de financiamento estudantil, expans\u00e3o de faculdades gratuitas e acesso universal \u00e0 pr\u00e9-escola. Estes seriam financiados com o dinheiro ganho com a retirada dos cortes de impostos da era Trump.<\/span><\/span><\/span><\/p>\n<p align=\"justify\">\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\">Fonte: G1<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coronav\u00edrus, emprego e renda, mudan\u00e7a clim\u00e1tica, racismo&#8230; Veja como o presidente eleito se posiciona e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/joe-biden.jpg","jetpack-related-posts":[{"id":14456,"url":"https:\/\/correiodasemana.com\/site\/biden-promete-pressao-para-que-paises-aumentem-protecao-ambiental\/","url_meta":{"origin":14435,"position":0},"title":"Biden promete press\u00e3o para que pa\u00edses aumentem prote\u00e7\u00e3o ambiental","author":"","date":"Novembro 9, 2020","format":false,"excerpt":"O presidente rec\u00e9m-eleito dos Estados Unidos, Joe Biden, apresentou em seu site o plano de prioridades de seu governo, que come\u00e7ar\u00e1 em 20 de janeiro. Os quatro temas priorit\u00e1rios, segundo o democrata, ser\u00e3o: igualdade racial, recupera\u00e7\u00e3o econ\u00f4mica, combate \u00e0\u00a0covid\u00a0e mudan\u00e7as clim\u00e1ticas. Na parte sobre o meio ambiente, Biden promete press\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/biden-briefing-750x430-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/biden-briefing-750x430-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/biden-briefing-750x430-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/biden-briefing-750x430-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22667,"url":"https:\/\/correiodasemana.com\/site\/todos-os-voos-nos-eua-sao-cancelados-apos-falha-de-sistema\/","url_meta":{"origin":14435,"position":1},"title":"Todos os voos nos EUA s\u00e3o cancelados ap\u00f3s falha de sistema","author":"","date":"Janeiro 11, 2023","format":false,"excerpt":"Os Estados Unidos suspenderam todos os voos do pa\u00eds hoje por causa de uma falha no sistema de computa\u00e7\u00e3o da Administra\u00e7\u00e3o Federal de Avia\u00e7\u00e3o. O mecanismo \u00e9 respons\u00e1vel por sinalizar aos pilotos os perigos de voo e as restri\u00e7\u00f5es em tempo real. Segundo a ag\u00eancia, o programa n\u00e3o est\u00e1 processando\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AAIRLINES-26-JUN-2020-comissariadevoo.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AAIRLINES-26-JUN-2020-comissariadevoo.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AAIRLINES-26-JUN-2020-comissariadevoo.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AAIRLINES-26-JUN-2020-comissariadevoo.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AAIRLINES-26-JUN-2020-comissariadevoo.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AAIRLINES-26-JUN-2020-comissariadevoo.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14635,"url":"https:\/\/correiodasemana.com\/site\/perfil-medio-do-vereador-eleito-no-brasil-e-homem-branco-casado-com-ensino-medio-completo-e-44-anos\/","url_meta":{"origin":14435,"position":2},"title":"Perfil m\u00e9dio do vereador eleito no Brasil \u00e9 homem, branco, casado, com ensino m\u00e9dio completo e 44 anos","author":"","date":"Novembro 19, 2020","format":false,"excerpt":"Conhe\u00e7a perfil dos mais de 58 mil vereadores eleitos neste domingo (15). 21% deles colocam 'vereador' como profiss\u00e3o declarada. Por Tha\u00eds Matos, G1 O perfil m\u00e9dio do vereador eleito neste domingo (15) \u00e9\u00a0homem, branco, casado, com ensino m\u00e9dio completo, 44 anos e vereador\u00a0como profiss\u00e3o declarada, segundo levantamento do\u00a0G1\u00a0com dados do\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/URNA-ELETRONICA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/URNA-ELETRONICA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/URNA-ELETRONICA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/URNA-ELETRONICA.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/URNA-ELETRONICA.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9426,"url":"https:\/\/correiodasemana.com\/site\/eleitos-os-dez-conselheiros-tutelares-de-sobral-para-o-quadrienio-2020-2024\/","url_meta":{"origin":14435,"position":3},"title":"Eleitos os dez conselheiros tutelares de Sobral para o quadri\u00eanio 2020-2024","author":"","date":"Outubro 14, 2019","format":false,"excerpt":"A popula\u00e7\u00e3o de Sobral compareceu \u00e0s urnas, neste domingo (06\/10), para escolher os membros dos Conselhos Tutelares para o per\u00edodo de 2020 a 2024. Pela primeira vez, foram eleitos dez membros para o colegiado. O prefeito Ivo Gomes sancionou, em abril deste ano, a lei que criou o segundo conselho\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/eleiccca7occ83es-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/eleiccca7occ83es-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/eleiccca7occ83es-01.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/eleiccca7occ83es-01.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14920,"url":"https:\/\/correiodasemana.com\/site\/quatro-cidades-do-ceara-podem-ter-novas-eleicoes\/","url_meta":{"origin":14435,"position":4},"title":"Quatro cidades do Cear\u00e1 podem ter novas elei\u00e7\u00f5es","author":"","date":"Dezembro 7, 2020","format":false,"excerpt":"\u2022 Cidades cujos prefeitos eleitos est\u00e3o sub-judice correm risco de terem resultado das elei\u00e7\u00f5es de 2020 anuladas. Por Joc\u00e9lio Tavares. Nas elei\u00e7\u00f5es municipais ocorridas no dia 15 de novembro, o Cear\u00e1 elegeu 184 prefeitos, dos quais quatro ainda aguardam decis\u00e3o judicial para terem as candidaturas regularizadas e, assim, assumirem os\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/eleicoes_2020_-_banner_destaque_01-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/eleicoes_2020_-_banner_destaque_01-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/eleicoes_2020_-_banner_destaque_01-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/eleicoes_2020_-_banner_destaque_01-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/eleicoes_2020_-_banner_destaque_01-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13946,"url":"https:\/\/correiodasemana.com\/site\/negras-sao-28-dos-brasileiros-mas-tem-baixa-participacao-politica\/","url_meta":{"origin":14435,"position":5},"title":"Negras s\u00e3o 28% dos brasileiros, mas t\u00eam baixa participa\u00e7\u00e3o pol\u00edtica","author":"","date":"Outubro 7, 2020","format":false,"excerpt":"Em 2016, \u00a03,2 % das prefeitas eleitas eram mulheres negras As mulheres negras representam 27,8% da popula\u00e7\u00e3o brasileira, entretanto tem baixa representatividade na pol\u00edtica. Em ano de elei\u00e7\u00f5es municipais, dados divulgados pelo\u00a0Movimento Mulheres Negras\u00a0mostram que, em 2016, o n\u00famero de eleitas, tanto para vereadoras quanto para prefeitas n\u00e3o chegou a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/03092010-03092010ef18664.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/03092010-03092010ef18664.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/03092010-03092010ef18664.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/03092010-03092010ef18664.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/03092010-03092010ef18664.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14435"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14435\/revisions"}],"predecessor-version":[{"id":14438,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14435\/revisions\/14438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14436"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}