{"id":14567,"date":"2020-11-16T00:32:53","date_gmt":"2020-11-16T03:32:53","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14567"},"modified":"2020-11-16T00:32:53","modified_gmt":"2020-11-16T03:32:53","slug":"em-tempo-57","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-57\/","title":{"rendered":"Em Tempo"},"content":{"rendered":"<p><strong>Transplantes de \u00f3rg\u00e3os e tecidos no Cear\u00e1<\/strong><br \/>\nO n\u00famero de transplantes de \u00f3rg\u00e3os e tecidos no Cear\u00e1 voltou a crescer ap\u00f3s o per\u00edodo cr\u00edtico da pandemia de Covid-19.\u00a0Em baixa entre os meses de mar\u00e7o a agosto, quando o maior registro foi de 74 procedimentos em um m\u00eas, em setembro foram realizados 171 transplantes.<br \/>\nO m\u00eas de outubro se manteve est\u00e1vel e registrou 149 cirurgias. Os dados foram obtidos por meio da Secretaria de Sa\u00fade do Estado. O retorno dos bons \u00edndices de transplantes est\u00e1 atrelado \u00e0 campanha de doa\u00e7\u00f5es intensificada setembro, com lives, palestras e divulga\u00e7\u00e3o.<\/p>\n<p><strong>Servi\u00e7o Social,Trabalho e Quest\u00e3o Social<\/strong><br \/>\nA Universidade Estadual do Cear\u00e1 (Uece) est\u00e1 com inscri\u00e7\u00f5es abertas, at\u00e9 27 de novembro, para processo seletivo do Mestrado Acad\u00eamico em Servi\u00e7o Social, Trabalho e Quest\u00e3o Social. Os interessados dever\u00e3o realizar inscri\u00e7\u00e3o online, no site\u00a0www.uece.br\/mass<br \/>\nS\u00e3o ofertadas 15 vagas, sendo uma para concorr\u00eancia entre pessoas com defici\u00eancia e tr\u00eas para as cotas \u00e9tnico-raciais e comunidades tradicionais. O curso tem como p\u00fablico-alvo egressos do curso de gradua\u00e7\u00e3o em Servi\u00e7o Social e das \u00e1reas de Ci\u00eancias Humanas e Sociais<\/p>\n<p><strong>\u201cRedemoinho em Dia Quente\u201d no Jabuti<\/strong><br \/>\n<strong>Foto: Reprodu\u00e7\u00e3o\/ Instagram<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft  wp-image-14568\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/1_jarid_arraes-13978214.jpg\" alt=\"\" width=\"297\" height=\"198\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/1_jarid_arraes-13978214.jpg 750w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/1_jarid_arraes-13978214-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/1_jarid_arraes-13978214-675x450.jpg 675w\" sizes=\"(max-width: 297px) 100vw, 297px\" \/><br \/>\n<strong>O livro a cearense\u00a0Jarid Arraes j\u00e1 ganhou o Pr\u00eamio APCA de Literatura de 2019<\/strong><br \/>\n62\u00aa edi\u00e7\u00e3o do Pr\u00eamio Jabuti anunciou os cinco finalistas de cada categoria. Cerim\u00f4nia de entrega do pr\u00eamio acontece on-line no dia 26 de novembro pelas redes sociais da C\u00e2mara Brasileira do Livro (CBL). O vencedor de cada grupo receber\u00e1 R$ 5 mil e uma estatueta.<br \/>\nNa categoria de contos, o destaque \u00e9 a cearense\u00a0Jarid Arraes, com \u201cRedemoinho em Dia Quente\u201d. Entre a fantasia e o realismo, conta hist\u00f3rias de mulheres do Cariri. A partir dessas personagens femininas, demonstra o extraordin\u00e1rio que permanece escondido no cotidiano.<\/p>\n<p><strong>P\u00f3s-Gradua\u00e7\u00e3o UFC em Economia Rural<\/strong><br \/>\nO Programa de P\u00f3s-Gradua\u00e7\u00e3o em Economia Rural, do Centro de Ci\u00eancias Agr\u00e1rias da Universidade Federal do Cear\u00e1, est\u00e1 com inscri\u00e7\u00f5es abertas, at\u00e9 30 de novembro, para sele\u00e7\u00e3o de mestrado e doutorado. S\u00e3o 12 vagas de mestrado e 5 de doutorado, com ingresso em 2021.1.<br \/>\nAs vagas s\u00e3o para as linhas de pesquisa Economia Aplicada ao Agroneg\u00f3cio, Economia de Recursos Naturais e Pol\u00edtica Ambiental, e Pol\u00edticas P\u00fablicas e Desenvolvimento Rural Sustent\u00e1vel. Informa\u00e7\u00f5es atrav\u00e9s do e-mail\u00a0econrura@ufc.br\u00a0ou pelo telefone (85) 3366 9716.<\/p>\n<p><strong>Morre radialista e m\u00fasico Eug\u00eanio Stone<\/strong><br \/>\nRadialista e m\u00fasico\u00a0Eug\u00eanio Gustavo Normando Stone\u00a0morreu, no dia 7 de novembro, em Fortaleza, aos 62 anos. Amigos de Eug\u00eanio organizaram nos dias 9, 10 e 11, a mostra virtual \u201cAlive Stone\u201d, com\u00a0lives de m\u00fasica em sua homenagem e arrecada\u00e7\u00e3o de fundos para a fam\u00edlia.<br \/>\nConhecido e respeitado entre artistas e profissionais da comunica\u00e7\u00e3o cearense, Stone enfrentava os efeitos do\u00a0Alzheimer\u00a0h\u00e1 dez anos. Colecionava no curr\u00edculo passagens por grandes ve\u00edculos de imprensa do Cear\u00e1. Stone faleceu no Dia do Radialista, sua profiss\u00e3o.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br). Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transplantes de \u00f3rg\u00e3os e tecidos no Cear\u00e1 O n\u00famero de transplantes de \u00f3rg\u00e3os e tecidos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-14567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg","jetpack-related-posts":[{"id":30694,"url":"https:\/\/correiodasemana.com\/site\/ceara-realiza-944-transplantes-no-primeiro-semestre-de-2024\/","url_meta":{"origin":14567,"position":0},"title":"Cear\u00e1 realiza 944 transplantes no primeiro semestre de 2024","author":"adminredacao","date":"Setembro 16, 2024","format":false,"excerpt":"C\u00f3rnea, f\u00edgado, rins e medula \u00f3ssea s\u00e3o os principais destaques dos procedimentos realizados no estado Para conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da doa\u00e7\u00e3o de \u00f3rg\u00e3os, o Minist\u00e9rio da Sa\u00fade lan\u00e7a a campanha \u201cSetembro Verde\u201d. Entre janeiro e junho deste ano, foram realizados 14.352 transplantes pelo\u00a0Sistema \u00danico de Sa\u00fade (SUS)\u00a0em\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/5ce6de4f-1419-4750-8606-6f18ac39d5c4.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/5ce6de4f-1419-4750-8606-6f18ac39d5c4.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/5ce6de4f-1419-4750-8606-6f18ac39d5c4.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/5ce6de4f-1419-4750-8606-6f18ac39d5c4.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30735,"url":"https:\/\/correiodasemana.com\/site\/regionalizacao-da-saude-fortalece-rede-de-transplantes\/","url_meta":{"origin":14567,"position":1},"title":"Regionaliza\u00e7\u00e3o da sa\u00fade fortalece rede de transplantes","author":"adminredacao","date":"Setembro 23, 2024","format":false,"excerpt":"O m\u00eas de setembro \u00e9 dedicado \u00e0 conscientiza\u00e7\u00e3o sobre a import\u00e2ncia da doa\u00e7\u00e3o de \u00f3rg\u00e3os e tecidos, por meio do Setembro Verde, que busca incentivar esse gesto de solidariedade que pode fazer a diferen\u00e7a no futuro de quem aguarda por um transplante. De um lado, a dor de parentes que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Hospitais-Regionais-captacao-orgaos-transplantes-1200x800-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Hospitais-Regionais-captacao-orgaos-transplantes-1200x800-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Hospitais-Regionais-captacao-orgaos-transplantes-1200x800-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Hospitais-Regionais-captacao-orgaos-transplantes-1200x800-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Hospitais-Regionais-captacao-orgaos-transplantes-1200x800-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9142,"url":"https:\/\/correiodasemana.com\/site\/sobral-e-referencia-em-transplante-de-cornea\/","url_meta":{"origin":14567,"position":2},"title":"Sobral \u00e9 refer\u00eancia em Transplante de C\u00f3rnea","author":"","date":"Setembro 15, 2019","format":false,"excerpt":"O Minist\u00e9rio da Sa\u00fade descreve\u00a0o transplante como um procedimento cir\u00fargico que consiste na reposi\u00e7\u00e3o de um \u00f3rg\u00e3o (cora\u00e7\u00e3o, pulm\u00e3o, rim, p\u00e2ncreas, f\u00edgado) ou tecido (medula \u00f3ssea, ossos, c\u00f3rneas) de uma pessoa doente (receptor), por outro \u00f3rg\u00e3o ou tecido normal de um doador vivo ou morto. Em Sobral, no ano de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-13-at-00.08.25.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-13-at-00.08.25.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-13-at-00.08.25.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-13-at-00.08.25.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-13-at-00.08.25.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":36151,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-realiza-segunda-captacao-de-coracao-para-transplante-do-ano\/","url_meta":{"origin":14567,"position":3},"title":"Santa Casa de Sobral realiza segunda capta\u00e7\u00e3o de cora\u00e7\u00e3o para transplante do ano","author":"adminredacao","date":"Novembro 3, 2025","format":false,"excerpt":"A Santa Casa de Miseric\u00f3rdia de Sobral realizou a segunda capta\u00e7\u00e3o de cora\u00e7\u00e3o para transplante deste ano no \u00faltimo s\u00e1bado (25). Gra\u00e7as \u00e0 generosidade de uma fam\u00edlia em luto, tamb\u00e9m foram doados f\u00edgado e rins, que seguiram para pacientes que aguardavam por um transplante no Cear\u00e1. Somente neste ano, a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/Doacao-de-orgaos-3-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/Doacao-de-orgaos-3-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/Doacao-de-orgaos-3-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/Doacao-de-orgaos-3-scaled.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/Doacao-de-orgaos-3-scaled.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/Doacao-de-orgaos-3-scaled.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14554,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-atinge-marca-de-400-transplantes-de-corneas-realizados\/","url_meta":{"origin":14567,"position":4},"title":"Santa Casa de Miseric\u00f3rdia de Sobral atinge marca de 400 transplantes de c\u00f3rneas realizados","author":"","date":"Novembro 16, 2020","format":false,"excerpt":"Hospital \u00e9 o \u00fanico do interior do Cear\u00e1 a realizar esse tipo de procedimento. Ascom Complexo SCMS \u201cAno passado descobri que precisaria fazer transplante de c\u00f3rneas nos meus dois olhos. No in\u00edcio foi dif\u00edcil aceitar, chorei bastante. Mas hoje estou feliz aqui na Santa Casa realizando o primeiro transplante no\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Tranplante-corneas-400.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Tranplante-corneas-400.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Tranplante-corneas-400.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16733,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-volta-a-realizar-captacao-de-multiplos-orgaos\/","url_meta":{"origin":14567,"position":5},"title":"Santa Casa de Sobral volta a realizar capta\u00e7\u00e3o de m\u00faltiplos \u00f3rg\u00e3os","author":"","date":"Junho 14, 2021","format":false,"excerpt":"A realiza\u00e7\u00e3o do procedimento foi interrompida devido \u00e0s dificuldades impostas pela pandemia de Covid- 19. Ascom Complexo SCMS A pandemia de Covid-19 tamb\u00e9m impactou a doa\u00e7\u00e3o de \u00f3rg\u00e3os no pa\u00eds, aumentando ainda mais a expectativa de pacientes que esperam por transplantes. Retomando as atividades de capta\u00e7\u00e3o de \u00f3rg\u00e3os, a Santa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Captacao-de-multiplos-orgaos-2021.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Captacao-de-multiplos-orgaos-2021.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Captacao-de-multiplos-orgaos-2021.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Captacao-de-multiplos-orgaos-2021.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14567"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14567\/revisions"}],"predecessor-version":[{"id":14569,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14567\/revisions\/14569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}