{"id":14591,"date":"2020-11-17T11:29:21","date_gmt":"2020-11-17T14:29:21","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14591"},"modified":"2020-11-17T11:29:21","modified_gmt":"2020-11-17T14:29:21","slug":"tres-fatores-chave-que-aumentam-o-risco-de-morte-por-covid-19","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/tres-fatores-chave-que-aumentam-o-risco-de-morte-por-covid-19\/","title":{"rendered":"Tr\u00eas fatores chave que aumentam o risco de morte por Covid-19"},"content":{"rendered":"<h2 class=\"western\" align=\"justify\"><span style=\"font-size: large;\">O novo coronav\u00edrus SARS-CoV-2, causador da Covid-19, afeta as pessoas de forma diferente &#8211; matando uns, enquanto outros permanecem sem sintomas e desconhecem sequer que est\u00e3o ou estiveram infectados<\/span><\/h2>\n<p align=\"justify\"><span style=\"font-size: large;\">Desde o in\u00edcio da pandemia que se tornou claro que os indiv\u00edduos mais velhos e com problemas pr\u00e9vios de sa\u00fade est\u00e3o em maior risco de ficarem gravemente doentes e morrer de Covid-19.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Contudo, com o passar do tempo os especialistas come\u00e7am a aprender mais sobre o modo como opera este novo coronav\u00edrus. E de acordo com os cientistas, existem determinados elementos chave compartilhados pela maioria das pessoas que morrem v\u00edtimas de Covid.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Uma equipe de investigadores de oito institui\u00e7\u00f5es na China e nos Estados Unidos &#8211; incluindo do Hospital Geral do Ex\u00e9rcito Popular de Liberta\u00e7\u00e3o Chin\u00eas em Beijing e da Universidade da California Davis &#8211; analisaram os dados de 85 pacientes que haviam morrido decorrente da m\u00faltipla fal\u00eancia de \u00f3rg\u00e3os ap\u00f3s terem recebido tratamento para a Covid-19 em estado grave.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Segundo os pesquisadores que realizaram o estudo, divulgado na publica\u00e7\u00e3o <a href=\"https:\/\/www.atsjournals.org\/doi\/10.1164\/rccm.202003-0543OC\" target=\"_blank\" rel=\"noopener noreferrer\">American Journal of Respiratory and Critical Care Medicine<\/a>, existem uma s\u00e9rie de fatores que grande parte destes pacientes tinham em comum.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">1. G\u00eanero<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">O SARS-CoV-2 parece representar uma amea\u00e7a maior para os homens, dizem os cientistas. <\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Os investigadores apuraram que 72.9% das pessoas que morreram de coronav\u00edrus pertenciam ao sexo masculino.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Para os especialistas existem algumas raz\u00f5es que explicam o motivo pela qual e eles morrem mais do que elas, incluindo alguns fatores biol\u00f3gicos e estilo de vida.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Lavar as m\u00e3os \u00e9 uma das melhores formas de prevenir a\u00a0infec\u00e7\u00e3o, por\u00e9m m\u00faltiplos estudos indicam que as mulheres apresentam uma probabilidade mais elevada de o fazer (e de usar sabonete ou sab\u00e3o al\u00e9m de\u00a0\u00e1gua), comparativamente aos homens.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Adicionalmente, h\u00e1bitos como o tabagismo ou doen\u00e7as como a hipertens\u00e3o s\u00e3o mais comuns entre os homens.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Dados apurados na China, apontam que um em cada sete homens com mais de 80 anos que contraiu o v\u00edrus acabou morrendo.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">2. Idade<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Os especialistas salientam que o novo\u00a0coronav\u00edrus n\u00e3o discrimina e que pode infectar<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">pessoas de todas as idades. Todavia, s\u00e3o os adultos de idade mais avan\u00e7ada &#8211; a partir dos 60 anos &#8211; que apresentam um maior risco de ficarem gravemente doentes, sendo que a maioria das mortes por Covid-19 ocorre em pacientes com uma idade m\u00e9dia de 65.8 anos.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Tal deve-se, de acordo com os m\u00e9dicos, ao fato do envelhecimento resultar no enfraquecimento do sistema imunit\u00e1rio, o que faz com que seja mais dif\u00edcil para uma pessoa idosa combater o SARS-CoV-2.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">3. Doen\u00e7as pr\u00e9-existentes<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">No estudo muitos daqueles que morreram de Covid-19 sofriam de problemas de sa\u00fade pr\u00e9vios, tais como de doen\u00e7a cardiovascular, hipertens\u00e3o ou de diabetes.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">&#8220;O maior n\u00famero de mortes na nossa amostra foram homens com mais de 50 anos que sofriam de doen\u00e7as cr\u00f4nicas&#8221;, reportaram os investigadores.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">&#8220;Esperamos que este estudo reitere o qu\u00e3o s\u00e9ria \u00e9 a Covid-19, sobretudo para os grupos de risco e homens com mais de 50 com doen\u00e7as pr\u00e9-existentes, como press\u00e3o alta, doen\u00e7a coron\u00e1ria e diabetes&#8221;, acrescentaram.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: large;\">Outras doen\u00e7as cr\u00f4nicas que elevam o risco de morte entre os pacientes incluem asma, c\u00e2ncer, fibrose c\u00edstica, doen\u00e7a pulmonar cr\u00f4nica obstrutiva (DPCO) e HIV.<\/span><\/p>\n<p align=\"justify\">Fonte: Not\u00edcias Ao Minuto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo coronav\u00edrus SARS-CoV-2, causador da Covid-19, afeta as pessoas de forma diferente &#8211; matando&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/naom_5fb2265324b22-1.jpg","jetpack-related-posts":[{"id":11241,"url":"https:\/\/correiodasemana.com\/site\/mais-de-10-sacerdotes-mortos-pelo-covid-19-na-italia\/","url_meta":{"origin":14591,"position":0},"title":"Mais de 10 sacerdotes mortos pelo Covid-19 na It\u00e1lia","author":"","date":"Mar\u00e7o 24, 2020","format":false,"excerpt":"At\u00e9 o dia 17 de mar\u00e7o, eram esses os sacerdotes que partiram para o Pai. Muitos eram capel\u00e3os em hospitais ou p\u00e1rocos nas \u00e1reas mais infectadas. O mais novo tinha 55 anos e o mais idoso 104. Por Andressa Collet \u2013 Cidade do Vaticano Pela primeira vez, o n\u00famero de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-19-at-10.09.35-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-19-at-10.09.35-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-19-at-10.09.35-1.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12293,"url":"https:\/\/correiodasemana.com\/site\/mais-de-16-milhao-de-pessoas-ja-se-recuperaram-da-covid-19-no-brasil\/","url_meta":{"origin":14591,"position":1},"title":"Mais de 1,6 milh\u00e3o de pessoas j\u00e1 se recuperaram da Covid-19 no Brasil","author":"","date":"Julho 28, 2020","format":false,"excerpt":"SA\u00daDE\/PANDEMIA At\u00e9 o \u00faltimo dia 27 o Brasil j\u00e1 tinha registrado a recupera\u00e7\u00e3o de 1.634.274 pessoas que foram infectadas pelo novo coronav\u00edrus. Os casos confirmados no pa\u00eds j\u00e1 ultrapassam os 2,4 milh\u00f5es. Segundo a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) em todo o mundo mais de 16 milh\u00f5es de pessoas ficaram\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/RECUPERADOS.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11229,"url":"https:\/\/correiodasemana.com\/site\/boletim-da-semana-13\/","url_meta":{"origin":14591,"position":2},"title":"Boletim da Semana","author":"","date":"Mar\u00e7o 18, 2020","format":false,"excerpt":"Organiza\u00e7\u00e3o Mundial da Sa\u00fade declara pandemia de coronav\u00edrus A mudan\u00e7a de classifica\u00e7\u00e3o n\u00e3o se deve \u00e0 gravidade da doen\u00e7a, e sim \u00e0 dissemina\u00e7\u00e3o geogr\u00e1fica r\u00e1pida que o Covid-19 tem apresentado. \u201cA OMS tem tratado da dissemina\u00e7\u00e3o [do Covid-19] em uma escala de tempo muito curta, e estamos muito preocupados com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11306,"url":"https:\/\/correiodasemana.com\/site\/hemocentro-adota-medidas-de-prevencao-ao-covid-19-e-convida-populacao-a-doar-sangue\/","url_meta":{"origin":14591,"position":3},"title":"Hemocentro adota medidas de preven\u00e7\u00e3o ao Covid-19 e convida popula\u00e7\u00e3o a doar sangue","author":"","date":"Mar\u00e7o 24, 2020","format":false,"excerpt":"O Centro de Hematologia e Hemoterapia do Cear\u00e1 (Hemoce), do Governo do Estado, apresenta nesta quarta-feira, 18, a partir das 10h, a nova campanha para doa\u00e7\u00e3o de sangue. Al\u00e9m de refor\u00e7ar a import\u00e2ncia de a popula\u00e7\u00e3o continuar doando, o Hemoce divulga medidas de preven\u00e7\u00e3o em todas as unidades para combater\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/hemoce-doa%C3%A7%C3%A3o-5-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/hemoce-doa%C3%A7%C3%A3o-5-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/hemoce-doa%C3%A7%C3%A3o-5-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/hemoce-doa%C3%A7%C3%A3o-5-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/hemoce-doa%C3%A7%C3%A3o-5-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/hemoce-doa%C3%A7%C3%A3o-5-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18598,"url":"https:\/\/correiodasemana.com\/site\/mais-de-5-mil-casos-de-covid-19-sao-confirmados-no-ceara-em-2022-sobral-ja-registra-2-obitos-para-a-doenca\/","url_meta":{"origin":14591,"position":4},"title":"Mais de 5 mil casos de Covid-19 s\u00e3o confirmados no Cear\u00e1 em 2022; Sobral j\u00e1 registra 2 \u00f3bitos para a doen\u00e7a","author":"","date":"Janeiro 16, 2022","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Segundo com dados da plataforma IntegraSUS, de 1\u00ba a 11 de janeiro de 2022, 5.263 cearenses tiveram diagn\u00f3stico confirmado para Covid-19. A plataforma foi atualizada \u00e0s 10h36 desta quinta-feira, 13. Ainda de acordo com a plataforma, Sobral est\u00e1 entre as cinco cidades com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11397,"url":"https:\/\/correiodasemana.com\/site\/sobral-recebera-10-respiradores-para-auxiliar-na-luta-contra-a-covid-19\/","url_meta":{"origin":14591,"position":5},"title":"Sobral receber\u00e1 10 respiradores para auxiliar na luta contra a covid-19","author":"","date":"Maio 18, 2020","format":false,"excerpt":"O Cear\u00e1 recebeu na tarde desta segunda-feira (18) respiradores e Equipamentos de Prote\u00e7\u00e3o Individual (EPIs) para os profissionais da sa\u00fade que est\u00e3o na linha de frente no combate ao v\u00edrus. O material trazido da China cont\u00e9m 200 respiradores para auxiliar no tratamento dos pacientes com grave quadro cl\u00ednico por coronav\u00edrus.\u2026","rel":"","context":"In &quot;Sa\u00fade&quot;","block_context":{"text":"Sa\u00fade","link":"https:\/\/correiodasemana.com\/site\/category\/saude\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/05\/89E97A53-77FB-403F-899A-B5FD2351B236-300x192.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14591"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14591\/revisions"}],"predecessor-version":[{"id":14594,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14591\/revisions\/14594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14592"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}