{"id":14607,"date":"2020-11-18T11:46:30","date_gmt":"2020-11-18T14:46:30","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14607"},"modified":"2020-11-18T11:46:30","modified_gmt":"2020-11-18T14:46:30","slug":"nucleo-hospitalar-de-epidemiologia-da-santa-casa-de-misericordia-de-sobral-recebe-visita-da-superintendencia-regional-da-saude-norte","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/nucleo-hospitalar-de-epidemiologia-da-santa-casa-de-misericordia-de-sobral-recebe-visita-da-superintendencia-regional-da-saude-norte\/","title":{"rendered":"N\u00facleo Hospitalar de Epidemiologia da Santa Casa de Miseric\u00f3rdia de Sobral recebe visita da Superintend\u00eancia Regional da Sa\u00fade Norte"},"content":{"rendered":"<p style=\"font-weight: 400;\">Visando conhecer os fluxos, funcion\u00e1rios e demandas do N\u00facleo Hospitalar de Epidemiologia (NHE) da Santa Casa de Miseric\u00f3rdia de Sobral (SCMS), que \u00e9 refer\u00eancia em assist\u00eancia em sa\u00fade para 55 munic\u00edpios da regi\u00e3o norte do estado, os farmac\u00eauticos Geilson Cisne e Luc\u00e9lia Pinto &#8211; membros da equipe que comp\u00f5e a Superintend\u00eancia Regional de Sa\u00fade Norte do estado do Cear\u00e1 &#8211; realizaram uma visita ao hospital na quinta-feira (22\/10).<\/p>\n<p style=\"font-weight: 400;\">De acordo com a enfermeira coordenadora do NHE da Santa Casa, Siomara Rodrigues, a visita enfatiza o apoio da superintend\u00eancia com o servi\u00e7o hospitalar:\u00a0<em>\u201cN\u00f3s trabalhamos em rede, no territ\u00f3rio de Sobral, e todas as informa\u00e7\u00f5es colhidas na Santa Casa, repassamos para a epidemiologia municipal, que repassa para a epidemiologia estadual, que no caso \u00e9 a superintend\u00eancia, que tem a fun\u00e7\u00e3o de apoiar e fiscalizar os n\u00facleos de epidemiologia e as vigil\u00e2ncias epidemiol\u00f3gicas da regi\u00e3o norte do estado do Cear\u00e1\u201d<\/em>, destaca Siomara.<\/p>\n<p>Santa Casa de Miseric\u00f3rdia de Sobral<\/p>\n<p>Assessoria de Comunica\u00e7\u00e3o<\/p>\n<p><b><strong>Thais Menezes\/ Henrique Brito\/ Domingos Jr.<\/strong><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visando conhecer os fluxos, funcion\u00e1rios e demandas do N\u00facleo Hospitalar de Epidemiologia (NHE) da Santa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Visita-Superintendencia.jpeg","jetpack-related-posts":[{"id":19843,"url":"https:\/\/correiodasemana.com\/site\/vigilancia-epidemiologica-do-ceara-visita-santa-casa-de-sobral-para-agradecer-parceria-na-transparencia-de-dados\/","url_meta":{"origin":14607,"position":0},"title":"Vigil\u00e2ncia Epidemiol\u00f3gica do Cear\u00e1 visita Santa Casa de Sobral para agradecer parceria na transpar\u00eancia de dados","author":"","date":"Maio 26, 2022","format":false,"excerpt":"Na ocasi\u00e3o, a enfermeira do NHE da Santa Casa foi presenteada com um curso que contribuir\u00e1 para a evolu\u00e7\u00e3o do trabalho em dados epidemiol\u00f3gicos. Ascom Complexo SCMS A dire\u00e7\u00e3o-geral da Santa Casa de Miseric\u00f3rdia de Sobral, na companhia da enfermeira respons\u00e1vel pelo N\u00facleo Hospitalar de Epidemiologia (NHE) da institui\u00e7\u00e3o, Siomara\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/santa-casa-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17022,"url":"https:\/\/correiodasemana.com\/site\/apoiadora-do-ministerio-da-saude-no-ceara-e-vigilancia-epidemiologica-municipal-visitam-santa-casa-de-sobral\/","url_meta":{"origin":14607,"position":1},"title":"Apoiadora do Minist\u00e9rio da Sa\u00fade no Cear\u00e1 e Vigil\u00e2ncia Epidemiol\u00f3gica Municipal visitam Santa Casa de Sobral","author":"","date":"Julho 19, 2021","format":false,"excerpt":"Durante a visita foram discutidos os principais indicadores epidemiol\u00f3gicos do NHE do hospital. Ascom Complexo SCMS Para apresentar o Plano Estadual de Fortalecimento e Amplia\u00e7\u00e3o da Rede Nacional de Vigil\u00e2ncia Epidemiol\u00f3gica Hospitalar (RENAVEH), a Santa Casa de Miseric\u00f3rdia de Sobral (SCMS), por meio do N\u00facleo Hospitalar de Epidemiologia (NHE), recebeu\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Capa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Capa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Capa.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":11218,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-treina-profissionais-para-possiveis-casos-suspeitos-ou-confirmados-do-novo-coronavirus\/","url_meta":{"origin":14607,"position":2},"title":"Santa Casa de Miseric\u00f3rdia de Sobral treina profissionais para poss\u00edveis casos suspeitos ou confirmados do Novo Coronav\u00edrus","author":"","date":"Mar\u00e7o 18, 2020","format":false,"excerpt":"Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) declarou Pandemia depois de mais de 118 mil casos ao redor do mundo e 4.291 mortes nas \u00faltimas semanas. Com objetivo de treinar seus profissionais para correta condu\u00e7\u00e3o da assist\u00eancia a poss\u00edveis casos suspeitos ou confirmados do Novo Coronav\u00edrus (COVID-19), a Santa Casa de Miseric\u00f3rdia\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/1.1-Palestra--scaled-e1584507158838.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/1.1-Palestra--scaled-e1584507158838.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/1.1-Palestra--scaled-e1584507158838.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/1.1-Palestra--scaled-e1584507158838.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/1.1-Palestra--scaled-e1584507158838.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13848,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-recebe-auditoria-da-superintendencia-regional-de-saude-de-sobral\/","url_meta":{"origin":14607,"position":3},"title":"Hospital do Cora\u00e7\u00e3o recebe auditoria da Superintend\u00eancia Regional de Sa\u00fade de Sobral","author":"","date":"Setembro 30, 2020","format":false,"excerpt":"O Hospital do Cora\u00e7\u00e3o recebeu, na sexta-feira (25\/09), a visita de auditores da Superintend\u00eancia Regional de Sa\u00fade de Sobral, representando a Secretaria Estadual de Sa\u00fade do Estado do Cear\u00e1. A a\u00e7\u00e3o tem como objetivo a renova\u00e7\u00e3o da habilita\u00e7\u00e3o da unidade como integrante da Rede de Aten\u00e7\u00e3o de Urg\u00eancia e Emerg\u00eancia\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Auditoria-no-HC.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Auditoria-no-HC.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Auditoria-no-HC.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Auditoria-no-HC.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/Auditoria-no-HC.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14941,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-recebe-visita-do-secretario-executivo-de-atencao-a-saude-e-desenvolvimento-regional\/","url_meta":{"origin":14607,"position":4},"title":"Santa Casa de Miseric\u00f3rdia de Sobral recebe visita do Secret\u00e1rio executivo de Aten\u00e7\u00e3o \u00e0 Sa\u00fade e Desenvolvimento Regional","author":"","date":"Dezembro 7, 2020","format":false,"excerpt":"O gestor conheceu os servi\u00e7os de assist\u00eancia da Santa Casa e os investimentos que a administra\u00e7\u00e3o vem realizando na unidade A Santa Casa de Miseric\u00f3rdia de Sobral recebeu, nesta quarta-feira (02\/12), a visita do Secret\u00e1rio executivo de Aten\u00e7\u00e3o \u00e0 Sa\u00fade e Desenvolvimento Regional do Cear\u00e1, Ivan Coelho. Acompanhado do diretor-geral\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/FOTO-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/FOTO-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/FOTO-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/FOTO-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/FOTO-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/FOTO-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12785,"url":"https:\/\/correiodasemana.com\/site\/as-mortes-eram-constantes-a-rotina-dos-profissionais-da-saude-na-batalha-contra-a-covid-19\/","url_meta":{"origin":14607,"position":5},"title":"As mortes eram constantes\u2019: A rotina dos profissionais da sa\u00fade na batalha contra a Covid-19","author":"","date":"Agosto 17, 2020","format":false,"excerpt":"Com um plant\u00e3o que chega a durar at\u00e9 12h, eles enfrentam o medo e o cansa\u00e7o para dar conta do aumento da demanda) Por Priscila Duarte Reda\u00e7\u00e3o Jornal Correio da Semana Na pandemia, algumas atividades se tornaram essenciais para o combate da Covid-19, dando destaque aos profissionais da sa\u00fade que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-13-at-15.47.09-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-13-at-15.47.09-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-13-at-15.47.09-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-13-at-15.47.09-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-13-at-15.47.09-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14607"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14607\/revisions"}],"predecessor-version":[{"id":14610,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14607\/revisions\/14610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14608"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}