{"id":14656,"date":"2020-11-23T01:34:33","date_gmt":"2020-11-23T04:34:33","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14656"},"modified":"2020-11-23T01:34:33","modified_gmt":"2020-11-23T04:34:33","slug":"hrn-abre-ambulatorio-de-hematologia","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/hrn-abre-ambulatorio-de-hematologia\/","title":{"rendered":"HRN abre ambulat\u00f3rio de hematologia"},"content":{"rendered":"<p>O Hospital Regional Norte, unidade da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado, administrado pelo Instituto de Sa\u00fade e Gest\u00e3o Hospitalar (ISGH) passa a contar com o Ambulat\u00f3rio de Hematologia. O servi\u00e7o \u00e9 destinado a pacientes com doen\u00e7as hematol\u00f3gicas, que comprometem a produ\u00e7\u00e3o dos componentes de sangue, como hem\u00e1cias, leuc\u00f3citos e plaquetas.<br \/>\nO ambulat\u00f3rio recebe pacientes adultos e pedi\u00e1tricos que precisam de um acompanhamento na \u00e1rea de Hematologia e s\u00e3o encaminhados pela Central de Regula\u00e7\u00e3o. \u201cO servi\u00e7o surgiu da necessidade de uma demanda maior que ocorreu no sistema. Temos uma demanda reprimida e o HRN, querendo melhorar o atendimento \u00e0 popula\u00e7\u00e3o, passou a disponibilizar outras especialidades no ambulat\u00f3rio, entre as quais a Hematologia\u201d, afirma a m\u00e9dica hematologista, Ala\u00edde Maria Rodrigues Pinheiro.<br \/>\nAla\u00edde ressalta ainda que existe um desconhecimento da popula\u00e7\u00e3o acerca das doen\u00e7as hematol\u00f3gicas. \u201cComo \u00e9 uma \u00e1rea espec\u00edfica, h\u00e1 peculiaridades que s\u00f3 o especialista pode esclarecer\u201d, avalia. Francisca Fernandes da Silva, 71, \u00e9 uma das pacientes acompanhadas pela equipe do HRN.<br \/>\nMoradora de Camocim, a 100 km de Sobral, a aposentada descobriu que possu\u00eda plaquetas baixas, o que prejudica a coagula\u00e7\u00e3o do sangue, e p\u00farpura, doen\u00e7a que causa manchas roxas ou avermelhadas indicativas de sangramentos na pele. \u201cA m\u00e9dica est\u00e1 aprovada. Trata a gente muito bem e o melhor rem\u00e9dio \u00e9 ser atendido com carinho. A gente j\u00e1 come\u00e7a at\u00e9 a se sentir melhor\u201d, disse sorridente.<br \/>\nInforma\u00e7\u00f5es para a Imprensa: Teresa Fernandes Assessoria de Comunica\u00e7\u00e3o do Hospital Regional Norte (HRN) Tel.:(88) 3677-9515 Ramal: 9515 Cel.:88 9 8883-4263 \/ assessoriadeimprensahrn@isgh.org.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital Regional Norte, unidade da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/ambulatorio-hematologia-3.jpg","jetpack-related-posts":[{"id":15412,"url":"https:\/\/correiodasemana.com\/site\/hrn-capacita-enfermeiros-do-hemoce-para-tratamento-de-lesoes-em-pacientes-com-doenca-falciforme\/","url_meta":{"origin":14656,"position":0},"title":"HRN capacita enfermeiros do Hemoce para tratamento de les\u00f5es em pacientes com doen\u00e7a falciforme","author":"","date":"Janeiro 18, 2021","format":false,"excerpt":"Capacita\u00e7\u00e3o aborda, entre outros assuntos, tratamento de \u00falceras em pacientes com anemia falciforme atendidos Por Joc\u00e9lio Tavares. Com informa\u00e7\u00f5es de Teresa Fernandes. O Hospital Regional Norte (HRN), da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado, est\u00e1 capacitando enfermeiros para o tratamento de les\u00f5es decorrentes da anemia falciforme,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/curso-HRN-e-Hemoce-1-768x569-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/curso-HRN-e-Hemoce-1-768x569-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/curso-HRN-e-Hemoce-1-768x569-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/curso-HRN-e-Hemoce-1-768x569-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37453,"url":"https:\/\/correiodasemana.com\/site\/campanha-de-carnaval-da-santa-casa-mobiliza-doadores-e-arrecada-quase-400-bolsas-de-sangue\/","url_meta":{"origin":14656,"position":1},"title":"Campanha de Carnaval da Santa Casa mobiliza doadores e arrecada quase 400 bolsas de sangue","author":"adminredacao","date":"Fevereiro 20, 2026","format":false,"excerpt":"A Campanha de Doa\u00e7\u00e3o de Sangue \u201cCarnaval 2026\u201d da Santa Casa de Miseric\u00f3rdia de Sobral alcan\u00e7ou um recorde com 397 bolsas arrecadadas e 458 candidatos \u00e0 doa\u00e7\u00e3o. A a\u00e7\u00e3o solid\u00e1ria ocorreu entre os dias 10 e 12 de fevereiro e envolveu colaboradores do hospital, al\u00e9m de acompanhantes de pacientes. O\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/Doacao-de-sangue.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/Doacao-de-sangue.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/Doacao-de-sangue.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/Doacao-de-sangue.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30628,"url":"https:\/\/correiodasemana.com\/site\/hemoce-sobral-recebe-doadores-em-novo-espaco\/","url_meta":{"origin":14656,"position":2},"title":"Hemoce Sobral recebe doadores em novo espa\u00e7o","author":"adminredacao","date":"Setembro 9, 2024","format":false,"excerpt":"Os doadores do munic\u00edpio de Sobral e da Regi\u00e3o Norte passam a contar, a partir desta sexta-feira (6), com um novo espa\u00e7o para doa\u00e7\u00e3o de sangue, plaquetas e cadastro de medula \u00f3ssea. A\u00a0Unidade de Atendimento ao Doador do Hemocentro Regional de Sobral\u00a0fica instalada no\u00a0Centro de Conven\u00e7\u00f5es da cidade, localizado na\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Novo-espaco-ja-esta-preparado-para-receber-os-doadores-de-Sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Novo-espaco-ja-esta-preparado-para-receber-os-doadores-de-Sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Novo-espaco-ja-esta-preparado-para-receber-os-doadores-de-Sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/Novo-espaco-ja-esta-preparado-para-receber-os-doadores-de-Sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10689,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-realizou-mais-de-5-700-transfusoes-de-sangue-em-2019\/","url_meta":{"origin":14656,"position":3},"title":"Santa Casa de Miseric\u00f3rdia de Sobral realizou mais de 5.700 transfus\u00f5es de sangue em 2019","author":"","date":"Fevereiro 3, 2020","format":false,"excerpt":"Os pacientes atendidos pelos diversos servi\u00e7os oferecidos pela Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) contam com a agilidade e rapidez do Servi\u00e7o de Hemoterapia, uma ag\u00eancia de banco de sangue e seus componentes, abastecidos diretamente pelo Hemoce Em 2019, o Servi\u00e7o de Hemoterapia realizou mais de 5.700 transfus\u00f5es de\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/banco.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/banco.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/banco.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":23902,"url":"https:\/\/correiodasemana.com\/site\/ambulatorio-de-avc-do-hrn-em-sobral-acompanha-pacientes-apos-alta-hospitalar\/","url_meta":{"origin":14656,"position":4},"title":"Ambulat\u00f3rio de AVC do HRN, em Sobral, acompanha pacientes ap\u00f3s alta hospitalar","author":"adminredacao","date":"Abril 11, 2023","format":false,"excerpt":"Os pacientes egressos da Unidade de Acidente Vascular Cerebral (AVC) do Hospital Regional Norte (HRN), em Sobral, passaram a ser acompanhados pelo atendimento ambulatorial do equipamento. Iniciado em mar\u00e7o deste ano, o servi\u00e7o oferece assist\u00eancia com m\u00e9dico neurologista. Cerca de 40 pessoas j\u00e1 foram beneficiadas. O espa\u00e7o possui 20 leitos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Arteriografia-cerebral-Maria-do-Socorro-de-Lima-Bruno-2-2-2-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Arteriografia-cerebral-Maria-do-Socorro-de-Lima-Bruno-2-2-2-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Arteriografia-cerebral-Maria-do-Socorro-de-Lima-Bruno-2-2-2-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Arteriografia-cerebral-Maria-do-Socorro-de-Lima-Bruno-2-2-2-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Arteriografia-cerebral-Maria-do-Socorro-de-Lima-Bruno-2-2-2-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/Arteriografia-cerebral-Maria-do-Socorro-de-Lima-Bruno-2-2-2-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":9181,"url":"https:\/\/correiodasemana.com\/site\/a-secretaria-de-servicos-publicos-sesep-em-parceria-com-o-instituto-de-formacao-para-o-trabalho-infort-e-o-centro-de-hematologia-e-hemoterapia-do-ceara-hemoce-realiza-acoes-solidarias\/","url_meta":{"origin":14656,"position":5},"title":"A Secretaria de Servi\u00e7os P\u00fablicos (SESEP) em parceria com o Instituto de Forma\u00e7\u00e3o para o Trabalho (INFORT) e o Centro de Hematologia e Hemoterapia do Cear\u00e1 (HEMOCE) realiza a\u00e7\u00f5es solid\u00e1rias","author":"","date":"Setembro 23, 2019","format":false,"excerpt":"A Secretaria de Servi\u00e7os P\u00fablicos (SESEP) em parceria com o Instituto de Forma\u00e7\u00e3o para o Trabalho (INFORT) e o Centro de Hematologia e Hemoterapia do Cear\u00e1 (HEMOCE) realizou na ter\u00e7a-feira (17) por meio de uma equipe de profissionais da sa\u00fade, coletas de doa\u00e7\u00e3o de sangue. Al\u00e9m de realizar essa a\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_3100.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_3100.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_3100.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_3100.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_3100.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/DSC_3100.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14656"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14656\/revisions"}],"predecessor-version":[{"id":14658,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14656\/revisions\/14658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14657"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}