{"id":14705,"date":"2020-11-24T10:25:52","date_gmt":"2020-11-24T13:25:52","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14705"},"modified":"2020-11-24T10:25:52","modified_gmt":"2020-11-24T13:25:52","slug":"parlamento-europeu-quer-tirar-700-mil-sem-abrigo-das-ruas-ate-2030","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/parlamento-europeu-quer-tirar-700-mil-sem-abrigo-das-ruas-ate-2030\/","title":{"rendered":"Parlamento Europeu quer tirar 700 mil sem-abrigo das ruas at\u00e9 2030"},"content":{"rendered":"<div class=\"col-lg-12 mb-3\">\n<div class=\"row\">\n<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">Apelo foi feito por parlamentares \u00e0 Uni\u00e3o Europeia<\/h3>\n<\/div>\n<\/div>\n<div class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<div class=\"post-item alt-font\">\n<div class=\"post-item-wrap\">\n<p>O Parlamento Europeu apelou\u00a0hoje (24) aos Estados-membros da Uni\u00e3o Europeia (UE) para adotarem medidas a fim de\u00a0tirar das ruas at\u00e9 2030 todos os sem-abrigo, cujo n\u00famero aumentou 70% na \u00faltima d\u00e9cada para 700 mil.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1394324&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1394324&amp;o=node\" \/><\/p>\n<p>Em resolu\u00e7\u00e3o\u00a0aprovada nesta ter\u00e7a-feira na sess\u00e3o plen\u00e1ria da assembleia europeia, que ocorre\u00a0em Bruxelas, na B\u00e9lgica, os eurodeputados destacam\u00a0que &#8220;a habita\u00e7\u00e3o \u00e9 um direito humano fundamental e pedem a\u00e7\u00e3o mais robusta por parte da Comiss\u00e3o Europeia e dos Estados-membros para erradicar o problema dos sem-abrigo at\u00e9 2030&#8221;.<\/p>\n<p>No texto, aprovado com 647 votos a favor, 13 contra e 32 absten\u00e7\u00f5es, o Parlamento Europeu cita\u00a0a situa\u00e7\u00e3o prec\u00e1ria dos mais de 700 mil sem-abrigo na Europa, n\u00famero que aumentou 70% nos \u00faltimos dez anos.<\/p>\n<p>Os eurodeputados sugerem v\u00e1rias medidas a serem adotadas pelos pa\u00edses da UE para atingir esse objetivo, entre elas\u00a0assumir a responsabilidade de enfrentar o problema e trabalhar na preven\u00e7\u00e3o e interven\u00e7\u00e3o precoce e apostar na descriminaliza\u00e7\u00e3o da situa\u00e7\u00e3o de sem-abrigo, na garantia de acesso igual aos servi\u00e7os p\u00fablicos (cuidados de sa\u00fade, educa\u00e7\u00e3o e servi\u00e7os sociais) e ainda no apoio \u00e0 integra\u00e7\u00e3o no mercado de trabalho.<\/p>\n<p>&#8220;Os Estados-membros devem tamb\u00e9m adotar o princ\u00edpio de `Habita\u00e7\u00e3o Primeiro`, que ajuda a reduzir significativamente o n\u00famero de sem-abrigo por meio\u00a0da introdu\u00e7\u00e3o de planos de a\u00e7\u00e3o e abordagens inovadoras baseadas no conceito de um lar enquanto direito humano fundamental&#8221;, dizem os parlamentares\u00a0no documento.<\/p>\n<p>Al\u00e9m disso, para acabar com o problema dos sem-abrigo, a Comiss\u00e3o Europeia dever\u00e1 apoiar os Estados-membros, melhorar o monitoramento, manter as contribui\u00e7\u00f5es financeiras e apresentar um quadro europeu de estrat\u00e9gias nacionais para essa popula\u00e7\u00e3o&#8221;, acrescentam.<\/p>\n<p>A assembleia europeia quer\u00a0ainda\u00a0que sejam alocadas verbas do novo Quadro Financeiro Plurianual (2021-2027) e do Mecanismo de Recupera\u00e7\u00e3o e Resili\u00eancia para melhorar as oportunidades de trabalho e a integra\u00e7\u00e3o social dos agregados familiares sem emprego.<\/p>\n<p>O texto\u00a0aprovado tem por base peti\u00e7\u00f5es que chegaram \u00e0 comiss\u00e3o parlamentar encarregada\u00a0dessas iniciativas de cidadania sobre o &#8220;aumento do n\u00famero de pessoas sem abrigo da UE&#8221;, apelando \u00e0 ado\u00e7\u00e3o de medidas.<\/p>\n<p>Em meio \u00e0 severa crise na Europa gerada pela pandemia de covid-19, alguns relat\u00f3rios admitem que essa perda de rendimentos possa levar a um incremento no n\u00famero de sem-abrigo.<\/p>\n<p>Por RTP &#8211; Lisboa<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apelo foi feito por parlamentares \u00e0 Uni\u00e3o Europeia O Parlamento Europeu apelou\u00a0hoje (24) aos Estados-membros&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/2017-11-06t124948z_1_lynxmpeda50zy_rtroptp_3_swiss-politics.jpg","jetpack-related-posts":[{"id":23626,"url":"https:\/\/correiodasemana.com\/site\/terremoto-na-turquia-e-siria-ja-se-aproximam-de-40-mil-mortos\/","url_meta":{"origin":14705,"position":0},"title":"Terremoto na Turquia e S\u00edria j\u00e1 se aproximam de 40 mil mortos","author":"","date":"Fevereiro 15, 2023","format":false,"excerpt":"ONU prev\u00ea aumento acelerado do contingente \u00e0 medida que as buscas e resgates s\u00e3o realizados nos territ\u00f3rios abalados. O \u00faltimo balan\u00e7o de v\u00edtimas do terremoto de magnitude 7,8 que atingiu o sul da Turquia e noroeste da S\u00edria aponta que o n\u00famero de mortos pela trag\u00e9dia se aproxima de 40\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/terremoto-na-siria-e-turquia-750x450-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/terremoto-na-siria-e-turquia-750x450-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/terremoto-na-siria-e-turquia-750x450-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/terremoto-na-siria-e-turquia-750x450-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14136,"url":"https:\/\/correiodasemana.com\/site\/brasil-e-banco-americano-assinam-acordo-de-us-1-bi-em-investimentos\/","url_meta":{"origin":14705,"position":1},"title":"Brasil e banco americano assinam acordo de US$ 1 bi em investimentos","author":"","date":"Outubro 20, 2020","format":false,"excerpt":"Recursos podem ser aplicados em tecnologia 5G e infraestrutura O Banco de Exporta\u00e7\u00e3o e Importa\u00e7\u00e3o dos Estados Unidos (EximBank) e o governo brasileiro assinaram hoje (20) um acordo para investimentos de at\u00e9 US$ 1 bilh\u00e3o (R$ 5,6 bilh\u00f5es) no Brasil. O Exim e o Minist\u00e9rio da Economia concordam em identificar\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/50509052943_fdb22433d0_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/50509052943_fdb22433d0_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/50509052943_fdb22433d0_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/50509052943_fdb22433d0_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/50509052943_fdb22433d0_o.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":29580,"url":"https:\/\/correiodasemana.com\/site\/educacao-e-cidadania-51\/","url_meta":{"origin":14705,"position":2},"title":"EDUCA\u00c7\u00c3O E CIDADANIA \u2022","author":"adminredacao","date":"Junho 10, 2024","format":false,"excerpt":"Cuidar do Meio Ambiente O mundo j\u00e1 se deparou com seis confer\u00eancias mundiais sobre o meio ambiente. Mesmo com tantos debates nesses encontros n\u00e3o se chegou ainda a um denominador comum para se cumprir com todos os objetivos acordados. A Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) promoveu o primeiro evento de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12682,"url":"https:\/\/correiodasemana.com\/site\/pais-deve-registrar-625-mil-novos-casos-de-cancer-ate-2022\/","url_meta":{"origin":14705,"position":3},"title":"Pa\u00eds deve registrar 625 mil novos casos de c\u00e2ncer at\u00e9 2022","author":"","date":"Agosto 10, 2020","format":false,"excerpt":"O oncologista Ramon Andrade de Mello relaciona alta com adiamento do tratamento durante a pandemia A pandemia do novo coronav\u00edrus alterou a rotina das pessoas e uma parcela significativa dos pacientes deixou de procurar um especialista para diagn\u00f3sticos e outros adiaram o tratamento. Em Portugal, um estudo recente do Sistema\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/cancer.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/cancer.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/cancer.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/cancer.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11229,"url":"https:\/\/correiodasemana.com\/site\/boletim-da-semana-13\/","url_meta":{"origin":14705,"position":4},"title":"Boletim da Semana","author":"","date":"Mar\u00e7o 18, 2020","format":false,"excerpt":"Organiza\u00e7\u00e3o Mundial da Sa\u00fade declara pandemia de coronav\u00edrus A mudan\u00e7a de classifica\u00e7\u00e3o n\u00e3o se deve \u00e0 gravidade da doen\u00e7a, e sim \u00e0 dissemina\u00e7\u00e3o geogr\u00e1fica r\u00e1pida que o Covid-19 tem apresentado. \u201cA OMS tem tratado da dissemina\u00e7\u00e3o [do Covid-19] em uma escala de tempo muito curta, e estamos muito preocupados com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/200130165125-corona-virus-cdc-image-exlarge-tease.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13029,"url":"https:\/\/correiodasemana.com\/site\/papa-defende-vacina-anti-covid-acessivel-a-todos\/","url_meta":{"origin":14705,"position":5},"title":"Papa defende vacina anti-Covid acess\u00edvel a todos","author":"","date":"Agosto 24, 2020","format":false,"excerpt":"Palavras do Papa encontram resson\u00e2ncia em v\u00e1rios organismos e iniciativas, a come\u00e7ar pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade Na terceira Audi\u00eancia Geral dedicada \u00e0 pandemia, o Papa Francisco afirmou que seria triste se uma vacina contra a Covi-19 fosse dada a prioridade aos ricos e que a assist\u00eancia econ\u00f4mica com dinheiro\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/vacinacovid.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/vacinacovid.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/vacinacovid.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14705"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14705\/revisions"}],"predecessor-version":[{"id":14708,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14705\/revisions\/14708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14706"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}