{"id":14850,"date":"2020-12-01T16:44:21","date_gmt":"2020-12-01T19:44:21","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14850"},"modified":"2020-12-01T16:44:21","modified_gmt":"2020-12-01T19:44:21","slug":"camara-pode-votar-novo-minha-casa-minha-vida-nesta-quarta","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/camara-pode-votar-novo-minha-casa-minha-vida-nesta-quarta\/","title":{"rendered":"C\u00e2mara pode votar novo Minha Casa Minha Vida nesta quarta"},"content":{"rendered":"<p>Est\u00e1 marcada para a quarta-feira (2) a vota\u00e7\u00e3o da Medida Provis\u00f3ria 996\/20, que cria o programa habitacional\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/tag\/casa-verde-e-amarela\/\"><strong>Casa Verde e Amarela<\/strong><\/a>\u00a0para financiar a constru\u00e7\u00e3o e pequenas reformas de resid\u00eancias para fam\u00edlias com at\u00e9 R$ 7 mil de renda mensal na \u00e1rea urbana e com at\u00e9 R$ 84 mil de renda ao ano na \u00e1rea rural.<\/p>\n<p>O programa substitui o\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/tag\/minha-casa-minha-vida\/\"><strong>Minha Casa, Minha Vida<\/strong><\/a>, criado em 2009 no governo do ex-presidente Lula (PT). As principais diferen\u00e7as entre os dois programas s\u00e3o o financiamento de melhorias em habita\u00e7\u00f5es j\u00e1 constru\u00eddas e o aumento dos valores totais dos im\u00f3veis que poder\u00e3o ser financiados.<\/p>\n<p>As taxas de juros devem ficar em torno de 5% ao ano, mas para os estados do Norte e do Nordeste podem chegar a 4,5% ou mesmo 4,25%, a depender\u00a0da faixa de renda familiar. Outra novidade \u00e9 o financiamento da regulariza\u00e7\u00e3o fundi\u00e1ria urbana.<\/p>\n<h5><strong>Vacina de Oxford<\/strong><\/h5>\n<p>Tamb\u00e9m est\u00e1 na pauta de vota\u00e7\u00e3o de quarta a MP 994\/20, que destina cr\u00e9dito extraordin\u00e1rio de R$ 1,995 bilh\u00e3o para viabilizar a compra de tecnologia e a produ\u00e7\u00e3o de vacinas contra o novo coronav\u00edrus. O dinheiro se refere a contrato entre a Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz), vinculada ao Minist\u00e9rio da Sa\u00fade, e o laborat\u00f3rio AstraZeneca. A empresa desenvolve uma vacina contra a covid-19 em parceria com a Universidade de Oxford, no Reino Unido.<\/p>\n<p>A vacina de Oxford est\u00e1 em fase de testes com volunt\u00e1rios no Brasil e em outros pa\u00edses. A inten\u00e7\u00e3o \u00e9 produzir 100 milh\u00f5es de doses, com previs\u00e3o de distribui\u00e7\u00e3o da vacina por meio do Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<div class=\"post-meta-wrap clearfix\">\n<div class=\"post-meta single-post-meta\"><a class=\"post-author-a post-author-avatar\" title=\"Artigos de autor\" href=\"https:\/\/congressoemfoco.uol.com.br\/author\/admin\/\"><span class=\"post-author-name\">Por\u00a0<b>Congresso Em Foco<\/b><\/span><\/a><\/div>\n<\/div>\n<p>Fonte: Congresso em Foco.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 marcada para a quarta-feira (2) a vota\u00e7\u00e3o da Medida Provis\u00f3ria 996\/20, que cria o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/2432afb4-1ac6-47c6-97df-535155b704ce-720x430-1.jpeg","jetpack-related-posts":[{"id":13162,"url":"https:\/\/correiodasemana.com\/site\/casa-verde-e-amarela-incluira-1-milhao-de-familias-no-credito-imobiliario\/","url_meta":{"origin":14850,"position":0},"title":"Casa Verde e Amarela incluir\u00e1 1 milh\u00e3o de fam\u00edlias no cr\u00e9dito imobili\u00e1rio","author":"","date":"Agosto 26, 2020","format":false,"excerpt":"O Programa Casa Verde e Amarela, do Minist\u00e9rio do Desenvolvimento Regional (MDR), vai facilitar o acesso da popula\u00e7\u00e3o a uma moradia digna, garantindo mais qualidade de vida. A partir de medidas que garantir\u00e3o efici\u00eancia na aplica\u00e7\u00e3o dos recursos, a meta \u00e9 atender 1,6 milh\u00e3o de fam\u00edlias de baixa renda com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/33-1536x1024-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":33245,"url":"https:\/\/correiodasemana.com\/site\/como-vai-funcionar-a-nova-faixa-do-minha-casa-minha-vida-para-quem-ganha-ate-r-12-mil\/","url_meta":{"origin":14850,"position":1},"title":"Como vai funcionar a nova faixa do Minha Casa, Minha Vida para quem ganha at\u00e9 R$ 12 mil","author":"adminredacao","date":"Abril 7, 2025","format":false,"excerpt":"Faixa 4 do programa habitacional foi anunciada nesta quinta-feira e visa contemplar p\u00fablico de classe m\u00e9dia Por Jean Laurindo O governo federal anunciou na quinta-feira uma nova divis\u00e3o do programa Minha Casa, Minha Vida para atender fam\u00edlias que possuem renda de at\u00e9 R$ 12 mil. A novidade consiste na cria\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/minha-casa-minha-vida-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/minha-casa-minha-vida-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/minha-casa-minha-vida-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/minha-casa-minha-vida-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/minha-casa-minha-vida-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28986,"url":"https:\/\/correiodasemana.com\/site\/no-ceara-5-768-moradias-sao-selecionadas-no-minha-casa-minha-vida-rural-e-entidades\/","url_meta":{"origin":14850,"position":2},"title":"No Cear\u00e1, 5.768 moradias s\u00e3o selecionadas no Minha Casa, Minha Vida Rural e Entidades","author":"adminredacao","date":"Abril 22, 2024","format":false,"excerpt":"Fonte:\u00a0Secretaria de Comunica\u00e7\u00e3o Social da Presid\u00eancia da Rep\u00fablica O Cear\u00e1 foi contemplado com 5.768 unidades habitacionais do Minha Casa, Minha Vida nas modalidades Rural e Entidades. O resultado da sele\u00e7\u00e3o foi anunciado pelo Governo Federal na \u00faltima quarta-feira, 10 de abril. Essas modalidades garantem moradia tanto para comunidades urbanas organizadas\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/c602fbd6-c596-4bab-b34d-fd88e8db1afc.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/c602fbd6-c596-4bab-b34d-fd88e8db1afc.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/c602fbd6-c596-4bab-b34d-fd88e8db1afc.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/c602fbd6-c596-4bab-b34d-fd88e8db1afc.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/c602fbd6-c596-4bab-b34d-fd88e8db1afc.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/c602fbd6-c596-4bab-b34d-fd88e8db1afc.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13154,"url":"https:\/\/correiodasemana.com\/site\/bolsonaro-rebatiza-minha-casa-minha-vida-reduz-juros-e-mira-norte-e-nordeste\/","url_meta":{"origin":14850,"position":3},"title":"Bolsonaro rebatiza Minha Casa, Minha Vida, reduz juros e mira Norte e Nordeste","author":"","date":"Agosto 25, 2020","format":false,"excerpt":"O governo lan\u00e7ou hoje, em cerim\u00f4nia no Pal\u00e1cio do Planalto,\u00a0o programa habitacional Casa Verde e Amarela, novo nome do Minha Casa, Minha Vida. O lan\u00e7amento \u00e9 a primeira iniciativa do presidente\u00a0Jair Bolsonaro\u00a0(sem partido) de tentar criar sua pr\u00f3pria marca social. Lan\u00e7ado em 2009, o Minha Casa, Minha Vida \u00e9 uma\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Bolsonaro-lanca-programa-habitacional-Casa-Verde-e-Amarela.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12658,"url":"https:\/\/correiodasemana.com\/site\/governo-federal-altera-regras-no-programa-minha-casa-minha-vida\/","url_meta":{"origin":14850,"position":4},"title":"Governo federal altera regras no programa Minha Casa, Minha Vida","author":"","date":"Agosto 10, 2020","format":false,"excerpt":"ECONOMIA Portaria estabelece novos crit\u00e9rios aos benefici\u00e1rios da faixa 1 do programa, que contempla fam\u00edlias com renda familiar mensal de at\u00e9 R$ 1,8 mil O Governo Federal anunciou mudan\u00e7as no programa de habita\u00e7\u00e3o Minha Casa, Minha Vida. As novas regras s\u00e3o v\u00e1lidas aos benefici\u00e1rios da faixa 1 do programa, que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/minha-casa-minha-vida.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/minha-casa-minha-vida.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/minha-casa-minha-vida.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/minha-casa-minha-vida.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12191,"url":"https:\/\/correiodasemana.com\/site\/projeto-de-socorro-a-agricultores-familiares-e-aprovado-pela-camara-dos-deputados\/","url_meta":{"origin":14850,"position":5},"title":"Projeto de socorro a agricultores familiares \u00e9 aprovado pela C\u00e2mara dos Deputados","author":"","date":"Julho 25, 2020","format":false,"excerpt":"Texto ainda ser\u00e1 avaliado pelos senadores; PL inclui grupo entre os benefici\u00e1rios do aux\u00edlio emergencial e suspende d\u00edvidas, entre outras medidas A C\u00e2mara dos Deputados aprovou na \u00faltima segunda-feira (20) uma s\u00e9rie de medidas emergenciais que visam ajudar agricultores familiares impactados pela crise econ\u00f4mica em decorr\u00eancia da pandemia da Covid-19.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14850"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14850\/revisions"}],"predecessor-version":[{"id":14853,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14850\/revisions\/14853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14851"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}