{"id":14872,"date":"2020-12-02T09:31:55","date_gmt":"2020-12-02T12:31:55","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14872"},"modified":"2020-12-02T09:31:55","modified_gmt":"2020-12-02T12:31:55","slug":"centrao-e-oposicao-assinam-manifesto-contra-reeleicao-de-maia-e-davi","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/centrao-e-oposicao-assinam-manifesto-contra-reeleicao-de-maia-e-davi\/","title":{"rendered":"Centr\u00e3o e oposi\u00e7\u00e3o assinam manifesto contra reelei\u00e7\u00e3o de Maia e Davi"},"content":{"rendered":"<div class=\"post-header post-tp-1-header\">\n<div class=\"single-featured\">\n<figure>Partidos do Centr\u00e3o e da oposi\u00e7\u00e3o se manifestaram nesta ter\u00e7a-feira (1\u00ba) contra a reelei\u00e7\u00e3o dos atuais presidentes da C\u00e2mara, <a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/174693\/perfil\"><strong>Rodrigo Maia<\/strong><\/a>\u00a0(DEM-RJ), e do Senado,\u00a0<a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/23830\/perfil\"><strong>Davi Alcolumbre<\/strong><\/a>\u00a0(DEM-AP). Em uma carta direcionada \u00e0 na\u00e7\u00e3o brasileira e ao Supremo Tribunal Federal, as dire\u00e7\u00f5es nacionais das siglas pressionam para que os atuais presidentes n\u00e3o possam concorrer \u00e0 reelei\u00e7\u00e3o em fevereiro de 2021.<\/figure>\n<\/div>\n<\/div>\n<div class=\"entry-content clearfix single-post-content on\">\n<p>Os ministros do STF v\u00e3o analisar nos pr\u00f3ximos dias\u00a0a A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 6.524, pela qual\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/legislativo\/ptb-vai-ao-stf-contra-reeleicao-de-maia-e-davi-alcolumbre\/\"><strong>o PTB contesta a possibilidade\u00a0de recondu\u00e7\u00e3o dos presidentes<\/strong><\/a>. A a\u00e7\u00e3o ser\u00e1 julgada em plen\u00e1rio virtual, entre os dias 4 a 11 de dezembro, sob relatoria do ministro\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/tag\/gilmar-mendes\/\"><strong>Gilmar Mendes<\/strong><\/a><\/p>\n<div class=\"bs-irp left bs-irp-text-2\">\n<div class=\"bs-pagination-wrapper main-term-none none \">\n<div class=\"listing listing-text listing-text-2 clearfix columns-1\">\n<div class=\"post-470122 type-post format-standard has-post-thumbnail   listing-item listing-item-text listing-item-text-2 main-term-28378\">\n<div class=\"item-inner\"><\/div>\n<\/div>\n<div class=\"post-470356 type-post format-standard has-post-thumbnail   listing-item listing-item-text listing-item-text-2 main-term-28376\">\n<div class=\"item-inner\">\n<div class=\"post-meta\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"iframe-container\"><iframe src=\"https:\/\/drive.google.com\/file\/d\/1j800i0tIK8eUIMv3bXlZyUYg67F6o6OB\/preview\" width=\"640\" height=\"480\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p>Atualmente, a Constitui\u00e7\u00e3o e os regimentos internos das duas Casas impedem a reelei\u00e7\u00e3o dentro de uma mesma legislatura, que \u00e9 o per\u00edodo de quatro anos que coincide com um mandato de deputado federal. S\u00f3 \u00e9 permitida a recondu\u00e7\u00e3o se ela ocorrer de uma legislatura para a seguinte. Tanto Davi quanto Maia foram eleitos pelos seus pares em fevereiro de 2019.<\/p>\n<p>Assinam a carta as seguintes siglas: PP, PL, PSD, Avante, Patriota, Solidariedade, PSC, PSB, Rede e Cidadania. Apesar de o Psol constar como signat\u00e1rio, a assessoria do partido informou que houve um equ\u00edvoco e que nem a bancada, nem a sigla assinaram o documento. Ainda assim, a bancada do partido na C\u00e2mara se diz contra a reelei\u00e7\u00e3o.<\/p>\n<p>\u201cUm Congresso Nacional forte \u00e9 aquele que respeita os ideais da temporalidade dos\u00a0 mandatos e do revezamento da dire\u00e7\u00e3o da suas respectivas Casas. Mudar este curso hist\u00f3rico fere o princ\u00edpio constitucional da veda\u00e7\u00e3o ao retrocesso democr\u00e1tico e se constituiu em um casu\u00edsmo tacanho que n\u00e3o combina com a tradi\u00e7\u00e3o do Supremo Tribunal Federal\u201d, diz o texto.<\/p>\n<p>As siglas classificam as tentativas de recondu\u00e7\u00e3o de \u201catitudes individualistas de extrapola\u00e7\u00e3o e excessos do exerc\u00edcio do poder\u201d.<\/p>\n<p>Os presidentes Rodrigo Maia e Davi Alcolumbre foram procurados, mas a reportagem ainda n\u00e3o teve retorno. De todo modo, Maia tem refor\u00e7ado que n\u00e3o \u00e9 candidato \u00e0 reelei\u00e7\u00e3o. Ontem (30) ele disse ao UOL que n\u00e3o pretende concorrer ao cargo novamente, ainda que permitido pelo STF.<\/p>\n<p>Maia tenta emplacar um aliado como seu sucessor e tenta, inclusive, arregimentar o apoio da esquerda, que deve ser o fiel da balan\u00e7a na disputa. Os principais cotados s\u00e3o os deputados\u00a0<strong><a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/1178975\/perfil\">Baleia Rossi<\/a>\u00a0<\/strong>(MDB-SP),\u00a0<strong><a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/1160527\/perfil\">Aguinaldo Ribeiro<\/a>\u00a0<\/strong>(PP-PB),\u00a0<strong><a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/1204506\/perfil\">Marcos Pereira<\/a><\/strong>\u00a0(Republicanos-SP) e\u00a0<strong><a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/174478\/perfil\">Luciano Bivar<\/a><\/strong>\u00a0(PSL-PE). O Centr\u00e3o, por outro lado, tem candidato pr\u00f3prio, o atual l\u00edder do bloc\u00e3o,\u00a0<a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/1160541\/perfil\"><strong>Arthur Lira<\/strong><\/a>\u00a0(PP-AL), pr\u00f3ximo de\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/tag\/jair-bolsonaro\/\"><strong>Jair Bolsonaro<\/strong><\/a>.<\/p>\n<p>J\u00e1 Davi coloca seu nome \u00e0 disposi\u00e7\u00e3o e n\u00e3o nega a inten\u00e7\u00e3o de concorrer a um segundo mandato de presidente.\u00a0Al\u00e9m do DEM, ele deve contar com o apoio do Republicanos, PP, PL e PDT. Com uma bancada de seis senadores,\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/legislativo\/pt-avalia-apoiar-reeleicao-de-davi-alcolumbre-a-presidencia-do-senado\/\"><strong>o PT\u00a0avalia apoiar o atual presidente para mais um mandato de dois anos<\/strong><\/a>. Em 2019, o partido esteve com o ex-presidente\u00a0<a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/270\/perfil\"><strong>Renan Calheiros<\/strong><\/a>\u00a0(MDB-AL).<\/p>\n<p>No Senado, a maioria dos poss\u00edveis candidatos \u00e0 sucess\u00e3o tem evitado apresentar seus nomes at\u00e9 o momento. O MDB, que tem tradi\u00e7\u00e3o de ocupar\u00a0a presid\u00eancia do Senado e possui a maior bancada da Casa, ainda mant\u00e9m compasso de espera e\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/legislativo\/resolucao-interna-para-viabilizar-reeleicao-de-davi-ganha-forca-no-senado\/\"><strong>formalmente\u00a0apoia a reelei\u00e7\u00e3o de Davi<\/strong><\/a>.<\/p>\n<h5><strong>Nota de senadores<\/strong><\/h5>\n<p>Em outro documento, senadores de diferentes legendas defendem que n\u00e3o h\u00e1\u00a0\u201cqualquer omiss\u00e3o ou lacuna a ser preenchida pelo caminho da interpreta\u00e7\u00e3o\u201d.\u00a0\u201cTentar alterar por via judicial essa escolha pol\u00edtico representa evidente subvers\u00e3o \u00e0 separa\u00e7\u00e3o dos poderes, verdadeiro atentado contra o estado democr\u00e1tico de direito\u201d, diz o texto assinado por senadores do\u00a0Cidadania, Podemos, Rede, PSL, PSDB e PP.<\/p>\n<p>O documento dos senadores cita ainda\u00a0<a href=\"https:\/\/congressoemfoco.uol.com.br\/legislativo\/parecer-da-consultoria-do-senado-e-contra-a-reeleicao-de-davi-alcolumbre\/\"><strong>nota t\u00e9cnica da Consultoria Legislativa do Senado<\/strong><\/a>\u00a0que considerou que \u00e9 vedada a reelei\u00e7\u00e3o para os mesmos cargos dentro da mesma legislatura.\u00a0\u00a0O parecer foi feito a pedido do senador\u00a0<strong><a class=\"parlLink\" href=\"https:\/\/radar.congressoemfoco.com.br\/parlamentar\/25982\/perfil\">Alessandro Vieira<\/a>\u00a0<\/strong>(Cidadania-SE), que foi um dos cabos eleitorais de Davi na sua primeira elei\u00e7\u00e3o para o cargo, mas hoje \u00e9 contr\u00e1rio \u00e0 sua reelei\u00e7\u00e3o por consider\u00e1-la irregular.<\/p>\n<p><a class=\"post-author-a post-author-avatar\" title=\"Artigos de autor\" href=\"https:\/\/congressoemfoco.uol.com.br\/author\/marina-oliveira\/\"><span class=\"post-author-name\">Por\u00a0<b>Marina Oliveira<\/b><\/span><\/a>\u00a0<a class=\"post-author-a post-author-avatar\" title=\"Artigos de autor\" href=\"https:\/\/congressoemfoco.uol.com.br\/author\/flaviasaid\/\"><span class=\"post-author-name\"><span class=\"author-separator\">\u00a0e<\/span>\u00a0<b>Fl\u00e1via Said<\/b><\/span><\/a><\/p>\n<p>Fonte: Congresso em Foco<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Partidos do Centr\u00e3o e da oposi\u00e7\u00e3o se manifestaram nesta ter\u00e7a-feira (1\u00ba) contra a reelei\u00e7\u00e3o dos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/49868387852_6cf197f8e5_k-750x430-1.jpg","jetpack-related-posts":[{"id":14908,"url":"https:\/\/correiodasemana.com\/site\/stf-vota-pela-inconstitucionalidade-da-reeleicao-de-maia-e-alcolumbre\/","url_meta":{"origin":14872,"position":0},"title":"STF vota pela inconstitucionalidade da reelei\u00e7\u00e3o de Maia e Alcolumbre","author":"","date":"Dezembro 7, 2020","format":false,"excerpt":"Vota\u00e7\u00e3o final ficou em 7 a 4 contra a Maia e 6 a 5 contra Alcolumbre O Supremo Tribunal Federal (STF) decidiu, no fim da noite desse domingo (6), durante sess\u00e3o de julgamento em plen\u00e1rio virtual, que os atuais presidentes da C\u00e2mara, Rodrigo Maia (DEM-RJ); e do Senado, Davi Alcolumbre\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/stf_1908200974.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/stf_1908200974.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/stf_1908200974.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/stf_1908200974.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/stf_1908200974.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":23100,"url":"https:\/\/correiodasemana.com\/site\/arthur-lira-aumenta-auxilio-moradia-dos-deputados\/","url_meta":{"origin":14872,"position":1},"title":"Arthur Lira aumenta aux\u00edlio-moradia dos deputados","author":"","date":"Janeiro 25, 2023","format":false,"excerpt":"Benef\u00edcio ter\u00e1 reajuste de 56%, passando de R$ 4.253 para R$ 6.654; pol\u00edtico \u00e9 favorito na disputa pelo comando da Casa. Os deputados federais v\u00e3o come\u00e7ar a nova legislatura, em fevereiro, com o aumento de 56% no valor do valor aux\u00edlio moradia. O benef\u00edcio passa dos R$ 4.253 para R$\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/fivzy2xwqaib8p.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/fivzy2xwqaib8p.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/fivzy2xwqaib8p.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14858,"url":"https:\/\/correiodasemana.com\/site\/estamos-caminhando-a-passos-largos-para-o-precipicio-diz-maia\/","url_meta":{"origin":14872,"position":2},"title":"Estamos caminhando a passos largos para o precip\u00edcio, diz Maia","author":"","date":"Dezembro 1, 2020","format":false,"excerpt":"Em live promovida pelo jornal\u00a0Valor Econ\u00f4mico\u00a0nesta segunda-feira (2), o presidente da C\u00e2mara,\u00a0Rodrigo Maia\u00a0(DEM-RJ), criticou a postura do governo com rela\u00e7\u00e3o \u00e0 agenda econ\u00f4mica. O deputado afirmou que est\u00e1 mais preocupado agora com a situa\u00e7\u00e3o do pa\u00eds do que em julho. \u201cHoje j\u00e1 n\u00e3o \u00e9 mais uma quest\u00e3o do que a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/rodrigo-maia-luis-macedo-camara-dos-deputados-750x430-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/rodrigo-maia-luis-macedo-camara-dos-deputados-750x430-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/rodrigo-maia-luis-macedo-camara-dos-deputados-750x430-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/rodrigo-maia-luis-macedo-camara-dos-deputados-750x430-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13639,"url":"https:\/\/correiodasemana.com\/site\/eleicoes-2020-conheca-os-candidatos-que-estao-na-disputa-em-sobral\/","url_meta":{"origin":14872,"position":3},"title":"Elei\u00e7\u00f5es 2020: conhe\u00e7a os candidatos que est\u00e3o na disputa em Sobral","author":"","date":"Setembro 21, 2020","format":false,"excerpt":"Ber\u00e7o pol\u00edtico da c\u00fapula do PDT no Estado do Cear\u00e1, o munic\u00edpio de Sobral deve ter uma disputa polarizada entre o atual prefeito, Ivo Gomes, e o opositor, Dr. Oscar Rodrigues. Maior col\u00e9gio eleitoral da regi\u00e3o Norte e quinto maior do Estado do Cear\u00e1, a cidade de Sobral deve ter\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/eleicoes-sobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/eleicoes-sobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/eleicoes-sobral.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":33890,"url":"https:\/\/correiodasemana.com\/site\/ccj-do-senado-aprova-fim-da-reeleicao-para-presidente-prefeitos-e-governadores\/","url_meta":{"origin":14872,"position":4},"title":"CCJ do Senado aprova fim da reelei\u00e7\u00e3o para presidente, prefeitos e governadores","author":"adminredacao","date":"Junho 3, 2025","format":false,"excerpt":"Proposta tamb\u00e9m amplia a dura\u00e7\u00e3o de mandatos e unifica data das elei\u00e7\u00f5es municipais e nacionais. Texto vai ao plen\u00e1rio. Por\u00a0Kevin Lima, g1\u00a0\u2014 Bras\u00edlia A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) do\u00a0Senado\u00a0aprovou na quarta-feira (21) uma\u00a0Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) que acaba com a reelei\u00e7\u00e3o\u00a0para prefeitos, governadores e presidente da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/eleicoes-2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/eleicoes-2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/eleicoes-2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/eleicoes-2022.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23298,"url":"https:\/\/correiodasemana.com\/site\/novo-congresso-toma-posse-nesta-quarta-1\/","url_meta":{"origin":14872,"position":5},"title":"Novo Congresso toma posse nesta quarta (1) fevereiro","author":"","date":"Fevereiro 1, 2023","format":false,"excerpt":"Nesta quarta-feira, 1\u00ba, inicia-se oficialmente a\u00a053\u00aa legislatura do\u00a0Congresso Nacional, com a posse de deputados federais e senadores eleitos e reeleitos no dia 2 de outubro do ano passado. Os primeiros exercer\u00e3o um mandato no quadri\u00eanio 2023-2027. Os integrantes da Casa Alta do Parlamento brasileiro, por sua vez, ter\u00e3o oito anos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14872"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14872\/revisions"}],"predecessor-version":[{"id":14875,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14872\/revisions\/14875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14873"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}