{"id":14965,"date":"2020-12-07T22:30:54","date_gmt":"2020-12-08T01:30:54","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14965"},"modified":"2020-12-07T22:30:54","modified_gmt":"2020-12-08T01:30:54","slug":"dezembro-chegou","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/dezembro-chegou\/","title":{"rendered":"DEZEMBRO CHEGOU&#8230;"},"content":{"rendered":"<p>Anualmente preparo-me para receber o m\u00eas de dezembro, m\u00eas no qual a hist\u00f3ria da humanidade se dividiu em antes e depois do principal aniversariante: Jesus, Deus-Menino. Este ano o tempo foi passando&#8230; E acumulamos expectativas, perdas e ganhos. E, de repente, n\u00e3o mais que de repente, como dizia Vin\u00edcius de Moraes, o m\u00eas mais belo chegou. Ainda vemos l\u00e1grimas nos olhos, preces nos l\u00e1bios, risos contidos, esperan\u00e7as sempre renovadas. O m\u00eas do Natal chegou. Vivemos literalmente o tempo das esperas. \u00c9 advento e aguardamos a chegada de Deus-Menino. Desde que me entendo por gente \u00e9 o m\u00eas de dezembro mais emblem\u00e1tico. O medo povoa o mundo, mas, a certeza de que Deus n\u00e3o nos desampara nunca nos faz esperar&#8230; Esperar, como diz o Padre Zezinho, contra toda a esperan\u00e7a e eu ouso dizer contra toda desesperan\u00e7a. Esperamos sempre e Deus nos guiar\u00e1!<br \/>\nAs ruas j\u00e1 est\u00e3o mais iluminadas, as ceias de Natal este ano ser\u00e3o reservadas a fam\u00edlias. O tempo n\u00e3o \u00e9 f\u00e1cil, mas, se tornar\u00e1 f\u00e1cil, pois o Deus-Menino-Ternura nos conduzir\u00e1 ao milagre t\u00e3o esperado: o fim da pandemia. Certamente nos abra\u00e7aremos sem temor, sem receios e celebraremos, lembrando: Deus \u00e9 maior, guiou seu povo \u00e0 Terra Prometida e agora o conduz \u00e0 cura f\u00edsica! Alguns n\u00e3o conseguiram chegar a esse dia e a tristeza deseja se tornar saudade. Poucos s\u00e3o os que n\u00e3o sentir\u00e3o falta de algu\u00e9m neste m\u00eas. Aquela liga\u00e7\u00e3o, aquele e-mail, aquela mensagem n\u00e3o tem mais endere\u00e7o certo. N\u00e3o podemos enviar nada al\u00e9m de ora\u00e7\u00f5es e preces aos c\u00e9us. Os olhos marejam, mas, a vida segue. Deus quer que sejamos felizes e seguiremos. Viveremos. Esperaremos. Sempre e por tudo daremos gl\u00f3rias a Deus.<br \/>\nToda essa viv\u00eancia de meses nos ensinou. Nos ensina. \u00c9 preciso que sa\u00edamos dessa \u201cbatalha\u201d melhores do que quando come\u00e7amos. Lembro-me da Semana Santa, t\u00e3o diferente. A imagem do \u00fanico verdadeiramente Chefe de Estado desse per\u00edodo, caminhando sozinho numa Pra\u00e7a que sempre re\u00fane o mundo para encontrar o Crucificado e aos p\u00e9s dele juntar suas l\u00e1grimas \u00e0s \u00e1guas da chuva fina que ca\u00eda naquela Pra\u00e7a de S\u00e3o Pedro. Obrigado, Senhor, pelo testemunho do Santo Padre, o Papa Francisco. Lembrar-me-ei sempre daqueles que sa\u00edram \u00e0s ruas para a caridade e aqui \u00e9 preciso citar um santo homem que perambula pelas ruas da maior cidade deste Pa\u00eds e que sempre me emociona por sua coragem e hero\u00edsmo: Padre J\u00falio Lancellotti. Que Deus o proteja sempre, Pe. J\u00falio e multiplique homens e mulheres com sua coragem, seu amor e zelo pelo pr\u00f3ximo!<br \/>\nE o pr\u00f3ximo dia 8 \u00e9, mundialmente, a Solenidade da Imaculada Concei\u00e7\u00e3o de Nossa Senhora para celebrarmos a pureza daquela que trouxe Deus ao mundo. N\u00e3o \u00e9 exagero a afirma\u00e7\u00e3o. Foi de Maria Sant\u00edssima, Nossa Senhora, ou, simplesmente, a M\u00e3e de todos, que nasceu Jesus. Deus que se humanizou na ternura de uma crian\u00e7a e ensinou-nos a amar o pr\u00f3ximo como a n\u00f3s mesmos! Salve!<br \/>\n\u00c9 este tamb\u00e9m, no Brasil, o dia da fam\u00edlia e da Justi\u00e7a. As celebra\u00e7\u00f5es se irmanam. Sendo eu devoto da M\u00e3e de Deus, oriundo de uma fam\u00edlia \u00e0 qual tento me dedicar e ter escolhido a Justi\u00e7a para nela viver, sou muito feliz com essas festividades. Festividades, sim. Com contratempos ou n\u00e3o, alegremo-nos. Respiremos o ar puro que Deus nos envia e a Ele confiemos o futuro, o Natal, o ano novo, o amanh\u00e3. Am\u00e9m!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anualmente preparo-me para receber o m\u00eas de dezembro, m\u00eas no qual a hist\u00f3ria da humanidade&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,41],"tags":[],"class_list":["post-14965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-jose-luis-lira"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose\u0301-1.jpg","jetpack-related-posts":[{"id":36686,"url":"https:\/\/correiodasemana.com\/site\/herculano-costa-5\/","url_meta":{"origin":14965,"position":0},"title":"Herculano Costa","author":"adminredacao","date":"Dezembro 11, 2025","format":false,"excerpt":"O Advento do Natal! Final de ano. \u00daltimo m\u00eas do Ano. Dezembro chega alegre, cheio de ternura, como uma brisa suave que sussurra esperan\u00e7a. Iniciamos h\u00e1 seis dias o m\u00eas de dezembro \u2014 um tempo que, mais do que marcar o fim de um ciclo, desperta em n\u00f3s a delicada\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/Herculano-Costa.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":36728,"url":"https:\/\/correiodasemana.com\/site\/novena-de-natal\/","url_meta":{"origin":14965,"position":1},"title":"Novena de Natal\u00a0","author":"adminredacao","date":"Dezembro 11, 2025","format":false,"excerpt":"Ao longo do tempo do Advento somos convidados a nos preparar bem para o Natal do Senhor por meio da Novena de Natal. Podemos realizar a Novena de Natal ao longo de todo o Advento; podemos reunir familiares, amigos e a comunidade para rez\u00e1-la uma ou duas vezes por semana,\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31993,"url":"https:\/\/correiodasemana.com\/site\/antifonas-em-o\/","url_meta":{"origin":14965,"position":2},"title":"Ant\u00edfonas em \u00d3\u00a0","author":"adminredacao","date":"Dezembro 24, 2024","format":false,"excerpt":"Entre os dias 17 e 23 de dezembro entramos propriamente no per\u00edodo da Semana de Prepara\u00e7\u00e3o pr\u00f3xima do Natal, antecedendo a vinda de Nosso Senhor, vivemos um per\u00edodo de expecta\u00e7\u00e3o, por isso, por esses dias celebramos a mem\u00f3ria lit\u00fargica de Nossa Senhora da Expecta\u00e7\u00e3o, N. Sra. do Parto ou Nossa\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15512,"url":"https:\/\/correiodasemana.com\/site\/esperanca-3\/","url_meta":{"origin":14965,"position":3},"title":"ESPERAN\u00c7A!","author":"","date":"Janeiro 24, 2021","format":false,"excerpt":"Costuma-se definir 31 de dezembro o dia da Esperan\u00e7a. N\u00e3o h\u00e1 registro nos calend\u00e1rios c\u00edvicos desta comemora\u00e7\u00e3o, contudo, nos habituamos a desejar um feliz ano novo e todos os anos fazemos isto. Rezamos. Comemoramos. Celebramos. Ano passado foi diferente, mas, a presen\u00e7a da esperan\u00e7a era percebida aqui e alhures. Domingo\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18195,"url":"https:\/\/correiodasemana.com\/site\/o-tempo-da-espera-confiante\/","url_meta":{"origin":14965,"position":4},"title":"O tempo da espera confiante","author":"","date":"Novembro 28, 2021","format":false,"excerpt":"A Igreja em todo o mundo se prepara para o in\u00edcio de mais um Ano Lit\u00fargico, com a chegada do tempo do Advento. Somos mais uma vez introduzidos nesse per\u00edodo de espera confiante no Senhor Jesus, que vem como sinal de salva\u00e7\u00e3o para todos os povos. E nesse clima, somos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27440,"url":"https:\/\/correiodasemana.com\/site\/o-tempo-da-espera-confiante-2\/","url_meta":{"origin":14965,"position":5},"title":"O tempo da espera confiante","author":"adminredacao","date":"Dezembro 4, 2023","format":false,"excerpt":"A Igreja em todo o mundo se prepara para o in\u00edcio de mais um Ano Lit\u00fargico, com a chegada do tempo do Advento. Somos mais uma vez introduzidos nesse per\u00edodo de espera confiante no Senhor Jesus, que vem como sinal de salva\u00e7\u00e3o para todos os povos. E nesse clima, somos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14965"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14965\/revisions"}],"predecessor-version":[{"id":14966,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14965\/revisions\/14966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7874"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}