{"id":14999,"date":"2020-12-14T15:43:12","date_gmt":"2020-12-14T18:43:12","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=14999"},"modified":"2020-12-14T15:43:12","modified_gmt":"2020-12-14T18:43:12","slug":"cai-numero-de-municipios-que-enviam-residuos-a-lixoes-diz-associacao","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/cai-numero-de-municipios-que-enviam-residuos-a-lixoes-diz-associacao\/","title":{"rendered":"Cai n\u00famero de munic\u00edpios que enviam res\u00edduos a lix\u00f5es, diz associa\u00e7\u00e3o"},"content":{"rendered":"<div class=\"col-lg-12 mb-3\">\n<div class=\"row\">\n<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">Descarte incorreto de res\u00edduos caiu de 3,2 mil para 2,7 mil cidades<\/h3>\n<\/div>\n<\/div>\n<div class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<div class=\"post-item alt-font\">\n<div class=\"post-item-wrap\">\n<p>A destina\u00e7\u00e3o dos res\u00edduos s\u00f3lidos em cada um dos 5.570 munic\u00edpios brasileiros foi mapeada pela Associa\u00e7\u00e3o Brasileira de Empresas de Tratamento de Res\u00edduos e Efluentes (Abetre), que constatou que 2,7 mil cidades descartam os res\u00edduos incorretamente em locais como lix\u00f5es.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1396385&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1396385&amp;o=node\" \/><\/p>\n<p>Apurado em setembro, o n\u00famero representa um avan\u00e7o em rela\u00e7\u00e3o ao primeiro trimestre do ano, quando 3.257 munic\u00edpios davam destina\u00e7\u00e3o incorreta aos res\u00edduos s\u00f3lidos, o que inclui lix\u00f5es em seu pr\u00f3prio territ\u00f3rio, lix\u00f5es em cidades vizinhas, ou os chamados aterros controlados que, diferentemente dos aterros sanit\u00e1rios, n\u00e3o incluem cuidados como a impermeabiliza\u00e7\u00e3o do solo.<\/p>\n<p>O trabalho teve como base as informa\u00e7\u00f5es prestadas ao Sistema Nacional de Informa\u00e7\u00f5es sobre a Gest\u00e3o de Res\u00edduos S\u00f3lidos (Sinir) e foi publicado na internet como uma plataforma interativa, que pode ser acessada por qualquer pessoa no\u00a0<a href=\"http:\/\/abetre.org.br\/atlas-da-destinacao-final-de-residuos-brasil-2020\/\" target=\"_blank\" rel=\"noopener\"><em>site\u00a0<\/em><\/a>da associa\u00e7\u00e3o. Para o presidente da Abetre, Luiz Gonzaga, a mudan\u00e7a foi impulsionada pelos prazos estabelecidos no novo Marco Legal do Saneamento, sancionado em julho.<\/p>\n<p>&#8220;Com a promulga\u00e7\u00e3o do Marco Legal do Saneamento, n\u00f3s verificamos que os novos prazos foram dados, e os prefeitos come\u00e7aram a trabalhar em cima deles. Uma das coisas que a gente notou \u00e9 que havia uma quantidade importante de prefeitos que n\u00e3o poderiam se reeleger e n\u00e3o queriam deixar o munic\u00edpio em situa\u00e7\u00e3o irregular, sob pena de aplica\u00e7\u00e3o da Lei de Responsabilidade Fiscal&#8221;, disse o presidente da Abetre. &#8220;Verificamos que muitos prefeitos contrataram aterros privados pr\u00f3ximos dos seus munic\u00edpios. Antes, eles n\u00e3o queriam ter esse \u00f4nus, mas essa quest\u00e3o da responsabilidade fiscal levou a isso. Outra coisa que verificamos \u00e9 que come\u00e7aram a surgir pedidos de organismos estaduais de meio ambiente, o que tamb\u00e9m contribuiu para que a situa\u00e7\u00e3o fosse aos poucos se transformando&#8221;.<\/p>\n<p>Com os prazos estabelecidos pelo Marco Legal do Saneamento, Gonzaga disse acreditar que o mapa tende a mudar para melhor nos pr\u00f3ximos anos. A lei sancionada em junho d\u00e1 o prazo para o fim dos lix\u00f5es: 2 de agosto de 2021 para capitais e regi\u00f5es metropolitanas; 2 de agosto de 2022, para cidades com mais de 100 mil habitantes; 2 de agosto 2023 para as que t\u00eam entre 50 e 100 mil habitantes; e 2 de agosto de 2024 as que t\u00eam menos de 50 mil habitantes.<\/p>\n<p>&#8220;A gente espera vencer, em prazo de um a tr\u00eas anos, essa letargia dos \u00faltimos anos, porque agora os prefeitos n\u00e3o v\u00e3o poder falar mais que n\u00e3o t\u00eam dinheiro para fazer&#8221;, afirmou Gonzaga. Ele lembrou que a lei tamb\u00e9m tornou obrigat\u00f3rio que o estabelecimento de uma tarifa de cobran\u00e7a pela coleta de lixo pelos munic\u00edpios, visando \u00e0 sustentabilidade da presta\u00e7\u00e3o do servi\u00e7o.<\/p>\n<p>O levantamento tamb\u00e9m contabiliza que 2.707 munic\u00edpios d\u00e3o destina\u00e7\u00f5es finais consideradas adequadas aos res\u00edduos s\u00f3lidos, em aterros sanit\u00e1rios privados, municipais ou intermunicipais, ou aterros em vala. Fora esses, 136 munic\u00edpios de Minas Gerais adotam usinas de triagem e compostagem e sete cidades do Cear\u00e1 contratam terceiros para a incinera\u00e7\u00e3o dos res\u00edduos.<\/p>\n<p>O n\u00famero de munic\u00edpios que destinam corretamente os res\u00edduos \u00e9 mais baixo em estados da Regi\u00e3o Norte, como o Amazonas, onde tr\u00eas dos 62 munic\u00edpios foram assim classificados no mapa da Abetre. No Par\u00e1, seis das 144 cidades est\u00e3o na mesma situa\u00e7\u00e3o. A exce\u00e7\u00e3o \u00e9 Rond\u00f4nia, onde h\u00e1 43 cidades com a destina\u00e7\u00e3o considerada correta e nove que recorrem a solu\u00e7\u00f5es irregulares.<\/p>\n<p>De acordo com Gonzaga, Santa Catarina \u00e9 o estado mais bem posicionado no pa\u00eds em rela\u00e7\u00e3o \u00e0 destina\u00e7\u00e3o final dos res\u00edduos s\u00f3lidos. Segundo o mapa, nenhuma cidade do estado transporta os res\u00edduos para lix\u00f5es ou aterros controlados, e as solu\u00e7\u00f5es adotadas s\u00e3o aterros sanit\u00e1rios privados, municipais ou consorciados entre mais de um munic\u00edpio. S\u00e3o Paulo e Alagoas tamb\u00e9m n\u00e3o t\u00eam munic\u00edpios dependentes de lix\u00f5es, segundo a associa\u00e7\u00e3o.<\/p>\n<p>Apesar dos problemas nas regi\u00f5es Norte, Nordeste e Centro-Oeste, o mapa da Abetre mostra que os estados de Alagoas e Rond\u00f4nia est\u00e3o acima da m\u00e9dia de suas regi\u00f5es. Alagoas foi o primeiro fora do eixo Sul-Sudeste a adotar aterros regionais, existindo em todo o estado com cinco aterros. J\u00e1 em Rond\u00f4nia, aterros sanit\u00e1rios privados em Cacoal e Vilhena, um aterro municipal em Candeias do Jamari e um consorciado em Ariquemes atendem boa parte do sul e leste do estado.<\/p>\n<p>Apesar dos problemas nas regi\u00f5es Norte, Nordeste e Centro-Oeste, o mapa da Abetre mostra que os estados de Alagoas e Rond\u00f4nia est\u00e3o acima da m\u00e9dia de suas regi\u00f5es. Alagoas foi o primeiro fora do eixo Sul-Sudeste a adotar aterros regionais, atendendo todo o estado com cinco aterros. J\u00e1 em Rond\u00f4nia, aterros sanit\u00e1rios privados em Cacoal e Vilhena, um aterro municipal em Candeias do Jamari, e um aterro consorciado em Ariquemes atendem boa parte do sul e leste do estado.<\/p>\n<p>Ao discutir a destina\u00e7\u00e3o dos res\u00edduos s\u00f3lidos em um semin\u00e1rio promovido pelo Banco Nacional do Desenvolvimento Econ\u00f4mico e Social (BNDES), em 3 de dezembro, Ricardo Salles afirmou que o saneamento urbano, o que inclui a gest\u00e3o dos res\u00edduos s\u00f3lidos, \u00e9 a maior quest\u00e3o ambiental a ser resolvida no pa\u00eds.<\/p>\n<p>As solu\u00e7\u00f5es para esses problemas, na vis\u00e3o do ministro, precisam ser flex\u00edveis para se adequar \u00e0s diferen\u00e7as que se apresentam nas regi\u00f5es brasileiras, com munic\u00edpios de diferentes dimens\u00f5es populacionais e territoriais.<\/p>\n<p>Por Vin\u00edcius Lisboa &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Descarte incorreto de res\u00edduos caiu de 3,2 mil para 2,7 mil cidades A destina\u00e7\u00e3o dos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/img_20170331_154553970.jpg","jetpack-related-posts":[{"id":10283,"url":"https:\/\/correiodasemana.com\/site\/central-de-tratamento-de-residuos-e-inaugurada-em-sobral\/","url_meta":{"origin":14999,"position":0},"title":"Central de Tratamento de Res\u00edduos \u00e9 inaugurada em Sobral","author":"","date":"Dezembro 23, 2019","format":false,"excerpt":"Buscando reduzir o n\u00famero de lix\u00f5es no Cear\u00e1, o Governo do Cear\u00e1 inaugurou, neste s\u00e1bado (14), a Central de Tratamento dos Res\u00edduos do Vale do Acara\u00fa (CTR Sobral), em Sobral. Foram inauguradas tamb\u00e9m seis Esta\u00e7\u00f5es de Transbordo de Res\u00edduos (ETRs): Corea\u00fa (uma na sede e outra no distrito de Ubauna),\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/INAUGURA%C3%87%C3%83O-CENTRAL-DE-RESIDUOS-S%C3%93LIDOS-DE-SOBRAL-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/INAUGURA%C3%87%C3%83O-CENTRAL-DE-RESIDUOS-S%C3%93LIDOS-DE-SOBRAL-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/INAUGURA%C3%87%C3%83O-CENTRAL-DE-RESIDUOS-S%C3%93LIDOS-DE-SOBRAL-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/INAUGURA%C3%87%C3%83O-CENTRAL-DE-RESIDUOS-S%C3%93LIDOS-DE-SOBRAL-4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/INAUGURA%C3%87%C3%83O-CENTRAL-DE-RESIDUOS-S%C3%93LIDOS-DE-SOBRAL-4.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/INAUGURA%C3%87%C3%83O-CENTRAL-DE-RESIDUOS-S%C3%93LIDOS-DE-SOBRAL-4.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12460,"url":"https:\/\/correiodasemana.com\/site\/metade-das-cidades-brasileiras-ainda-despeja-lixo-a-ceu-aberto-e-58-delas-nao-tem-sustentabilidade-financeira-para-tratar-os-residuos-revela-estudo\/","url_meta":{"origin":14999,"position":1},"title":"Metade das cidades brasileiras ainda despeja lixo a c\u00e9u aberto e 58% delas n\u00e3o t\u00eam sustentabilidade financeira para tratar os res\u00edduos, revela estudo","author":"","date":"Agosto 4, 2020","format":false,"excerpt":"Dez anos ap\u00f3s a promulga\u00e7\u00e3o da Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos, pa\u00eds ainda est\u00e1 longe de atingir as metas estabelecidas na lei H\u00e1 exatos dez anos, entrava em vigor em todo o territ\u00f3rio brasileiro a Pol\u00edtica Nacional de Res\u00edduos S\u00f3lidos, estabelecendo um prazo de quatro anos para os munic\u00edpios providenciarem\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/8yQjZ0ImN6InYu02bj5SYuFWblNXYk9WalJncvNGQvF2YhRWZypDO1MjM4cTN5cjOnVGcq5SM2MDNxgjNzIjMGJTJzIjMGJTJ3QjM1YkMlUjMwMTMf1SNx0yXt92YuIHct1SaGJTJGJTJBNTJwRHdopTO.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/8yQjZ0ImN6InYu02bj5SYuFWblNXYk9WalJncvNGQvF2YhRWZypDO1MjM4cTN5cjOnVGcq5SM2MDNxgjNzIjMGJTJzIjMGJTJ3QjM1YkMlUjMwMTMf1SNx0yXt92YuIHct1SaGJTJGJTJBNTJwRHdopTO.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/8yQjZ0ImN6InYu02bj5SYuFWblNXYk9WalJncvNGQvF2YhRWZypDO1MjM4cTN5cjOnVGcq5SM2MDNxgjNzIjMGJTJzIjMGJTJ3QjM1YkMlUjMwMTMf1SNx0yXt92YuIHct1SaGJTJGJTJBNTJwRHdopTO.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/8yQjZ0ImN6InYu02bj5SYuFWblNXYk9WalJncvNGQvF2YhRWZypDO1MjM4cTN5cjOnVGcq5SM2MDNxgjNzIjMGJTJzIjMGJTJ3QjM1YkMlUjMwMTMf1SNx0yXt92YuIHct1SaGJTJGJTJBNTJwRHdopTO.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/8yQjZ0ImN6InYu02bj5SYuFWblNXYk9WalJncvNGQvF2YhRWZypDO1MjM4cTN5cjOnVGcq5SM2MDNxgjNzIjMGJTJzIjMGJTJ3QjM1YkMlUjMwMTMf1SNx0yXt92YuIHct1SaGJTJGJTJBNTJwRHdopTO.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":33059,"url":"https:\/\/correiodasemana.com\/site\/a-saude-do-planeta-e-a-sustentabilidade-da-vida-ii\/","url_meta":{"origin":14999,"position":2},"title":"A Sa\u00fade do Planeta e a Sustentabilidade da Vida (II)","author":"adminredacao","date":"Mar\u00e7o 24, 2025","format":false,"excerpt":"(Continua\u00e7\u00e3o da edi\u00e7\u00e3o anterior) LIXO DOM\u00c9STICO - O lixo que produzimos todos os dias surge nos diversos setores de nossas atividades. O lixo org\u00e2nico, no caso, vem dos restos de comida ou dos restos de prepara\u00e7\u00e3o desta. Acumulam-se na lixeira da nossa cozinha. H\u00e1 outras lixeiras em nossas casas, em\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/Herculano-Costa.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8549,"url":"https:\/\/correiodasemana.com\/site\/lixeiras-implantadas-em-sobral-possuem-inspiracao-em-grandes-centros-urbanos-como-nova-york-e-buenos-aires\/","url_meta":{"origin":14999,"position":3},"title":"Lixeiras implantadas em Sobral possuem inspira\u00e7\u00e3o em grandes centros urbanos como Nova York e Buenos Aires","author":"","date":"Agosto 6, 2019","format":false,"excerpt":"700 lixeiras destinadas ao descarte de res\u00edduos secos ser\u00e3o espalhadas pela cidade em \u00e1reas de maior circula\u00e7\u00e3o. Primeira fase fixar\u00e1 200 unidades nas principais vias do centro do munic\u00edpio e durar\u00e1 cerca de quatro meses Visando uma solu\u00e7\u00e3o pr\u00e1tica e essencial para o descarte adequado de res\u00edduos secos na cidade\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/DSC7561.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8297,"url":"https:\/\/correiodasemana.com\/site\/fiscais-da-ama-e-guardas-ambientais-notificam-pessoas-e-empresas-que-insistem-em-jogar-lixo-nas-ruas\/","url_meta":{"origin":14999,"position":4},"title":"Fiscais da AMA e guardas ambientais notificam pessoas e empresas que insistem em jogar lixo nas ruas","author":"","date":"Julho 16, 2019","format":false,"excerpt":"Ao longo da \u00faltima semana, servidores da Ag\u00eancia Municipal do Meio Ambiente (AMA) realizaram a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o ambiental nos bairros Junco, Alto da Bras\u00edlia, Centro e Sinh\u00e1 Saboia. A atividade tamb\u00e9m contou com a presen\u00e7a da rec\u00e9m-criada Guarda Ambiental. As fiscaliza\u00e7\u00f5es seguir\u00e3o ativas no munic\u00edpio No caso de carroceiros, que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/DSC_0030.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/DSC_0030.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/DSC_0030.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/DSC_0030.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/DSC_0030.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/DSC_0030.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10494,"url":"https:\/\/correiodasemana.com\/site\/o-lixo-e-sua-destinacao\/","url_meta":{"origin":14999,"position":5},"title":"O LIXO E SUA DESTINA\u00c7\u00c3O","author":"","date":"Janeiro 22, 2020","format":false,"excerpt":"Os costumes e valores que terminaram por reinarem no s\u00e9culo XX; frente a um novo mil\u00eanio, n\u00e3o ser\u00e1 mais poss\u00edvel fugir a uma ampla discurs\u00e3o acerca dos problemas advindos da errada destina\u00e7\u00e3o do lixo no Brasil. Como se sabe, o lixo atua silencioso todos os dias como a fome, a\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/2eb1b9e7-5e8d-45f8-ba25-371bc8ae2e3c.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/2eb1b9e7-5e8d-45f8-ba25-371bc8ae2e3c.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/2eb1b9e7-5e8d-45f8-ba25-371bc8ae2e3c.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/2eb1b9e7-5e8d-45f8-ba25-371bc8ae2e3c.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=14999"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14999\/revisions"}],"predecessor-version":[{"id":15002,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/14999\/revisions\/15002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15000"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=14999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=14999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=14999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}