{"id":15217,"date":"2020-12-27T23:33:01","date_gmt":"2020-12-28T02:33:01","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15217"},"modified":"2020-12-27T23:33:01","modified_gmt":"2020-12-28T02:33:01","slug":"santa-casa-de-misericordia-de-sobral-elege-diretoria-executiva-2021-2024-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-elege-diretoria-executiva-2021-2024-2\/","title":{"rendered":"Santa Casa de Miseric\u00f3rdia de Sobral elege Diretoria Executiva 2021\/2024"},"content":{"rendered":"<p>Vota\u00e7\u00e3o contou com a participa\u00e7\u00e3o do provedor do Complexo Santa Casa, Bispo Dom Jos\u00e9 Luiz Gomes de Vasconcelos<\/p>\n<p>Ascom Complexo SCMS<br \/>\nA Associa\u00e7\u00e3o da Santa Casa de Miseric\u00f3rdia de Sobral se reuniu e elegeu, nesta segunda-feira (21\/12), a Diretoria Executiva para o pr\u00f3ximo quadri\u00eanio (2021\/2024). A elei\u00e7\u00e3o aconteceu no Audit\u00f3rio S\u00e3o Jo\u00e3o Paulo II, no CETRESO, e teve a participa\u00e7\u00e3o do provedor do Complexo Santa Casa, Bispo Dom Jos\u00e9 Luiz Gomes de Vasconcelos.<br \/>\nForam eleitos os novos membros da Diretoria Executiva: Klebson Carvalho Soares (Diretor-Geral), Maria Alice Am\u00e2ncio Melo (Primeira Secret\u00e1ria), Rosana Maria Feij\u00e3o (Segunda Secret\u00e1ria), Luciano Marques Vasconcelos (Primeiro Tesoureiro) e Francisco das Chagas de Sousa Ponte (Segundo Tesoureiro).\u00a0\u201cPrometo exercer a profiss\u00e3o e a fun\u00e7\u00e3o de diretor-geral do Complexo Santa Casa de Miseric\u00f3rdia de Sobral com dignidade, \u00e9tica e profissionalismo\u201d, destacou Klebson Carvalho em seu discurso de posse.<br \/>\nNa ocasi\u00e3o o Diretor-Geral, apresentou as reformas e constru\u00e7\u00f5es realizadas em todas as unidades do Complexo Santa Casa nos \u00faltimos dois anos.<br \/>\nSanta Casa de Miseric\u00f3rdia de Sobral &#8211; Assessoria de Comunica\u00e7\u00e3o Thais Menezes\/ Henrique Brito\/ Domingos Jr.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-15218\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1-1.jpeg\" alt=\"\" width=\"1018\" height=\"654\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1-1.jpeg 1018w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1-1-300x193.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1-1-768x493.jpeg 768w\" sizes=\"(max-width: 1018px) 100vw, 1018px\" \/> <img decoding=\"async\" class=\"alignleft size-full wp-image-15219\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Klebson3.jpg-768x432-1.jpeg\" alt=\"\" width=\"768\" height=\"432\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Klebson3.jpg-768x432-1.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Klebson3.jpg-768x432-1-300x169.jpeg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vota\u00e7\u00e3o contou com a participa\u00e7\u00e3o do provedor do Complexo Santa Casa, Bispo Dom Jos\u00e9 Luiz&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Klebson3.jpg-768x432-1.jpeg","jetpack-related-posts":[{"id":15161,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-elege-diretoria-executiva-2021-2024\/","url_meta":{"origin":15217,"position":0},"title":"Santa Casa de Miseric\u00f3rdia de Sobral elege Diretoria Executiva 2021\/2024","author":"","date":"Dezembro 22, 2020","format":false,"excerpt":"A Associa\u00e7\u00e3o da Santa Casa de Miseric\u00f3rdia de Sobral se reuniu e elegeu, nesta segunda-feira (21\/12), a Diretoria Executiva para o pr\u00f3ximo quadri\u00eanio (2021\/2024). A elei\u00e7\u00e3o aconteceu no Audit\u00f3rio Dom Walfrido da Diocese de Sobral e teve a participa\u00e7\u00e3o do provedor do Complexo Santa Casa, Bispo Dom Jos\u00e9 Luiz Gomes\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/klebson1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16668,"url":"https:\/\/correiodasemana.com\/site\/em-assembleia-ordinaria-virtual-novo-conselho-fiscal-do-complexo-santa-casa-de-misericordia-de-sobral-e-eleito\/","url_meta":{"origin":15217,"position":1},"title":"Em Assembleia Ordin\u00e1ria virtual, novo conselho fiscal do Complexo Santa Casa de Miseric\u00f3rdia de Sobral \u00e9 eleito","author":"","date":"Junho 7, 2021","format":false,"excerpt":"Encontro virtual contou com a participa\u00e7\u00e3o do bispo da diocese de Sobral e provedor do Complexo SCMS, Dom Jos\u00e9 Luiz Gomes de Vasconcelos, al\u00e9m de toda dire\u00e7\u00e3o-geral da institui\u00e7\u00e3o, associados e convidados. Ascom Complexo SCMS Com o objetivo de continuar o desenvolvimento dos processos administrativos do Complexo Santa Casa de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15211,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-50\/","url_meta":{"origin":15217,"position":2},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Dezembro 27, 2020","format":false,"excerpt":"O vereador Vicente de Paulo (Paul\u00e3o -PDT), registrou na segunda-feira (21) no legislativo, a sua chapa para concorrer\u00a0\u00e0 presid\u00eancia da c\u00e2mara de sobral, no dia 1\u00ba de janeiro de 2021.\u00a0Na Chapa registrada pelo Paulo constam os seguintes nomes que far\u00e3o parte da Mesa Diretora para o bi\u00eanio 2021-2022:\u00a0Presidente: Vicente de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15647,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-de-sobral-realiza-solenidade-em-virtude-da-acreditacao-nivel-1\/","url_meta":{"origin":15217,"position":3},"title":"Hospital do Cora\u00e7\u00e3o de Sobral realiza solenidade em virtude da Acredita\u00e7\u00e3o N\u00edvel 1","author":"","date":"Fevereiro 6, 2021","format":false,"excerpt":"Na ocasi\u00e3o, o bispo da Diocese de Sobral Provedor do Complexo Santa Casa, Dom Jos\u00e9 Luiz Gomes de Vasconcelos, foi homenageado pelos diretores com uma comenda em agradecimento pela confian\u00e7a depositada durante o processo de Acredita\u00e7\u00e3o. Ascom Complexo SCMS H\u00e1 um ano o Hospital do Cora\u00e7\u00e3o, unidade de sa\u00fade do\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/Foto-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/Foto-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/Foto-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/Foto-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16876,"url":"https:\/\/correiodasemana.com\/site\/padre-jose-linhares-ponte-lanca-livros-sobre-historia-da-santa-casa-de-misericordia-de-sobral\/","url_meta":{"origin":15217,"position":4},"title":"Padre Jos\u00e9 Linhares Ponte lan\u00e7a livros sobre hist\u00f3ria da Santa Casa de Miseric\u00f3rdia de Sobral","author":"","date":"Julho 5, 2021","format":false,"excerpt":"Padre Z\u00e9 ainda recebeu uma comenda de agradecimento pelos 33 anos de dedica\u00e7\u00e3o ao desenvolvimento do hospital, pelas m\u00e3os do bispo da Diocese de Sobral e provedor do Complexo Santa Casa de Sobral, Dom Jos\u00e9 Luiz Gomes de Vasconcelos. Por Henrique Brito \u201cDedico esta obra a todos os pacientes que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16589,"url":"https:\/\/correiodasemana.com\/site\/recital-de-musica-marca-aniversario-de-96-anos-da-santa-casa-de-misericordia-de-sobral\/","url_meta":{"origin":15217,"position":5},"title":"Recital de m\u00fasica marca anivers\u00e1rio de 96 anos da Santa Casa de Miseric\u00f3rdia de Sobral","author":"","date":"Maio 31, 2021","format":false,"excerpt":"Homenagem musical destacou a import\u00e2ncia da institui\u00e7\u00e3o para a sa\u00fade de Sobral e outros 54 munic\u00edpios da regi\u00e3o norte do estado do Cear\u00e1. Ascom Complexo SCMS Fundada em 24 de maio de 1925, a Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) celebrou nesta segunda-feira seus 96 anos de portas abertas\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Foto-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Foto-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Foto-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Foto-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15217"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15217\/revisions"}],"predecessor-version":[{"id":15220,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15217\/revisions\/15220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15219"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}