{"id":15324,"date":"2021-01-10T23:55:26","date_gmt":"2021-01-11T02:55:26","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15324"},"modified":"2021-01-10T23:55:26","modified_gmt":"2021-01-11T02:55:26","slug":"tres-autores-e-curiosidades-aos-vestibulandos-da-uva","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/tres-autores-e-curiosidades-aos-vestibulandos-da-uva\/","title":{"rendered":"TR\u00caS AUTORES E CURIOSIDADES AOS VESTIBULANDOS DA UVA!"},"content":{"rendered":"<p>Feliz 2021. As primeiras chuvas banham nosso Cear\u00e1, de forma discreta, mas, acendem em n\u00f3s a esperan\u00e7a de bom inverno. Com data de aplica\u00e7\u00e3o prevista para 14\/03\/2021 visando selecionar alunos para o segundo semestre de 2021, em 09\/12\/20, foi anunciado o Vestibular da Universidade Estadual Vale do Acara\u00fa \u2013 UVA, na qual sou professor, com muita honra, e uma curiosidade nos livros sugeridos me moveram a tecer coment\u00e1rios a certame t\u00e3o bem e diligentemente organizado pelo meu confrade na Academia Sobralense de Estudos e Letras, o Prof. Jos\u00e9 Ferreira Portella Netto, honrado cidad\u00e3o e grande profissional. Os tr\u00eas \u00faltimos romances indicados fizeram o tempo voltar quando vi\u00a0S\u00e3o Bernardo, de Graciliano Ramos;\u00a0As Tr\u00eas Marias, de Rachel de Queiroz e\u00a0Iracema, de Jos\u00e9 de Alencar. N\u00e3o s\u00f3 porque li os livros, evidentemente. Tenho uma preservada segunda edi\u00e7\u00e3o (1938) de S\u00e3o Bernardo. D\u2019As Tr\u00eas Marias tenho primeira, segunda, terceira edi\u00e7\u00f5es e outras cl\u00e1ssicas. De Iracema n\u00e3o tenho primeiras edi\u00e7\u00f5es, mas, possuo muitas comemorativas.<br \/>\n\u201cIracema\u201d \u00e9 o sexto romance de Jos\u00e9 de Alencar (1865), de cunho indianista \u00e9 precedido por Guarany (1857) e sucedido por Ubirajara (1874). Ler Iracema, vez por outra adquiro uma nova edi\u00e7\u00e3o sa\u00edda de modo especial ou que seja edi\u00e7\u00e3o com n\u00famero fechado (100\u00aa de tal editora etc.), d\u00e1 uma saudade da inf\u00e2ncia e da curiosidade de conhecer o grande cen\u00e1rio da primeira parte de Iracema, Ipu. Ali est\u00e1 o v\u00e9u de noiva e parece que at\u00e9 ouvimos suas passadas naquelas matas. Depois, crescido, encontrei seu segundo cen\u00e1rio, a praia de Iracema, onde ela aguarda Martin, com Moacir que alguns etimologistas definem como \u201cfilho da dor\u201d, o primeiro brasileiro miscigenado, conforme a lenda. Alencar \u00e9 o fundador do romance nacional.<br \/>\nQuanto ao \u201cAs Tr\u00eas Marias\u201d penso at\u00e9 que me fa\u00e7o suspeito em falar. O cen\u00e1rio do livro \u00e9 o \u201cviveiro adorado\u201d, Col\u00e9gio da Imaculada Concei\u00e7\u00e3o de Fortaleza. Lendo o in\u00edcio do romance, ainda hoje, tenho a impress\u00e3o de que estou ingressando no Col\u00e9gio. Maria Augusta (Guta), era a pr\u00f3pria autora, Rachel. Maria da Gl\u00f3ria \u00e9 Odorina que se casou e foi residir no Cariri. Maria Jos\u00e9 \u00e9 Alba, amiga querida de Rachel que faleceu no acidente a\u00e9reo em que tamb\u00e9m morreu Castelo Branco. Podemos dizer que \u201cAs Tr\u00eas Marias\u201d \u00e9 romance-autobiogr\u00e1fico, n\u00e3o autobiografia, pois, em sua genialidade, a autora deu novas faces a personagens e espa\u00e7os desenvolvidos na trama. O livro \u00e9 de 1939. Rachel, com menos de 30 anos, j\u00e1 \u00e9 escritora conhecida em todo o Pa\u00eds, pelo sucesso da cl\u00e1ssica obra prima \u201cO Quinze\u201d (1930). Ela viveu quase 93 anos e afirmou a mim uma vez: \u201cVivi muito. Sofri muito e tomei pouco ju\u00edzo\u201d. A escritora recebeu t\u00edtulo de doutora honoris causa da UVA. \u00c9 uma das mulheres mais importantes do s\u00e9culo XX, a primeira mulher a ingressar na Academia Brasileira de Letras, possuidora de rara intelig\u00eancia e franqueza. Apontei-me suspeito porque sou afilhado, bi\u00f3grafo e tive a honra de ser seu amigo. No Imaculada conheci a \u201cSanta\u201d Irm\u00e3 Elisabeth Silveira e a querida Profa. Norma Soares que teve importante participa\u00e7\u00e3o na UVA. A obra j\u00e1 foi destaque no vestibular anterior.<br \/>\nMas, a curiosidade maior para mim entre os tr\u00eas autores \u00e9 que Graciliano era amigo de Rachel e a escritora foi respons\u00e1vel por salvar \u201cAng\u00fastia\u201d, escrito em 1936, que Graciliano queria jogar no lixo. Enredo para uma outra conversa por conta do espa\u00e7o. Alencar era neto da hero\u00edna B\u00e1rbara de Alencar e B\u00e1rbara tamb\u00e9m \u00e9 quinta-av\u00f3 de Rachel. Nestes tr\u00eas livros temos Rachel amiga de um e prima de outro. Salve Rachel!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feliz 2021. As primeiras chuvas banham nosso Cear\u00e1, de forma discreta, mas, acendem em n\u00f3s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,41],"tags":[],"class_list":["post-15324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-jose-luis-lira"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose\u0301-1.jpg","jetpack-related-posts":[{"id":17735,"url":"https:\/\/correiodasemana.com\/site\/formacao-do-cristianismo-de-eliandro-nascimento\/","url_meta":{"origin":15324,"position":0},"title":"FORMA\u00c7\u00c3O DO CRISTIANISMO DE ELIANDRO NASCIMENTO\u00a0","author":"","date":"Outubro 11, 2021","format":false,"excerpt":"Desde que foi lan\u00e7ado, em 2020, fiquei curioso em ler o livro do colega de magist\u00e9rio e investigador cient\u00edfico, Prof. Francisco Eliandro do Nascimento, doutorando em Filosofia pela Universidade Federal do Cear\u00e1. Eliandro \u00e9 t\u00e3o presente nos cursos de Direito, onde leciona Filosofia Jur\u00eddica, que achei que ele era formado\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20817,"url":"https:\/\/correiodasemana.com\/site\/instituto-historico-e-geografico-de-sobral-e-instalado\/","url_meta":{"origin":15324,"position":1},"title":"Instituto Hist\u00f3rico e Geogr\u00e1fico de Sobral \u00e9 instalado","author":"","date":"Agosto 29, 2022","format":false,"excerpt":"\u201c\u00c9 com grande satisfa\u00e7\u00e3o que a sociedade sobralense se re\u00fane para a sess\u00e3o hist\u00f3rica e solene de instala\u00e7\u00e3o, posse da diretoria e dos primeiros s\u00f3cios do Instituto Hist\u00f3rico e Geogr\u00e1fico de Sobral (IHGS), tendo por patrono o Mons. Francisco Sadoc de Ara\u00fajo\u201d, assim se expressou o mestre de cerim\u00f4nias, F\u00e1bio\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/Autoridades-e-socios.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/Autoridades-e-socios.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/Autoridades-e-socios.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/Autoridades-e-socios.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19387,"url":"https:\/\/correiodasemana.com\/site\/tres-ilustres-sobralenses\/","url_meta":{"origin":15324,"position":2},"title":"TR\u00caS ILUSTRES SOBRALENSES&#8230;\u00a0","author":"","date":"Abril 3, 2022","format":false,"excerpt":"Este fim de semana tr\u00eas importantes eventos marcam a vida de tr\u00eas ilustres sobralenses. Os tr\u00eas s\u00e3o t\u00e3o importantes que eu os classificaria no mesmo valor afetivo. Ent\u00e3o, pedirei permiss\u00e3o \u00e0s duas damas e vou iniciar pelo cavalheiro, um\u00a0Lord, na acep\u00e7\u00e3o da palavra. Falo do professor, gestor e acad\u00eamico Jos\u00e9\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16984,"url":"https:\/\/correiodasemana.com\/site\/a-santa-casa-pelo-padre-ze-linhares\/","url_meta":{"origin":15324,"position":3},"title":"A Santa Casa pelo Padre Z\u00e9 Linhares\u00a0","author":"","date":"Julho 12, 2021","format":false,"excerpt":"O t\u00edtulo desta coluna que hoje ser\u00e1 maior que o habitual, tem sentido amplo. Referiremos \u00e0 publica\u00e7\u00e3o do livro enciclop\u00e9dico e hist\u00f3rico em dois volumes escrito pelo Padre Jos\u00e9 Linhares Ponte, nosso querido Padre Z\u00e9: \u201cA Hist\u00f3ria da Santa Casa de Miseric\u00f3rdia de Sobral: Sonho, Saga, Sacramental (Mist\u00e9rio e Milagre)\u201d.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30027,"url":"https:\/\/correiodasemana.com\/site\/tributo-a-profa-hilce-girao\/","url_meta":{"origin":15324,"position":4},"title":"Tributo \u00e0 Prof\u00aa. Hilce Gir\u00e3o","author":"adminredacao","date":"Julho 22, 2024","format":false,"excerpt":"\u00a0Por Giovana Saboya Mont\u2019Alverne Gir\u00e3o (Professora Em\u00e9rita da UVA, da Academia Sobralense de Estudos e Letras e do Instituto Hist\u00f3rico e Geogr\u00e1fico de Sobral) Bem-aventurados os que fazem da morte um renascimento e promovem do afastamento, uma saudosa lembran\u00e7a. Estamos vivendo em tempo de pesar, de reconhecimento, de homenagem p\u00f3stuma,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/FOTO-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/FOTO-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/FOTO-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/FOTO-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20124,"url":"https:\/\/correiodasemana.com\/site\/centenario-da-academia-sobralense-de-letras\/","url_meta":{"origin":15324,"position":5},"title":"Centen\u00e1rio da Academia Sobralense de Letras","author":"","date":"Junho 13, 2022","format":false,"excerpt":"Ter\u00e7a-feira, dia 7, foi o dia dos 100 anos da funda\u00e7\u00e3o da Academia Sobralense de Letras que teve reuni\u00e3o preparat\u00f3ria em 3 de maio de 1922, fundada pelo Pe. Leopoldo Fernandes que j\u00e1 havia sido p\u00e1roco da Igreja da S\u00e9 de Sobral e Diretor do Correio da Semana e naquele\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/academia-sobralense-de-letras-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/academia-sobralense-de-letras-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/academia-sobralense-de-letras-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/academia-sobralense-de-letras-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/academia-sobralense-de-letras-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15324"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15324\/revisions"}],"predecessor-version":[{"id":15325,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15324\/revisions\/15325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/8256"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}