{"id":15517,"date":"2021-01-24T23:20:42","date_gmt":"2021-01-25T02:20:42","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15517"},"modified":"2021-01-24T23:20:42","modified_gmt":"2021-01-25T02:20:42","slug":"idosos-do-abrigo-sagrado-coracao-de-jesus-em-sobral-sao-vacinados-contra-covid-19","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/idosos-do-abrigo-sagrado-coracao-de-jesus-em-sobral-sao-vacinados-contra-covid-19\/","title":{"rendered":"Idosos do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus em Sobral s\u00e3o vacinados contra Covid-19"},"content":{"rendered":"<p><strong>A vacina\u00e7\u00e3o contempla a primeira fase da imuniza\u00e7\u00e3o no munic\u00edpio que al\u00e9m dos profissionais da sa\u00fade abrange Institui\u00e7\u00f5es de Longa Perman\u00eancia para Idosos (ILPI).<\/strong><\/p>\n<p>Ascom Complexo SCMS<br \/>\nOs 32 idosos acolhidos pelo Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, unidade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, foram os primeiros idosos institucionalizados a receberem a primeira dose da vacina contra a Covid-19 em Sobral na ter\u00e7a-feira (19\/01). As vacinas foram enviadas pelo Governo Federal, intermediadas pelo Governo do Estado do Cear\u00e1 e repassadas pela Secretaria de Sa\u00fade Municipal, que iniciou a campanha de vacina\u00e7\u00e3o na noite da segunda-feira (18\/01).<br \/>\nJos\u00e9 Milton de Oliveira, 84, foi o primeiro idoso da institui\u00e7\u00e3o a ser vacinado. De acordo com a enfermeira e respons\u00e1vel t\u00e9cnica pelo Abrigo, D\u00e9borah Lopes, o momento foi emocionante.\u00a0\u201cA vacina representa esperan\u00e7a e certeza que dias melhores vir\u00e3o. Foi emocionante presenciar nossos idosos sendo imunizados contra esse v\u00edrus que deixou a humanidade no escuro. Mas com a vacina, j\u00e1 \u00e9 poss\u00edvel caminharmos para a luz\u201d, enfatiza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vacina\u00e7\u00e3o contempla a primeira fase da imuniza\u00e7\u00e3o no munic\u00edpio que al\u00e9m dos profissionais da&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-15517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1.jpeg",780,791,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1-150x150.jpeg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1-296x300.jpeg",296,300,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1-768x779.jpeg",640,649,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1.jpeg",640,649,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1.jpeg",780,791,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1.jpeg",780,791,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1.jpeg",780,791,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1-720x380.jpeg",540,285,true]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19-1.jpeg","jetpack-related-posts":[{"id":15443,"url":"https:\/\/correiodasemana.com\/site\/idosos-do-abrigo-sagrado-coracao-de-jesus-sao-vacinados-contra-covid-19\/","url_meta":{"origin":15517,"position":0},"title":"Idosos do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus s\u00e3o vacinados contra Covid-19","author":"","date":"Janeiro 19, 2021","format":false,"excerpt":"Os 32 idosos acolhidos pelo Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, unidade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, foram os primeiros idosos institucionalizados a receberem a primeira dose da vacina contra a Covid-19 em Sobral nesta ter\u00e7a-feira (19\/01). As vacinas foram enviadas pelo Governo Federal, e repassadas pela Secretaria\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Vacinacao-Abrigo-Covid-19.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16782,"url":"https:\/\/correiodasemana.com\/site\/em-clima-de-arraia-idosos-do-abrigo-sagrado-coracao-de-jesus-sao-vacinados-contra-gripe-h1n1\/","url_meta":{"origin":15517,"position":1},"title":"Em clima de arrai\u00e1, idosos do Abrigo Sagrado Cora\u00e7\u00e3o de Jesus s\u00e3o vacinados contra gripe H1N1","author":"","date":"Junho 20, 2021","format":false,"excerpt":"Para celebrar a imuniza\u00e7\u00e3o contra a gripe H1N1 dos 31 idosos acolhidos no Abrigo Sagrado Cora\u00e7\u00e3o de Jesus, unidade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, a institui\u00e7\u00e3o organizou nesta quarta-feira (16\/06) o \u2018Arrai\u00e1 H1N1\u2019. O momento em clima de festa junina aconteceu seguindo a campanha de vacina\u00e7\u00e3o municipal,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/arraia-coracaodejesus.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/arraia-coracaodejesus.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/arraia-coracaodejesus.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/arraia-coracaodejesus.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/arraia-coracaodejesus.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15493,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-52\/","url_meta":{"origin":15517,"position":2},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Janeiro 24, 2021","format":false,"excerpt":"O prefeito de Sobral, Ivo Gomes e a vice-prefeita, Christianne coelho, participaram na noite de segunda-feira (18),\u00a0no Hospital de Campanha Francisco Alves, da solenidade em que a Agente de Sa\u00fade, moradora do Bairro Sumar\u00e9, Ana Maria Nascimento, recebeu a primeira dose da vacina contra a Covid-19 no munic\u00edpio.\u00a0Durante a solenidade\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17672,"url":"https:\/\/correiodasemana.com\/site\/populacao-que-vive-em-abrigos-de-sobral-recebe-aplicacao-da-dose-de-reforco\/","url_meta":{"origin":15517,"position":3},"title":"Popula\u00e7\u00e3o que vive em abrigos de Sobral recebe aplica\u00e7\u00e3o da dose de refor\u00e7o","author":"","date":"Outubro 4, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana A dose de refor\u00e7o da vacina contra a Covid-19 foi aplicada em idosos de 70 anos ou mais que vivem nos abrigos Bom Samaritano e Sagrado Cora\u00e7\u00e3o de Jesus pela Secretaria da Sa\u00fade (SMS). A terceira dose, desde a semana passada foi disponibilizada\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/vacinacao-idoso-800x445-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/vacinacao-idoso-800x445-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/vacinacao-idoso-800x445-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/vacinacao-idoso-800x445-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15495,"url":"https:\/\/correiodasemana.com\/site\/vacinacao-contra-covid-19-comeca-em-sobral-profissionais-da-saude-sao-primeiras-a-serem-vacinadas-na-cidade\/","url_meta":{"origin":15517,"position":4},"title":"Vacina\u00e7\u00e3o contra COVID-19 come\u00e7a em Sobral; profissionais da sa\u00fade s\u00e3o primeiras a serem vacinadas na cidade","author":"","date":"Janeiro 24, 2021","format":false,"excerpt":"Primeira pessoa vacinada recebeu dose na noite da \u00faltima segunda-feira (18\/01) com presen\u00e7a do prefeito Ivo Gomes. Ao todo, Sobral recebeu 2.251 doses do imunizante. Por Joc\u00e9lio Tavares. A agente de sa\u00fade Ana Maria do Nascimento, de 64 anos, e a t\u00e9cnica em enfermagem Francisca Elenilda Rodrigues Garcia, de 52,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/139694114_3596788763775393_7440338198691976003_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/139694114_3596788763775393_7440338198691976003_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/139694114_3596788763775393_7440338198691976003_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/139694114_3596788763775393_7440338198691976003_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15476,"url":"https:\/\/correiodasemana.com\/site\/profissionais-do-hrn-comecam-a-ser-vacinados-contra-a-covid-19\/","url_meta":{"origin":15517,"position":5},"title":"Profissionais do HRN come\u00e7am a ser vacinados contra a Covid-19","author":"","date":"Janeiro 24, 2021","format":false,"excerpt":"Emo\u00e7\u00e3o e esperan\u00e7a marcaram o in\u00edcio da vacina\u00e7\u00e3o contra a Covid-19 dos profissionais do Hospital Regional Norte (HRN), unidade do Governo do Estado, administrado pelo Instituto de Sa\u00fade e Gest\u00e3o Hospitalar (ISGH) na quarta-feira, 20. Entram na primeira fase de vacina\u00e7\u00e3o os colaboradores que atuam na linha de frente do\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Profissionais-UTI-Covid_-Denise-Martins-enfermeira-Luis-Gilson-Gomes-tecnico-de-enfermagem-e-Stefhania-Araujo-fisioterapeuta.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Profissionais-UTI-Covid_-Denise-Martins-enfermeira-Luis-Gilson-Gomes-tecnico-de-enfermagem-e-Stefhania-Araujo-fisioterapeuta.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Profissionais-UTI-Covid_-Denise-Martins-enfermeira-Luis-Gilson-Gomes-tecnico-de-enfermagem-e-Stefhania-Araujo-fisioterapeuta.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/Profissionais-UTI-Covid_-Denise-Martins-enfermeira-Luis-Gilson-Gomes-tecnico-de-enfermagem-e-Stefhania-Araujo-fisioterapeuta.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15517"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15517\/revisions"}],"predecessor-version":[{"id":15520,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15517\/revisions\/15520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15518"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}