{"id":15693,"date":"2021-02-16T00:17:20","date_gmt":"2021-02-16T03:17:20","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15693"},"modified":"2021-02-16T00:17:20","modified_gmt":"2021-02-16T03:17:20","slug":"sobral-sobral-27","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sobral-sobral-27\/","title":{"rendered":"Sobral, Sobral"},"content":{"rendered":"<p><strong>\u201cO MUNDO N\u00c3O QUER SABER DOS TEMPORAIS QUE VOC\u00ca ENFRENTOU. QUER SABER SE VOC\u00ca TROUXE O NAVIO !!\u201d. (AN\u00d4NIMO)<\/strong><\/p>\n<p><strong>MINHAS HIST\u00d3RIAS&#8230;<\/strong><br \/>\n<strong>DAVIZ QUERIA IR SOZINHO PRA CASA DA AV\u00d3&#8230;<\/strong><\/p>\n<p>Todos os anos os pais do DAVIZ levavam o filho<br \/>\npara a casa da av\u00f3,<br \/>\na fim de passar as f\u00e9rias de ver\u00e3o. Eles<br \/>\nvoltavam para casa<br \/>\nno mesmo trem, no dia seguinte.<\/p>\n<p>Um dia a crian\u00e7a disse aos pais:<br \/>\n\u2032\u2032&#8212; Pai. J\u00e1 estou crescido.<br \/>\nPosso ir sozinho para casa da minha av\u00f3?\u201d.<\/p>\n<p>Depois de uma breve discuss\u00e3o,<br \/>\nos pais aceitaram.<\/p>\n<p>Eles est\u00e3o parados esperando a sa\u00edda do trem. Despedem-se do filho, dando as \u00faltimas orienta\u00e7\u00f5es, pela janela. Enquanto<br \/>\nDAVIZ, meio envergonhado, repetia:<\/p>\n<p>\u201c&#8212; Eu sei.<br \/>\nJ\u00e1 me disseram isso mais de mil vezes\u201d.<\/p>\n<p>O trem est\u00e1 prestes a sair<br \/>\ne o pai murmura no ouvido do DAVIZ:<\/p>\n<p>\u2032\u2032&#8212; Filho, se voc\u00ea se sentir mal ou inseguro&#8230;<br \/>\nIsso \u00e9 para voc\u00ea!\u201d.<br \/>\nE colocou algo no bolso dele.<\/p>\n<p>Agora o DAVIZ est\u00e1 sozinho,<br \/>\nsentado no trem como queria, pela primeira vez<br \/>\nsem a companhia dos seus pais.<\/p>\n<p>Admira a paisagem pela janela.<br \/>\nAo seu redor, alguns desconhecidos se empurram.<br \/>\nFazem muito barulho.<br \/>\nEles entram e saem do vag\u00e3o.<\/p>\n<p>O supervisor faz alguns coment\u00e1rios<br \/>\nsobre o fato do menino estar sozinho, embora com autoriza\u00e7\u00e3o dos pais.<\/p>\n<p>Uma pessoa olhou para ele com olhos de tristeza.<\/p>\n<p>DAVIZ agora est\u00e1 se sentindo mal<br \/>\na cada minuto que passa.<br \/>\nE sente um pouco de medo.<\/p>\n<p>Abaixa a cabe\u00e7a e&#8230;<br \/>\nse sente encurralado e sozinho.<br \/>\nL\u00e1grimas nos olhos.<\/p>\n<p>Ent\u00e3o se lembra do que o pai lhe entregou ao se despedir na esta\u00e7\u00e3o.<br \/>\nTinha algo no bolso dele.<br \/>\nTremendo, procurou o que o pai colocou l\u00e1.<\/p>\n<p>Ao encontrar o peda\u00e7o de papel,<br \/>\nnele estava escrito:<\/p>\n<p>\u201c&#8212; MEU FILHO, EU E SUA M\u00c3E ESTAMOS NO \u00daLTIMO VAG\u00c3O !\u201d<\/p>\n<p>Assim \u00e9 a vida,<br \/>\nN\u00f3s n\u00e3o podemos evitar nossos filhos irem embora.<br \/>\nN\u00f3s devemos confiar neles !!<\/p>\n<p>Mas n\u00f3s sempre estaremos<br \/>\nno \u00faltimo vag\u00e3o, vigiando,<br \/>\ncaso eles tenham medo ou caso eles encontrem<br \/>\nobst\u00e1culos e n\u00e3o saibam o que fazer !!<\/p>\n<p>Lutamos para estar perto deles,<br \/>\nenquanto ainda estivermos vivos. Sofremos quando eles crescem, ganham asas e querem voar. Para n\u00f3s, os filhos nunca crescem. E a eterna lembran\u00e7a que guardamos deles \u00e9 a do beb\u00ea carente e t\u00e3o dependente de n\u00f3s !!!!!! (autor desconhecido)<\/p>\n<p><strong>MINHAS M\u00daSICAS&#8230;<\/strong><br \/>\nMOLIENDO CAFE \/ CARAVAN &#8211; IVANILDO E SEU CONJUNTO 1963. Dois grandes sucessos do pernambucano de AMARAJI, IVANILDO SILVA, rei das tert\u00falias dos anos 50, 60 e 70, nos principais clubes de FORTALEZA, como N\u00c1UTICO, AABB, DI\u00c1RIOS, L\u00cdBANO, CLUBE MASSAPEENSE e MAGUARY, o \u00fanico longe da praia, na rua Bar\u00e3o do Rio Branco, pr\u00f3ximo \u00e0 avenida 13 de maio. Em SOBRAL, IVANILDO era sempre contratado para os bailes de debutantes.<br \/>\nToda festa na PRINCESA DO NORTE naquela \u00e9poca come\u00e7ava com sucessos do SAX DE OURO (para encher o sal\u00e3o de dan\u00e7arinos): A CHEGADA DA CEGONHA, CRIOULA, SIBONEY, PARA VIGO ME VOY, QUIZAS, QUIZAS, etc. MOLIENDO CAFE \u00e9 uma can\u00e7\u00e3o do venezuelano HUGO BLANCO(1961). CARAVAN (1936) um jazz americano composto por DUKE ELLINGTON e JUAN TIZOL. Letra de IRVING MILLS. TIZOL tinha t\u00e3o pouco apre\u00e7o pela m\u00fasica que vendeu sua parte de direitos autorais por apenas U$ 25,00 (D\u00f3lares) &#8211; (150 reais). Com o sucesso mundial de CARAVAN, o letrista teve a honradez de dar a TIZOL uma percentagem nos royalties. Aos 86 anos o astro do sax mora em NATAL-RN.<\/p>\n<p><strong>MINHAS FRASES&#8230;<\/strong><br \/>\n\u201cA MENTE QUE SE ABRE A UMA NOVA IDEIA JAMAIS VOLTAR\u00c1 AO SEU TAMANHO ORIGINAL\u201d<br \/>\n( ALBERT EINSTEIN 1879-1955 f\u00edsico te\u00f3rico alem\u00e3o cuja Lei da Relatividade foi comprovada em SOBRAL- CE, em 1919)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO MUNDO N\u00c3O QUER SABER DOS TEMPORAIS QUE VOC\u00ca ENFRENTOU. QUER SABER SE VOC\u00ca TROUXE&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,75],"tags":[],"class_list":["post-15693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-carolino-soares"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/02.png","jetpack-related-posts":[{"id":8710,"url":"https:\/\/correiodasemana.com\/site\/pai-papai\/","url_meta":{"origin":15693,"position":0},"title":"PAI, PAPAI","author":"","date":"Agosto 17, 2019","format":false,"excerpt":"Semana passada homenageamos os sacerdotes, os padres, pater no latim, pai. Eu recordei da m\u00fasica \u201cAmor celibat\u00e1rio\u201d, dos padres Ilara e Zezinho: \u201cDizem por a\u00ed\/ padre n\u00e3o casa, porque n\u00e3o ama\/ ou ent\u00e3o, n\u00e3o ama porque n\u00e3o casa\/ n\u00e3o sabem nada\/ n\u00e3o sabem nada de paternidade\/ de maternidade, de ser\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9824,"url":"https:\/\/correiodasemana.com\/site\/ela-esta-para-chegar\/","url_meta":{"origin":15693,"position":1},"title":"ELA EST\u00c1 PARA CHEGAR","author":"","date":"Novembro 11, 2019","format":false,"excerpt":"Passaram-se alguns meses. De in\u00edcio, um pequeno sinal, mas, a alegria j\u00e1 era grande. E nossa Princesinha Isadora soube que no seu reino surgiria mais um Pr\u00edncipe ou Princesa. Ela dizia. Se for menina, eu e as mulheres vamos cuidar. Se for homem, os homens cuidar\u00e3o. E os dias foram\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15896,"url":"https:\/\/correiodasemana.com\/site\/graca-do-rio-de-fernando-ferraz\/","url_meta":{"origin":15693,"position":2},"title":"GRA\u00c7A DO RIO, DE FERNANDO FERRAZ\u00a0\u00a0","author":"","date":"Mar\u00e7o 7, 2021","format":false,"excerpt":"Fernando Basto Ferraz, piauiense de nascimento e cearense por ado\u00e7\u00e3o \u00e9 conhecido no meio acad\u00eamico como advogado, jurista, professor universit\u00e1rio, poeta e memorialista. Al\u00e9m do mais \u00e9 um excelente marido, pai, av\u00f4 e amigo, do que falo com c\u00e1tedra. Nos conhecemos h\u00e1 quase quatro anos, mas, parecemos amigos de inf\u00e2ncia.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33724,"url":"https:\/\/correiodasemana.com\/site\/educacao-e-cidadania-78\/","url_meta":{"origin":15693,"position":3},"title":"EDUCA\u00c7\u00c3O E CIDADANIA \u2022","author":"adminredacao","date":"Maio 12, 2025","format":false,"excerpt":"Como Aprender a Conviver Com a Raiva Segundo o psiquiatra Daniel Martins de Barros falando sobre positividade e negatividade em seu livro \u201cO Lado Bom do Lado Ruim\u201d ele faz refer\u00eancia \u00e0s emo\u00e7\u00f5es prim\u00e1rias que temos constantemente: alegria, tristeza, medo, raiva e nojo. Ele chama a aten\u00e7\u00e3o o fato de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13547,"url":"https:\/\/correiodasemana.com\/site\/ela-completou-10-meses\/","url_meta":{"origin":15693,"position":4},"title":"ELA COMPLETOU 10 MESES","author":"","date":"Setembro 15, 2020","format":false,"excerpt":"A fam\u00edlia sempre \u00e9 tema presente em meus escritos. O exemplo de meus pais com alegrias, tristezas, \u00e0s vezes, certezas e incertezas, mas, com muita esperan\u00e7a \u00e9 uma refer\u00eancia para mim. E, assim, tamb\u00e9m n\u00f3s os filhos fomos buscando nossos caminhos, conservando sempre a esperan\u00e7a. E, desse modo, em 11\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10304,"url":"https:\/\/correiodasemana.com\/site\/ganhamos-um-sacerdote-e-nascimento-do-salvador\/","url_meta":{"origin":15693,"position":5},"title":"Ganhamos um Sacerdote e nascimento do Salvador!","author":"","date":"Dezembro 23, 2019","format":false,"excerpt":"No \u00faltimo dia 17 de dezembro,\u00a0data natal\u00edcia do Papa Francisco, do Mons. Sadoc de Ara\u00fajo e minha,na Catedral Metropolitana de Olinda e Recife, em celebra\u00e7\u00e3o presidida por Dom Fernando Saburido, que j\u00e1 foi nosso Bispo, foi ordenado sacerdote o sobralense Jo\u00e3o Batista Arag\u00e3o de Oliveira Filho, o Jo\u00e3ozinho do Padre\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15693"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15693\/revisions"}],"predecessor-version":[{"id":15694,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15693\/revisions\/15694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/14934"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}