{"id":15695,"date":"2021-02-16T00:19:16","date_gmt":"2021-02-16T03:19:16","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15695"},"modified":"2021-02-16T00:19:16","modified_gmt":"2021-02-16T03:19:16","slug":"projeto-sugere-substituicao-de-casas-de-taipa-por-alvenaria-no-ceara","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/projeto-sugere-substituicao-de-casas-de-taipa-por-alvenaria-no-ceara\/","title":{"rendered":"Projeto sugere substitui\u00e7\u00e3o de casas de taipa por alvenaria no Cear\u00e1"},"content":{"rendered":"<p>*Com informa\u00e7\u00f5es da AL-CE (Foto: Divulga\u00e7\u00e3o\/AL-CE)<\/p>\n<p>Est\u00e1 em tramita\u00e7\u00e3o na Assembleia Legislativa um projeto que prop\u00f5e a cria\u00e7\u00e3o do Programa de Substitui\u00e7\u00e3o das Casas de Taipa por Alvenaria no Cear\u00e1. De autoria do deputado Acr\u00edsio Sena (PT), a proposta tem objetivo de oferecer melhores condi\u00e7\u00f5es sanit\u00e1rias \u00e0 popula\u00e7\u00e3o cearense.<br \/>\nEm seu texto, o parlamentar destaca que levantamento feito pela Secretaria das Cidades identificou no estado 22.947 moradias inadequadas &#8211; constru\u00eddas em taipa, madeira aparelhada ou reaproveitada, palha e outros materiais. Do total, 10.852 est\u00e3o na \u00e1rea urbana e 12.095 nas \u00e1reas rurais, de acordo com os dados.<br \/>\nAcr\u00edsio defende que o espa\u00e7o para as fam\u00edlias deve proporcionar um \u201cconv\u00edvio seguro, acolhedor, apraz\u00edvel e, ainda, com condi\u00e7\u00f5es sanit\u00e1rias favor\u00e1veis ao pleno desenvolvimento de seus moradores\u201d.<br \/>\nO projeto prev\u00ea que as fam\u00edlias atendidas sejam benefici\u00e1rias de outros programas sociais e tenham cadastro em situa\u00e7\u00e3o regular. Durante as reformas, o p\u00fablico dever\u00e1 ser realocado temporariamente.<br \/>\nPelo texto, a estrutura da casa dever\u00e1 seguir os padr\u00f5es legais de cada munic\u00edpio, contando com uma sala, dois quartos, cozinha e banheiro, sendo todos os ambientes revestidos em piso cer\u00e2mico.<br \/>\nAs despesas do Programa, segundo a proposi\u00e7\u00e3o parlamentar, seriam custeadas por dota\u00e7\u00f5es or\u00e7ament\u00e1rias pr\u00f3prias e suplementares, se necess\u00e1rio, sendo obrigat\u00f3ria a inclus\u00e3o em or\u00e7amentos futuros, podendo ainda ser custeadas pelo Fundo Estadual de Combate \u00e0 Pobreza (Fecop) ou por outros fundos criados com esse fim.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Com informa\u00e7\u00f5es da AL-CE (Foto: Divulga\u00e7\u00e3o\/AL-CE) Est\u00e1 em tramita\u00e7\u00e3o na Assembleia Legislativa um projeto que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/Casa-de-Taipa-de-Mao1.jpg","jetpack-related-posts":[{"id":8543,"url":"https:\/\/correiodasemana.com\/site\/projeto-joao-de-barro-tem-ritmo-acelerado-em-sobral\/","url_meta":{"origin":15695,"position":0},"title":"Projeto Jo\u00e3o de Barro tem ritmo acelerado em Sobral","author":"","date":"Agosto 6, 2019","format":false,"excerpt":"Constru\u00e7\u00e3o de 29 casas de alvenaria no lugar de casas de taipa proporciona realiza\u00e7\u00e3o de um sonho e qualidade de vida para os beneficiados. Primeira etapa entregar\u00e1 14 resid\u00eancias no dia 16 de agosto. Pedreiros e serventes trabalham a todo vapor Observar a a\u00e7\u00e3o do cimento sendo misturado na areia,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/DSC_6292.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/DSC_6292.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/DSC_6292.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/DSC_6292.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10592,"url":"https:\/\/correiodasemana.com\/site\/panorama-politica\/","url_meta":{"origin":15695,"position":1},"title":"Panorama Pol\u00edtica","author":"","date":"Janeiro 27, 2020","format":false,"excerpt":"Prefeito Ivo Gomes visita casas construidas pelo projeto Jo\u00e3o de Barro O prefeito Ivo Gomes esteve no Bairro Sumar\u00e9 para visitar as 14 fam\u00edlias que tiveram suas casas de taipas substitu\u00eddas por alvenarias. A a\u00e7\u00e3o \u00e9 fruto do Projeto Jo\u00e3o de Bairro do Centro de Forma\u00e7\u00e3o Humana Padre Ibiapina, coordenado\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10372,"url":"https:\/\/correiodasemana.com\/site\/favela-no-campo-e-o-fim\/","url_meta":{"origin":15695,"position":2},"title":"Favela no campo \u00e9 o fim","author":"","date":"Janeiro 5, 2020","format":false,"excerpt":"Os sistemas de favelas s\u00f3 funcionam nas grandes cidades. Mentira, pois conhe\u00e7o uma favela com todos os percal\u00e7os sociais, encravada no meio das montanhas da Serra da Meruoca, bem ali no distrito de S\u00e3o Francisco. Favela sim, doa a quem doer. A hist\u00f3ria desta vila foi seguinte: havia uma fam\u00edlia\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Meruoca-Tabocas-Serra-da-Meruoca-Claudio-Oliveira-Lima-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Meruoca-Tabocas-Serra-da-Meruoca-Claudio-Oliveira-Lima-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Meruoca-Tabocas-Serra-da-Meruoca-Claudio-Oliveira-Lima-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Meruoca-Tabocas-Serra-da-Meruoca-Claudio-Oliveira-Lima-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Meruoca-Tabocas-Serra-da-Meruoca-Claudio-Oliveira-Lima-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/Meruoca-Tabocas-Serra-da-Meruoca-Claudio-Oliveira-Lima-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":27964,"url":"https:\/\/correiodasemana.com\/site\/sobral-ganha-conjunto-habitacional-e-urbanizacao-no-bairro-padre-palhano\/","url_meta":{"origin":15695,"position":3},"title":"Sobral ganha conjunto habitacional e urbaniza\u00e7\u00e3o no bairro Padre Palhano","author":"adminredacao","date":"Janeiro 8, 2024","format":false,"excerpt":"Novo residencial custou mais de R$ 5 milh\u00f5es, e contou com aporte estadual de R$ 3,25 milh\u00f5es Fonte: Governo do Estado do Cear\u00e1 A dona de casa Maria Lucinete n\u00e3o escondia a satisfa\u00e7\u00e3o de ver seu sonho da casa pr\u00f3pria ser concretizado. Acompanhada pelo marido e pelo filho, Paulo Jos\u00e9,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/Jornal-Correio-da-Semana-No-1001-Copia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/Jornal-Correio-da-Semana-No-1001-Copia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/Jornal-Correio-da-Semana-No-1001-Copia-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":36092,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-139\/","url_meta":{"origin":15695,"position":4},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Outubro 29, 2025","format":false,"excerpt":"O analfabetismo \u00e9 um agravante ou uma agravante? O analfabetismo, assim como falta de respeito, ser\u00e1 sempre uma agravante na forma\u00e7\u00e3o de qualquer personalidade. A exemplo de atenuante, a palavra agravante \u00e9 feminina, apesar de muita gente boa us\u00e1-la como masculina, o agravante, o atenuante, doravante use a atenuante, a\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10168,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-24\/","url_meta":{"origin":15695,"position":5},"title":"Panorama Pol\u00edtico","author":"","date":"Dezembro 16, 2019","format":false,"excerpt":"Prefeito Ivo Gomes inaugura pra\u00e7a em Santa Luzia e Posto de Sa\u00fade em Jaibaras O prefeito Ivo Gomes inaugurou quarta-feira, 11, a Pra\u00e7a Manoel Rodrigues de Lima na localidade de Santa Luzia - Baracho e anunciou que vai fazer o complemento da pavimenta\u00e7\u00e3o da estrada e disse sobre as obras\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15695"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15695\/revisions"}],"predecessor-version":[{"id":15697,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15695\/revisions\/15697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15696"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}