{"id":15724,"date":"2021-02-16T00:39:09","date_gmt":"2021-02-16T03:39:09","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15724"},"modified":"2021-02-16T00:39:09","modified_gmt":"2021-02-16T03:39:09","slug":"igor-bezerra-pdt-apresenta-mais-projetos-de-indicacao-protocolados-em-seu-primeiro-mes-de-mandato","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/igor-bezerra-pdt-apresenta-mais-projetos-de-indicacao-protocolados-em-seu-primeiro-mes-de-mandato\/","title":{"rendered":"Igor Bezerra  (PDT), apresenta mais projetos de indica\u00e7\u00e3o protocolados em seu primeiro m\u00eas de mandato"},"content":{"rendered":"<p>Por Reda\u00e7\u00e3o Correio da Semana<br \/>\nFaz um m\u00eas desde que o novato, Igor Bezerra (PDT), iniciou suas atividades na C\u00e2mara Municipal de Sobral e o vereador n\u00e3o decepcionou quando se trata de trabalho prestado. Igor apresentou em seu perfil na rede social Instagram (@igorbezerravereador) alguns dos projetos de indica\u00e7\u00e3o protocolados neste primeiro m\u00eas de mandato.<br \/>\nEntre as indica\u00e7\u00f5es feitas, s\u00e3o destaque a inclus\u00e3o do projeto Bolsa Cultura no programa #ocupajuventude, o maior investimento da hist\u00f3ria de Sobral em oportunidades para jovens. Igor tamb\u00e9m mostrou que ainda \u00e9 um grande aliado \u00e0 causa do Esporte e da Juventude sobralense, como mostrado por seu pedido para a constru\u00e7\u00e3o de uma Areninha no bairro Junco e uma Esta\u00e7\u00e3o Juventude no Sumar\u00e9.<br \/>\n\u201cComo vereador, eu sempre fiz quest\u00e3o de escutar a popula\u00e7\u00e3o. Sendo assim, eu n\u00e3o poderia deixar de fazer do meu mandato uma experi\u00eancia participativa e tentar expandir alguns projetos queridos pela comunidade quando estive a frente da SECJEL (Secretaria de Cultura, Juventude, Esporte e Lazer)\u201d, explicou Igor.<br \/>\nIgor Bezerra mant\u00e9m uma forte presen\u00e7a em suas redes sociais (Instagram e Facebook), fazendo tours e publica\u00e7\u00f5es com a inten\u00e7\u00e3o de trazer a popula\u00e7\u00e3o se apropriar da C\u00e2mara, ao mesmo tempo que presta conta de seus mais recentes trabalhos para a comunidade.<\/p>\n<p><strong>Projeto de Lei e Requerimento para inclus\u00e3o de int\u00e9rprete de Libras em Reparti\u00e7\u00f5es P\u00fablicas<\/strong><br \/>\nA popula\u00e7\u00e3o brasileira \u00e9 composta por mais de 10 milh\u00f5es de pessoas surdas e ainda falta aten\u00e7\u00e3o para com essas pessoas. A inclus\u00e3o se faz cada vez mais necess\u00e1ria! A comunica\u00e7\u00e3o \u00e9 um direito de todos.<br \/>\nIgor Bezerra (PDT) protocolou um projeto de lei apoiado por um requerimento que visa manter funcion\u00e1rio com dom\u00ednio e flu\u00eancia em Libras nas reparti\u00e7\u00f5es p\u00fablicas municipais, objetivando manter um atendimento igualit\u00e1rio a\u00a0todos.\u00a0Esses projetos funcionam em conson\u00e2ncia com o Decreto Federal n 5.626, de 22 de dezembro de 2005, que regulamenta a Lei n. 10.436 de 24 de abril de 2002.<br \/>\n\u201c\u00c9 uma imensa felicidade ver este projeto tomando forma. H\u00e1 algum tempo que estou ao lado dos representantes da comunidade surda de Sobral e fico muito orgulhoso de trazer ao p\u00fablico as nossas ideias de mudan\u00e7a\u201d, disse o vereador do PDT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Reda\u00e7\u00e3o Correio da Semana Faz um m\u00eas desde que o novato, Igor Bezerra (PDT),&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/Vereador-Igor-Gomes-7-scaled.jpg","jetpack-related-posts":[{"id":18979,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-97\/","url_meta":{"origin":15724,"position":0},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Fevereiro 21, 2022","format":false,"excerpt":"Na tarde do s\u00e1bado (12\/02), o prefeito Ivo Gomes e o governador Camilo Santana cumpriram extensa\u00a0agenda no munic\u00edpio, acompanhados de suas respectivas vices, Christianne Coelho e Izolda Cela. Os gestores inauguraram a Delegacia Municipal de Pol\u00edcia Civil e o Parque Evangelina Saboya. Ainda na agenda, Ivo Gomes e Camilo Santana\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15410,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-51\/","url_meta":{"origin":15724,"position":1},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Janeiro 18, 2021","format":false,"excerpt":"'O deputado federal Le\u00f4nidas Cristino participou de audi\u00eancia com o Secret\u00e1rio de Seguran\u00e7a P\u00fablica e Defesa Social, Sandro Caron e com o Secret\u00e1rio Executivo da SSPDS, Cel. Paulo S\u00e9rgio. Com Le\u00f4nidas estavam os prefeitos Ed\u00e9zio Sitonio (Corea\u00fa), Ant\u00f4nio Martins (Carir\u00e9), Ren\u00ea Vasconcelos (Ubajara) e Edinardo Filho (Forquilha), que foram pedir\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17754,"url":"https:\/\/correiodasemana.com\/site\/vila-olimpica-de-sobral-foi-inaugurada-com-grande-evento-e-diversidade-de-atividades-esportivas-essa-semana\/","url_meta":{"origin":15724,"position":2},"title":"Vila Ol\u00edmpica de Sobral foi inaugurada com grande evento e diversidade de atividades esportivas essa semana","author":"","date":"Outubro 17, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana A Prefeitura de Sobral, por meio das secretarias da Juventude, Esporte e Lazer (Secjel) e da Infraestrutura (Seinfra), inaugurou com grande evento na \u00faltima ter\u00e7a-feira (12) a Vila Ol\u00edmpica de Sobral, o maior complexo esportivo do interior do Cear\u00e1. O equipamento esportivo e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-14-at-17.09.55-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-14-at-17.09.55-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-14-at-17.09.55-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-14-at-17.09.55-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-14-at-17.09.55-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16351,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-60\/","url_meta":{"origin":15724,"position":3},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Maio 3, 2021","format":false,"excerpt":"A Prefeitura de Sobral anunciou no domingo (25\/04), a renova\u00e7\u00e3o das medidas de isolamento social at\u00e9 2 de maio. Por\u00e9m, o Decreto n\u00ba 2637 traz novidades para a economia do munic\u00edpio. Entre elas, a libera\u00e7\u00e3o do com\u00e9rcio e de academias.\u00a0Na quarta-feira (28\/04), ficou autorizado o com\u00e9rcio de rua e servi\u00e7os,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11284,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-35\/","url_meta":{"origin":15724,"position":4},"title":"Panorama Pol\u00edtico","author":"","date":"Mar\u00e7o 24, 2020","format":false,"excerpt":"Vereador Joaquim Feij\u00e3o faz aquisi\u00e7\u00e3o de academia ao ar livre Preocupado com o bem-estar da popula\u00e7\u00e3o de Sobral e distritos, o vereador Joaquim Feij\u00e3o (PDT), apresentou no Plen\u00e1rio 05 de Julho, diversos requerimentos e projetos solicitando benfeitoria para a popula\u00e7\u00e3o de Sobral e distritos. Tendo indicado saneamento b\u00e1sico na Rua\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31936,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-197\/","url_meta":{"origin":15724,"position":5},"title":"Becco ponto Com","author":"adminredacao","date":"Dezembro 24, 2024","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Dos fatos e boatos nas emissoras sobre a pol\u00edtica t\u00e3o nossa. Dos bab\u00f5es contumazes na porta do novo poder. Ufa, Sobral! De uma oposi\u00e7\u00e3o odienta e incapaz puxada as coisas petistas. Dos pol\u00edticos poderosos que n\u00e3o aceitam perder o osso, ufa! Da ruma de bancos de emprestar dinheiro\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15724"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15724\/revisions"}],"predecessor-version":[{"id":15726,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15724\/revisions\/15726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15725"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}