{"id":15727,"date":"2021-02-16T00:40:48","date_gmt":"2021-02-16T03:40:48","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15727"},"modified":"2021-02-16T00:42:37","modified_gmt":"2021-02-16T03:42:37","slug":"fazenda-da-esperanca-na-serra-da-meruoca-tem-inauguracao-prevista-para-abril-de-2021","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/fazenda-da-esperanca-na-serra-da-meruoca-tem-inauguracao-prevista-para-abril-de-2021\/","title":{"rendered":"Fazenda da Esperan\u00e7a na Serra da Meruoca tem inaugura\u00e7\u00e3o prevista para abril de 2021"},"content":{"rendered":"<p><strong>Primeira unidade feminina da Fazenda na regi\u00e3o ter\u00e1 capacidade para acolher 15 mulheres em recupera\u00e7\u00e3o das drogas<\/strong><\/p>\n<p>J\u00e1 se encontra em fase de finaliza\u00e7\u00e3o a primeira unidade feminina da Fazenda da Esperan\u00e7a na regi\u00e3o Norte do Cear\u00e1, destinada \u00e0 recupera\u00e7\u00e3o de mulheres contra o v\u00edcio das drogas. O projeto, que atua h\u00e1 mais de 12 em Sobral atrav\u00e9s da Fazenda da Esperan\u00e7a S\u00e3o Bento, unidade masculina instalada no distrito de Patriarca, atuar\u00e1 tamb\u00e9m na Serra da Meruoca, no distrito de Palestina, com capacidade inicial para acolher 15 mulheres que desejem abandonar o v\u00edcio das drogas.<br \/>\nInstitui\u00e7\u00e3o sem fins lucrativos com centenas de unidades espalhadas em mais de 20 pa\u00edses por todo o mundo, a Fazenda da Esperan\u00e7a atua desde 1983 com um m\u00e9todo terap\u00eautico de acolhimento baseado nos pilares Trabalho como processo pedag\u00f3gico, Conviv\u00eancia em fam\u00edlia e a Espiritualidade para encontrar o sentido da vida. Com quatro unidades em funcionamento no Cear\u00e1, sendo a quinta a unidade a ser inaugurada na Serra da Meruoca, a Fazenda da Esperan\u00e7a, ao longo de sua atua\u00e7\u00e3o na regi\u00e3o norte do Estado, tem empreendido diversas iniciativas, por meio de seus mission\u00e1rios, volunt\u00e1rios e parceiros, para socorrer as pessoas que diuturnamente chegam at\u00e9 a institui\u00e7\u00e3o pedindo ajuda para se recuperar das drogas.<br \/>\n\u201cEm 2017 conseguimos realizar uma feira solid\u00e1ria com mercadorias doadas pela Receita Federal e um jantar beneficente, e no ano de 2018 tivemos um show com o Padre Reginaldo Manzotti, em prol da Fazenda feminina. Gra\u00e7as aos recursos arrecadados nessas iniciativas pudemos dar in\u00edcio \u00e0 constru\u00e7\u00e3o da Fazenda Santa Clara\u201d, destaca Liciana Fillizola, volunt\u00e1ria que coordena o novo projeto da comunidade terap\u00eautica.<br \/>\nSegundo Liciana, \u00e9 o envolvimento de toda sociedade civil que torna poss\u00edvel a concretiza\u00e7\u00e3o do sonho de uma unidade feminina da Fazenda da Esperan\u00e7a na regi\u00e3o. \u201c\u00c9 uma alegria estarmos concretizando esse sonho que nasceu no Ano da Miseric\u00f3rdia, em 2015, e que vem trazer \u00e0 nossa comunidade mais uma op\u00e7\u00e3o de acolhimento de mulheres para recuper\u00e1-las das drogas, tendo como diferencial a possibilidade de levar seus filhos, se necess\u00e1rio for, sendo mais uma fortaleza para contribuir com o seu tratamento\u201d, explica a volunt\u00e1ria.<br \/>\nDe acordo com Liciana, muitos foram os obst\u00e1culos enfrentados, no entanto maiores foram as d\u00e1divas e manifesta\u00e7\u00f5es da provid\u00eancia divina. \u201cForam muitos obst\u00e1culos enfrentados, que s\u00f3 nos fortaleceram e nos mostraram que as coisas de Deus nem sempre s\u00e3o f\u00e1ceis, mas no fim, al\u00e9m da evangeliza\u00e7\u00e3o, da transforma\u00e7\u00e3o de vida dessas mulheres que vamos recuperar, teremos a oportunidade de propagar a palavra do Evangelho e a Esperan\u00e7a a muitas pessoas que n\u00e3o t\u00eam problemas com a depend\u00eancia, mas t\u00eam fragilidades na f\u00e9, falta de Esperan\u00e7a e sentido de vida\u201d.<\/p>\n<p><strong>Campanha<\/strong><br \/>\nPara dar in\u00edcio ao trabalho de acolhimento e recupera\u00e7\u00e3o de mulheres na Serra da Meruoca, a Fazenda da Esperan\u00e7a est\u00e1 lan\u00e7ando uma campanha para mobiliar a primeira casa da comunidade terap\u00eautica. Com inaugura\u00e7\u00e3o prevista para o dia 11 de abril, dia em que ser\u00e1 celebrado o Domingo da Miseric\u00f3rdia no calend\u00e1rio lit\u00fargico, a Fazenda da Esperan\u00e7a est\u00e1 precisando de mob\u00edlia, eletrodom\u00e9sticos, utens\u00edlios de cozinha e colch\u00f5es para a casa. \u201cNessa reta final para inaugurar nossa Fazenda feminina, continuamos contando com a ajuda de toda a sociedade civil, toda ajuda \u00e9 bem vinda nesse projeto que tem como objetivo recuperar vidas e resgatar a dignidade de tantas mulheres e fam\u00edlias\u201d, enfatiza Liciana.<br \/>\nPara saber como ajudar a Fazenda da Esperan\u00e7a Santa Clara, entre em contato pelo fone (88) 3611-0054 ou pelo whatsapp (88) 99671-1865.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-15728\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.13.56.jpeg\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.13.56.jpeg 940w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.13.56-300x251.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.13.56-768x644.jpeg 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/> <img decoding=\"async\" class=\"alignleft size-full wp-image-15729\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.07.09.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.07.09.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.07.09-300x225.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.07.09-1024x768.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.07.09-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primeira unidade feminina da Fazenda na regi\u00e3o ter\u00e1 capacidade para acolher 15 mulheres em recupera\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-11-at-18.07.09.jpeg","jetpack-related-posts":[{"id":16847,"url":"https:\/\/correiodasemana.com\/site\/inaugurada-unidade-feminina-da-fazenda-da-esperanca-na-meruoca\/","url_meta":{"origin":15727,"position":0},"title":"Inaugurada unidade feminina da Fazenda da Esperan\u00e7a na Meruoca","author":"","date":"Junho 27, 2021","format":false,"excerpt":"Fazenda Santa Clara \u00e9 a segunda unidade de acolhimento para mulheres do Estado A Fazenda da Esperan\u00e7a \u00e9 uma comunidade terap\u00eautica que atua desde 1983 no processo de recupera\u00e7\u00e3o de pessoas que buscam a liberta\u00e7\u00e3o de seus v\u00edcios, principalmente do \u00e1lcool e da droga. No Brasil s\u00e3o mais de 105\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/fazenda-da-esperanca-santa-clara-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/fazenda-da-esperanca-santa-clara-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/fazenda-da-esperanca-santa-clara-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/fazenda-da-esperanca-santa-clara-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16584,"url":"https:\/\/correiodasemana.com\/site\/fazenda-da-esperanca-se-prepara-para-inauguracao-de-unidade-feminina-na-meruoca\/","url_meta":{"origin":15727,"position":1},"title":"Fazenda da Esperan\u00e7a se prepara para inaugura\u00e7\u00e3o de unidade feminina na Meruoca","author":"","date":"Maio 31, 2021","format":false,"excerpt":"Fazenda Santa Clara \u00e9 a segunda unidade feminina do Estado e ser\u00e1 inaugurada em junho Por Za\u00edra Almeida - Fazenda da Esperan\u00e7a A Fazenda da Esperan\u00e7a, institui\u00e7\u00e3o sem fins lucrativos que atua na recupera\u00e7\u00e3o de dependentes qu\u00edmicos, j\u00e1 iniciou os preparativos finais para inaugurar, no dia 20 de junho, mais\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/foto-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/foto-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/foto-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/foto-2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/foto-2.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15752,"url":"https:\/\/correiodasemana.com\/site\/missionaria-partilha-sua-experiencia-em-prol-da-recuperacao-de-mulheres-na-fazenda-da-esperanca\/","url_meta":{"origin":15727,"position":2},"title":"Mission\u00e1ria partilha sua experi\u00eancia em prol da recupera\u00e7\u00e3o de mulheres na Fazenda da Esperan\u00e7a","author":"","date":"Fevereiro 24, 2021","format":false,"excerpt":"\u201cDeixei tudo para tr\u00e1s, fam\u00edlia, trabalho e comecei essa divina aventura de escolher Deus como tudo\u201d A Fazenda da Esperan\u00e7a \u00e9 uma Associa\u00e7\u00e3o Internacional de Fi\u00e9is com reconhecimento pontif\u00edcio. Seu carisma teve in\u00edcio com a experi\u00eancia do jovem paulista Nelson Giovanelli, que \u00e0 \u00e9poca encontrou uma forma concreta de viver\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-18-at-18.59.59.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-18-at-18.59.59.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-18-at-18.59.59.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-18-at-18.59.59.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9120,"url":"https:\/\/correiodasemana.com\/site\/fazenda-da-esperanca-recebe-visita-da-vice-prefeita-de-sobral\/","url_meta":{"origin":15727,"position":3},"title":"Fazenda da Esperan\u00e7a recebe visita da vice-prefeita de Sobral","author":"","date":"Setembro 15, 2019","format":false,"excerpt":"Christianne Coelho conheceu as instala\u00e7\u00f5es da comunidade terap\u00eautica e reafirmou apoio aos projetos em prol da recupera\u00e7\u00e3o de dependentes qu\u00edmicos Za\u00edra Almeida - Assessoria de Imprensa da Fazenda da Esperan\u00e7a A vice-prefeita de Sobral, Christianne Coelho, visitou na \u00faltima quinta-feira (12) a Fazenda da Esperan\u00e7a S\u00e3o Bento, comunidade terap\u00eautica que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/vice-prefeita-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/vice-prefeita-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/vice-prefeita-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/vice-prefeita-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12373,"url":"https:\/\/correiodasemana.com\/site\/fazenda-da-esperanca-monta-espaco-para-acolher-dependentes-quimicos-em-situacao-de-rua\/","url_meta":{"origin":15727,"position":4},"title":"Fazenda da Esperan\u00e7a monta espa\u00e7o para acolher dependentes qu\u00edmicos em situa\u00e7\u00e3o de rua","author":"","date":"Julho 30, 2020","format":false,"excerpt":"A Coordena\u00e7\u00e3o da Fazenda da Esperan\u00e7a S\u00e3o Bento em Sobral, abra\u00e7a um novo projeto de instala\u00e7\u00e3o da Casa Padre Pio na Serra da Meruoca, com a miss\u00e3o de acolher pessoas com necessidades decorrentes das depend\u00eancias qu\u00edmicas em \u00e1lcool e outras drogas com extrema vulnerabilidade social que esteja em situa\u00e7\u00e3o de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/fazenda-da-esperan%C3%A7a-s%C3%A3o-bento2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/fazenda-da-esperan%C3%A7a-s%C3%A3o-bento2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/fazenda-da-esperan%C3%A7a-s%C3%A3o-bento2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/fazenda-da-esperan%C3%A7a-s%C3%A3o-bento2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/fazenda-da-esperan%C3%A7a-s%C3%A3o-bento2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":11957,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-celebra-missa-em-honra-a-sao-bento-na-fazenda-da-esperanca\/","url_meta":{"origin":15727,"position":5},"title":"Dom Vasconcelos celebra missa em honra a S\u00e3o Bento na Fazenda da Esperan\u00e7a","author":"","date":"Julho 19, 2020","format":false,"excerpt":"Celebra\u00e7\u00e3o eucar\u00edstica tamb\u00e9m marcou o anivers\u00e1rio de cinco anos de inaugura\u00e7\u00e3o do Santu\u00e1rio da Esperan\u00e7a O bispo da Diocese de Sobral, Dom Vasconcelos, esteve na Fazenda da Esperan\u00e7a S\u00e3o Bento no \u00faltimo dia 11 de julho, ocasi\u00e3o em que celebrou a missa em honra a S\u00e3o Bento, santo padroeiro da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/dom-11-07-2020-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/dom-11-07-2020-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/dom-11-07-2020-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/dom-11-07-2020-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15727"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15727\/revisions"}],"predecessor-version":[{"id":15731,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15727\/revisions\/15731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15729"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}