{"id":15732,"date":"2021-02-16T00:44:16","date_gmt":"2021-02-16T03:44:16","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15732"},"modified":"2021-02-16T00:44:16","modified_gmt":"2021-02-16T03:44:16","slug":"em-tempo-69","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-69\/","title":{"rendered":"Em Tempo"},"content":{"rendered":"<p><strong>Material do Projeto #EstudoEmCasa<\/strong><br \/>\nSecret\u00e1rio da Educa\u00e7\u00e3o de Sobral, Herbert Lima, recebeu das m\u00e3os do coordenador da 6\u00aa Coordenadoria da Educa\u00e7\u00e3o, Daniel Costa, material de apoio do projeto #EstudoEmCasa, para apoiar professores do Ensino Fundamental e Educa\u00e7\u00e3o Infantil nas aulas remotas.<br \/>\nForam entregues 945 exemplares de colet\u00e2nea com material de forma\u00e7\u00e3o docente e para estudantes do 1\u00ba ao 9\u00ba ano, nas disciplinas de L\u00edngua Portuguesa, Matem\u00e1tica, Ci\u00eancias da Natureza e Ci\u00eancias Humanas, al\u00e9m de v\u00eddeos, podcast, cadernos de atividades e cards.<\/p>\n<p><strong>Cursos do Porto Iracema das Artes<\/strong><br \/>\nO Porto Iracema das Artes inicia o ano letivo de 2021, em Fortaleza, com oferta de 165 vagas para diferentes \u00e1reas. Ser\u00e3o sete forma\u00e7\u00f5es distribu\u00eddas entre o Programa de Fotopo\u00e9ticas (90 vagas) e os Cursos B\u00e1sicos de Artes Visuais (40), Artes C\u00eanicas (20) e Audiovisual (15).<br \/>\nInscri\u00e7\u00f5es at\u00e9 18 de fevereiro. O p\u00fablico priorit\u00e1rio \u00e9 da faixa et\u00e1ria entre 16 e 29 anos, bem como alunos da escola p\u00fablica cursando ou que tenham conclu\u00eddo o Ensino M\u00e9dio. Aulas ser\u00e3o online e os cursos gratuitos. Informa\u00e7\u00f5es no site: http:\/\/portal.portoiracemadasartes.org<\/p>\n<p><strong>Instrumental Pingo de Fortaleza <\/strong><br \/>\n<strong>Foto &#8211; Luiz Alves<\/strong><br \/>\n<strong><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-15733 alignright\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/DRAGAO_Pingo-de-Fortaleza1-Foto-Luiz-Alves-600x397-1.jpg\" alt=\"\" width=\"320\" height=\"212\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/DRAGAO_Pingo-de-Fortaleza1-Foto-Luiz-Alves-600x397-1.jpg 600w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/DRAGAO_Pingo-de-Fortaleza1-Foto-Luiz-Alves-600x397-1-300x199.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>Pingo de Fortaleza demonstrou toda sua capacidade de compositor e m\u00fasico<\/strong><br \/>\nO Espet\u00e1culo \u201cInstrumental Pingo de Fortaleza\u201d, apresentou de forma in\u00e9dita o m\u00fasico cearense oito composi\u00e7\u00f5es, com uma t\u00e9cnica pr\u00f3pria e\u00a0apurada, que mescla o viol\u00e3o medieval e renascentista com a sonoridade e os ritmos contempor\u00e2neos\u00a0nordestinos e de outras ess\u00eancias.<br \/>\nO show ocorreu no dia 12 de fevereiro, \u00e0s 19h, no Youtube, com apoio da Secretaria da Cultura do Cear\u00e1, na programa\u00e7\u00e3o de Carnaval.\u00a0Esse in\u00e9dito \u201cInstrumental Pingo de Fortaleza\u201d foi gravado e editado pelo artista, em sua resid\u00eancia, nesses tempos de distanciamento Social.<\/p>\n<p><strong>Dessaliniza\u00e7\u00e3o de \u00e1gua-marinha\u00a0<\/strong><br \/>\nAs obras para constru\u00e7\u00e3o da\u00a0usina de dessaliniza\u00e7\u00e3o\u00a0de \u00e1gua-marinha que ficar\u00e1 instalada na regi\u00e3o da Praia do Futuro devem ser iniciadas em at\u00e9 18 meses, portanto, at\u00e9 agosto de 2022. Informa\u00e7\u00e3o \u00e9 da empresa cearense Marquise, l\u00edder do Cons\u00f3rcio \u00c1guas de Fortaleza.<br \/>\nNo dia 9 de fevereiro, a Companhia de \u00c1gua e Esgoto do Cear\u00e1 (Cagece) reconheceu o cons\u00f3rcio como habilitado no processo licitat\u00f3rio para constru\u00e7\u00e3o, opera\u00e7\u00e3o e manuten\u00e7\u00e3o do equipamento, ap\u00f3s apresentar uma proposta de\u00a0R$ 118 milh\u00f5es, a de menor valor.<\/p>\n<p><strong>Sistemas de energia solar no Cear\u00e1<\/strong><br \/>\nEm 2020, o Cear\u00e1 ultrapassou a marca de 10 mil sistemas de energia solar. No ano, o Estado recebeu\u00a06.050 novas conex\u00f5es\u00a0de sistemas fotovoltaicos de gera\u00e7\u00e3o distribu\u00edda, o que representou um incremento de\u00a0135%\u00a0em rela\u00e7\u00e3o ao registrado em 2019 (2.573 novas conex\u00f5es).<br \/>\nApenas neste ano, de 1\u00b0 de janeiro at\u00e9 8 de fevereiro, foram feitas mais 622 novas conex\u00f5es de sistemas solares. Com este incremento, Cear\u00e1 tem hoje,\u00a0170,9 megawatts (MW) de pot\u00eancia instalada, sendo o nono estado brasileiro com maior pot\u00eancia e o maior do Nordeste.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br). Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Material do Projeto #EstudoEmCasa Secret\u00e1rio da Educa\u00e7\u00e3o de Sobral, Herbert Lima, recebeu das m\u00e3os do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-15732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg","jetpack-related-posts":[{"id":17036,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-91\/","url_meta":{"origin":15732,"position":0},"title":"Em Tempo","author":"","date":"Julho 19, 2021","format":false,"excerpt":"Cursos de l\u00ednguas estrangeiras O Pal\u00e1cio de Ci\u00eancias e L\u00ednguas Estrangeiras, da Secretaria da Educa\u00e7\u00e3o de Sobral, est\u00e1 com inscri\u00e7\u00f5es abertas para novos alunos dos cursos de Ingl\u00eas, Espanhol, Franc\u00eas, Italiano e Inform\u00e1tica. As inscri\u00e7\u00f5es seguem at\u00e9 23 de julho, exclusivamente, pela internet. As aulas come\u00e7am dia 16 de agosto.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27565,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-205\/","url_meta":{"origin":15732,"position":1},"title":"Em Tempo","author":"adminredacao","date":"Dezembro 11, 2023","format":false,"excerpt":"145 vagas para professor na UVA A Universidade Estadual Vale do Acara\u00fa (UVA) divulgou o novo cronograma do concurso p\u00fablico para professor efetivo nas classes Auxiliar, Assistente e Adjunto, destinado ao preenchimento de 145 vagas nos campi de Sobral, S\u00e3o Benedito, Acara\u00fa e Camocim. Aplica\u00e7\u00e3o da prova escrita dissertativa (1\u00aa\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/Fabricio-escritor-300x200.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":24657,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-175\/","url_meta":{"origin":15732,"position":2},"title":"Em Tempo","author":"adminredacao","date":"Maio 14, 2023","format":false,"excerpt":"Sobral sediar\u00e1 congresso internacional Nos dias 8,9 e 10 de junho acontecer\u00e1 em Sobral o XIX Congresso Internacional sobre Patologia e Reabilita\u00e7\u00e3o das Constru\u00e7\u00f5es (Cinpar 2023). O presidente do comit\u00ea executivo \u00e9 o professor Francisco Carvalho, vice-reitor da Universidade Estadual Vale do Acara\u00fa (UVA). O Cinpar surgiu em 2003, com\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/ok-rita_6--300x179.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":33317,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-272\/","url_meta":{"origin":15732,"position":3},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Abril 14, 2025","format":false,"excerpt":"Inscri\u00e7\u00f5es para o Vestibular UVA 2025.2 A Universidade Estadual Vale do Acara\u00fa (UVA) recebe inscri\u00e7\u00f5es at\u00e9 o dia 6 de maio para Vestibular 2025.2, com aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem). Ser\u00e3o aceitas as pontua\u00e7\u00f5es das dez \u00faltimas edi\u00e7\u00f5es, realizadas entre 2015 e 2024. S\u00e3o ofertadas\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10385,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-25\/","url_meta":{"origin":15732,"position":4},"title":"Em Tempo","author":"","date":"Janeiro 5, 2020","format":false,"excerpt":"UFC tem quatro vagas de professor A Universidade Federal do Cear\u00e1 realizar\u00e1 sele\u00e7\u00e3o de professor substituto para os campi de Fortaleza e Quixad\u00e1. Ao todo, s\u00e3o disponibilizadas\u00a0quatro vagas, com\u00a0inscri\u00e7\u00f5es a partir do dia 6 de janeiro. A jornada de trabalho \u00e9 de 40 horas. No edital, per\u00edodo de inscri\u00e7\u00e3o e\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/frei-.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/frei-.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/frei-.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/frei-.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37590,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-316\/","url_meta":{"origin":15732,"position":5},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Mar\u00e7o 3, 2026","format":false,"excerpt":"Fortalecimento da agricultura ecol\u00f3gica A Universidade Estadual Vale do Acara\u00fa (UVA), com apoio do Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico (CNPq), recebeu, dia 12 de fevereiro, equipamentos e insumos paraa\u00e7\u00f5es de pesquisa e inova\u00e7\u00e3o voltadas \u00e0 agroecologia e \u00e0 produ\u00e7\u00e3o org\u00e2nica. Entre os itens, destaca-se um tratorito, entregue na\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/03\/okFeito-Pipa-_.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/03\/okFeito-Pipa-_.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/03\/okFeito-Pipa-_.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/03\/okFeito-Pipa-_.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/03\/okFeito-Pipa-_.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15732"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15732\/revisions"}],"predecessor-version":[{"id":15735,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15732\/revisions\/15735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}