{"id":15800,"date":"2021-02-28T21:28:13","date_gmt":"2021-03-01T00:28:13","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15800"},"modified":"2021-02-28T21:28:59","modified_gmt":"2021-03-01T00:28:59","slug":"igreja-menino-deus-esta-com-85-de-suas-obras-de-restauracao-concluidas","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/igreja-menino-deus-esta-com-85-de-suas-obras-de-restauracao-concluidas\/","title":{"rendered":"Igreja Menino Deus est\u00e1 com 85% de suas obras de restaura\u00e7\u00e3o conclu\u00eddas"},"content":{"rendered":"<p>Por Samuel Carvalho &#8211; Reda\u00e7\u00e3o Correio da Semana<br \/>\nEm reforma desde o dia 28 de Janeiro de 2020, a Igreja Menino Deus localizada no centro de Sobral e pr\u00f3xima a Pra\u00e7a S\u00e3o Jo\u00e3o j\u00e1 apresenta 85% de suas obras conclu\u00eddas. Apesar do n\u00famero expressivo, grande parte da restaura\u00e7\u00e3o ainda precisa ser conclu\u00edda no interior da Igreja, enquanto sua parte externa j\u00e1 est\u00e1 pronta.<br \/>\nConstru\u00edda na d\u00e9cada de 1810, a Igreja Menino Deus e o convento anexado foram constru\u00eddos com ajuda das doa\u00e7\u00f5es e generosidades de fam\u00edlias sobralenses por duas irm\u00e3s carmelitas, junto \u00e0s Freiras de Ordem Terceira das Carmelitas Emerenciana de Sant\u2019Ana e Teresa de Jesus. A reforma em curso tem o objetivo de retornar \u00e0s origens da obra, a fim de preservar tanto a igreja como estrutura, mas tamb\u00e9m resgatar sua hist\u00f3ria atrav\u00e9s das diversas modifica\u00e7\u00f5es feitas ao longo dos anos.<br \/>\nEntre as partes conclu\u00eddas, destacam-se a pintura original da Igreja descoberta atrav\u00e9s da raspagem de camadas de tinta at\u00e9 chegar na primeira m\u00e3o, nas cores amarelo e branco. Externamente, foram adicionados tamb\u00e9m para-raios para evitar poss\u00edveis danos causados por descargas el\u00e9tricas na estrutura da Igreja. Por fora, as obras parecem estar em andamento acelerado, entretanto o interior da igreja ainda precisa ser trabalhado com afinco para sua inaugura\u00e7\u00e3o completa.<br \/>\n\u201cA principal reforma foi o forro lateral e o telhado. Estava todo podre e reformamos por inteiro, telhas, amarramos todas elas, restauramos as portas, muito da parte de baixo delas tamb\u00e9m estavam podres e n\u00f3s refizemos. O reboco tamb\u00e9m descascamos mais de 50% por dentro e por fora e rebocamos novamente, a fia\u00e7\u00e3o que era toda de sobrepor, colocamos toda embutida o que \u00e9 importante para a Igreja ficar bonita\u201d revelou Jos\u00e9 Bonfim, mestre de obras respons\u00e1vel pela execu\u00e7\u00e3o do projeto estrutural. Assim como a pintura original externa, tamb\u00e9m foi descoberta a cor original das portas de madeira de todo a igreja, que s\u00e3o verdes, todas tamb\u00e9m cuidadosamente retornaram a como eram quando foi inaugurada pela primeira vez.<br \/>\nApesar do estado avan\u00e7ado de obras, boa parte da nave principal ainda precisa ser trabalhada. Um dos destaques da Igreja Menino Deus \u00e9 seu forro central que apresenta um not\u00e1vel baixo relevo em talha policromada, de car\u00e1ter popular, representando a Sagrada Fam\u00edlia em fuga para o Egito. Toda essa parte ser\u00e1 detalhadamente restaurada, preservando a identidade da Igreja e real\u00e7ando as cores que estavam desgastadas com pelo o tempo. Essa parte do processo est\u00e1 em espera, pois ser\u00e1 realizada por restauradores vindos de Salvador, Bahia, que ir\u00e3o terminar de concluir todo o forro.<br \/>\nSegundo Valdenir J\u00fanior, engenheiro respons\u00e1vel pela obra grande parte dos esfor\u00e7os foi para assegurar a preserva\u00e7\u00e3o hist\u00f3rica, deixando apenas aquilo que caracteriza o estilo arquitet\u00f4nico do edif\u00edcio. O que foi mantido intacto foram as imagens de santos e santas presentes no templo, hoje retirados para preserv\u00e1-los durante as obras. O sacr\u00e1rio e o piso tamb\u00e9m n\u00e3o foram alterados e ser\u00e1 uma das poucas partes da igreja que ir\u00e3o ser mantidos como eram antes da obra de restaura\u00e7\u00e3o.<br \/>\nOutra mudan\u00e7a significativa est\u00e1 no altar que foi rebaixado 71 cm para voltar ao piso original do altar constru\u00eddo na d\u00e9cada de 1810. Todo o gratino presente tamb\u00e9m ser\u00e1 renovado para garantir um aspecto novo ao altar. O piso ainda ser\u00e1 completamente polido bem como os bancos tamb\u00e9m ganhar\u00e3o tratamento especial para a inaugura\u00e7\u00e3o.<br \/>\nMuito foi feito, por\u00e9m muito ainda precisa ser trabalhado. Ainda sem data de inaugura\u00e7\u00e3o, a expectativa \u00e9 que a obra esteja completa em 2 meses. Devido \u00e1 pandemia ainda n\u00e3o se sabe como ocorrer\u00e1 a cerim\u00f4nia que vai devolver a Igreja Menino Deus \u00e0 popula\u00e7\u00e3o sobralense, que \u00e9 uma das mais queridas e visitas pelos habitantes de Sobral, mas uma coisa \u00e9 certa: a espera valer\u00e1 a pena.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-15801\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-2.jpg\" alt=\"\" width=\"999\" height=\"669\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-2.jpg 999w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-2-300x201.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-2-768x514.jpg 768w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/> <img decoding=\"async\" class=\"alignleft size-full wp-image-15802\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-3.jpg\" alt=\"\" width=\"999\" height=\"669\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-3.jpg 999w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-3-300x201.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-3-768x514.jpg 768w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/> <img decoding=\"async\" class=\"alignleft size-full wp-image-15803\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-4.jpg\" alt=\"\" width=\"999\" height=\"669\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-4.jpg 999w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-4-300x201.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-4-768x514.jpg 768w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho &#8211; Reda\u00e7\u00e3o Correio da Semana Em reforma desde o dia 28 de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/reforma-da-igreja-menino-Deus-3.jpg","jetpack-related-posts":[{"id":14385,"url":"https:\/\/correiodasemana.com\/site\/restauracao-da-igreja-menino-deus-em-sobral-segue-em-estado-avancado\/","url_meta":{"origin":15800,"position":0},"title":"Restaura\u00e7\u00e3o da Igreja Menino Deus, em Sobral, segue em estado avan\u00e7ado","author":"","date":"Novembro 3, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. As obras de restaura\u00e7\u00e3o da Igreja Menino Deus, localizada na cidade de Sobral (CE) seguem avan\u00e7ando e se encontram em estado avan\u00e7ado. A reforma j\u00e1 se encontra com cerca de 70% das obras conclu\u00eddas. As obras ficaram cerca de tr\u00eas meses paradas, por conta do isolamento social\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/DSC8355.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/DSC8355.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/DSC8355.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13514,"url":"https:\/\/correiodasemana.com\/site\/reforma-da-igreja-menino-deus-esta-com-70-das-obras-concluidas\/","url_meta":{"origin":15800,"position":1},"title":"Reforma da Igreja Menino Deus est\u00e1 com 70% das Obras Conclu\u00eddas","author":"","date":"Setembro 15, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. Foram retomadas, a cerca de um m\u00eas, as obras de reforma da Igreja Menino Deus, localizada na cidade de Sobral (CE). A reforma j\u00e1 se encontra com cerca de 70% das obras conclu\u00eddas. As obras ficaram cerca de tr\u00eas meses paradas, por conta do isolamento social obrigat\u00f3rio\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/DSC3537.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/DSC3537.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/DSC3537.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/09\/DSC3537.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18802,"url":"https:\/\/correiodasemana.com\/site\/sobral-recebe-visita-do-ministro-do-turismo-para-entrega-da-igreja-menino-deus-e-vistoria-da-ponte-estaiada\/","url_meta":{"origin":15800,"position":2},"title":"Sobral recebe visita do Ministro do Turismo para entrega da Igreja Menino Deus e vistoria da ponte estaiada","author":"","date":"Fevereiro 7, 2022","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana O Ministro do Turismo, Gilson Machado visitou Sobral, sexta-feira (04\/02), para juntamente aos representantes da Diocese de Sobral, Secretaria da Cultura e Turismo de Sobral, Secretaria de Urbanismo, Habita\u00e7\u00e3o e Meio Ambiente e Prefeitura de Sobral entregar a reforma da Igreja do Menino\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-6.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-6.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18776,"url":"https:\/\/correiodasemana.com\/site\/igreja-do-menino-deus-e-reinaugurada\/","url_meta":{"origin":15800,"position":3},"title":"Igreja do Menino Deus \u00e9 reinaugurada","author":"","date":"Fevereiro 7, 2022","format":false,"excerpt":"Reda\u00e7\u00e3o Correio da Semana Nesta sexta-feira (04\/02), a Igreja do Menino foi reinaugurada em ato solene. A restaura\u00e7\u00e3o \u00e9 uma realiza\u00e7\u00e3o do munic\u00edpio de Sobral com o Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional (IPHAN) e contou com investimento de mais de R$ 1,3 milh\u00f5es. A obra da constru\u00e7\u00e3o hist\u00f3rica\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-8.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-8.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-8.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/igreja-menino-deus-8.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18321,"url":"https:\/\/correiodasemana.com\/site\/dirigentes-do-iphan-e-ivo-gomes-fazem-visitas-a-obras-de-restauracao-em-sobral\/","url_meta":{"origin":15800,"position":4},"title":"Dirigentes do IPHAN e Ivo Gomes fazem visitas a obras de restaura\u00e7\u00e3o em Sobral","author":"","date":"Dezembro 12, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana O prefeito Ivo Gomes (PDT) visitou na manh\u00e3 da \u00faltima ter\u00e7a-feira (07), junto com o diretor do Departamento de Projetos Especiais do Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional (Iphan) de Bras\u00edlia, Arlindo Pires Lopes, e com o superintendente do Iphan no Cear\u00e1,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-09-at-20.06.39.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-09-at-20.06.39.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-09-at-20.06.39.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/WhatsApp-Image-2021-12-09-at-20.06.39.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35080,"url":"https:\/\/correiodasemana.com\/site\/comunidade-de-reriutaba-vive-noite-historica-com-a-dedicacao-do-altar-e-da-igreja-matriz\/","url_meta":{"origin":15800,"position":5},"title":"Comunidade de Reriutaba vive noite hist\u00f3rica com a Dedica\u00e7\u00e3o do Altar e da Igreja Matriz","author":"adminredacao","date":"Agosto 17, 2025","format":false,"excerpt":"Em uma celebra\u00e7\u00e3o repleta de simbolismos e significados, a comunidade paroquial de Reriutaba participou, na noite desta ter\u00e7a-feira (05), da Solenidade de Dedica\u00e7\u00e3o do Altar e da Igreja Matriz de Nossa Senhora do Perp\u00e9tuo Socorro. A Santa Missa, presidida por Dom Vasconcelos, marcou a abertura da Festa em honra \u00e0\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/igreja-reriutaba-14.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/igreja-reriutaba-14.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/igreja-reriutaba-14.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/igreja-reriutaba-14.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/igreja-reriutaba-14.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/igreja-reriutaba-14.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15800"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15800\/revisions"}],"predecessor-version":[{"id":15804,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15800\/revisions\/15804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15802"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}