{"id":15869,"date":"2021-03-07T22:14:47","date_gmt":"2021-03-08T01:14:47","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15869"},"modified":"2021-03-07T22:14:47","modified_gmt":"2021-03-08T01:14:47","slug":"a-figura-do-auditor-instrutor-e-suas-funcoes-no-tribunal-eclesiastico","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/a-figura-do-auditor-instrutor-e-suas-funcoes-no-tribunal-eclesiastico\/","title":{"rendered":"A Figura do auditor\/instrutor e suas fun\u00e7\u00f5es no Tribunal Eclesi\u00e1stico"},"content":{"rendered":"<p>\u201cA Igreja Cat\u00f3lica disp\u00f5e de um ordenamento jur\u00eddico que atende na sua organiza\u00e7\u00e3o \u00e0quelas demandas surgidas na vida pastoral, mas que cont\u00e9m um ato jur\u00eddico de fundo, como \u00e9 o caso do Matrim\u00f4nio. Para tanto, existem na Igreja os tribunais eclesi\u00e1sticos. Trata-se de um instrumento t\u00e9cnico-jur\u00eddico, utilizado para a resolu\u00e7\u00e3o dos conflitos entre os fi\u00e9is. Podem ser objeto de julgamento um fato jur\u00eddico a ser declarado, como a validade ou n\u00e3o de um matrim\u00f4nio, os problemas de indisciplina de pessoas do clero e de leigos, as faltas contra os sacramentos e outros assuntos. O tribunal \u00e9 de fundamental import\u00e2ncia para o exame, a discuss\u00e3o e a decis\u00e3o de um assunto de compet\u00eancia da Igreja.<br \/>\nOs tribunais podem ser de primeira inst\u00e2ncia ou se segunda inst\u00e2ncia. Onde n\u00e3o houver um tribunal, normalmente haver\u00e1 uma c\u00e2mara eclesi\u00e1stica, que \u00e9 um importante instrumento de aux\u00edlio ao tribunal interdiocesano ou regional.<br \/>\nO presidente do tribunal pode designar um auditor para realizar a instru\u00e7\u00e3o da causa, escolhendo-o entre os ju\u00edzes do tribunal ou entre as pessoas aprovadas pelo bispo para esta fun\u00e7\u00e3o. O auditor n\u00e3o julga a causa, apenas ouve as pessoas envolvidas no processo e recolhe as provas e as entrega ao juiz. Pode ser um cl\u00e9rigo ou um leigo que se distinga pelos bons costumes, prud\u00eancia e doutrina (c\u00e2n. 142, \u00a7 1 e \u00a7 2). Para as c\u00e2maras eclesi\u00e1sticas, a nomea\u00e7\u00e3o do auditor e do not\u00e1rio \u00e9 feita sempre pelo bispo diocesano da respectiva diocese (DC art. 23 \u00a7 2).<br \/>\nA fun\u00e7\u00e3o dos auditores, portanto, \u00e9 instruir a causa, recolher as provas (ouvir os depoimentos das partes, fazer os interrogat\u00f3rios das testemunhas e coletar os documentos e boletins periciais); fixar a audi\u00eancia e os prazos para os atos das partes e das testemunhas e, conclu\u00edda a fase instrut\u00f3ria, remeter todos os autos ao tribunal interdiocesano ou regional\u0094<\/p>\n<p>Pe. Jo\u00e3o Batista Nery de Abreu &#8211; Juiz Instrutor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA Igreja Cat\u00f3lica disp\u00f5e de um ordenamento jur\u00eddico que atende na sua organiza\u00e7\u00e3o \u00e0quelas demandas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,33],"tags":[],"class_list":["post-15869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-direito-canonico"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/padre-nery.jpg","jetpack-related-posts":[{"id":21464,"url":"https:\/\/correiodasemana.com\/site\/matrimonio-declarado-nulo-pelo-tribunal-eclesiastico-regional-e-de-apelacao-do-ceara-terace\/","url_meta":{"origin":15869,"position":0},"title":"MATRIM\u00d4NIO DECLARADO NULO PELO TRIBUNAL ECLESI\u00c1STICO REGIONAL E DE APELA\u00c7\u00c3O DO CEAR\u00c1- TERACE","author":"","date":"Novembro 6, 2022","format":false,"excerpt":"01. Matrim\u00f4nio DECLARADO NULO pelo Tribunal Eclesi\u00e1stico do Cear\u00e1. Protocolo 24\/2020 com Senten\u00e7a Executiva em 28\/09\/2022. De acordo com o c\u00e2n. 1684,1, GEORGIANE H\u00c9LIA VASCONCELOS e MILTON C\u00c9SAR SILVEIRA retornam a liberdade no foro eclesi\u00e1stico, podendo contrair novas n\u00fapcias perante a Igreja Cat\u00f3lica. 02. Matrim\u00f4nio DECLARADO NULO pelo Tribunal Eclesi\u00e1stico\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Igreja-do-Menino-Deus-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Igreja-do-Menino-Deus-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Igreja-do-Menino-Deus-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Igreja-do-Menino-Deus-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Igreja-do-Menino-Deus-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Igreja-do-Menino-Deus-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12977,"url":"https:\/\/correiodasemana.com\/site\/tse-rejeita-punicao-para-abuso-de-poder-religioso-nas-eleicoes\/","url_meta":{"origin":15869,"position":1},"title":"TSE rejeita puni\u00e7\u00e3o para abuso de poder religioso nas elei\u00e7\u00f5es","author":"","date":"Agosto 19, 2020","format":false,"excerpt":"Maioria dos ministros divergiu do entendimento do relator O Tribunal Superior Eleitoral (TSE) rejeitou hoje (13) a possibilidade da aplica\u00e7\u00e3o da conduta de abuso de poder religioso nas elei\u00e7\u00f5es municipais deste ano. A maioria dos ministros do tribunal divergiu do entendimento do relator, Edson Fachin, que defendeu a tese para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/tribunal-superior-eleitoral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/tribunal-superior-eleitoral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/tribunal-superior-eleitoral.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/tribunal-superior-eleitoral.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/tribunal-superior-eleitoral.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15645,"url":"https:\/\/correiodasemana.com\/site\/palavras-do-santo-padre\/","url_meta":{"origin":15869,"position":2},"title":"Palavras do Santo Padre","author":"","date":"Fevereiro 6, 2021","format":false,"excerpt":"\u201cPapa Francisco, na audi\u00eancia desta sexta-feira (29) de inaugura\u00e7\u00e3o do Ano Judici\u00e1rio do Tribunal Apost\u00f3lico da Rota Romana, no Vaticano, direcionou o discurso ao tema do matrim\u00f4nio legalmente declarado nulo de uma quest\u00e3o relevante: \u201co que ser\u00e1 dos filhos e da parte que n\u00e3o aceita a declara\u00e7\u00e3o de nulidade?.\u201d Francisco\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/2020-06-03t113251z_1_lynxmpeg5214t_rtroptp_3_religiao-papa-racismo-eua.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/2020-06-03t113251z_1_lynxmpeg5214t_rtroptp_3_religiao-papa-racismo-eua.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/2020-06-03t113251z_1_lynxmpeg5214t_rtroptp_3_religiao-papa-racismo-eua.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/2020-06-03t113251z_1_lynxmpeg5214t_rtroptp_3_religiao-papa-racismo-eua.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/2020-06-03t113251z_1_lynxmpeg5214t_rtroptp_3_religiao-papa-racismo-eua.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":36705,"url":"https:\/\/correiodasemana.com\/site\/a-oab-subseccao-sobral-instala-comissao-especial-de-direito-canonico\/","url_meta":{"origin":15869,"position":3},"title":"A OAB Subsec\u00e7\u00e3o Sobral instala Comiss\u00e3o Especial de Direito Can\u00f4nico","author":"adminredacao","date":"Dezembro 11, 2025","format":false,"excerpt":"A OAB Subsec\u00e7\u00e3o Sobral realizou, nesta quarta-feira (03\/12), a solenidade oficial de instala\u00e7\u00e3o da Comiss\u00e3o Especial de Direito Can\u00f4nico, marcando um momento in\u00e9dito e significativo para a advocacia sobralense. O evento reuniu advogados, acad\u00eamicos, autoridades eclesi\u00e1sticas e convidados, selando o in\u00edcio das atividades da nova comiss\u00e3o. A cerim\u00f4nia, presidida pelo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-05-at-13.02.41.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-05-at-13.02.41.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-05-at-13.02.41.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-05-at-13.02.41.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-05-at-13.02.41.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-05-at-13.02.41.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":25497,"url":"https:\/\/correiodasemana.com\/site\/encerrada-a-fase-diocesana-da-causa-de-beatificacao-e-canonizacao-do-servo-de-deus-pe-arnobio\/","url_meta":{"origin":15869,"position":4},"title":"Encerrada a fase diocesana da Causa de Beatifica\u00e7\u00e3o e Canoniza\u00e7\u00e3o do Servo de Deus,\u00a0Pe.\u00a0Arn\u00f3bio","author":"adminredacao","date":"Julho 3, 2023","format":false,"excerpt":"Dia 30 de junho de 2023, com j\u00fabilo e muita f\u00e9 as Mission\u00e1rias Reparadoras do Cora\u00e7\u00e3o de Jesus, junto \u00e0 Diocese de Sobral, na pessoa de Dom Jos\u00e9 Lu\u00eds Gomes de Vasconcelos, celebra o encerramento da fase diocesana da Causa de Beatifica\u00e7\u00e3o e Canoniza\u00e7\u00e3o do Servo de Deus Joaquim Arn\u00f3bio\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/DSC5964.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/DSC5964.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/DSC5964.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/DSC5964.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9563,"url":"https:\/\/correiodasemana.com\/site\/stf-suspende-julgamento-de-prisao-apos-condenacao-em-segunda-instancia\/","url_meta":{"origin":15869,"position":5},"title":"STF suspende julgamento de pris\u00e3o ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia","author":"","date":"Outubro 28, 2019","format":false,"excerpt":"Por\u00a0Andr\u00e9 Richter \u2013 Rep\u00f3rter da Ag\u00eancia Brasil\u00a0\u00a0Bras\u00edlia O ministro do Supremo Tribunal Federal (STF) Ricardo Lewandowski votou dia (24) contra a validade da execu\u00e7\u00e3o provis\u00f3ria de condena\u00e7\u00f5es criminais, conhecida como pris\u00e3o ap\u00f3s segunda inst\u00e2ncia. Com o voto do ministro, ap\u00f3s quatro sess\u00f5es de julgamento, o placar est\u00e1 4 votos a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15869"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15869\/revisions"}],"predecessor-version":[{"id":15871,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15869\/revisions\/15871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15870"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}