{"id":15886,"date":"2021-03-07T23:41:36","date_gmt":"2021-03-08T02:41:36","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15886"},"modified":"2021-03-07T23:41:36","modified_gmt":"2021-03-08T02:41:36","slug":"nova-parcela-do-auxilio-emergencial-deve-comecar-a-ser-pago-dia-18-de-marco","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/nova-parcela-do-auxilio-emergencial-deve-comecar-a-ser-pago-dia-18-de-marco\/","title":{"rendered":"Nova parcela do aux\u00edlio emergencial deve come\u00e7ar a ser pago dia 18 de Mar\u00e7o"},"content":{"rendered":"<p>Por Samuel Carvalho &#8211; Reda\u00e7\u00e3o Correio da Semana<\/p>\n<p>O Governo Federal deve iniciar o pagamento da nova parcela do aux\u00edlio emergencial no dia 18 de Mar\u00e7o, frente ao avan\u00e7o da pandemia no pa\u00eds. A data inicial \u00e9 destinada aos benefici\u00e1rios do Bolsa Fam\u00edlia, j\u00e1 o restante dos trabalhadores deve receber a partir dos \u00faltimos dias do m\u00eas. O Minist\u00e9rio da Economia est\u00e1 elaborando modelos para manter o valor total do programa em R$ 30 bilh\u00f5es, com valor m\u00e1ximo previsto o total de R$ 40 bilh\u00f5es.<br \/>\nO programa segue com reformula\u00e7\u00f5es e agora deve considerar o n\u00famero de pessoas e composi\u00e7\u00e3o familiar para ceder o novo aux\u00edlio emergencial. Os valores dever\u00e3o ser pagos em quatro parcelas para apenas um membro da fam\u00edlia. As novas faixas de pagamento preveem que para mulheres chefes de fam\u00edlia recebam R$ 375,00 segundo o plano. J\u00e1 para fam\u00edlias com duas ou mais pessoas, exceto daquelas com m\u00e3es chefes de fam\u00edlia devem receber um total de R$ 250,00. Para fam\u00edlias com apenas uma pessoa, inicialmente o valor estabelecido \u00e9 de R$ 150,00 o que pode sofrer varia\u00e7\u00f5es entre R$ 125,00 e R$ 175,00.<br \/>\nO texto-base da Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) Emergencial foi aprovado na \u00faltima quarta-feira, medida esta reformulada para destravar a nova rodada do aux\u00edlio emergencial. Ao todo, foram 62 votos favor\u00e1veis e 16 contr\u00e1rios. Os senadores ainda v\u00e3o analisar altera\u00e7\u00f5es no texto e votar a medida em segundo turno. Ap\u00f3s, a proposta vai para a C\u00e2mara dos Deputados. A aprova\u00e7\u00e3o da PEC tamb\u00e9m permite que o Governo possa decretar um novo estado de calamidade a qualquer momento para combater efeitos sociais e econ\u00f4micos potencializados por uma crise, como a de covid-19. Dessa forma a medida possibilita um aumento de gastos mais simplificado para conseguir conceber benef\u00edcios, por exemplo repasse para Estados e munic\u00edpios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho &#8211; Reda\u00e7\u00e3o Correio da Semana O Governo Federal deve iniciar o pagamento&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/unnamed-8.jpg","jetpack-related-posts":[{"id":16019,"url":"https:\/\/correiodasemana.com\/site\/nova-rodada-do-auxilio-emergencial-como-serao-os-pagamentos-quem-vai-receber-e-o-que-falta-saber\/","url_meta":{"origin":15886,"position":0},"title":"Nova rodada do Aux\u00edlio Emergencial: como ser\u00e3o os pagamentos, quem vai receber e o que falta saber","author":"","date":"Mar\u00e7o 22, 2021","format":false,"excerpt":"Pagamento ser\u00e1 feito em quarto parcelas; valor m\u00e9dio ser\u00e1 de R$ 250, mas pode variar conforme o perfil do benefici\u00e1rio. olta do benef\u00edcio. O novo aux\u00edlio ter\u00e1 4 parcelas de R$ 150 a R$ 375 Fonte: G1 Com o agravamento da pandemia de coronav\u00edrus em todo o pa\u00eds, o governo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/auxilio-emergencial-caixa-1592266093900_v2_900x506-750x370-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15782,"url":"https:\/\/correiodasemana.com\/site\/sobral-e-outros-municipios-cearenses-buscam-alternativas-para-suprir-a-suspensao-temporaria-do-auxilio-emergencial\/","url_meta":{"origin":15886,"position":1},"title":"Sobral e outros munic\u00edpios cearenses buscam alternativas para suprir a suspens\u00e3o tempor\u00e1ria do Aux\u00edlio Emergencial","author":"","date":"Fevereiro 24, 2021","format":false,"excerpt":"Por Samuel Carvalho - Reda\u00e7\u00e3o Correio da Semana O novo aux\u00edlio emergencial ainda segue em discuss\u00e3o no Congresso Nacional, enquanto isso, munic\u00edpios do estado do Cear\u00e1 tentam criar alternativas para garantir assist\u00eancia econ\u00f4mica para a popula\u00e7\u00e3o diante das incertezas de como ir\u00e1 acontecer as novas parcelas do programa. Em Sobral,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/unnamed.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":22235,"url":"https:\/\/correiodasemana.com\/site\/beneficiarios-com-nis-final-3-recebem-hoje-14-o-auxilio-brasil\/","url_meta":{"origin":15886,"position":2},"title":"Benefici\u00e1rios com NIS final 3 recebem hoje (14) o Aux\u00edlio Brasil","author":"","date":"Dezembro 14, 2022","format":false,"excerpt":"A Caixa Econ\u00f4mica Federal paga hoje (14) a parcela de dezembro do Aux\u00edlio Brasil aos benefici\u00e1rios com N\u00famero de Inscri\u00e7\u00e3o Social (NIS) de final 3. \u00c9 a quinta parcela com o valor m\u00ednimo de R$ 600, que vigorar\u00e1 at\u00e9 dezembro, conforme emenda constitucional promulgada em julho pelo Congresso Nacional. A\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":22309,"url":"https:\/\/correiodasemana.com\/site\/beneficiarios-com-nis-final-5-recebem-hoje-16-o-auxilio-brasil\/","url_meta":{"origin":15886,"position":3},"title":"Benefici\u00e1rios com NIS final 5 recebem hoje (16) o Aux\u00edlio Brasil","author":"","date":"Dezembro 16, 2022","format":false,"excerpt":"A Caixa Econ\u00f4mica Federal paga\u00a0hoje\u00a0(16) a parcela\u00a0de dezembro\u00a0do Aux\u00edlio Brasil aos benefici\u00e1rios com N\u00famero de Inscri\u00e7\u00e3o Social (NIS) de\u00a0final 5. \u00c9\u00a0a\u00a0quinta\u00a0parcela com o valor m\u00ednimo de R$ 600, que vigorar\u00e1 at\u00e9 dezembro, conforme\u00a0emenda constitucional\u00a0promulgada em julho pelo Congresso Nacional. A menos que uma nova proposta de emenda \u00e0 Constitui\u00e7\u00e3o (PEC)\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":21787,"url":"https:\/\/correiodasemana.com\/site\/beneficiarios-com-nis-final-5-recebem-hoje-o-auxilio-brasil\/","url_meta":{"origin":15886,"position":4},"title":"Benefici\u00e1rios com NIS final 5 recebem hoje o Aux\u00edlio Brasil","author":"","date":"Novembro 23, 2022","format":false,"excerpt":"A Caixa Econ\u00f4mica Federal paga\u00a0hoje\u00a0(23) a parcela\u00a0de novembro\u00a0do Aux\u00edlio Brasil aos benefici\u00e1rios com N\u00famero de Inscri\u00e7\u00e3o Social (NIS) de\u00a0final 5. Essa \u00e9 a\u00a0quarta\u00a0parcela com o valor m\u00ednimo de R$ 600, que vigorar\u00e1 at\u00e9 dezembro, conforme emenda constitucional promulgada em julho pelo Congresso Nacional. A menos que uma nova proposta de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/8cqgv3z9n2d9pk45eetohsi20.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/8cqgv3z9n2d9pk45eetohsi20.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/8cqgv3z9n2d9pk45eetohsi20.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/8cqgv3z9n2d9pk45eetohsi20.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22400,"url":"https:\/\/correiodasemana.com\/site\/beneficiarios-com-nis-final-7-recebem-hoje-20-o-auxilio-brasil\/","url_meta":{"origin":15886,"position":5},"title":"Benefici\u00e1rios com NIS final 7 recebem hoje (20) o Aux\u00edlio Brasil","author":"","date":"Dezembro 20, 2022","format":false,"excerpt":"A Caixa Econ\u00f4mica Federal paga\u00a0hoje\u00a0(20) a parcela\u00a0de dezembro\u00a0do Aux\u00edlio Brasil aos benefici\u00e1rios com N\u00famero de Inscri\u00e7\u00e3o Social (NIS) com final 7. Essa \u00e9 a\u00a0quinta\u00a0parcela com o valor m\u00ednimo de R$ 600, que vigorar\u00e1 at\u00e9 dezembro, conforme emenda constitucional promulgada em julho pelo Congresso Nacional. A menos que uma nova proposta\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7-1024x576-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7-1024x576-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7-1024x576-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/naom_62b19833858e7-1024x576-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15886"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15886\/revisions"}],"predecessor-version":[{"id":15888,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15886\/revisions\/15888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15887"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}