{"id":15911,"date":"2021-03-08T09:46:23","date_gmt":"2021-03-08T12:46:23","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15911"},"modified":"2021-03-08T09:46:23","modified_gmt":"2021-03-08T12:46:23","slug":"com-dez-novos-leitos-hrn-soma-100-unidades-de-enfermaria-e-de-uti-para-covid-19","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/com-dez-novos-leitos-hrn-soma-100-unidades-de-enfermaria-e-de-uti-para-covid-19\/","title":{"rendered":"Com dez novos leitos, HRN soma 100 unidades de enfermaria e de UTI para Covid-19"},"content":{"rendered":"<p dir=\"ltr\">Em meio ao avan\u00e7o de casos de Covid-19 na regi\u00e3o Norte do Cear\u00e1, o Hospital Regional Norte (HRN), unidade da Secretaria de Sa\u00fade da Estado (Sesa), vem ampliando os leitos de enfermaria e de Unidade de Terapia Intensiva (UTI\u2019s) exclusivos para atendimento a pacientes Covid. Nesta semana, foram disponibilizados mais dez leitos de UTI Covid, somando 68 apenas no HRN. A unidade, administrada pelo Instituto de Sa\u00fade e Gest\u00e3o Hospitalar (ISGH), conta tamb\u00e9m com 32 leitos de enfermaria Covid.<\/p>\n<p dir=\"ltr\">Segundo a superintendente da Regional de Sa\u00fade Norte, M\u00f4nica Lima, a amplia\u00e7\u00e3o de leitos tem acontecido em toda a regi\u00e3o. Dados da plataforma IntegraSUS apontam que o Norte cearense conta com 115 leitos de UTI Covid e 253 leitos de enfermaria exclusivos para a doen\u00e7a. \u201cO dimensionamento est\u00e1 sendo realizado conforme a necessidade das regi\u00f5es\u201d, explica M\u00f4nica Lima.<\/p>\n<p dir=\"ltr\">O diretor geral do HRN, Daniel Hardy Melo, explica que o hospital est\u00e1 se estruturando para a amplia\u00e7\u00e3o de leitos e para o atendimento \u00e0 popula\u00e7\u00e3o. \u201cEstamos nos preparando frente \u00e0s necessidades da regi\u00e3o para adequar a estrutura hospitalar nesse contexto de pandemia, al\u00e9m de estarmos recrutando e treinando recursos humanos para fazer frente aos desafios\u201d, afirma.<\/p>\n<p dir=\"ltr\">Para suprir a amplia\u00e7\u00e3o de leitos, o HRN j\u00e1 contratou mais de 100 colaboradores tempor\u00e1rios neste ano em fun\u00e7\u00f5es assistenciais como m\u00e9dicos, enfermeiros, t\u00e9cnicos de enfermagem, fisioterapeutas e apoios como auxiliares administrativos, auxiliares de laborat\u00f3rio, auxiliares de farm\u00e1cia e conferencistas de roupa.<\/p>\n<p dir=\"ltr\">Emerg\u00eancia aberta<\/p>\n<p dir=\"ltr\">Al\u00e9m de ser refer\u00eancia para casos de m\u00e9dia e alta complexidade da Covid-19, o HRN segue com as emerg\u00eancias adulto e pedi\u00e1trica com funcionamento 24h para receber pacientes de diversas enfermidades. S\u00e3o tomadas precau\u00e7\u00f5es em todas as etapas do atendimento, desde a classifica\u00e7\u00e3o inicial at\u00e9 a assist\u00eancia direta. Al\u00e9m disso, h\u00e1 equipes individualizadas para atendimento a casos suspeitos da doen\u00e7a e a pacientes com outras enfermidades.<\/p>\n<p dir=\"ltr\">Regi\u00e3o Norte<\/p>\n<p dir=\"ltr\">O Hospital Municipal de Campanha de Sobral Dr. Francisco Alves foi reaberto no dia 15 de fevereiro para ampliar a assist\u00eancia a pacientes com Covid-19 em Sobral. A estrutura conta com 15 leitos de UTI e 30 de enfermaria ativos.<\/p>\n<p dir=\"ltr\">Outra refer\u00eancia na Regi\u00e3o de Sa\u00fade Norte \u00e9 o Hospital S\u00e3o Lucas, em Crate\u00fas, que ampliou dez leitos de UTI exclusivos para a doen\u00e7a na \u00faltima semana de fevereiro, alcan\u00e7ando assim 20 unidades ativas.<\/p>\n<div><span style=\"color: #000000;\"><b>Por Teresa Fernandes<\/b><br \/>\n<\/span><\/div>\n<div><a target=\"_blank\" rel=\"noopener\">Assessoria de Comunica\u00e7\u00e3o do Hospital Regional Norte (HRN)<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em meio ao avan\u00e7o de casos de Covid-19 na regi\u00e3o Norte do Cear\u00e1, o Hospital&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/image-40-768x481-1.png","jetpack-related-posts":[{"id":11946,"url":"https:\/\/correiodasemana.com\/site\/regiao-norte-recebe-57-novos-respiradores-e-soma-agora-185-leitos-de-uti-2\/","url_meta":{"origin":15911,"position":0},"title":"Regi\u00e3o Norte recebe 57 novos respiradores e soma agora 185 leitos de UTI","author":"","date":"Julho 19, 2020","format":false,"excerpt":"Os munic\u00edpios de Sobral, Crate\u00fas, Tiangu\u00e1, Ubajara e Camocim receberam juntos mais 57 respiradores e com isso a regi\u00e3o agora conta com 185 leitos de Unidade de Terapia Intensiva (UTI), a maioria exclusivos para o tratamento de Covid-19. A distribui\u00e7\u00e3o dos 300 novos ventiladores mec\u00e2nicos do modelo VG70, adquiridos com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/HRN-UTI-COVID19.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/HRN-UTI-COVID19.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/HRN-UTI-COVID19.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/HRN-UTI-COVID19.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/HRN-UTI-COVID19.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/HRN-UTI-COVID19.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":11933,"url":"https:\/\/correiodasemana.com\/site\/regiao-norte-recebe-57-novos-respiradores-e-soma-agora-185-leitos-de-uti\/","url_meta":{"origin":15911,"position":1},"title":"Regi\u00e3o Norte recebe 57 novos respiradores e soma agora 185 leitos de UTI","author":"","date":"Julho 16, 2020","format":false,"excerpt":"A distribui\u00e7\u00e3o dos 300 novos ventiladores mec\u00e2nicos do modelo VG70, adquiridos com recursos pr\u00f3prios do Governo do Cear\u00e1, foi conclu\u00edda para a Regi\u00e3o de Sa\u00fade Norte. Os munic\u00edpios de Sobral, Crate\u00fas, Tiangu\u00e1, Ubajara e Camocim receberam juntos mais 57 respiradores e com isso a regi\u00e3o agora conta com 185 leitos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/200618_HRN-UTI-COVID19_TF19082.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/200618_HRN-UTI-COVID19_TF19082.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/200618_HRN-UTI-COVID19_TF19082.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/200618_HRN-UTI-COVID19_TF19082.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/200618_HRN-UTI-COVID19_TF19082.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/200618_HRN-UTI-COVID19_TF19082.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16071,"url":"https:\/\/correiodasemana.com\/site\/novo-hospital-de-campanha-de-sobral-comeca-a-ser-montado-em-anexo-ao-hospital-regional-norte\/","url_meta":{"origin":15911,"position":2},"title":"Novo Hospital de Campanha de Sobral come\u00e7a a ser montado em anexo ao Hospital Regional Norte","author":"","date":"Mar\u00e7o 29, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Em decorr\u00eancia do aumento de casos na regi\u00e3o norte do estado do Cear\u00e1, um novo hospital de campanha est\u00e1 em constru\u00e7\u00e3o, anexado ao Hospital Regional Norte na cidade de Sobral. A estrutura contar\u00e1 com 60 leitos de enfermaria exclusivos para o tratamento de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16009,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-abre-novos-leitos-de-uti-e-enfermaria-para-tratamento-de-pacientes-com-covid-19\/","url_meta":{"origin":15911,"position":3},"title":"Santa Casa de Miseric\u00f3rdia de Sobral abre novos leitos de UTI e enfermaria para tratamento de pacientes com Covid-19","author":"","date":"Mar\u00e7o 22, 2021","format":false,"excerpt":"A\u00a0abertura dos novos leitos reitera o compromisso que a Santa Casa tem com a sociedade.\u00a0\u00a0 Com o avan\u00e7o da Covid-19 na Regi\u00e3o Norte do estado do Cear\u00e1, a Santa Casa de Miseric\u00f3rdia de Sobral abriu, nesta ter\u00e7a-feira (16\/03), dez leitos de Unidade de Terapia Intensiva (UTI) e dezesseis de enfermaria\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/IMG_5716.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/IMG_5716.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/IMG_5716.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/IMG_5716.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16041,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-adapta-servicos-e-abre-novos-leitos-de-uti-e-enfermaria\/","url_meta":{"origin":15911,"position":4},"title":"Santa Casa de Miseric\u00f3rdia de Sobral adapta servi\u00e7os e abre novos leitos de UTI e Enfermaria","author":"","date":"Mar\u00e7o 29, 2021","format":false,"excerpt":"A Santa Casa de Miseric\u00f3rdia de Sobral vai aumentar, a partir desta quinta-feira (25\/03), o n\u00famero de leitos de Unidade de Terapia Intensiva (UTI) para tratamento de pacientes com Covid-19. Ser\u00e3o dez novos leitos de UTI. Com a transfer\u00eancia provis\u00f3ria de alguns servi\u00e7os da Santa Casa, a Institui\u00e7\u00e3o conta agora\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14031,"url":"https:\/\/correiodasemana.com\/site\/hospital-regional-norte-supera-1200-altas-por-covid-19-em-seis-meses-de-combate-a-pandemia\/","url_meta":{"origin":15911,"position":5},"title":"Hospital Regional Norte supera 1200 altas por COVID-19 em seis meses de combate \u00e0 pandemia","author":"","date":"Outubro 13, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. Com informa\u00e7\u00f5es de Teresa Fernandes O Hospital Regional Norte (HRN), do Governo do Cear\u00e1, administrado pelo Instituto de Sa\u00fade e Gest\u00e3o Hospitalar (ISGH), \u00e9 refer\u00eancia no atendimento a casos de m\u00e9dia e alta complexidade da Covid-19 na Regi\u00e3o Norte do Cear\u00e1. Completando seis meses do primeiro caso\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/IMG-20201007-WA0019.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/IMG-20201007-WA0019.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/IMG-20201007-WA0019.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/IMG-20201007-WA0019.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/IMG-20201007-WA0019.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15911"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15911\/revisions"}],"predecessor-version":[{"id":15914,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15911\/revisions\/15914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15912"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}