{"id":15940,"date":"2021-03-14T13:19:48","date_gmt":"2021-03-14T16:19:48","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15940"},"modified":"2021-03-14T13:19:48","modified_gmt":"2021-03-14T16:19:48","slug":"e-hora-de-estancar-a-escalada-da-morte-cobram-em-nota-as-entidades-signatarias-do-pacto-pela-vida-e-pelo-brasil-frente-o-agravamento-da-pandemia-no-brasil","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/e-hora-de-estancar-a-escalada-da-morte-cobram-em-nota-as-entidades-signatarias-do-pacto-pela-vida-e-pelo-brasil-frente-o-agravamento-da-pandemia-no-brasil\/","title":{"rendered":"\u201c\u00c9 HORA DE ESTANCAR A ESCALADA DA MORTE!\u201d COBRAM, EM NOTA, AS ENTIDADES SIGNAT\u00c1RIAS DO PACTO PELA VIDA E PELO BRASIL FRENTE O AGRAVAMENTO DA PANDEMIA NO BRASIL"},"content":{"rendered":"<p>Fonte: CNBB<br \/>\nAs institui\u00e7\u00f5es signat\u00e1rias do Pacto pela Vida e pelo Brasil (Confer\u00eancia Nacional dos Bispos do Brasil, Ordem dos Advogados do Brasil, Comiss\u00e3o de Defesa dos Direitos Humanos Dom Paulo Evaristo Arns, Academia Brasileira de Ci\u00eancias, Associa\u00e7\u00e3o Brasileira de Imprensa e Sociedade Brasileira para o Progresso da Ci\u00eancia) lan\u00e7aram na tarde desta quinta-feira, 11 de mar\u00e7o, uma nota frente ao quadro de agravamento da pandemia do novo Coronavirus e das suas tr\u00e1gicas consequ\u00eancias na vida do povo brasileiro, do Sistema \u00danico de Sa\u00fade e do Brasil.<br \/>\nSegundo o documento, intitulado\u00a0O povo n\u00e3o pode pagar com a pr\u00f3pria vida!, \u201co v\u00edrus circula de norte a sul do Brasil, replicando cepas, afetando diferentes grupos et\u00e1rios, castigando os mais vulner\u00e1veis. No documento, as entidades se solidarizam com as fam\u00edlias que perderam seus entes queridos e aponta a urgente necessidade de maior empenho e integra\u00e7\u00e3o do tr\u00eas poderes (Executivo, Legislativo e Judici\u00e1rio) do Brasil, e entre estados e munic\u00edpios, na busca por encontrar solu\u00e7\u00f5es para enfrentar a pandemia.<br \/>\nAs organiza\u00e7\u00f5es signat\u00e1rias do Paco pelo Brasil fazem um apelo especial \u00e0 juventude. \u201cO v\u00edrus est\u00e1 infectando e matando os mais jovens e saud\u00e1veis, valendo-se deles como vetores de transmiss\u00e3o. Que a juventude brasileira assuma o seu protagonismo hist\u00f3rico na defesa da vida e do pa\u00eds, desconstruindo o negacionismo que agencia a morte\u201d, afirma o documento. Veja, abaixo, a \u00edntegra do documento cujas vers\u00f5es em pdf, com as logos de todas organiza\u00e7\u00f5es, podem ser encontrada\u00a0aqui\u00a0e em ingl\u00eas aqui.<\/p>\n<p>Origem do Pacto pela Vida e pelo Brasil<br \/>\nO Pacto pela Vida e Pelo Brasil foi lan\u00e7ado no Dia Mundial da Sa\u00fade, em 7 de abril de 2020, pela Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), juntamente com a Ordem dos Advogados do Brasil (OAB), a Comiss\u00e3o Arns, a Academia Brasileira de Ci\u00eancias, a Associa\u00e7\u00e3o Brasileira de Imprensa e a Sociedade Brasileira para o Progresso da Ci\u00eancia.<br \/>\nJ\u00e1 na primeira nota, as entidades apontavam que o Brasil vive uma grave crise \u2013 sanit\u00e1ria, econ\u00f4mica, social e pol\u00edtica \u2013 e que exige de todos, especialmente de governantes e representantes do povo, o exerc\u00edcio de uma cidadania guiada pelos princ\u00edpios da solidariedade e da dignidade humana, assentada no di\u00e1logo maduro, correspons\u00e1vel, na busca de solu\u00e7\u00f5es conjuntas para o bem comum, particularmente dos mais pobres e vulner\u00e1veis.<br \/>\nConhe\u00e7a o primeiro documento<\/p>\n<p>O povo n\u00e3o pode pagar com a pr\u00f3pria vida!<br \/>\nN\u00f3s, entidades signat\u00e1rias do Pacto pela Vida e pelo Brasil, sob o peso da dor e com sentido de m\u00e1xima urg\u00eancia, voltamos a nos dirigir \u00e0 sociedade brasileira, diante do agravamento da pandemia e das suas consequ\u00eancias. Nossa primeira palavra \u00e9 de solidariedade \u00e0s fam\u00edlias que perderam seus entes queridos.<br \/>\nN\u00e3o h\u00e1 tempo a perder, negacionismo mata. O v\u00edrus circula de norte a sul do Brasil, replicando cepas, afetando diferentes grupos et\u00e1rios, castigando os mais vulner\u00e1veis. Doentes morrem agonizando por falta de recursos hospitalares. O Sistema \u00danico de Sa\u00fade \u2013 SUS continua salvando vidas. No entanto, os profissionais da sa\u00fade, ap\u00f3s um ano na linha de frente, est\u00e3o \u00e0 beira da exaust\u00e3o. A eles, nosso reconhecimento.<br \/>\n\u00c9 hora de estancar a escalada da morte! A popula\u00e7\u00e3o brasileira necessita de vacina agora. O v\u00edrus n\u00e3o ser\u00e1 dissipado com obscurantismos, discursos raivosos ou frases ofensivas. Basta de insensatez e irresponsabilidade. Al\u00e9m de vacina j\u00e1 e para todos, o Brasil precisa urgentemente que o Minist\u00e9rio da Sa\u00fade cumpra o seu papel, sendo indutor eficaz das pol\u00edticas de sa\u00fade em n\u00edvel nacional, garantindo acesso r\u00e1pido aos medicamentos e testes validados pela ci\u00eancia, a rastreabilidade permanente do v\u00edrus e um m\u00ednimo de serenidade ao povo.<br \/>\nA inefici\u00eancia do Governo Federal, primeiro respons\u00e1vel pela trag\u00e9dia que vivemos, \u00e9 not\u00f3ria. Governadores e prefeitos n\u00e3o podem assumir o papel de c\u00famplices no desprezo pela vida. Assim, apoiamos seus esfor\u00e7os para garantir o cumprimento do rol de medidas sanit\u00e1rias de prote\u00e7\u00e3o, paralelamente \u00e0 imuniza\u00e7\u00e3o r\u00e1pida e consistente da popula\u00e7\u00e3o. Que governadores e prefeitos ajam com olhos n\u00e3o s\u00f3 voltados para os seus estados e munic\u00edpios, mas para o pa\u00eds, atrav\u00e9s de um grande pacto. Somos um s\u00f3 Brasil.<br \/>\nAo Congresso Nacional, instamos que d\u00ea m\u00e1xima prioridade a mat\u00e9rias relacionadas ao enfrentamento da COVID-19, uma vez que preservar vidas \u00e9 o que h\u00e1 de mais urgente. Nesse sentido, o aux\u00edlio emergencial digno, e pelo tempo que for necess\u00e1rio, ser\u00e1 imprescind\u00edvel para salvar vidas e dinamizar a economia. Ao Poder Judici\u00e1rio, sob a lideran\u00e7a do Supremo Tribunal Federal, pedimos que zele pelos direitos da cidadania e pela harmonia entre os entes federativos. Que a imprensa atue livre e vigorosamente, de forma \u00e9tica, cumprindo sua miss\u00e3o de transmitir informa\u00e7\u00f5es confi\u00e1veis e com base cient\u00edfica, sobre o que se passa. Enfim, que a voz das institui\u00e7\u00f5es soe muito firme na defesa do povo brasileiro!<br \/>\nFazemos ainda um apelo particular \u00e0 juventude. O v\u00edrus est\u00e1 infectando e matando os mais jovens e saud\u00e1veis, valendo-se deles como vetores de transmiss\u00e3o. Que a juventude brasileira assuma o seu protagonismo hist\u00f3rico na defesa da vida e do pa\u00eds, desconstruindo o negacionismo que agencia a morte.<br \/>\nSabemos que a travessia \u00e9 desafiadora, a oportunidade de reconstru\u00e7\u00e3o da sociedade brasileira \u00e9 \u00fanica e a esperan\u00e7a \u00e9 a luz que nos guiar\u00e1 rumo a um novo tempo.<br \/>\nQuarta-feira, 10 de mar\u00e7o de 2021<\/p>\n<p>Dom Walmor Oliveira de Azevedo &#8211; Presidente da Confer\u00eancia Nacional dos Bispos do Brasil \u2013 CNBB<br \/>\nFelipe Santa Cruz &#8211; Presidente da Ordem dos Advogados do Brasil \u2013 OAB<br \/>\nJos\u00e9 Carlos Dias &#8211; Presidente da Comiss\u00e3o de Defesa dos Direitos Humanos Dom Paulo Evaristo Arns \u2013 Comiss\u00e3o Arns<br \/>\nLuiz Davidovich &#8211; Presidente da Academia Brasileira de Ci\u00eancias \u2013 ABC<br \/>\nPaulo Jeronimo de Sousa &#8211; Presidente da Associa\u00e7\u00e3o Brasileira de Imprensa \u2013 ABI<br \/>\nIldeu de Castro Moreira &#8211; Presidente da Sociedade Brasileira para o Progresso da Ci\u00eancia \u2013 SBPC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: CNBB As institui\u00e7\u00f5es signat\u00e1rias do Pacto pela Vida e pelo Brasil (Confer\u00eancia Nacional dos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/Nota-Pacto-pela-Vida.jpg","jetpack-related-posts":[{"id":16254,"url":"https:\/\/correiodasemana.com\/site\/carta-ao-papa-da-58a-ag-cnbb\/","url_meta":{"origin":15940,"position":0},"title":"CARTA AO PAPA DA 58\u00aa AG CNBB","author":"","date":"Abril 18, 2021","format":false,"excerpt":"Amado Papa Francisco, N\u00f3s, os Bispos do Brasil, reunidos neste ano, de 12 a 16 de abril, por plataforma virtual, a partir de nossas Igrejas Particulares, vivenciamos nossa 58\u00aa Assembleia Geral Ordin\u00e1ria. Neste tempo dif\u00edcil e desafiador, quisemos viver, neste formato poss\u00edvel, nosso encontro anual, que n\u00e3o nos foi poss\u00edvel\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11981,"url":"https:\/\/correiodasemana.com\/site\/situacao-dos-indigenas-e-povos-originarios-se-agrava-com-a-pandemia-de-covid-19\/","url_meta":{"origin":15940,"position":1},"title":"Situa\u00e7\u00e3o dos ind\u00edgenas e povos origin\u00e1rios se agrava com a pandemia de Covid-19","author":"","date":"Julho 19, 2020","format":false,"excerpt":"A situa\u00e7\u00e3o de vulnerabilidade dos ind\u00edgenas e povos origin\u00e1rios tem se agravado com a pandemia de Covid-19. Irm\u00e3 Laura Vicu\u00f1a Pereira, catequista franciscana de origem ind\u00edgena Kariri e que integra a Confer\u00eancia Eclesial da Amaz\u00f4nia, acredita que a for\u00e7a das experi\u00eancias ancestrais at\u00e9 hoje pode ajudar a potencializar a a\u00e7\u00e3o\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14071,"url":"https:\/\/correiodasemana.com\/site\/cnbb-68-anos-a-atual-presidencia-reflete-a-instituicao-entre-o-seu-passado-e-futuro\/","url_meta":{"origin":15940,"position":2},"title":"CNBB 68 ANOS: A ATUAL PRESID\u00caNCIA REFLETE A INSTITUI\u00c7\u00c3O ENTRE O SEU PASSADO E FUTURO","author":"","date":"Outubro 14, 2020","format":false,"excerpt":"Para celebrar o anivers\u00e1rio de 68 da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), neste dia 14 de outubro, os quatro bispos que integram a atual presid\u00eancia foram provocados a destacar os marcos do passado e do presente da institui\u00e7\u00e3o, bem como lan\u00e7ar um olhar sobre o seu futuro. Eleitos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Presidencia-da-CNBB-owvum80xl84ugjzhi2z7kkg8jajwtwf5cla6ohu454.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Presidencia-da-CNBB-owvum80xl84ugjzhi2z7kkg8jajwtwf5cla6ohu454.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Presidencia-da-CNBB-owvum80xl84ugjzhi2z7kkg8jajwtwf5cla6ohu454.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/Presidencia-da-CNBB-owvum80xl84ugjzhi2z7kkg8jajwtwf5cla6ohu454.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16936,"url":"https:\/\/correiodasemana.com\/site\/isolamento-imposto-pela-covid-19-agrava-saude-ocular-da-populacao\/","url_meta":{"origin":15940,"position":3},"title":"Isolamento imposto pela Covid-19 agrava sa\u00fade ocular da popula\u00e7\u00e3o","author":"","date":"Julho 12, 2021","format":false,"excerpt":"Pandemia trouxe mudan\u00e7as significativas no comportamento das pessoas em rela\u00e7\u00e3o ao tempo de exposi\u00e7\u00e3o \u00e0s luzes dos aparelhos eletr\u00f4nicos Com o trabalho remoto e os estudos online impostos pela pandemia de Covid-19, a exposi\u00e7\u00e3o excessiva \u00e0s luzes geradas pelos aparelhos eletr\u00f4nicos contribui para o surgimento e aumento da fadiga ocular.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/isolamento-da-covid-agrava-problemas-de-visao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/isolamento-da-covid-agrava-problemas-de-visao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/isolamento-da-covid-agrava-problemas-de-visao.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/isolamento-da-covid-agrava-problemas-de-visao.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/isolamento-da-covid-agrava-problemas-de-visao.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/isolamento-da-covid-agrava-problemas-de-visao.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12920,"url":"https:\/\/correiodasemana.com\/site\/datafolha-79-dos-brasileiros-dizem-que-reabertura-de-escolas-no-pais-agravara-a-pandemia\/","url_meta":{"origin":15940,"position":4},"title":"Datafolha: 79% dos brasileiros dizem que reabertura de escolas no pa\u00eds agravar\u00e1 a pandemia","author":"","date":"Agosto 18, 2020","format":false,"excerpt":"79% defendem que as escolas devem ficar fechadas nos pr\u00f3ximos dois meses; 19% disseram que escolas devem ser reabertas. Pesquisa Datafolha publicada no final da noite desta segunda-feira (17) no site do jornal \"Folha de S.Paulo\" apontou os seguintes percentuais para a volta ou n\u00e3o \u00e0s aulas e a reabertura\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/d4e47160-db02-11ea-977f-09774f9c346a.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/d4e47160-db02-11ea-977f-09774f9c346a.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/d4e47160-db02-11ea-977f-09774f9c346a.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/d4e47160-db02-11ea-977f-09774f9c346a.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28232,"url":"https:\/\/correiodasemana.com\/site\/mais-de-50-das-criancas-do-2o-ano-do-fundamental-nao-conseguem-ler\/","url_meta":{"origin":15940,"position":5},"title":"Mais de 50% das crian\u00e7as do 2\u00ba ano do fundamental n\u00e3o conseguem ler","author":"adminredacao","date":"Fevereiro 6, 2024","format":false,"excerpt":"Para Unicef, situa\u00e7\u00e3o se agravou durante a pandemia de covid-19 Por Fabiana Sampaio - Rep\u00f3rter da R\u00e1dio Nacional - Rio de Janeiro Mais\u00a0da\u00a0metade\u00a0das\u00a0crian\u00e7as do segundo ano do Ensino Fundamental\u00a0da\u00a0rede p\u00fablica n\u00e3o aprenderam a ler e escrever no Brasil. A informa\u00e7\u00e3o \u00e9 do Fundo Internacional de Emerg\u00eancia das Na\u00e7\u00f5es Unidas para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/AADA.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15940"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15940\/revisions"}],"predecessor-version":[{"id":15942,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15940\/revisions\/15942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15941"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}