{"id":15957,"date":"2021-03-14T13:27:26","date_gmt":"2021-03-14T16:27:26","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=15957"},"modified":"2021-03-14T13:27:26","modified_gmt":"2021-03-14T16:27:26","slug":"sistema-de-saude-de-sobral-e-regiao-norte-entram-em-colapso-com-100-dos-leitos-de-uti-ocupados","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sistema-de-saude-de-sobral-e-regiao-norte-entram-em-colapso-com-100-dos-leitos-de-uti-ocupados\/","title":{"rendered":"Sistema de sa\u00fade de Sobral e Regi\u00e3o Norte entram em colapso com 100% dos leitos de UTI ocupados"},"content":{"rendered":"<p>Por Samuel Carvalho &#8211; Reda\u00e7\u00e3o Correio da Semana<br \/>\nDurante essa semana, a taxa de ocupa\u00e7\u00e3o de leitos de pelo menos 11 hospitais na Regi\u00e3o Norte atingiu sua totalidade. A situa\u00e7\u00e3o mais preocupante est\u00e1 na macrorregi\u00e3o de Sobral que abrange 55 munic\u00edpios, pois desde segunda-feira (8) todas as UTIs dispon\u00edveis na regi\u00e3o, adultas, infantis, neonatais e gestantes, est\u00e3o ocupadas, informa a plataforma IntegraSUS, da Secretaria de Sa\u00fade do Estado (Sesa).<br \/>\nOs seis hospitais da macrorregi\u00e3o de Sobral que possuem leitos de UTI est\u00e3o com 100% de sua capacidade ocupados. S\u00e3o eles: Hospital S\u00e3o Lucas (20 leitos), em Crate\u00fas; Hospital Maternidade Madalena Nunes (10), em Tiangu\u00e1; Hospital Regional Norte (75), Hospital de Campanha Dr. Francisco Alves (21), Santa Casa da Miseric\u00f3rdia, em Sobral; e Hospital Municipal Dr. Pedro de Castro Marinho (3), em Irau\u00e7uba. De acordo com o IntegraSUS, em todas as regi\u00f5es do Cear\u00e1 o n\u00famero de leitos de UTI ocupados est\u00e3o acima de 90%.<br \/>\nsegundo a presidente do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems\/CE), Sayonara Cidade, \u00e9 uma situa\u00e7\u00e3o preocupante j\u00e1 que todas as regi\u00f5es est\u00e3o enfrentando uma alta nos n\u00fameros de internados ao mesmo tempo o que resulta numa fila de espera em todo o estado por leitos. \u201cQuando a situa\u00e7\u00e3o estava grave na regi\u00e3o Norte, o Cariri estava mais tranquilo, por exemplo. Com a pandemia forte em todas as regi\u00f5es, estamos com pessoas em filas, esperando vaga na UTI\u201d, detalha.<br \/>\nDiante da urg\u00eancia algumas unidades como as Unidades de Pronto Atendimento (UPAs) e hospitais est\u00e3o sendo readequados para atender os pacientes mais graves.<br \/>\n\u201cOs leitos est\u00e3o com respiradores, os capacetes Elmo chegaram e foram distribu\u00eddos para os hopitais polo e evitar que evolua para uma intuba\u00e7\u00e3o. \u00c9 todo um esfor\u00e7o\u201d, afrimou Sayonara Cidade. De acordo com a Secretaria de Sa\u00fade do Estado, o Cear\u00e1 j\u00e1 conta com mais de 200 novos leitos de UTI atrav\u00e9s de hospitais de campanha com dois j\u00e1 montados no interior, dois em Quixeramobim e Sobral, ampliando com mais 40 e 39 vagas, respectivamente.<br \/>\nOs n\u00fameros na macrorregi\u00e3o de Sobral s\u00e3o similares a quantidade de internados na macrorregi\u00e3o do Cariri que possui outras quatro unidades lotadas. O Instituto Madre Tereza de Apoio \u00e0 Vida (10 leitos), em Brejo Santo; o Hospital Maternidade S\u00e3o Vicente de Paulo (10), em Barbalha; o Hospital Regional do Cariri (35) e o Hospital Maternidade S\u00e3o Francisco de Assis (10), em Crato. Na macrorregi\u00e3o do Litoral Leste\/Jaguaribe todas as 10 vagas de UTI dispon\u00edveis no Hospital S\u00e3o Raimundo, em Limoeiro do Norte, est\u00e3o preenchidas. J\u00e1 no Sert\u00e3o Central, a ocupa\u00e7\u00e3o de UTIs adultas chega a 92,73%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho &#8211; Reda\u00e7\u00e3o Correio da Semana Durante essa semana, a taxa de ocupa\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/hospital-de-campanha-de-sobral.jpg","jetpack-related-posts":[{"id":16071,"url":"https:\/\/correiodasemana.com\/site\/novo-hospital-de-campanha-de-sobral-comeca-a-ser-montado-em-anexo-ao-hospital-regional-norte\/","url_meta":{"origin":15957,"position":0},"title":"Novo Hospital de Campanha de Sobral come\u00e7a a ser montado em anexo ao Hospital Regional Norte","author":"","date":"Mar\u00e7o 29, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Em decorr\u00eancia do aumento de casos na regi\u00e3o norte do estado do Cear\u00e1, um novo hospital de campanha est\u00e1 em constru\u00e7\u00e3o, anexado ao Hospital Regional Norte na cidade de Sobral. A estrutura contar\u00e1 com 60 leitos de enfermaria exclusivos para o tratamento de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-21-at-17.46.261.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":10702,"url":"https:\/\/correiodasemana.com\/site\/desafios-da-neonatologia-na-macrorregiao-de-sobral-sao-discutidos-por-orgaos-de-saude-em-hospital-do-municipio\/","url_meta":{"origin":15957,"position":1},"title":"Desafios da Neonatologia na Macrorregi\u00e3o de Sobral s\u00e3o discutidos por \u00f3rg\u00e3os de sa\u00fade em hospital do munic\u00edpio","author":"","date":"Fevereiro 3, 2020","format":false,"excerpt":"Com objetivo de encontrar solu\u00e7\u00f5es para os principais problemas do Servi\u00e7o de Neonatologia da Macrorregi\u00e3o de Sobral, que abrange 55 munic\u00edpios, a Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) promoveu na quarta-feira (29\/01) a primeira reuni\u00e3o envolvendo \u00f3rg\u00e3os de sa\u00fade do munic\u00edpio de Sobral. O encontro aconteceu no audit\u00f3rio do\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15911,"url":"https:\/\/correiodasemana.com\/site\/com-dez-novos-leitos-hrn-soma-100-unidades-de-enfermaria-e-de-uti-para-covid-19\/","url_meta":{"origin":15957,"position":2},"title":"Com dez novos leitos, HRN soma 100 unidades de enfermaria e de UTI para Covid-19","author":"","date":"Mar\u00e7o 8, 2021","format":false,"excerpt":"Em meio ao avan\u00e7o de casos de Covid-19 na regi\u00e3o Norte do Cear\u00e1, o Hospital Regional Norte (HRN), unidade da Secretaria de Sa\u00fade da Estado (Sesa), vem ampliando os leitos de enfermaria e de Unidade de Terapia Intensiva (UTI\u2019s) exclusivos para atendimento a pacientes Covid. Nesta semana, foram disponibilizados mais\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/image-40-768x481-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/image-40-768x481-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/image-40-768x481-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/image-40-768x481-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17033,"url":"https:\/\/correiodasemana.com\/site\/sobral-segue-avancando-na-vacinacao-com-mais-de-1-700-pessoas-vacinadas-em-um-unico-dia-e-ocupacao-de-numero-de-leitos-decresce\/","url_meta":{"origin":15957,"position":3},"title":"Sobral segue avan\u00e7ando na vacina\u00e7\u00e3o com mais de 1.700 pessoas vacinadas em um \u00fanico dia e ocupa\u00e7\u00e3o de n\u00famero de leitos decresce","author":"","date":"Julho 19, 2021","format":false,"excerpt":"Por Samuel Carvalho - Reda\u00e7\u00e3o Correio da Semana A Secretaria da Sa\u00fade de Sobral aplicou 1.717 doses da vacina contra a Covid-19, em drive-thru, na noite do \u00faltimo domingo (11), na Pra\u00e7a do Theatro S\u00e3o Jo\u00e3o. Nessa leva de imuniza\u00e7\u00e3o foi disponibilizada em sua maioria a primeira dose dos imunizantes.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Sobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Sobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Sobral.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":11462,"url":"https:\/\/correiodasemana.com\/site\/pacientes-que-venceram-o-coronavirus-sobral-registra-456-pessoas-recuperadas\/","url_meta":{"origin":15957,"position":4},"title":"Pacientes que venceram o coronav\u00edrus; Sobral registra 456 pessoas recuperadas","author":"","date":"Maio 30, 2020","format":false,"excerpt":"A doen\u00e7a deixa assintom\u00e1ticos, casos com sintomas leves, similares aos de uma gripe, e pessoas que precisam de cuidados especiais pois apresentam sintomas graves, como insufici\u00eancia respirat\u00f3ria. Por Thais Menezes e Correio da Semana At\u00e9 o fechamento desta edi\u00e7\u00e3o, realizado na quinta-feira (28), Sobral registrava 456 casos recuperados e 60\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-28-at-19.19.08-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-28-at-19.19.08-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-28-at-19.19.08-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-28-at-19.19.08-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16041,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-adapta-servicos-e-abre-novos-leitos-de-uti-e-enfermaria\/","url_meta":{"origin":15957,"position":5},"title":"Santa Casa de Miseric\u00f3rdia de Sobral adapta servi\u00e7os e abre novos leitos de UTI e Enfermaria","author":"","date":"Mar\u00e7o 29, 2021","format":false,"excerpt":"A Santa Casa de Miseric\u00f3rdia de Sobral vai aumentar, a partir desta quinta-feira (25\/03), o n\u00famero de leitos de Unidade de Terapia Intensiva (UTI) para tratamento de pacientes com Covid-19. Ser\u00e3o dez novos leitos de UTI. Com a transfer\u00eancia provis\u00f3ria de alguns servi\u00e7os da Santa Casa, a Institui\u00e7\u00e3o conta agora\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/UTI-COVID-3.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=15957"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15957\/revisions"}],"predecessor-version":[{"id":15959,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/15957\/revisions\/15959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15958"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=15957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=15957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=15957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}