{"id":16074,"date":"2021-03-29T01:02:36","date_gmt":"2021-03-29T04:02:36","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=16074"},"modified":"2021-03-29T01:02:36","modified_gmt":"2021-03-29T04:02:36","slug":"em-tempo-75","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-75\/","title":{"rendered":"Em Tempo"},"content":{"rendered":"<p><strong>Concurso da Pol\u00edcia Rodovi\u00e1ria Federal<\/strong><br \/>\nO novo cronograma do concurso p\u00fablico\u00a0para a Pol\u00edcia Rodovi\u00e1ria Federal foi divulgado no dia 22. Na publica\u00e7\u00e3o, o \u00f3rg\u00e3o e o Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (Cebraspe) confirmam a realiza\u00e7\u00e3o das provas em 9 de maio.<br \/>\nO\u00a0adiamento do exame j\u00e1 tinha sido antecipado\u00a0em raz\u00e3o das restri\u00e7\u00f5es adotadas\u00a0contra a Covid-19 por estados e munic\u00edpios. Al\u00e9m disso, foi confirmada a divulga\u00e7\u00e3o dos locais de prova, prevista para 30 de abril. Mais informa\u00e7\u00f5es no site https:\/\/cdn.cebraspe.org.br.<\/p>\n<p><strong>Sele\u00e7\u00e3o para 27 professores na UECE<\/strong><br \/>\nA Funda\u00e7\u00e3o Universidade Estadual do Cear\u00e1 (Funece) torna p\u00fablico o edital de sele\u00e7\u00e3o para os professores do Programa de Forma\u00e7\u00e3o Inicial e Continuada (FIC) Qualifica Mais. As inscri\u00e7\u00f5es para o processo seletivo dever\u00e3o ser feitas at\u00e9 o dia 4 de abril de 2021.<br \/>\nS\u00e3o ofertadas 27 vagas na \u00e1rea t\u00e9cnica Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o, sendo tr\u00eas vagas para o curso \u201cProgramador de dispositivos m\u00f3veis\u201d, 12 vagas para o curso \u201cProgramador de sistemas\u201d e 12 vagas para o curso \u201cProgramador web\u201d. Edital no site http:\/\/www.uece.br\/pronatec.<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16075\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/Lei_2064-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/Lei_2064-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/Lei_2064-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/Lei_2064-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/03\/Lei_2064.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Compra direta de vacina contra Covid <\/strong><br \/>\n<strong>Foto \u2013Divulga\u00e7\u00e3o<\/strong><br \/>\n<strong>\u2022 Prefeito de Sobral, Ivo Gomes, sancionou lei para compra direta de vacina contra Covid-19<\/strong><br \/>\nO prefeito Ivo Gomes sancionou a Lei n\u00ba 2.064\/21, que ratifica o protocolo de inten\u00e7\u00f5es firmado entre munic\u00edpios brasileiros com a finalidade de adquirir vacinas para combate \u00e0 pandemia do coronav\u00edrus, medicamentos, insumos e equipamentos na \u00e1rea da sa\u00fade.<br \/>\nO cons\u00f3rcio para compra direta de vacina \u00e9 de abrang\u00eancia nacional e conta com manifesta\u00e7\u00e3o de interesse de 1.703 munic\u00edpios. Visa fortalecer o Sistema \u00danico de Sa\u00fade, na medida em que todas as doses ser\u00e3o obrigatoriamente ofertadas \u00e0 popula\u00e7\u00e3o de forma gratuita.<\/p>\n<p><strong>Orquestra Sinf\u00f4nica da UFC Sobral<\/strong><br \/>\nA Orquestra Sinf\u00f4nica da Universidade Federal do Cear\u00e1\u00a0\u2013 Campus Sobral foi a vencedora, na categoria Grupo, do Concurso Internacional de Criatividade para Crian\u00e7as e Jovens Instrumentistas, da Federa\u00e7\u00e3o Russa ART Festival \u2013 Roza Vetrov (Rosa dos Ventos).<br \/>\nDivulgado no dia 12 de mar\u00e7o, o resultado veio com a execu\u00e7\u00e3o da m\u00fasica \u201cSanfona Sentida\u201d, de Dominguinhos, com arranjo de Rian Rafaiel, egresso do Curso de M\u00fasica da UFC em Fortaleza. Em sua 26\u00aa edi\u00e7\u00e3o, o concurso de instrumentistas aconteceu totalmente virtual.<\/p>\n<p><strong>Cursos t\u00e9cnicos do projeto Arte Urgente<\/strong><br \/>\nO projeto Arte Urgente: A Cultura como farol do Cear\u00e1\u00a0est\u00e1 com inscri\u00e7\u00f5es abertas at\u00e9 o dia 27 de mar\u00e7o, para a segunda turma dos\u00a0cursos t\u00e9cnicos da a\u00e7\u00e3o Ateli\u00eas de Cria\u00e7\u00e3o, que ser\u00e3o realizados em abril.\u00a0S\u00e3o\u00a014 cursos, com 20 vagas cada e carga hor\u00e1ria de 40 horas\/aula.<br \/>\nAs forma\u00e7\u00f5es s\u00e3o nas \u00e1reas de circo, cultura popular, dan\u00e7a, m\u00fasica, audiovisual e teatro. Inscri\u00e7\u00f5es e informa\u00e7\u00f5es atrav\u00e9s do site :www.arteurgente.com.br. Redes sociais: Instagram: @arteurgente.labs | Fabecook: Arte Urgente.Os selecionados receber\u00e3o bolsa de R$ 375,00.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br). Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concurso da Pol\u00edcia Rodovi\u00e1ria Federal O novo cronograma do concurso p\u00fablico\u00a0para a Pol\u00edcia Rodovi\u00e1ria Federal&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,36],"tags":[],"class_list":["post-16074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",720,960,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2-225x300.jpg",225,300,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",640,853,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",640,853,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",720,960,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",720,960,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",720,960,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg",255,340,false]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/em-tempo\/\" rel=\"category tag\">Em Tempo<\/a>","tag_info":"Em Tempo","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg","jetpack-related-posts":[{"id":15320,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-64\/","url_meta":{"origin":16074,"position":0},"title":"Em Tempo","author":"","date":"Janeiro 10, 2021","format":false,"excerpt":"Concurso da Pol\u00edcia Rodovi\u00e1ria Federal O edital do concurso da Pol\u00edcia Rodovi\u00e1ria Federal ser\u00e1 publicado no dia 19 de janeiro. As\u00a0inscri\u00e7\u00f5es iniciam no dia 25 de janeiro. As provas objetivas e discursivas est\u00e3o previstas para o dia 28 de mar\u00e7o. Os\u00a0testes de aptid\u00e3o f\u00edsica\u00a0ser\u00e3o feitos entre 8 e 9 de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27778,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-206\/","url_meta":{"origin":16074,"position":1},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Dezembro 19, 2023","format":false,"excerpt":"Casas de Cultura Estrangeira UFC Estar\u00e3o abertas, de 19 de dezembro a 7 de janeiro, pela Internet, as inscri\u00e7\u00f5es para a sele\u00e7\u00e3o de novos alunos das Casas de Cultura Estrangeira da Universidade Federal do Cear\u00e1, no semestre letivo 2024.1. S\u00e3o ofertadas 957 vagas em cursos regulares presenciais de idiomas. Sele\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/Oracao1-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/Oracao1-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/Oracao1-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/Oracao1-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11301,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-36\/","url_meta":{"origin":16074,"position":2},"title":"Em Tempo","author":"","date":"Mar\u00e7o 24, 2020","format":false,"excerpt":"DETRAN suspende exames no Cear\u00e1 Em preven\u00e7\u00e3o contra a transmiss\u00e3o do\u00a0Coronav\u00edrus, o Departamento de Tr\u00e2nsito do Cear\u00e1 adotou um conjunto de medidas e suspendeu, no per\u00edodo de 18 a 31 de mar\u00e7o, todos os exames pr\u00e1ticos e de legisla\u00e7\u00e3o.\u00a0A fiscaliza\u00e7\u00e3o tamb\u00e9m passar\u00e1 por altera\u00e7\u00f5es. A suspens\u00e3o abrange todos os cursos,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Inaugura_Jaibaras_2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Inaugura_Jaibaras_2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Inaugura_Jaibaras_2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Inaugura_Jaibaras_2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Inaugura_Jaibaras_2.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15892,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-72\/","url_meta":{"origin":16074,"position":3},"title":"Em Tempo","author":"","date":"Mar\u00e7o 7, 2021","format":false,"excerpt":"Edital do concurso da Sefaz O edital do\u00a0concurso p\u00fablico\u00a0da Secretaria da Fazenda do Cear\u00e1 (Sefaz-CE) ser\u00e1 encaminhado para publica\u00e7\u00e3o at\u00e9 o dia\u00a031 de mar\u00e7o. A informa\u00e7\u00e3o foi revelada pela secret\u00e1ria da pasta,\u00a0Fernanda Pacobahyba, durante uma transmiss\u00e3o ao vivo nas redes sociais. A sele\u00e7\u00e3o oferecer\u00e1\u00a0100 vagas\u00a0e ser\u00e1 realizada em tr\u00eas fases:\u00a0prova\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15960,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-73\/","url_meta":{"origin":16074,"position":4},"title":"Em Tempo","author":"","date":"Mar\u00e7o 14, 2021","format":false,"excerpt":"Provas do Concurso da Pol\u00edcia Federal O concurso da Pol\u00edcia Federal\u00a0teve suas provas adiadas. Os exames objetivo e discursivo, que seriam aplicados em 21 de mar\u00e7o deste ano, devem ocorrer, provavelmente, no dia\u00a023 de maio, conforme comunicado da Diretoria de Gest\u00e3o de Pessoal do \u00f3rg\u00e3o. O adiamento se deu em\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":21104,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-152\/","url_meta":{"origin":16074,"position":5},"title":"Em Tempo","author":"","date":"Setembro 26, 2022","format":false,"excerpt":"Concurso para professor da UFC A Universidade Federal do Cear\u00e1 (UFC) recebe, de 10 a 28 de outubro, inscri\u00e7\u00f5es de concurso p\u00fablico para professor do Campus em Sobral. De acordo com o\u00a0Edital n\u00ba 128\/2022, s\u00e3o oferecidas duas vagas, uma para Engenharia da Computa\u00e7\u00e3o e outra para o curso de Medicina.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/09\/col-em-tempo-300x153.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=16074"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16074\/revisions"}],"predecessor-version":[{"id":16076,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16074\/revisions\/16076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=16074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=16074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=16074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}