{"id":16176,"date":"2021-04-12T02:43:24","date_gmt":"2021-04-12T05:43:24","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=16176"},"modified":"2021-04-12T02:43:24","modified_gmt":"2021-04-12T05:43:24","slug":"becco-ponto-com-35","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-35\/","title":{"rendered":"Becco ponto Com"},"content":{"rendered":"<p>Livrai-nos, senhor!<br \/>\nDos ataques a santa C\u00e2mara Municipal com seus discipulos aliados do poder central.<br \/>\nDa alegria barata dos corruptos de ocasi\u00e3o mamando nas tetas dos poderosos, ui!<br \/>\nDas esmolas doadas por pol\u00edticos fotografando a d\u00e1diva em redes sociais aos pobres.<br \/>\nDas esmolas sociais nas c\u00e2maras municipais atrav\u00e9s de sal\u00e1rios doados via votos, ufa!<br \/>\nDa briga pela vacina da vergonha em um pa\u00eds manchado pelo \u00f3dio e a vergonha nacional.<br \/>\nDa briga lulistas e bolsonaristas pelo poder de uma nac\u00e3o semi-morta t\u00e3o imoral, ufa!<br \/>\nDa briga surda-pol\u00edtica pela vacina em um pa\u00eds de bandidos pol\u00edticos enquartelados.<br \/>\nDo virus da pandemia da ignor\u00e2ncia pol\u00edtica social matando o povo brasileiro pobre.<br \/>\nDa sess\u00e3o louca tranca ruas no pa\u00eds de analfabetos e ignorantes imposta pelo poder.<br \/>\nDos morta-fomes pelo poder a qualquer custo em um pa\u00eds que mata seu povo de fome.<\/p>\n<p><strong>NOTICIANDO<\/strong><br \/>\n01 &#8211; O centro cultural dom jos\u00e9 est\u00e1 marcando para julho, a posse de sua nova diretoria que ser\u00e1 votada no m\u00eas de maio, em grande estilo na cidade. O presidente que dever\u00e1 ser eleito por unanimidade \u00e9 o advogado, poeta e escritor dr. mendes junior. O ato de posse se dar\u00e1 no plen\u00e1rio 5 de julho, em julho, m\u00eas que o centro completar\u00e1 35 anos de sua funda\u00e7\u00e3o na cidade. Aguardar \u00e9 preciso esta festa cultural.<br \/>\n02 &#8211; o centro cultural iniciou a escolha dos homenageados com o trof\u00e9u dom jos\u00e9, deste ano, iniciando tal escolha por mulheres do ano. Foram indicadas: a vereadora socorrinha brasileiro, educadora ana emilia dias pinheiro, a empres\u00e1ria maria do carmo ponte da emplatec e a jornalista do sistema verdes mares de cominica\u00e7ao, maristela gl\u00e1ucia, rep\u00f3rter da zona Norte, todas por m\u00e9ritos.<br \/>\n03 &#8211; o homem de imprensa da zona norte escolhido este ano foi o caro rep\u00f3rter popular da cidade, viana farias, o famoso m\u00e3o cheia da r\u00e1dio tupinamb\u00e1 fm. O padrinho do homenageado ser\u00e1 carlos torres, do programa \u201cnos bastidores da politica\u201d com entrega agendada para setembro no plen\u00e1rio 05 de julho, em grande estilo na cidade de dom jos\u00e9 tupinamb\u00e1 da frota. Aguardar \u00e9 preciso amigos.<br \/>\n04 &#8211; existe uma expectativa boa para ainda este ano \u00e9 que o novo presidente do centro cultural dom jos\u00e9 dr. mendes junior dar\u00e1 ecoar em parceria com a secretaria de urbanismo dra. marilia gouveia lima lan\u00e7arem uma nova vers\u00e3o do livro a \u201chist\u00f3ria de sobral\u201d escrito por dom jos\u00e9 tupinamb\u00e1 da frota. Vamos torcer para este pr\u00eamio para sobral, brevemente. Viva o centro cultural dom jose!<\/p>\n<p><strong>PAREI AQUI \u2013 FALTA FAZER O ITEM 5<\/strong><br \/>\n05 &#8211; O programa \u201civan frota\u201d no becco do cotovelo voltar\u00e1 ao ar em julho, com uma nova roupagem, um novo prefixo fm e muitas novidades para cidade com shows ao vivo, reportagens e entrevistas bomb\u00e1sticas. Tudo ao vivo, via canais sociais de tv e r\u00e1dio para todo mundo. Aguardar e preciso bequeanos amigos,<br \/>\n06 &#8211; o diretor do jornal correio da semana padre lucas sera homenageado por m\u00e9ritos, pelo Centro, este ano e representando a diocese de sobral com o trof\u00e9u Dom Jos\u00e9, quando setembro vier na cidade. Ser\u00e1 o reconheciento de um ser humano que se doa a causa Sobral e a igreja irmanada em tempos t\u00e3o dificies a que ivenciamos na modernidade. Uma justa homenagem a quem faz pela vida.<br \/>\n07 &#8211; vivemos dias sofridos magoados pelo virus do mundo, o coronovirus de todos os males sociais. Somos cavaleiros do destino so deus na causa para salvar o mundo. Vamos orar pela vida pelas perdas, e pela paz mundial. Salva jesus teu povo bom e sofrido nestecalvario de dor e morte. Am\u00e9m, Jesus!<br \/>\n08 &#8211; dizem por a\u00ed que ou abominamos os pol\u00edticos corruptos de carteirinhas ou eles acabar\u00e3o com j\u00e1 com nossas vidas de sonhadores de um mundo melhor para nossa na\u00e7\u00e3o verde e amarela de fome e vergonha. Vamos modificar as nossas vidas visando um futuro de amor e paz entre os homens da terra. Am\u00e9m!<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16177\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1-244x300.jpg\" alt=\"\" width=\"244\" height=\"300\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1-244x300.jpg 244w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1-832x1024.jpg 832w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1-768x945.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1-1248x1536.jpg 1248w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1-1024x1261.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Naldo-e-padre-Lucas-1.jpg 1277w\" sizes=\"(max-width: 244px) 100vw, 244px\" \/>PERFIL: <\/strong><strong>Padre lucas<\/strong><br \/>\nUm cidad\u00e3o com todas as letras, digno sacerdote, amigo da imprernsa, diretor maior do nossso Jornal Correio da Semana, fundado por dom Jos\u00e9, h\u00e1 mais de cem anos, um entusiasta social da vida, cat\u00f3lico em toda regiao Norte. Hoje figurando por m\u00e9ritos como o perfil da semana neste noticioso da nossa diocese amada e respeitada em todo pa\u00eds. Viva o jornal Correio da Semana de Sobral!<br \/>\nLivre pensar: + Morrer n\u00e3o \u00e9 nada. Horrivel \u00e9 n\u00e3o viver (Victor Hugo). Chico Prado (Poeta e escritor).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Livrai-nos, senhor! Dos ataques a santa C\u00e2mara Municipal com seus discipulos aliados do poder central&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":16178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,27],"tags":[],"class_list":["post-16176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-becco-ponto-com"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg",781,903,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22-259x300.jpg",259,300,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22-768x888.jpg",640,740,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg",640,740,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg",781,903,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg",781,903,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg",781,903,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22-540x340.jpg",540,340,true]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/becco-ponto-com\/\" rel=\"category tag\">Becco Ponto Com<\/a>","tag_info":"Becco Ponto Com","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg","jetpack-related-posts":[{"id":21151,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-102\/","url_meta":{"origin":16176,"position":0},"title":"Becco ponto Com","author":"","date":"Outubro 2, 2022","format":false,"excerpt":"Livrai-nos, senhor! 01. Dos resultados das urnas nas elei\u00e7\u00f5es. 02. Do mel cruel nos bares da cidade, ufa! 03. Dos ignorantes a hist\u00f3ria de Sobral, ui! 04. Dos fg\u2019s perderem estas elei\u00e7\u00f5es no ce. 05. Da corrup\u00e7\u00e3o ganhar for\u00e7a em 2023, ui! 06. Da demora em abrir o centro da\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16207,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-36\/","url_meta":{"origin":16176,"position":1},"title":"Becco ponto Com","author":"","date":"Abril 18, 2021","format":false,"excerpt":"Livrai-Nos Senhor! Dos bab\u00f5es de plant\u00e3o da cidade os tais caixas pretas. Da briga surda entre a oposi\u00e7\u00e3o e a situa\u00e7\u00e3o t\u00e3o baixa. Dos negacionistas brigando por vacinas pol\u00edticas, ufa! Das festinhas ricas e modernas nas caladas das noites. Da tristeza mortal nas ruas de sobral com tranca tudo. Dos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18094,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-62\/","url_meta":{"origin":16176,"position":2},"title":"Becco ponto Com","author":"","date":"Novembro 22, 2021","format":false,"excerpt":"Livrai-nos, senhor! Das a\u00e7\u00f5es nefastas dos aquinhoados do poder central. Das cren\u00e7as modernas por um Deus de moedas reais, ui! Dos papagaios de piratas e dos pol\u00edticos caras de pau, ui! Do ensino moderno formando analfabetos funcionais. Dos mortos-vivos salvos da pandemia pol\u00edtica nacional. Dos picaretas do voto, formando filas\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9876,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-19\/","url_meta":{"origin":16176,"position":3},"title":"Becco ponto Com","author":"","date":"Novembro 18, 2019","format":false,"excerpt":"LIVRAI -NOS, SENHOR! Da soltura do tal LULA LIVRE e louco, ufa! Do p\u00e3o e circo que vem por a\u00ed via VOTOS. Da tomada do PODER pelo PT um dia, ufa! Da qualidade do ensino com FACILIDADES. Do abandono da pra\u00e7a da SANTA CASA, ui! Das faculdades formando SEMIANALFAS. Do\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/Vereador-Camilo-Motos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/Vereador-Camilo-Motos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/Vereador-Camilo-Motos.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16406,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-38\/","url_meta":{"origin":16176,"position":4},"title":"Becco ponto Com","author":"","date":"Maio 10, 2021","format":false,"excerpt":"LIVRAI-NOS, SENHOR! 01. Dos acordos pol\u00edticos que sempre viram pizza. 02. Do chororo do iptu dos novos ricos por aqui. 03. Da volta do capit\u00e3o mito ao planalto um dia, ui! 04. Da briga surda dos edis da situa\u00e7\u00e3o calados. 05. Da ruma de candidatos \u00e0 presidente no Cear\u00e1. 06.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16475,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-39\/","url_meta":{"origin":16176,"position":5},"title":"Becco ponto Com","author":"","date":"Maio 17, 2021","format":false,"excerpt":"Livrai-nos, Senhor! Dos alaridos pol\u00edticos picaretas e corruptos. Da falta da vacina. Vergonha para um pa\u00eds doente. Dos pobres nas filas da morte da covid, 400 mil, ui! Da matan\u00e7a de um povo doente por fome e justi\u00e7a. Dos marreteiros do voto do povo de 4 em 4 anos. Dos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=16176"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16176\/revisions"}],"predecessor-version":[{"id":16179,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16176\/revisions\/16179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/16178"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=16176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=16176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=16176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}