{"id":16376,"date":"2021-05-10T00:31:56","date_gmt":"2021-05-10T03:31:56","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=16376"},"modified":"2021-05-10T00:31:56","modified_gmt":"2021-05-10T03:31:56","slug":"5g-vai-revolucionar-vida-das-empresas","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/5g-vai-revolucionar-vida-das-empresas\/","title":{"rendered":"5G vai revolucionar vida das empresas"},"content":{"rendered":"<p><strong><em>O governo deve realizar o leil\u00e3o do 5G ainda este ano<\/em><\/strong><\/p>\n<p>Por Luciano Nascimento &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/p>\n<p>O ministro das Comunica\u00e7\u00f5es, F\u00e1bio Faria, disse hoje (6) que a chegada da tecnologia 5G vai revolucionar a vida das empresas do pa\u00eds, ao participar do evento virtual da Semana Nacional das Comunica\u00e7\u00f5es Di\u00e1logo Conexis. O ministro destacou que a tecnologia vai aumentar as aplica\u00e7\u00f5es de internet das coisas (IoT, na sigla em ingl\u00eas), especialmente em setores como o agroneg\u00f3cio.<br \/>\n\u201cTeremos aumento do PIB do agroneg\u00f3cio, avan\u00e7os na telemedicina e em seguran\u00e7a p\u00fablica, al\u00e9m da possibilidade de acabar com o deserto digital que atinge hoje cerca de 40 milh\u00f5es de brasileiros, grande parte deles na Regi\u00e3o Norte\u201d, disse o ministro. \u201cO setor [do agroneg\u00f3cio] ter\u00e1 potencial para crescer 20% ao ano, o que significa dobrar de tamanho em cinco anos\u201d, afirmou.<br \/>\nSegundo Faria, o governo deve realizar o leil\u00e3o do 5G ainda este ano. Ele disse que o edital do leil\u00e3o ainda est\u00e1 em an\u00e1lise no Tribunal de Contas da Uni\u00e3o (TCU) e a expectativa \u00e9 que a corte finalize a an\u00e1lise em junho.<br \/>\n\u201cIremos levar internet para a popula\u00e7\u00e3o brasileira que ainda n\u00e3o t\u00eam. O 4G revolucionou a vida das pessoas e o 5G ir\u00e1 revolucionar a ind\u00fastria, as empresas e possibilitar avan\u00e7os no que se refere \u00e0 Internet das Coisas\u201d, disse.<br \/>\nO ministro ressaltou o impacto que a implementa\u00e7\u00e3o do 5G trar\u00e1 para a economia. \u201cO Brasil \u00e9 um dos pa\u00edses que mais atrai investimentos em tecnologia, e com o 5G vamos melhorar nosso ambiente de neg\u00f3cios e expandir as telecomunica\u00e7\u00f5es em todo o territ\u00f3rio nacional\u201d, disse.<br \/>\nDe acordo com o ministro, 90% das novas antenas que ser\u00e3o usadas para oferta espec\u00edfica do servi\u00e7o poder\u00e3o ser caracterizadas como de pequeno porte, fazendo com que a sua instala\u00e7\u00e3o seja simplificada.<br \/>\nUm decreto sobre a instala\u00e7\u00e3o de antenas foi publicado pela pasta no ano passado. Segundo o ministro, a medida diminuiu os entraves para a instala\u00e7\u00e3o desse tipo de equipamento pelas operadoras de telecomunica\u00e7\u00f5es.<br \/>\n\u201cSem o decreto da\u00a0Lei Geral de Antenas, seria imposs\u00edvel termos 5G. Principalmente em rela\u00e7\u00e3o ao sil\u00eancio positivo. Em v\u00e1rios estados do Brasil n\u00f3s demor\u00e1vamos dois, tr\u00eas anos para termos retorno\u201d, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo deve realizar o leil\u00e3o do 5G ainda este ano Por Luciano Nascimento &#8211;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-16376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg",1170,700,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803-300x179.jpg",300,179,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803-768x459.jpg",640,383,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803-1024x613.jpg",640,383,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg",1170,700,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg",1170,700,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803-1024x613.jpg",1024,613,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803-540x340.jpg",540,340,true]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg","jetpack-related-posts":[{"id":31539,"url":"https:\/\/correiodasemana.com\/site\/dois-anos-de-5g-no-brasil-qual-o-cronograma-para-o-futuro\/","url_meta":{"origin":16376,"position":0},"title":"Dois anos de 5G no Brasil: qual o cronograma para o futuro?","author":"adminredacao","date":"Novembro 24, 2024","format":false,"excerpt":"Com uma agenda definida pela Anatel, a tecnologia m\u00f3vel precisa se estabelecer para incentivar a inova\u00e7\u00e3o e garantir a integra\u00e7\u00e3o de tecnologias como Intelig\u00eancia Artificial e Internet das Coisas CURITIBA, 22\/11\/2024 - Com dois anos completos em julho no Brasil, o 5G j\u00e1 est\u00e1 presente em quase 600 munic\u00edpios, sendo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/5G-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/5G-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/5G-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/5G-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20373,"url":"https:\/\/correiodasemana.com\/site\/tecnologia-5g-estreia-no-brasil-brasilia-foi-a-primeira-cidade-a-receber-nova-tecnologia\/","url_meta":{"origin":16376,"position":1},"title":"Tecnologia 5G estreia no Brasil:  Bras\u00edlia foi a primeira cidade a receber nova tecnologia","author":"","date":"Julho 11, 2022","format":false,"excerpt":"Por Wellton M\u00e1ximo \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia O sinal de 5G puro (sem interfer\u00eancia de outras frequ\u00eancias) estreiou no Brasil na\u00a0quarta-feira (5). A primeira cidade a oferecer o sinal foi\u00a0Bras\u00edlia, cujo funcionamento foi aprovado na \u00faltima\u00a0segunda-feira (4) pela Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel). Pr\u00f3xima gera\u00e7\u00e3o da internet\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/exposicao_de_tecnologia_5g_digita_day_fpzzb_abr_0405217803.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14701,"url":"https:\/\/correiodasemana.com\/site\/lei-sobre-internet-das-coisas-pode-gerar-milhoes-de-empregos\/","url_meta":{"origin":16376,"position":2},"title":"Lei sobre Internet das Coisas pode gerar milh\u00f5es de empregos","author":"","date":"Novembro 24, 2020","format":false,"excerpt":"Avalia\u00e7\u00e3o \u00e9 do Minist\u00e9rio das Comunica\u00e7\u00f5es Com\u00a0a aprova\u00e7\u00e3o, pelo Senado, do Projeto de Lei (PL) n\u00ba 6.549\/2019, que cria isen\u00e7\u00e3o tribut\u00e1ria para dispositivos e sistemas de comunica\u00e7\u00e3o m\u00e1quina a m\u00e1quina (), a expectativa \u00e9 que a implementa\u00e7\u00e3o da internet das coisas e da internet 5G gere mais de 10 milh\u00f5es\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/internet_dsc5833.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/internet_dsc5833.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/internet_dsc5833.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/internet_dsc5833.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/internet_dsc5833.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":30340,"url":"https:\/\/correiodasemana.com\/site\/brisanet-inicia-venda-do-fwa-5g-em-76-cidades-do-nordeste\/","url_meta":{"origin":16376,"position":3},"title":"Brisanet inicia venda do FWA 5G em 76 cidades do Nordeste","author":"adminredacao","date":"Agosto 12, 2024","format":false,"excerpt":"O servi\u00e7o utiliza a rede 5G como meio de acesso \u00e0\u00a0 internet fixa, dispensando o uso de cabos Seguindo a estrat\u00e9gia de proporcionar excel\u00eancia em conectividade para seus clientes, a Brisanet inicia a comercializa\u00e7\u00e3o do seu mais novo servi\u00e7o: a internet banda larga Brisa FWA 5G (Fixed Wireless Access). O\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/6937321e-c56a-4bcd-8c5d-a847a8b9fe50.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/6937321e-c56a-4bcd-8c5d-a847a8b9fe50.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/6937321e-c56a-4bcd-8c5d-a847a8b9fe50.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/6937321e-c56a-4bcd-8c5d-a847a8b9fe50.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/6937321e-c56a-4bcd-8c5d-a847a8b9fe50.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/6937321e-c56a-4bcd-8c5d-a847a8b9fe50.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12278,"url":"https:\/\/correiodasemana.com\/site\/autocritica-na-comunicacao-melhora-imagem-de-bolsonaro-diz-fabio-faria\/","url_meta":{"origin":16376,"position":4},"title":"Autocr\u00edtica na comunica\u00e7\u00e3o melhora imagem de Bolsonaro, diz F\u00e1bio Faria","author":"","date":"Julho 27, 2020","format":false,"excerpt":"Ministro \u00e9 \u201capaziguador\u201d pol\u00edtico. Vai investir em imagem no exterior. 5G: Leil\u00e3o \u00e9 assunto presidencial O ministro das Comunica\u00e7\u00f5es, F\u00e1bio Faria, de 42 anos, declara que a mudan\u00e7a do presidente Jair Bolsonaro na maneira de se comunicar fez a imagem do governo melhorar. De acordo com Faria, o ambiente era\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/maxresdefault.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/maxresdefault.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/maxresdefault.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/maxresdefault.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/maxresdefault.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":31218,"url":"https:\/\/correiodasemana.com\/site\/tim-ativa-rede-5g-em-mais-quatro-cidades-cearenses-entre-elas-sobral\/","url_meta":{"origin":16376,"position":5},"title":"TIM ativa rede 5G em mais quatro cidades cearenses entre elas Sobral","author":"adminredacao","date":"Novembro 3, 2024","format":false,"excerpt":"Operadora avan\u00e7a na expans\u00e3o da nova tecnologia para novos munic\u00edpios, chegando a 495 cidades no Brasil; No Nordeste, o crescimento do tr\u00e1fego de dados na rede 5G foi de 102% no \u00faltimo ano; A TIM, operadora com a maior cobertura m\u00f3vel, presente com 4G em todos os munic\u00edpios do Brasil,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/img_Connectivity.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/img_Connectivity.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/img_Connectivity.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/img_Connectivity.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/img_Connectivity.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=16376"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16376\/revisions"}],"predecessor-version":[{"id":16378,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16376\/revisions\/16378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/16377"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=16376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=16376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=16376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}