{"id":16751,"date":"2021-06-14T01:33:04","date_gmt":"2021-06-14T04:33:04","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=16751"},"modified":"2021-06-14T01:33:04","modified_gmt":"2021-06-14T04:33:04","slug":"em-tempo-86","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-86\/","title":{"rendered":"Em Tempo"},"content":{"rendered":"<p><strong>Vacina cearense\u00a0contra a Covid-19<\/strong><br \/>\nIniciada em abril de 2020, a pesquisa da Universidade Estadual do Cear\u00e1 (Uece) para o desenvolvimento de vacina contra a Covid-19 se prepara para a segunda fase, que consiste na realiza\u00e7\u00e3o de testes em humanos. Para isso, a institui\u00e7\u00e3o aguarda aprova\u00e7\u00e3o pela Anvisa.<br \/>\nA pesquisa \u00e9 desenvolvida no Laborat\u00f3rio de Biotecnologia e Biologia Molecular da Uece (LBBM). A primeira fase da investiga\u00e7\u00e3o, com realiza\u00e7\u00e3o de testes em camundongos, foi conclu\u00edda com sucesso. A vacina cearense em testes j\u00e1 tem nome: HH-120-Defenser.<\/p>\n<p><strong>UFC oferta mestrado em psicologia<\/strong><br \/>\nO Programa de P\u00f3s-Gradua\u00e7\u00e3o Profissional em Psicologia e Pol\u00edticas P\u00fablicas do Campus da Universidade Federal do Cear\u00e1 (UFC) em Sobral recebe inscri\u00e7\u00f5es,\u00a0at\u00e9 30 de junho, para processo seletivo da turma 2021.2 de mestrado. S\u00e3o ofertadas\u00a0at\u00e9 19 vagas.<br \/>\nInscri\u00e7\u00f5es ser\u00e3o feitas pela Internet, atrav\u00e9s do site https:\/\/si3.ufc.br\/sigaa. A sele\u00e7\u00e3o acontecer\u00e1 de 15 de julho a 17 de setembro, em tr\u00eas etapas, sendo as duas primeiras eliminat\u00f3rias, e a \u00faltima, classificat\u00f3ria: projeto de pesquisa, argui\u00e7\u00e3o sobre o projeto e an\u00e1lise de curr\u00edculo.<\/p>\n<p><strong>CD \u201cBelchior canta Cruz e Sousa\u201d<\/strong><br \/>\n<strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16752\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/belchior-1-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/belchior-1-300x188.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/belchior-1-768x482.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/belchior-1-540x340.jpg 540w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/belchior-1-400x250.jpg 400w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/belchior-1.jpg 780w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Foto \u2013 Divulga\u00e7\u00e3o<\/strong><br \/>\n<strong>O cantor e compositor cearense Belchior gravou oito poemas de Cruz e Sousa<\/strong><br \/>\nFoi lan\u00e7ada uma campanha de financiamento coletivo da obra\u00a0\u201cBelchior canta Cruz e Sousa\u201d, atrav\u00e9s da\u00a0Benfeitoria, plataforma pioneira em\u00a0crowdfunding. O per\u00edodo de doa\u00e7\u00e3o ir\u00e1 at\u00e9 fins de julho. Link\u00a0j\u00e1 est\u00e1 dispon\u00edvel: www.benfeitoria.com\/belchiorcantacruzesousa.<br \/>\nEm sua \u00faltima turn\u00ea, no ano de 2005, em Santa Catarina, Belchior musicou e apresentou oito sonetos do poeta simbolista catarinense Cruz e Sousa. E agora, quase 16 anos depois, essa turn\u00ea vai virar um CD em embalagem customizada, tipo digipack, com tr\u00eas pain\u00e9is e um box.<\/p>\n<p><strong>Casa de Teatro Dona Zefinha<\/strong><br \/>\nPara celebrar seus 10 anos, a\u00a0Casa de Teatro Dona Zefinha, em Itapipoca (CE), realiza eventos virtuais a partir de 12 de junho, com a divulga\u00e7\u00e3o do \u00e1lbum \u201cSom das Pedras\u201d, com 10 can\u00e7\u00f5es de m\u00fasicos da cidade. Todos os conte\u00fados estar\u00e3o dispon\u00edveis nas plataformas digitais.<br \/>\nA obra reunir\u00e1 v\u00e1rios nomes da cena itapipoquense com o objetivo de homenagear os diversos estilos e experimenta\u00e7\u00f5es feitos na regi\u00e3o. A colet\u00e2nea \u00e9 inspirada no disco \u201cCoquetel das Pedras\u201d, lan\u00e7ado em 1994. Outras informa\u00e7\u00f5es no perfil do Instagram\u00a0@dona.zefinha.<\/p>\n<p><strong>90 anos do cantor Jo\u00e3o Gilberto<\/strong><br \/>\nO cantor Jo\u00e3o Gilberto (1931 \u2013 2019) completaria 90 anos de idade no dia 10 de junho. Em homenagem ao artista, a r\u00e1dio Batuta, do Instituto Moreira Salles, divulgou, no dia 2 de junho,\u00a0grava\u00e7\u00f5es in\u00e9ditas\u00a0do m\u00fasico, dispon\u00edveis no\u00a0site\u00a0https:\/\/radiobatuta.com.br.<br \/>\nO material re\u00fane o conte\u00fado de\u00a0tr\u00eas fitas de rolo\u00a0gravadas em Salvador entre setembro de 1959 e dezembro de 1960 pelo m\u00fasico e cronista\u00a0Carlos Coqueijo. No material, Jo\u00e3o Gilberto interpreta\u00a041 can\u00e7\u00f5es\u00a0de diversos m\u00fasicos, como Dorival Caymmi, Tom Jobim e Carlos Lyra.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br). Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vacina cearense\u00a0contra a Covid-19 Iniciada em abril de 2020, a pesquisa da Universidade Estadual do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-16751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg","jetpack-related-posts":[{"id":16981,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-90\/","url_meta":{"origin":16751,"position":0},"title":"Em Tempo","author":"","date":"Julho 12, 2021","format":false,"excerpt":"Vacina cearense contra Covid-19\u00a0 A Universidade Estadual do Cear\u00e1 (Uece) recebeu, no m\u00eas de junho, comitiva da Fiocruz Cear\u00e1 e da Fiocruz Rio de Janeiro para tratativas de coopera\u00e7\u00e3o t\u00e9cnica e cient\u00edfica entre as institui\u00e7\u00f5es, no tocante ao desenvolvimento da vacina contra a covid-19, 2H120 Defense. A coopera\u00e7\u00e3o visa fazer\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17675,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-102\/","url_meta":{"origin":16751,"position":1},"title":"Em Tempo","author":"","date":"Outubro 4, 2021","format":false,"excerpt":"Sele\u00e7\u00e3o para bolsistas na Embrapa Embrapa Caprinos e Ovinos selecionar\u00e1 bolsistas para projetos de pesquisa, com atua\u00e7\u00e3o na sua sede, em Sobral (CE) e em n\u00facleos regionais em Campina Grande (PB) e em Coronel Pacheco (MG). As inscri\u00e7\u00f5es v\u00e3o at\u00e9 8 de outubro pelo e-mail\u00a0cnpc.estagios@embrapa.br. O edital de sele\u00e7\u00e3o prev\u00ea\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16134,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-76\/","url_meta":{"origin":16751,"position":2},"title":"Em Tempo","author":"","date":"Abril 5, 2021","format":false,"excerpt":"Mestrado em Engenharia Mec\u00e2nica O Programa de P\u00f3s-Gradua\u00e7\u00e3o em Engenharia Mec\u00e2nica da Universidade Federal do Cear\u00e1 (UFC) recebe inscri\u00e7\u00f5es, at\u00e9 o dia 13 de abril, para o processo seletivo da turma de mestrado acad\u00eamico de 2021. Inscri\u00e7\u00f5es devem ser feitas pela Internet, no site https:\/\/si3.ufc.br\/sigaa. De acordo com o\u00a0Edital n\u00ba\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15227,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-63\/","url_meta":{"origin":16751,"position":3},"title":"Em Tempo","author":"","date":"Dezembro 27, 2020","format":false,"excerpt":"Freezers para armazenamento de vacinas\u00a0 A Universidade Federal do Cear\u00e1 (UFC) disponibilizou \u00e0 Secretaria da Sa\u00fade do Estado do Cear\u00e1 (SESA)\u00a0oito freezers de alta pot\u00eancia\u00a0para o armazenamento de at\u00e9 53 milh\u00f5es de doses\u00a0das vacinas contra a Covid-19, a uma temperatura de 70 graus negativos. No dia 18 de dezembro, o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16192,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-77\/","url_meta":{"origin":16751,"position":4},"title":"Em Tempo","author":"","date":"Abril 12, 2021","format":false,"excerpt":"Festival de Bolso de M\u00fasica Brasileira Qual interse\u00e7\u00e3o entre a m\u00fasica e a poesia? Melodias, letras e poemas se misturam. Tornam-se espa\u00e7o de encontros art\u00edsticos e reflex\u00f5es. Com essa proposta, o \u201cPoem\u00fasica \u2013 Festival de Bolso de M\u00fasica Brasileira\u201d acontece em abril nas plataformas virtuais. Na sexta-feira, dia 9, a\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14507,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-56\/","url_meta":{"origin":16751,"position":5},"title":"Em Tempo","author":"","date":"Novembro 12, 2020","format":false,"excerpt":"TRE pro\u00edbe aglomera\u00e7\u00f5es no Cear\u00e1 Tribunal Regional Eleitoral do Cear\u00e1 (TRE) proibiu atos presenciais de campanha que gerem aglomera\u00e7\u00f5es. Est\u00e3o proibidos com\u00edcios, bandeira\u00e7os, passeatas, caminhadas, carreatas e similares, ainda que no formato drive-thru ou drive-in, em espa\u00e7os abertos semi-abertos. Resolu\u00e7\u00e3o, de 4 de novembro, abrange todo o Estado. Em caso\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=16751"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16751\/revisions"}],"predecessor-version":[{"id":16753,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/16751\/revisions\/16753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=16751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=16751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=16751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}